{"id":91941,"date":"2016-10-05T16:48:51","date_gmt":"2016-10-05T21:48:51","guid":{"rendered":"http:\/\/www.fiscalia.gov.co\/colombia\/?p=91941"},"modified":"2016-10-05T16:48:51","modified_gmt":"2016-10-05T21:48:51","slug":"fiscalia-investiga-hurto-de-comida-para-estudiantes-en-colegio-de-floridablanca-santander","status":"publish","type":"post","link":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/fiscalia-investiga-hurto-de-comida-para-estudiantes-en-colegio-de-floridablanca-santander\/","title":{"rendered":"Fiscal\u00eda investiga hurto de comida para estudiantes en colegio de Floridablanca (Santander)"},"content":{"rendered":"<p>La Direcci\u00f3n Seccional de \u00a0Fiscal\u00edas de Santander abri\u00f3 investigaci\u00f3n formal en el caso de hurto ocurrido en la sede D del colegio Metropolitano del Sur, en el barrio Villabel de Floridablanca.<\/p>\n<p>Por tercera vez, este establecimiento educativo fue v\u00edctima de los delincuentes; pero esta vez se llevaron los suministros para la preparaci\u00f3n de la comida para los m\u00e1s de 300 alumnos de esta instituci\u00f3n, en hechos ocurridos durante la noche del 1\u00ba de octubre del 2016.<\/p>\n<p>&nbsp;<\/p>\n<p>DRAO \/ AAEA<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n\n<div class=\"twitter-share\"><a href=\"https:\/\/twitter.com\/intent\/tweet?via=fiscaliacol\" class=\"twitter-share-button\">Tweet<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La Direcci\u00f3n Seccional de \u00a0Fiscal\u00edas de Santander abri\u00f3 investigaci\u00f3n formal en el caso de hurto ocurrido en la sede D del colegio Metropolitano del Sur, en el barrio Villabel de [&hellip;]<\/p>\n","protected":false},"author":143,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[322,303],"tags":[],"class_list":["post-91941","post","type-post","status-publish","format-standard","category-seccional-bucaramanga","category-seccionales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fiscal\u00eda General de la Naci\u00f3n<\/title>\n<meta name=\"description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/fiscalia-investiga-hurto-de-comida-para-estudiantes-en-colegio-de-floridablanca-santander\/\" \/>\n<meta property=\"og:site_name\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FiscaliaCol\" \/>\n<meta property=\"article:published_time\" content=\"2016-10-05T21:48:51+00:00\" \/>\n<meta name=\"author\" content=\"dfgordillo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:site\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"dfgordillo\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/fiscalia-investiga-hurto-de-comida-para-estudiantes-en-colegio-de-floridablanca-santander\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/fiscalia-investiga-hurto-de-comida-para-estudiantes-en-colegio-de-floridablanca-santander\/\"},\"author\":{\"name\":\"dfgordillo\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/3903856a3ce2d54b094c69eb29247895\"},\"headline\":\"Fiscal\u00eda investiga hurto de comida para estudiantes en colegio de Floridablanca (Santander)\",\"datePublished\":\"2016-10-05T21:48:51+00:00\",\"dateModified\":\"2016-10-05T21:48:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/fiscalia-investiga-hurto-de-comida-para-estudiantes-en-colegio-de-floridablanca-santander\/\"},\"wordCount\":98,\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"articleSection\":[\"Seccional Bucaramanga\",\"Seccionales\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/fiscalia-investiga-hurto-de-comida-para-estudiantes-en-colegio-de-floridablanca-santander\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/fiscalia-investiga-hurto-de-comida-para-estudiantes-en-colegio-de-floridablanca-santander\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\"},\"datePublished\":\"2016-10-05T21:48:51+00:00\",\"dateModified\":\"2016-10-05T21:48:51+00:00\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/fiscalia-investiga-hurto-de-comida-para-estudiantes-en-colegio-de-floridablanca-santander\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/fiscalia-investiga-hurto-de-comida-para-estudiantes-en-colegio-de-floridablanca-santander\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/fiscalia-investiga-hurto-de-comida-para-estudiantes-en-colegio-de-floridablanca-santander\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fiscal\u00eda investiga hurto de comida para estudiantes en colegio de Floridablanca (Santander)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"contentUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"width\":300,\"height\":90,\"caption\":\"Fiscal\u00eda General de la Naci\u00f3n\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/FiscaliaCol\",\"https:\/\/x.com\/FiscaliaCol\",\"https:\/\/www.instagram.com\/fiscaliacol\",\"https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/\",\"https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/3903856a3ce2d54b094c69eb29247895\",\"name\":\"dfgordillo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b6356e21c5657c60757fe6fb9493e947?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b6356e21c5657c60757fe6fb9493e947?s=96&d=mm&r=g\",\"caption\":\"dfgordillo\"},\"sameAs\":[\"dfgordillo\"],\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/author\/dfgordillo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Fiscal\u00eda General de la Naci\u00f3n","og_description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","og_url":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/fiscalia-investiga-hurto-de-comida-para-estudiantes-en-colegio-de-floridablanca-santander\/","og_site_name":"Fiscal\u00eda General de la Naci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/FiscaliaCol","article_published_time":"2016-10-05T21:48:51+00:00","author":"dfgordillo","twitter_card":"summary_large_image","twitter_creator":"@FiscaliaCol","twitter_site":"@FiscaliaCol","twitter_misc":{"Escrito por":"dfgordillo"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/fiscalia-investiga-hurto-de-comida-para-estudiantes-en-colegio-de-floridablanca-santander\/#article","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/fiscalia-investiga-hurto-de-comida-para-estudiantes-en-colegio-de-floridablanca-santander\/"},"author":{"name":"dfgordillo","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/3903856a3ce2d54b094c69eb29247895"},"headline":"Fiscal\u00eda investiga hurto de comida para estudiantes en colegio de Floridablanca (Santander)","datePublished":"2016-10-05T21:48:51+00:00","dateModified":"2016-10-05T21:48:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/fiscalia-investiga-hurto-de-comida-para-estudiantes-en-colegio-de-floridablanca-santander\/"},"wordCount":98,"publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"articleSection":["Seccional Bucaramanga","Seccionales"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/fiscalia-investiga-hurto-de-comida-para-estudiantes-en-colegio-de-floridablanca-santander\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/fiscalia-investiga-hurto-de-comida-para-estudiantes-en-colegio-de-floridablanca-santander\/","name":"Fiscal\u00eda General de la Naci\u00f3n","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website"},"datePublished":"2016-10-05T21:48:51+00:00","dateModified":"2016-10-05T21:48:51+00:00","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","breadcrumb":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/fiscalia-investiga-hurto-de-comida-para-estudiantes-en-colegio-de-floridablanca-santander\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/fiscalia-investiga-hurto-de-comida-para-estudiantes-en-colegio-de-floridablanca-santander\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/fiscalia-investiga-hurto-de-comida-para-estudiantes-en-colegio-de-floridablanca-santander\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fiscalia.gov.co\/colombia\/"},{"@type":"ListItem","position":2,"name":"Fiscal\u00eda investiga hurto de comida para estudiantes en colegio de Floridablanca (Santander)"}]},{"@type":"WebSite","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","name":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization","name":"Fiscal\u00eda General de la Naci\u00f3n","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","contentUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","width":300,"height":90,"caption":"Fiscal\u00eda General de la Naci\u00f3n"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FiscaliaCol","https:\/\/x.com\/FiscaliaCol","https:\/\/www.instagram.com\/fiscaliacol","https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/","https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh"]},{"@type":"Person","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/3903856a3ce2d54b094c69eb29247895","name":"dfgordillo","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b6356e21c5657c60757fe6fb9493e947?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6356e21c5657c60757fe6fb9493e947?s=96&d=mm&r=g","caption":"dfgordillo"},"sameAs":["dfgordillo"],"url":"https:\/\/www.fiscalia.gov.co\/colombia\/author\/dfgordillo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/91941","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/users\/143"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/comments?post=91941"}],"version-history":[{"count":2,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/91941\/revisions"}],"predecessor-version":[{"id":91943,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/91941\/revisions\/91943"}],"wp:attachment":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/media?parent=91941"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/categories?post=91941"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/tags?post=91941"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}