{"id":91253,"date":"2016-09-28T16:49:36","date_gmt":"2016-09-28T21:49:36","guid":{"rendered":"http:\/\/www.fiscalia.gov.co\/colombia\/?p=91253"},"modified":"2016-09-28T16:49:36","modified_gmt":"2016-09-28T21:49:36","slug":"asegurado-presunto-cabecilla-de-banda-dedicada-a-la-extorsion-en-betulia-antioquia","status":"publish","type":"post","link":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-medellin\/asegurado-presunto-cabecilla-de-banda-dedicada-a-la-extorsion-en-betulia-antioquia\/","title":{"rendered":"Asegurado presunto cabecilla de banda dedicada a la extorsi\u00f3n en Betulia (Antioquia)"},"content":{"rendered":"<p>Juan Bautista Mar\u00edn Chavarriaga, alias Juanchito, presunto cabecilla de una organizaci\u00f3n criminal conocida como la banda de Los Parmalat, fue enviado a la c\u00e1rcel por el Juzgado 17 Penal Municipal de Medell\u00edn, con funci\u00f3n de control de garant\u00edas, como presunto responsable\u00a0de concierto para delinquir agravado\u00a0con fines de extorsi\u00f3n y tentativa de extorsi\u00f3n.<\/p>\n<p>La investigaci\u00f3n est\u00e1 relacionada con una serie de exigencias econ\u00f3micas de las que fueron v\u00edctimas finqueros, comerciantes y transportadores del municipio de Betulia (Antioquia) por parte de un grupo que se identific\u00f3 inicialmente como Autodefensas Gaitanistas de Colombia.<\/p>\n<p>Los investigadores establecieron que los presuntos extorsionistas trabajaban para el denominado Clan de Golfo y que una de las v\u00edctimas fue Le\u00f3n Dar\u00edo V\u00e9lez Yepes, exalcalde de la citada poblaci\u00f3n,\u00a0a quien le exigieron la suma de 10\u00a0millones de pesos a cambio de no atentar contra su vida.<\/p>\n<p>Alias Juanchito, quien habr\u00eda ingresado a la estructura criminal desde el a\u00f1o 2012, fue capturado este martes entre los municipios antioque\u00f1os de Betulia y Concordia por servidores del CTI adscritos al Gaula Militar con apoyo del Ej\u00e9rcito Nacional y no acept\u00f3 los cargos que le imput\u00f3 la Fiscal\u00eda.<\/p>\n<p>Otros siete integrantes de Los Parmalat est\u00e1n presos,\u00a0\u00a0seis de los cuales fueron condenados a 4 a\u00f1os de prisi\u00f3n por v\u00eda de preacuerdo.\u00a0 El \u00a0restante tambi\u00e9n acept\u00f3 cargos y est\u00e1 pendiente de sentencia.<\/p>\n<p>&nbsp;<\/p>\n<p>LFML \/ AAEA<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n\n<div class=\"twitter-share\"><a href=\"https:\/\/twitter.com\/intent\/tweet?via=fiscaliacol\" class=\"twitter-share-button\">Tweet<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Juan Bautista Mar\u00edn Chavarriaga, alias Juanchito, presunto cabecilla de una organizaci\u00f3n criminal conocida como la banda de Los Parmalat, fue enviado a la c\u00e1rcel por el Juzgado 17 Penal Municipal [&hellip;]<\/p>\n","protected":false},"author":143,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[331],"tags":[9486,7336,935,3268],"class_list":["post-91253","post","type-post","status-publish","format-standard","category-seccional-medellin","tag-autodefensas-gaitanistas-de-colombia","tag-concierto-para-delinquir-agravado","tag-extorsion","tag-tentativa-de-extorsion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fiscal\u00eda General de la Naci\u00f3n<\/title>\n<meta name=\"description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-medellin\/asegurado-presunto-cabecilla-de-banda-dedicada-a-la-extorsion-en-betulia-antioquia\/\" \/>\n<meta property=\"og:site_name\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FiscaliaCol\" \/>\n<meta property=\"article:published_time\" content=\"2016-09-28T21:49:36+00:00\" \/>\n<meta name=\"author\" content=\"dfgordillo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:site\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"dfgordillo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-medellin\/asegurado-presunto-cabecilla-de-banda-dedicada-a-la-extorsion-en-betulia-antioquia\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-medellin\/asegurado-presunto-cabecilla-de-banda-dedicada-a-la-extorsion-en-betulia-antioquia\/\"},\"author\":{\"name\":\"dfgordillo\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/3903856a3ce2d54b094c69eb29247895\"},\"headline\":\"Asegurado presunto cabecilla de banda dedicada a la extorsi\u00f3n en Betulia (Antioquia)\",\"datePublished\":\"2016-09-28T21:49:36+00:00\",\"dateModified\":\"2016-09-28T21:49:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-medellin\/asegurado-presunto-cabecilla-de-banda-dedicada-a-la-extorsion-en-betulia-antioquia\/\"},\"wordCount\":262,\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"keywords\":[\"Autodefensas Gaitanistas de Colombia\",\"Concierto para delinquir agravado\",\"Extorsi\u00f3n\",\"Tentativa de extorsi\u00f3n\"],\"articleSection\":[\"Seccional Medell\u00edn\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-medellin\/asegurado-presunto-cabecilla-de-banda-dedicada-a-la-extorsion-en-betulia-antioquia\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-medellin\/asegurado-presunto-cabecilla-de-banda-dedicada-a-la-extorsion-en-betulia-antioquia\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\"},\"datePublished\":\"2016-09-28T21:49:36+00:00\",\"dateModified\":\"2016-09-28T21:49:36+00:00\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-medellin\/asegurado-presunto-cabecilla-de-banda-dedicada-a-la-extorsion-en-betulia-antioquia\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-medellin\/asegurado-presunto-cabecilla-de-banda-dedicada-a-la-extorsion-en-betulia-antioquia\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-medellin\/asegurado-presunto-cabecilla-de-banda-dedicada-a-la-extorsion-en-betulia-antioquia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Asegurado presunto cabecilla de banda dedicada a la extorsi\u00f3n en Betulia (Antioquia)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"contentUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"width\":300,\"height\":90,\"caption\":\"Fiscal\u00eda General de la Naci\u00f3n\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/FiscaliaCol\",\"https:\/\/x.com\/FiscaliaCol\",\"https:\/\/www.instagram.com\/fiscaliacol\",\"https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/\",\"https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/3903856a3ce2d54b094c69eb29247895\",\"name\":\"dfgordillo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b6356e21c5657c60757fe6fb9493e947?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b6356e21c5657c60757fe6fb9493e947?s=96&d=mm&r=g\",\"caption\":\"dfgordillo\"},\"sameAs\":[\"dfgordillo\"],\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/author\/dfgordillo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Fiscal\u00eda General de la Naci\u00f3n","og_description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","og_url":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-medellin\/asegurado-presunto-cabecilla-de-banda-dedicada-a-la-extorsion-en-betulia-antioquia\/","og_site_name":"Fiscal\u00eda General de la Naci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/FiscaliaCol","article_published_time":"2016-09-28T21:49:36+00:00","author":"dfgordillo","twitter_card":"summary_large_image","twitter_creator":"@FiscaliaCol","twitter_site":"@FiscaliaCol","twitter_misc":{"Escrito por":"dfgordillo","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-medellin\/asegurado-presunto-cabecilla-de-banda-dedicada-a-la-extorsion-en-betulia-antioquia\/#article","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-medellin\/asegurado-presunto-cabecilla-de-banda-dedicada-a-la-extorsion-en-betulia-antioquia\/"},"author":{"name":"dfgordillo","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/3903856a3ce2d54b094c69eb29247895"},"headline":"Asegurado presunto cabecilla de banda dedicada a la extorsi\u00f3n en Betulia (Antioquia)","datePublished":"2016-09-28T21:49:36+00:00","dateModified":"2016-09-28T21:49:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-medellin\/asegurado-presunto-cabecilla-de-banda-dedicada-a-la-extorsion-en-betulia-antioquia\/"},"wordCount":262,"publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"keywords":["Autodefensas Gaitanistas de Colombia","Concierto para delinquir agravado","Extorsi\u00f3n","Tentativa de extorsi\u00f3n"],"articleSection":["Seccional Medell\u00edn"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-medellin\/asegurado-presunto-cabecilla-de-banda-dedicada-a-la-extorsion-en-betulia-antioquia\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-medellin\/asegurado-presunto-cabecilla-de-banda-dedicada-a-la-extorsion-en-betulia-antioquia\/","name":"Fiscal\u00eda General de la Naci\u00f3n","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website"},"datePublished":"2016-09-28T21:49:36+00:00","dateModified":"2016-09-28T21:49:36+00:00","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","breadcrumb":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-medellin\/asegurado-presunto-cabecilla-de-banda-dedicada-a-la-extorsion-en-betulia-antioquia\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-medellin\/asegurado-presunto-cabecilla-de-banda-dedicada-a-la-extorsion-en-betulia-antioquia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-medellin\/asegurado-presunto-cabecilla-de-banda-dedicada-a-la-extorsion-en-betulia-antioquia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fiscalia.gov.co\/colombia\/"},{"@type":"ListItem","position":2,"name":"Asegurado presunto cabecilla de banda dedicada a la extorsi\u00f3n en Betulia (Antioquia)"}]},{"@type":"WebSite","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","name":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization","name":"Fiscal\u00eda General de la Naci\u00f3n","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","contentUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","width":300,"height":90,"caption":"Fiscal\u00eda General de la Naci\u00f3n"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FiscaliaCol","https:\/\/x.com\/FiscaliaCol","https:\/\/www.instagram.com\/fiscaliacol","https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/","https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh"]},{"@type":"Person","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/3903856a3ce2d54b094c69eb29247895","name":"dfgordillo","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b6356e21c5657c60757fe6fb9493e947?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6356e21c5657c60757fe6fb9493e947?s=96&d=mm&r=g","caption":"dfgordillo"},"sameAs":["dfgordillo"],"url":"https:\/\/www.fiscalia.gov.co\/colombia\/author\/dfgordillo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/91253","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/users\/143"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/comments?post=91253"}],"version-history":[{"count":1,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/91253\/revisions"}],"predecessor-version":[{"id":91254,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/91253\/revisions\/91254"}],"wp:attachment":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/media?parent=91253"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/categories?post=91253"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/tags?post=91253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}