{"id":91128,"date":"2016-09-27T17:38:16","date_gmt":"2016-09-27T22:38:16","guid":{"rendered":"http:\/\/www.fiscalia.gov.co\/colombia\/?p=91128"},"modified":"2016-09-27T17:38:16","modified_gmt":"2016-09-27T22:38:16","slug":"asegurada-presunta-responsable-de-ofrecer-a-su-hija-y-otras-ninas-para-pornografia","status":"publish","type":"post","link":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-medellin\/asegurada-presunta-responsable-de-ofrecer-a-su-hija-y-otras-ninas-para-pornografia\/","title":{"rendered":"Asegurada presunta responsable de ofrecer a su hija y otras ni\u00f1as para pornograf\u00eda"},"content":{"rendered":"<p>El Juzgado16 Penal Municipal de Medell\u00edn, con funciones de control de garant\u00edas, envi\u00f3 a la c\u00e1rcel a una mujer de 38 a\u00f1os de edad\u00a0como presunta responsable de proxenetismo con menores\u00a0\u00a0de edad y pornograf\u00eda con menor de 18 a\u00f1os.<\/p>\n<p>La mujer fue capturada en la Comuna Trece de Medell\u00edn\u00a0por la Polic\u00eda Nacional y es investigada por reclutar menores para\u00a0\u00a0fotograf\u00edas de car\u00e1cter er\u00f3tico-sexual \u00a0que eran publicadas en\u00a0\u00a0varias p\u00e1ginas de internet. Entre las v\u00edctimas figuran\u00a0\u00a0su hija de 13 a\u00f1os y otra ni\u00f1a.<\/p>\n<p>Los investigadores establecieron que su hija fue fotografiada desde los 9 a\u00f1os de edad y en una ocasi\u00f3n habr\u00eda\u00a0recibido\u00a0la suma de \u00a0$ 1 900 000 pesos por una sesi\u00f3n de fotos. \u00a0Las menores eran enga\u00f1adas con falsas promesas de trabajo en el modelaje.<\/p>\n<p>Por los mismos hechos y delitos tiene igual medida de aseguramiento el ciudadano mejicano Jenaro Mart\u00ednez Reyes, alias Lalo, quien hac\u00eda las veces de\u00a0fot\u00f3grafo. El extranjero fue capturado el 16 de junio de este a\u00f1o en la capital antioque\u00f1a.<\/p>\n<p>&nbsp;<\/p>\n<p>LFML \/ AAEA<\/p>\n<p>&nbsp;<\/p>\n\n<div class=\"twitter-share\"><a href=\"https:\/\/twitter.com\/intent\/tweet?via=fiscaliacol\" class=\"twitter-share-button\">Tweet<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El Juzgado16 Penal Municipal de Medell\u00edn, con funciones de control de garant\u00edas, envi\u00f3 a la c\u00e1rcel a una mujer de 38 a\u00f1os de edad\u00a0como presunta responsable de proxenetismo con menores\u00a0\u00a0de [&hellip;]<\/p>\n","protected":false},"author":143,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[331],"tags":[20437,20436],"class_list":["post-91128","post","type-post","status-publish","format-standard","category-seccional-medellin","tag-pornografia-con-menor-de-18-anos","tag-proxenetismo-con-menores-de-edad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fiscal\u00eda General de la Naci\u00f3n<\/title>\n<meta name=\"description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-medellin\/asegurada-presunta-responsable-de-ofrecer-a-su-hija-y-otras-ninas-para-pornografia\/\" \/>\n<meta property=\"og:site_name\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FiscaliaCol\" \/>\n<meta property=\"article:published_time\" content=\"2016-09-27T22:38:16+00:00\" \/>\n<meta name=\"author\" content=\"dfgordillo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:site\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"dfgordillo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-medellin\/asegurada-presunta-responsable-de-ofrecer-a-su-hija-y-otras-ninas-para-pornografia\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-medellin\/asegurada-presunta-responsable-de-ofrecer-a-su-hija-y-otras-ninas-para-pornografia\/\"},\"author\":{\"name\":\"dfgordillo\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/3903856a3ce2d54b094c69eb29247895\"},\"headline\":\"Asegurada presunta responsable de ofrecer a su hija y otras ni\u00f1as para pornograf\u00eda\",\"datePublished\":\"2016-09-27T22:38:16+00:00\",\"dateModified\":\"2016-09-27T22:38:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-medellin\/asegurada-presunta-responsable-de-ofrecer-a-su-hija-y-otras-ninas-para-pornografia\/\"},\"wordCount\":205,\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"keywords\":[\"pornograf\u00eda con menor de 18 a\u00f1os\",\"proxenetismo con menores de edad\"],\"articleSection\":[\"Seccional Medell\u00edn\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-medellin\/asegurada-presunta-responsable-de-ofrecer-a-su-hija-y-otras-ninas-para-pornografia\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-medellin\/asegurada-presunta-responsable-de-ofrecer-a-su-hija-y-otras-ninas-para-pornografia\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\"},\"datePublished\":\"2016-09-27T22:38:16+00:00\",\"dateModified\":\"2016-09-27T22:38:16+00:00\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-medellin\/asegurada-presunta-responsable-de-ofrecer-a-su-hija-y-otras-ninas-para-pornografia\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-medellin\/asegurada-presunta-responsable-de-ofrecer-a-su-hija-y-otras-ninas-para-pornografia\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-medellin\/asegurada-presunta-responsable-de-ofrecer-a-su-hija-y-otras-ninas-para-pornografia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Asegurada presunta responsable de ofrecer a su hija y otras ni\u00f1as para pornograf\u00eda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"contentUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"width\":300,\"height\":90,\"caption\":\"Fiscal\u00eda General de la Naci\u00f3n\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/FiscaliaCol\",\"https:\/\/x.com\/FiscaliaCol\",\"https:\/\/www.instagram.com\/fiscaliacol\",\"https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/\",\"https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/3903856a3ce2d54b094c69eb29247895\",\"name\":\"dfgordillo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b6356e21c5657c60757fe6fb9493e947?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b6356e21c5657c60757fe6fb9493e947?s=96&d=mm&r=g\",\"caption\":\"dfgordillo\"},\"sameAs\":[\"dfgordillo\"],\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/author\/dfgordillo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Fiscal\u00eda General de la Naci\u00f3n","og_description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","og_url":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-medellin\/asegurada-presunta-responsable-de-ofrecer-a-su-hija-y-otras-ninas-para-pornografia\/","og_site_name":"Fiscal\u00eda General de la Naci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/FiscaliaCol","article_published_time":"2016-09-27T22:38:16+00:00","author":"dfgordillo","twitter_card":"summary_large_image","twitter_creator":"@FiscaliaCol","twitter_site":"@FiscaliaCol","twitter_misc":{"Escrito por":"dfgordillo","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-medellin\/asegurada-presunta-responsable-de-ofrecer-a-su-hija-y-otras-ninas-para-pornografia\/#article","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-medellin\/asegurada-presunta-responsable-de-ofrecer-a-su-hija-y-otras-ninas-para-pornografia\/"},"author":{"name":"dfgordillo","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/3903856a3ce2d54b094c69eb29247895"},"headline":"Asegurada presunta responsable de ofrecer a su hija y otras ni\u00f1as para pornograf\u00eda","datePublished":"2016-09-27T22:38:16+00:00","dateModified":"2016-09-27T22:38:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-medellin\/asegurada-presunta-responsable-de-ofrecer-a-su-hija-y-otras-ninas-para-pornografia\/"},"wordCount":205,"publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"keywords":["pornograf\u00eda con menor de 18 a\u00f1os","proxenetismo con menores de edad"],"articleSection":["Seccional Medell\u00edn"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-medellin\/asegurada-presunta-responsable-de-ofrecer-a-su-hija-y-otras-ninas-para-pornografia\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-medellin\/asegurada-presunta-responsable-de-ofrecer-a-su-hija-y-otras-ninas-para-pornografia\/","name":"Fiscal\u00eda General de la Naci\u00f3n","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website"},"datePublished":"2016-09-27T22:38:16+00:00","dateModified":"2016-09-27T22:38:16+00:00","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","breadcrumb":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-medellin\/asegurada-presunta-responsable-de-ofrecer-a-su-hija-y-otras-ninas-para-pornografia\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-medellin\/asegurada-presunta-responsable-de-ofrecer-a-su-hija-y-otras-ninas-para-pornografia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-medellin\/asegurada-presunta-responsable-de-ofrecer-a-su-hija-y-otras-ninas-para-pornografia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fiscalia.gov.co\/colombia\/"},{"@type":"ListItem","position":2,"name":"Asegurada presunta responsable de ofrecer a su hija y otras ni\u00f1as para pornograf\u00eda"}]},{"@type":"WebSite","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","name":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization","name":"Fiscal\u00eda General de la Naci\u00f3n","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","contentUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","width":300,"height":90,"caption":"Fiscal\u00eda General de la Naci\u00f3n"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FiscaliaCol","https:\/\/x.com\/FiscaliaCol","https:\/\/www.instagram.com\/fiscaliacol","https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/","https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh"]},{"@type":"Person","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/3903856a3ce2d54b094c69eb29247895","name":"dfgordillo","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b6356e21c5657c60757fe6fb9493e947?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6356e21c5657c60757fe6fb9493e947?s=96&d=mm&r=g","caption":"dfgordillo"},"sameAs":["dfgordillo"],"url":"https:\/\/www.fiscalia.gov.co\/colombia\/author\/dfgordillo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/91128","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/users\/143"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/comments?post=91128"}],"version-history":[{"count":1,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/91128\/revisions"}],"predecessor-version":[{"id":91129,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/91128\/revisions\/91129"}],"wp:attachment":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/media?parent=91128"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/categories?post=91128"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/tags?post=91128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}