{"id":75982,"date":"2015-11-24T11:50:26","date_gmt":"2015-11-24T16:50:26","guid":{"rendered":"http:\/\/www.fiscalia.gov.co\/colombia\/?p=75982"},"modified":"2021-03-18T09:34:43","modified_gmt":"2021-03-18T14:34:43","slug":"fiscalia-imputara-cargos-a-gobernador-del-choco-por-presunta-apropiacion-de-recursos-del-sistema-de-salud","status":"publish","type":"post","link":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-imputara-cargos-a-gobernador-del-choco-por-presunta-apropiacion-de-recursos-del-sistema-de-salud\/","title":{"rendered":"Fiscal\u00eda imputar\u00e1 cargos a Gobernador del Choc\u00f3 por presunta apropiaci\u00f3n de recursos del sistema de salud"},"content":{"rendered":"<p>El pr\u00f3ximo 3 de diciembre, ante el Tribunal Superior de Bogot\u00e1, la Fiscal\u00eda General de la Naci\u00f3n imputar\u00e1 cargos y solicitar\u00e1 medida de aseguramiento en contra el Gobernador del Choc\u00f3, Efr\u00e9n Palacios Serna, por incurrir presuntamente en los delitos de contrato sin cumplimiento de requisitos legales, peculado por apropiaci\u00f3n, inter\u00e9s indebido en la celebraci\u00f3n de contratos y falsedad en documentos.<\/p>\n<p>La petici\u00f3n de la Fiscal\u00eda para llevar a cabo dichas audiencias de basa en la hip\u00f3tesis de \u201cque el se\u00f1or Gobernador habr\u00eda utilizado de forma indebida recursos del sistema de salud y de seguridad social para el pago de cr\u00e9ditos de su campa\u00f1a pol\u00edtica; recursos que deb\u00edan haberse destinado a la compra de medicamentos para poblaci\u00f3n vulnerable\u201d, se\u00f1al\u00f3 el Vicefiscal Jorge Fernando Perdomo Torres.<\/p>\n<p>Seg\u00fan las investigaciones, el departamento chocoano a trav\u00e9s de la Secretar\u00eda de Salud celebr\u00f3 contratos de prestaci\u00f3n de servicios para el suministro de medicamentos pos y no pos para esta poblaci\u00f3n; sin embargo,\u00a0 el Vicefiscal Perdomo indic\u00f3 que \u201cen el tr\u00e1mite y celebraci\u00f3n de estos contratos, se violaron los principios de contrataci\u00f3n p\u00fablica porque se inobservaron requisitos legales esenciales, especialmente los previstos de manera particular para este tipo de contratos\u201d.<\/p>\n<p>\u201cEl se\u00f1or Gobernador del Choc\u00f3 habr\u00eda contado con la participaci\u00f3n de varios funcionarios de su administraci\u00f3n para la celebraci\u00f3n irregular de estos contratos. Algunos de estos funcionarios ya fueron imputados y otros siguen siendo investigados por estos hechos\u201d, agreg\u00f3 el alto funcionario.<\/p>\n<p>Igualmente se habr\u00eda determinado que el mandatario departamental tuvo conocimiento de que los servicios no fueron prestados, as\u00ed como que los pacientes no hab\u00edan acudido al sistema de salud; pero para dar apariencia de legalidad requiri\u00f3 la expedici\u00f3n de certificados de auditor\u00eda m\u00e9dica por un funcionario designado con esa finalidad e hizo efectivo el pago.<\/p>\n<p>Perdomo concluy\u00f3 que \u201ca partir de la evidencia del proceso se logr\u00f3 establecer que en la actividad contractual particip\u00f3 el se\u00f1or gobernador de forma directa, quien al constituir la llamada red de prestaci\u00f3n de servicios de salud, fue consciente que la \u00fanica finalidad era apropiar los recursos del erario para retribuir los gastos de su campa\u00f1a\u201d.<\/p>\n<p>DLBM<\/p>\n\n<div class=\"twitter-share\"><a href=\"https:\/\/twitter.com\/intent\/tweet?via=fiscaliacol\" class=\"twitter-share-button\">Tweet<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El pr\u00f3ximo 3 de diciembre, ante el Tribunal Superior de Bogot\u00e1, la Fiscal\u00eda General de la Naci\u00f3n imputar\u00e1 cargos y solicitar\u00e1 medida de aseguramiento en contra el Gobernador del Choc\u00f3, [&hellip;]<\/p>\n","protected":false},"author":143,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[1],"tags":[4112],"class_list":["post-75982","post","type-post","status-publish","format-video","category-noticias","tag-irregularidades-en-contratacion","post_format-post-format-video"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fiscal\u00eda General de la Naci\u00f3n<\/title>\n<meta name=\"description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-imputara-cargos-a-gobernador-del-choco-por-presunta-apropiacion-de-recursos-del-sistema-de-salud\/\" \/>\n<meta property=\"og:site_name\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FiscaliaCol\" \/>\n<meta property=\"article:published_time\" content=\"2015-11-24T16:50:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-18T14:34:43+00:00\" \/>\n<meta name=\"author\" content=\"dfgordillo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:site\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"dfgordillo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-imputara-cargos-a-gobernador-del-choco-por-presunta-apropiacion-de-recursos-del-sistema-de-salud\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-imputara-cargos-a-gobernador-del-choco-por-presunta-apropiacion-de-recursos-del-sistema-de-salud\/\"},\"author\":{\"name\":\"dfgordillo\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/3903856a3ce2d54b094c69eb29247895\"},\"headline\":\"Fiscal\u00eda imputar\u00e1 cargos a Gobernador del Choc\u00f3 por presunta apropiaci\u00f3n de recursos del sistema de salud\",\"datePublished\":\"2015-11-24T16:50:26+00:00\",\"dateModified\":\"2021-03-18T14:34:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-imputara-cargos-a-gobernador-del-choco-por-presunta-apropiacion-de-recursos-del-sistema-de-salud\/\"},\"wordCount\":405,\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"keywords\":[\"Irregularidades en contrataci\u00f3n\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-imputara-cargos-a-gobernador-del-choco-por-presunta-apropiacion-de-recursos-del-sistema-de-salud\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-imputara-cargos-a-gobernador-del-choco-por-presunta-apropiacion-de-recursos-del-sistema-de-salud\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\"},\"datePublished\":\"2015-11-24T16:50:26+00:00\",\"dateModified\":\"2021-03-18T14:34:43+00:00\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-imputara-cargos-a-gobernador-del-choco-por-presunta-apropiacion-de-recursos-del-sistema-de-salud\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-imputara-cargos-a-gobernador-del-choco-por-presunta-apropiacion-de-recursos-del-sistema-de-salud\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-imputara-cargos-a-gobernador-del-choco-por-presunta-apropiacion-de-recursos-del-sistema-de-salud\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fiscal\u00eda imputar\u00e1 cargos a Gobernador del Choc\u00f3 por presunta apropiaci\u00f3n de recursos del sistema de salud\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"contentUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"width\":300,\"height\":90,\"caption\":\"Fiscal\u00eda General de la Naci\u00f3n\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/FiscaliaCol\",\"https:\/\/x.com\/FiscaliaCol\",\"https:\/\/www.instagram.com\/fiscaliacol\",\"https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/\",\"https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/3903856a3ce2d54b094c69eb29247895\",\"name\":\"dfgordillo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b6356e21c5657c60757fe6fb9493e947?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b6356e21c5657c60757fe6fb9493e947?s=96&d=mm&r=g\",\"caption\":\"dfgordillo\"},\"sameAs\":[\"dfgordillo\"],\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/author\/dfgordillo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Fiscal\u00eda General de la Naci\u00f3n","og_description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","og_url":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-imputara-cargos-a-gobernador-del-choco-por-presunta-apropiacion-de-recursos-del-sistema-de-salud\/","og_site_name":"Fiscal\u00eda General de la Naci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/FiscaliaCol","article_published_time":"2015-11-24T16:50:26+00:00","article_modified_time":"2021-03-18T14:34:43+00:00","author":"dfgordillo","twitter_card":"summary_large_image","twitter_creator":"@FiscaliaCol","twitter_site":"@FiscaliaCol","twitter_misc":{"Escrito por":"dfgordillo","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-imputara-cargos-a-gobernador-del-choco-por-presunta-apropiacion-de-recursos-del-sistema-de-salud\/#article","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-imputara-cargos-a-gobernador-del-choco-por-presunta-apropiacion-de-recursos-del-sistema-de-salud\/"},"author":{"name":"dfgordillo","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/3903856a3ce2d54b094c69eb29247895"},"headline":"Fiscal\u00eda imputar\u00e1 cargos a Gobernador del Choc\u00f3 por presunta apropiaci\u00f3n de recursos del sistema de salud","datePublished":"2015-11-24T16:50:26+00:00","dateModified":"2021-03-18T14:34:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-imputara-cargos-a-gobernador-del-choco-por-presunta-apropiacion-de-recursos-del-sistema-de-salud\/"},"wordCount":405,"publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"keywords":["Irregularidades en contrataci\u00f3n"],"articleSection":["Noticias"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-imputara-cargos-a-gobernador-del-choco-por-presunta-apropiacion-de-recursos-del-sistema-de-salud\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-imputara-cargos-a-gobernador-del-choco-por-presunta-apropiacion-de-recursos-del-sistema-de-salud\/","name":"Fiscal\u00eda General de la Naci\u00f3n","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website"},"datePublished":"2015-11-24T16:50:26+00:00","dateModified":"2021-03-18T14:34:43+00:00","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","breadcrumb":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-imputara-cargos-a-gobernador-del-choco-por-presunta-apropiacion-de-recursos-del-sistema-de-salud\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-imputara-cargos-a-gobernador-del-choco-por-presunta-apropiacion-de-recursos-del-sistema-de-salud\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-imputara-cargos-a-gobernador-del-choco-por-presunta-apropiacion-de-recursos-del-sistema-de-salud\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fiscalia.gov.co\/colombia\/"},{"@type":"ListItem","position":2,"name":"Fiscal\u00eda imputar\u00e1 cargos a Gobernador del Choc\u00f3 por presunta apropiaci\u00f3n de recursos del sistema de salud"}]},{"@type":"WebSite","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","name":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization","name":"Fiscal\u00eda General de la Naci\u00f3n","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","contentUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","width":300,"height":90,"caption":"Fiscal\u00eda General de la Naci\u00f3n"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FiscaliaCol","https:\/\/x.com\/FiscaliaCol","https:\/\/www.instagram.com\/fiscaliacol","https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/","https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh"]},{"@type":"Person","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/3903856a3ce2d54b094c69eb29247895","name":"dfgordillo","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b6356e21c5657c60757fe6fb9493e947?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6356e21c5657c60757fe6fb9493e947?s=96&d=mm&r=g","caption":"dfgordillo"},"sameAs":["dfgordillo"],"url":"https:\/\/www.fiscalia.gov.co\/colombia\/author\/dfgordillo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/75982","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/users\/143"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/comments?post=75982"}],"version-history":[{"count":2,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/75982\/revisions"}],"predecessor-version":[{"id":216020,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/75982\/revisions\/216020"}],"wp:attachment":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/media?parent=75982"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/categories?post=75982"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/tags?post=75982"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}