{"id":71719,"date":"2015-08-25T17:18:43","date_gmt":"2015-08-25T22:18:43","guid":{"rendered":"http:\/\/www.fiscalia.gov.co\/colombia\/?p=71719"},"modified":"2015-08-25T17:19:22","modified_gmt":"2015-08-25T22:19:22","slug":"jefe-de-los-rastrojos-en-el-bajo-cauca-antioqueno-sera-condenado-por-crimen-de-profesor","status":"publish","type":"post","link":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/jefe-de-los-rastrojos-en-el-bajo-cauca-antioqueno-sera-condenado-por-crimen-de-profesor\/","title":{"rendered":"Jefe de Los Rastrojos en el Bajo Cauca Antioque\u00f1o ser\u00e1 condenado por crimen de profesor"},"content":{"rendered":"<p>Un juez penal\u00a0del circuito especializado de Bogot\u00e1 anunci\u00f3 fallo condenatorio contra\u00a0Freddy Alberto Vega Rua, alias Junior, quien fue hallado responsable de los delitos de homicidio agravado en concurso con tr\u00e1fico, fabricaci\u00f3n y porte de armas de fuego.<\/p>\n<p>En su decisi\u00f3n, el juez indic\u00f3 que la Fiscalia General de la Naci\u00f3n demostr\u00f3 m\u00e1s all\u00e1 de toda duda que el sentenciado\u00a0fue quien particip\u00f3 en los hechos ocurridos el 14 de abril de 2010, en zona rural de la carretera que comunica\u00a0 los municipios antioque\u00f1os de Caucasia y C\u00e1ceres, donde fue asesinado por un sicario de Los Rastrojos, el profesor de 29 a\u00f1os Francisco Manuel Valerio Orozco, quien ense\u00f1aba en la escuela de una vereda de Caucasia.<\/p>\n<p>Seg\u00fan el relato de la profesora Patricia Carrascal, quien le acompa\u00f1aba al momento del crimen, minutos antes, un hombre uniformado le hab\u00eda hecho entrega de 40 mil pesos a la v\u00edctima, los cuales le deb\u00eda entregar\u00a0en la carretera a una persona que le estaba esperando.<\/p>\n<p>Everly de Jes\u00fas Cantillo Julio, el sicario que dispar\u00f3 contra el profesor, en desarrollo del juicio indic\u00f3 que hab\u00eda recibido la orden de disparar en contra de quien le entregara los 40 mil pesos y eso fue lo que hizo.<\/p>\n<p>Cantillo Julio preso en Caucasia y condenado por el crimen a 17 a\u00f1os, se\u00f1al\u00f3 a alias Junior, como uno de los jefes de los Rastrojos en la regi\u00f3n.<\/p>\n<p>Freddy Alberto Vega Rua en la actualidad permanece prisionero en la c\u00e1rcel de Combita, en Boyac\u00e1, donde\u00a0es procesado por el delito de concierto para delinquir, luego de ser capturado junto con 5 de sus hombres y a quienes se les incaut\u00f3 armas largas y cortas, entre ellas el rev\u00f3lver con el cual se cometi\u00f3 el crimen del profesor.<\/p>\n<p>Se \u00a0indic\u00f3 por parte de la Fiscal\u00eda que el homicidio de Valerio Orozco se present\u00f3 porque este\u00a0reprochaba a sus alumnas por las relaciones que manten\u00edan con integrantes del grupo al margen de la ley.<\/p>\n<p>La lectura de la sentencia fue anunciada por el juez para el mes de octubre.<\/p>\n<p>&nbsp;<\/p>\n<p>ANM\/DLBM<\/p>\n\n<div class=\"twitter-share\"><a href=\"https:\/\/twitter.com\/intent\/tweet?via=fiscaliacol\" class=\"twitter-share-button\">Tweet<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Un juez penal\u00a0del circuito especializado de Bogot\u00e1 anunci\u00f3 fallo condenatorio contra\u00a0Freddy Alberto Vega Rua, alias Junior, quien fue hallado responsable de los delitos de homicidio agravado en concurso con tr\u00e1fico, [&hellip;]<\/p>\n","protected":false},"author":143,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[1],"tags":[686,14842,13510],"class_list":["post-71719","post","type-post","status-publish","format-standard","category-noticias","tag-homicidio-agravado","tag-los-rastrojos-en-el-bajo-cauca-antioqueno","tag-trafico-fabricacion-y-porte-de-armas-de-fuego"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fiscal\u00eda General de la Naci\u00f3n<\/title>\n<meta name=\"description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/jefe-de-los-rastrojos-en-el-bajo-cauca-antioqueno-sera-condenado-por-crimen-de-profesor\/\" \/>\n<meta property=\"og:site_name\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FiscaliaCol\" \/>\n<meta property=\"article:published_time\" content=\"2015-08-25T22:18:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-08-25T22:19:22+00:00\" \/>\n<meta name=\"author\" content=\"dfgordillo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:site\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"dfgordillo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/jefe-de-los-rastrojos-en-el-bajo-cauca-antioqueno-sera-condenado-por-crimen-de-profesor\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/jefe-de-los-rastrojos-en-el-bajo-cauca-antioqueno-sera-condenado-por-crimen-de-profesor\/\"},\"author\":{\"name\":\"dfgordillo\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/3903856a3ce2d54b094c69eb29247895\"},\"headline\":\"Jefe de Los Rastrojos en el Bajo Cauca Antioque\u00f1o ser\u00e1 condenado por crimen de profesor\",\"datePublished\":\"2015-08-25T22:18:43+00:00\",\"dateModified\":\"2015-08-25T22:19:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/jefe-de-los-rastrojos-en-el-bajo-cauca-antioqueno-sera-condenado-por-crimen-de-profesor\/\"},\"wordCount\":375,\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"keywords\":[\"Homicidio agravado\",\"Los Rastrojos en el Bajo Cauca Antioque\u00f1o\",\"tr\u00e1fico fabricaci\u00f3n y porte de armas de fuego\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/jefe-de-los-rastrojos-en-el-bajo-cauca-antioqueno-sera-condenado-por-crimen-de-profesor\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/jefe-de-los-rastrojos-en-el-bajo-cauca-antioqueno-sera-condenado-por-crimen-de-profesor\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\"},\"datePublished\":\"2015-08-25T22:18:43+00:00\",\"dateModified\":\"2015-08-25T22:19:22+00:00\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/jefe-de-los-rastrojos-en-el-bajo-cauca-antioqueno-sera-condenado-por-crimen-de-profesor\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/jefe-de-los-rastrojos-en-el-bajo-cauca-antioqueno-sera-condenado-por-crimen-de-profesor\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/jefe-de-los-rastrojos-en-el-bajo-cauca-antioqueno-sera-condenado-por-crimen-de-profesor\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jefe de Los Rastrojos en el Bajo Cauca Antioque\u00f1o ser\u00e1 condenado por crimen de profesor\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"contentUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"width\":300,\"height\":90,\"caption\":\"Fiscal\u00eda General de la Naci\u00f3n\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/FiscaliaCol\",\"https:\/\/x.com\/FiscaliaCol\",\"https:\/\/www.instagram.com\/fiscaliacol\",\"https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/\",\"https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/3903856a3ce2d54b094c69eb29247895\",\"name\":\"dfgordillo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b6356e21c5657c60757fe6fb9493e947?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b6356e21c5657c60757fe6fb9493e947?s=96&d=mm&r=g\",\"caption\":\"dfgordillo\"},\"sameAs\":[\"dfgordillo\"],\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/author\/dfgordillo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Fiscal\u00eda General de la Naci\u00f3n","og_description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","og_url":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/jefe-de-los-rastrojos-en-el-bajo-cauca-antioqueno-sera-condenado-por-crimen-de-profesor\/","og_site_name":"Fiscal\u00eda General de la Naci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/FiscaliaCol","article_published_time":"2015-08-25T22:18:43+00:00","article_modified_time":"2015-08-25T22:19:22+00:00","author":"dfgordillo","twitter_card":"summary_large_image","twitter_creator":"@FiscaliaCol","twitter_site":"@FiscaliaCol","twitter_misc":{"Escrito por":"dfgordillo","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/jefe-de-los-rastrojos-en-el-bajo-cauca-antioqueno-sera-condenado-por-crimen-de-profesor\/#article","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/jefe-de-los-rastrojos-en-el-bajo-cauca-antioqueno-sera-condenado-por-crimen-de-profesor\/"},"author":{"name":"dfgordillo","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/3903856a3ce2d54b094c69eb29247895"},"headline":"Jefe de Los Rastrojos en el Bajo Cauca Antioque\u00f1o ser\u00e1 condenado por crimen de profesor","datePublished":"2015-08-25T22:18:43+00:00","dateModified":"2015-08-25T22:19:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/jefe-de-los-rastrojos-en-el-bajo-cauca-antioqueno-sera-condenado-por-crimen-de-profesor\/"},"wordCount":375,"publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"keywords":["Homicidio agravado","Los Rastrojos en el Bajo Cauca Antioque\u00f1o","tr\u00e1fico fabricaci\u00f3n y porte de armas de fuego"],"articleSection":["Noticias"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/jefe-de-los-rastrojos-en-el-bajo-cauca-antioqueno-sera-condenado-por-crimen-de-profesor\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/jefe-de-los-rastrojos-en-el-bajo-cauca-antioqueno-sera-condenado-por-crimen-de-profesor\/","name":"Fiscal\u00eda General de la Naci\u00f3n","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website"},"datePublished":"2015-08-25T22:18:43+00:00","dateModified":"2015-08-25T22:19:22+00:00","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","breadcrumb":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/jefe-de-los-rastrojos-en-el-bajo-cauca-antioqueno-sera-condenado-por-crimen-de-profesor\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/jefe-de-los-rastrojos-en-el-bajo-cauca-antioqueno-sera-condenado-por-crimen-de-profesor\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/jefe-de-los-rastrojos-en-el-bajo-cauca-antioqueno-sera-condenado-por-crimen-de-profesor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fiscalia.gov.co\/colombia\/"},{"@type":"ListItem","position":2,"name":"Jefe de Los Rastrojos en el Bajo Cauca Antioque\u00f1o ser\u00e1 condenado por crimen de profesor"}]},{"@type":"WebSite","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","name":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization","name":"Fiscal\u00eda General de la Naci\u00f3n","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","contentUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","width":300,"height":90,"caption":"Fiscal\u00eda General de la Naci\u00f3n"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FiscaliaCol","https:\/\/x.com\/FiscaliaCol","https:\/\/www.instagram.com\/fiscaliacol","https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/","https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh"]},{"@type":"Person","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/3903856a3ce2d54b094c69eb29247895","name":"dfgordillo","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b6356e21c5657c60757fe6fb9493e947?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6356e21c5657c60757fe6fb9493e947?s=96&d=mm&r=g","caption":"dfgordillo"},"sameAs":["dfgordillo"],"url":"https:\/\/www.fiscalia.gov.co\/colombia\/author\/dfgordillo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/71719","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/users\/143"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/comments?post=71719"}],"version-history":[{"count":2,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/71719\/revisions"}],"predecessor-version":[{"id":71731,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/71719\/revisions\/71731"}],"wp:attachment":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/media?parent=71719"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/categories?post=71719"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/tags?post=71719"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}