{"id":60552,"date":"2015-01-09T09:09:50","date_gmt":"2015-01-09T14:09:50","guid":{"rendered":"http:\/\/www.fiscalia.gov.co\/colombia\/?p=60552"},"modified":"2015-01-09T09:09:50","modified_gmt":"2015-01-09T14:09:50","slug":"asegurado-hombre-por-el-homicidio-de-personas-en-su-carro","status":"publish","type":"post","link":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurado-hombre-por-el-homicidio-de-personas-en-su-carro\/","title":{"rendered":"Asegurado hombre por el homicidio de personas en su carro"},"content":{"rendered":"<p>A la c\u00e1rcel nacional Picota fue enviado el abogado Ariel Ulloa Galvis luego de que le fuera impuesta medida de aseguramiento como presunto responsable de dos homicidios agravados.<\/p>\n<p><span style=\"font-size: 13px;\">La Fiscal\u00eda manifest\u00f3 que los hechos se registraron despu\u00e9s de la medianoche del pasado seis de enero en el kil\u00f3metro 14 de la v\u00eda Los Arrayanes, al norte de Bogot\u00e1. All\u00ed, una llamada an\u00f3nima acerca de una situaci\u00f3n sospechosa en la que un veh\u00edculo de alta gama aparec\u00eda accidentado con varias personas adentro.<\/span><\/p>\n<p><span style=\"font-size: 13px;\">Cuando lleg\u00f3 la Polic\u00eda, se encontr\u00f3 un cad\u00e1ver y a su lado un herido que al parecer recibi\u00f3 heridas mortales desde la parte trasera del veh\u00edculo. Al parecer, Ulloa Galvis, quien se encontraba en estado de embriaguez, fue quien realiz\u00f3 los disparos.<\/span><\/p>\n<p><span style=\"font-size: 13px;\">De acuerdo con testigos, el procesado fue visto tratando de esconder el arma implicada en los hechos en el ba\u00fal del veh\u00edculo. All\u00ed la encontraron los investigadores.<\/span><\/p>\n<p><span style=\"font-size: 13px;\">Las v\u00edctimas fueron identificadas como Carlos Julio Ruiz Vega y Pedro Jos\u00e9 Espa\u00f1a.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>CMR \/ AAEA<\/p>\n\n<div class=\"twitter-share\"><a href=\"https:\/\/twitter.com\/intent\/tweet?via=fiscaliacol\" class=\"twitter-share-button\">Tweet<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>A la c\u00e1rcel nacional Picota fue enviado el abogado Ariel Ulloa Galvis luego de que le fuera impuesta medida de aseguramiento como presunto responsable de dos homicidios agravados. La Fiscal\u00eda [&hellip;]<\/p>\n","protected":false},"author":143,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[1],"tags":[409],"class_list":["post-60552","post","type-post","status-publish","format-standard","category-noticias","tag-homicidio"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fiscal\u00eda General de la Naci\u00f3n<\/title>\n<meta name=\"description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurado-hombre-por-el-homicidio-de-personas-en-su-carro\/\" \/>\n<meta property=\"og:site_name\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FiscaliaCol\" \/>\n<meta property=\"article:published_time\" content=\"2015-01-09T14:09:50+00:00\" \/>\n<meta name=\"author\" content=\"dfgordillo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:site\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"dfgordillo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurado-hombre-por-el-homicidio-de-personas-en-su-carro\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurado-hombre-por-el-homicidio-de-personas-en-su-carro\/\"},\"author\":{\"name\":\"dfgordillo\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/3903856a3ce2d54b094c69eb29247895\"},\"headline\":\"Asegurado hombre por el homicidio de personas en su carro\",\"datePublished\":\"2015-01-09T14:09:50+00:00\",\"dateModified\":\"2015-01-09T14:09:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurado-hombre-por-el-homicidio-de-personas-en-su-carro\/\"},\"wordCount\":191,\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"keywords\":[\"Homicidio\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurado-hombre-por-el-homicidio-de-personas-en-su-carro\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurado-hombre-por-el-homicidio-de-personas-en-su-carro\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\"},\"datePublished\":\"2015-01-09T14:09:50+00:00\",\"dateModified\":\"2015-01-09T14:09:50+00:00\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurado-hombre-por-el-homicidio-de-personas-en-su-carro\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurado-hombre-por-el-homicidio-de-personas-en-su-carro\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurado-hombre-por-el-homicidio-de-personas-en-su-carro\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Asegurado hombre por el homicidio de personas en su carro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"contentUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"width\":300,\"height\":90,\"caption\":\"Fiscal\u00eda General de la Naci\u00f3n\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/FiscaliaCol\",\"https:\/\/x.com\/FiscaliaCol\",\"https:\/\/www.instagram.com\/fiscaliacol\",\"https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/\",\"https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/3903856a3ce2d54b094c69eb29247895\",\"name\":\"dfgordillo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b6356e21c5657c60757fe6fb9493e947?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b6356e21c5657c60757fe6fb9493e947?s=96&d=mm&r=g\",\"caption\":\"dfgordillo\"},\"sameAs\":[\"dfgordillo\"],\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/author\/dfgordillo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Fiscal\u00eda General de la Naci\u00f3n","og_description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","og_url":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurado-hombre-por-el-homicidio-de-personas-en-su-carro\/","og_site_name":"Fiscal\u00eda General de la Naci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/FiscaliaCol","article_published_time":"2015-01-09T14:09:50+00:00","author":"dfgordillo","twitter_card":"summary_large_image","twitter_creator":"@FiscaliaCol","twitter_site":"@FiscaliaCol","twitter_misc":{"Escrito por":"dfgordillo","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurado-hombre-por-el-homicidio-de-personas-en-su-carro\/#article","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurado-hombre-por-el-homicidio-de-personas-en-su-carro\/"},"author":{"name":"dfgordillo","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/3903856a3ce2d54b094c69eb29247895"},"headline":"Asegurado hombre por el homicidio de personas en su carro","datePublished":"2015-01-09T14:09:50+00:00","dateModified":"2015-01-09T14:09:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurado-hombre-por-el-homicidio-de-personas-en-su-carro\/"},"wordCount":191,"publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"keywords":["Homicidio"],"articleSection":["Noticias"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurado-hombre-por-el-homicidio-de-personas-en-su-carro\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurado-hombre-por-el-homicidio-de-personas-en-su-carro\/","name":"Fiscal\u00eda General de la Naci\u00f3n","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website"},"datePublished":"2015-01-09T14:09:50+00:00","dateModified":"2015-01-09T14:09:50+00:00","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","breadcrumb":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurado-hombre-por-el-homicidio-de-personas-en-su-carro\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurado-hombre-por-el-homicidio-de-personas-en-su-carro\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurado-hombre-por-el-homicidio-de-personas-en-su-carro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fiscalia.gov.co\/colombia\/"},{"@type":"ListItem","position":2,"name":"Asegurado hombre por el homicidio de personas en su carro"}]},{"@type":"WebSite","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","name":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization","name":"Fiscal\u00eda General de la Naci\u00f3n","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","contentUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","width":300,"height":90,"caption":"Fiscal\u00eda General de la Naci\u00f3n"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FiscaliaCol","https:\/\/x.com\/FiscaliaCol","https:\/\/www.instagram.com\/fiscaliacol","https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/","https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh"]},{"@type":"Person","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/3903856a3ce2d54b094c69eb29247895","name":"dfgordillo","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b6356e21c5657c60757fe6fb9493e947?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6356e21c5657c60757fe6fb9493e947?s=96&d=mm&r=g","caption":"dfgordillo"},"sameAs":["dfgordillo"],"url":"https:\/\/www.fiscalia.gov.co\/colombia\/author\/dfgordillo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/60552","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/users\/143"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/comments?post=60552"}],"version-history":[{"count":2,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/60552\/revisions"}],"predecessor-version":[{"id":60554,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/60552\/revisions\/60554"}],"wp:attachment":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/media?parent=60552"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/categories?post=60552"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/tags?post=60552"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}