{"id":363863,"date":"2026-05-13T16:02:49","date_gmt":"2026-05-13T21:02:49","guid":{"rendered":"https:\/\/www.fiscalia.gov.co\/colombia\/?p=363863"},"modified":"2026-05-13T16:02:49","modified_gmt":"2026-05-13T21:02:49","slug":"en-isnos-huila-fueron-judicializadas-11-personas-senaladas-de-trafico-local-de-estupefacientes","status":"publish","type":"post","link":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/en-isnos-huila-fueron-judicializadas-11-personas-senaladas-de-trafico-local-de-estupefacientes\/","title":{"rendered":"En Isnos (Huila) fueron judicializadas 11 personas se\u00f1aladas de tr\u00e1fico local de estupefacientes"},"content":{"rendered":"<p>La <strong>Fiscal\u00eda General de la Naci\u00f3n<\/strong> present\u00f3 ante un juez de control de garant\u00edas a 11 personas, que estar\u00edan involucradas en actividades de narcomenudeo en el barrio La Mortilla de <strong>Isnos (Huila).<\/strong><\/p>\n<p>Se trata de Orfali Astudillo, Andr\u00e9s Alirio Cer\u00f3n Urbano, Juan Carlos Collazos Carvajal, Maicol Estiven Calder\u00f3n Rojas, Jerson Uriel Rojas Losada, Mar\u00eda de los \u00c1ngeles Perdomo Hoyos, Oliver Yordani \u00d1a\u00f1ez Mu\u00f1oz, Yuly Viviana Mapallo L\u00f3pez, Maicol Rojas Hern\u00e1ndez, Mar\u00eda Lina Iles Guenis y Silverio Mart\u00ednez Urbano.<\/p>\n<p>De acuerdo con la <strong>investigaci\u00f3n<\/strong>, desde julio de 2025, estas personas, presuntamente, distribu\u00edan marihuana, bazuco y coca\u00edna en el sector El Zanj\u00f3n.\u00a0 Adem\u00e1s, ocultaban las sustancias en techos e inodoros de sus viviendas, para evadir la acci\u00f3n de las autoridades.<\/p>\n<p>Estas personas fueron capturadas durante ocho<strong> diligencias de allanamiento y registro<\/strong>, realizadas por la Polic\u00eda Nacional. En los operativos se incautaron estupefacientes, armas traum\u00e1ticas y artesanales con capacidad para percutir, <strong>dinero en efectivo<\/strong> y elementos para la dosificaci\u00f3n de sustancias il\u00edcitas.<\/p>\n<p>Por estos hechos, un fiscal de la <strong>Seccional Huila<\/strong> les imput\u00f3 el delito de tr\u00e1fico, fabricaci\u00f3n o porte de estupefacientes; y fabricaci\u00f3n, tr\u00e1fico, porte o tenencia de armas de fuego, accesorios, partes o municiones. Los cargos fueron aceptados por Collazos Carvajal, Perdomo Hoyos, Iles Guenis y Mart\u00ednez Urbano.<\/p>\n<p>Un <strong>juez de control de garant\u00edas<\/strong> impuso medida de aseguramiento en centro carcelario contra Astudillo, Cer\u00f3n Urbano, Calder\u00f3n Rojas, \u00d1a\u00f1ez Mu\u00f1oz y Rojas Lozada. Los dem\u00e1s procesados fueron afectados con <strong>detenci\u00f3n domiciliaria.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>WAGG\/LMFO\/AMCJ\/OHN\/JCFJ\/DSH<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><em>La informaci\u00f3n contenida en este bolet\u00edn de prensa corresponde a la narraci\u00f3n de los hechos noticiosos objetivos, suministrados por los funcionarios encargados de adelantar las investigaciones penales al interior de la Fiscal\u00eda General de la Naci\u00f3n. Para el momento de la divulgaci\u00f3n de este comunicado, la situaci\u00f3n jur\u00eddica de la(s) persona(s) relacionada(s) se encuentra pendiente de resolver por la autoridad judicial competente, siempre bajo los preceptos de la presunci\u00f3n de inocencia, consagrados en el art\u00edculo 29 de la Constituci\u00f3n Pol\u00edtica y el art\u00edculo 7\u00ba de la Ley 906 de 2004.<\/em><\/p>\n\n<div class=\"twitter-share\"><a href=\"https:\/\/twitter.com\/intent\/tweet?via=fiscaliacol\" class=\"twitter-share-button\">Tweet<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La Fiscal\u00eda General de la Naci\u00f3n present\u00f3 ante un juez de control de garant\u00edas a 11 personas, que estar\u00edan involucradas en actividades de narcomenudeo en el barrio La Mortilla de [&hellip;]<\/p>\n","protected":false},"author":182,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[1,24099],"tags":[3148,5636,19,12799,35942,50,3618,4140,1047,16,28110,1264,6194,698,24485,916],"class_list":["post-363863","post","type-post","status-publish","format-standard","category-noticias","category-seguridad-territorial","tag-allanamiento","tag-bazuco","tag-cocaina","tag-comercializacion","tag-dosificacion","tag-estupefacientes","tag-expendio","tag-fabricacion","tag-fiscalia-general-de-la-nacion","tag-huila","tag-isnos","tag-marihuana","tag-municion","tag-porte-de-armas","tag-seccional-huila","tag-trafico"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fiscal\u00eda General de la Naci\u00f3n<\/title>\n<meta name=\"description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/en-isnos-huila-fueron-judicializadas-11-personas-senaladas-de-trafico-local-de-estupefacientes\/\" \/>\n<meta property=\"og:site_name\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FiscaliaCol\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-13T21:02:49+00:00\" \/>\n<meta name=\"author\" content=\"Paula Andrea Castillo Lenis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:site\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Paula Andrea Castillo Lenis\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/en-isnos-huila-fueron-judicializadas-11-personas-senaladas-de-trafico-local-de-estupefacientes\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/en-isnos-huila-fueron-judicializadas-11-personas-senaladas-de-trafico-local-de-estupefacientes\/\"},\"author\":{\"name\":\"Paula Andrea Castillo Lenis\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/66c172905e0492f1de6bbe5f93c4668f\"},\"headline\":\"En Isnos (Huila) fueron judicializadas 11 personas se\u00f1aladas de tr\u00e1fico local de estupefacientes\",\"datePublished\":\"2026-05-13T21:02:49+00:00\",\"dateModified\":\"2026-05-13T21:02:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/en-isnos-huila-fueron-judicializadas-11-personas-senaladas-de-trafico-local-de-estupefacientes\/\"},\"wordCount\":398,\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"keywords\":[\"Allanamiento\",\"Bazuco\",\"Coca\u00edna\",\"Comercializaci\u00f3n\",\"dosificaci\u00f3n\",\"Estupefacientes\",\"Expendio\",\"Fabricaci\u00f3n\",\"Fiscal\u00eda General de la Naci\u00f3n\",\"Huila\",\"Isnos\",\"Marihuana\",\"Munici\u00f3n\",\"Porte de armas\",\"Seccional Huila\",\"Tr\u00e1fico\"],\"articleSection\":[\"Noticias\",\"Seguridad territorial\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/en-isnos-huila-fueron-judicializadas-11-personas-senaladas-de-trafico-local-de-estupefacientes\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/en-isnos-huila-fueron-judicializadas-11-personas-senaladas-de-trafico-local-de-estupefacientes\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\"},\"datePublished\":\"2026-05-13T21:02:49+00:00\",\"dateModified\":\"2026-05-13T21:02:49+00:00\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/en-isnos-huila-fueron-judicializadas-11-personas-senaladas-de-trafico-local-de-estupefacientes\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/en-isnos-huila-fueron-judicializadas-11-personas-senaladas-de-trafico-local-de-estupefacientes\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/en-isnos-huila-fueron-judicializadas-11-personas-senaladas-de-trafico-local-de-estupefacientes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"En Isnos (Huila) fueron judicializadas 11 personas se\u00f1aladas de tr\u00e1fico local de estupefacientes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"contentUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"width\":300,\"height\":90,\"caption\":\"Fiscal\u00eda General de la Naci\u00f3n\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/FiscaliaCol\",\"https:\/\/x.com\/FiscaliaCol\",\"https:\/\/www.instagram.com\/fiscaliacol\",\"https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/\",\"https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/66c172905e0492f1de6bbe5f93c4668f\",\"name\":\"Paula Andrea Castillo Lenis\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cb060d9561f2947c4102d1825739f868?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cb060d9561f2947c4102d1825739f868?s=96&d=mm&r=g\",\"caption\":\"Paula Andrea Castillo Lenis\"},\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/author\/paula-castillo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Fiscal\u00eda General de la Naci\u00f3n","og_description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","og_url":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/en-isnos-huila-fueron-judicializadas-11-personas-senaladas-de-trafico-local-de-estupefacientes\/","og_site_name":"Fiscal\u00eda General de la Naci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/FiscaliaCol","article_published_time":"2026-05-13T21:02:49+00:00","author":"Paula Andrea Castillo Lenis","twitter_card":"summary_large_image","twitter_creator":"@FiscaliaCol","twitter_site":"@FiscaliaCol","twitter_misc":{"Escrito por":"Paula Andrea Castillo Lenis","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/en-isnos-huila-fueron-judicializadas-11-personas-senaladas-de-trafico-local-de-estupefacientes\/#article","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/en-isnos-huila-fueron-judicializadas-11-personas-senaladas-de-trafico-local-de-estupefacientes\/"},"author":{"name":"Paula Andrea Castillo Lenis","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/66c172905e0492f1de6bbe5f93c4668f"},"headline":"En Isnos (Huila) fueron judicializadas 11 personas se\u00f1aladas de tr\u00e1fico local de estupefacientes","datePublished":"2026-05-13T21:02:49+00:00","dateModified":"2026-05-13T21:02:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/en-isnos-huila-fueron-judicializadas-11-personas-senaladas-de-trafico-local-de-estupefacientes\/"},"wordCount":398,"publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"keywords":["Allanamiento","Bazuco","Coca\u00edna","Comercializaci\u00f3n","dosificaci\u00f3n","Estupefacientes","Expendio","Fabricaci\u00f3n","Fiscal\u00eda General de la Naci\u00f3n","Huila","Isnos","Marihuana","Munici\u00f3n","Porte de armas","Seccional Huila","Tr\u00e1fico"],"articleSection":["Noticias","Seguridad territorial"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/en-isnos-huila-fueron-judicializadas-11-personas-senaladas-de-trafico-local-de-estupefacientes\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/en-isnos-huila-fueron-judicializadas-11-personas-senaladas-de-trafico-local-de-estupefacientes\/","name":"Fiscal\u00eda General de la Naci\u00f3n","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website"},"datePublished":"2026-05-13T21:02:49+00:00","dateModified":"2026-05-13T21:02:49+00:00","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","breadcrumb":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/en-isnos-huila-fueron-judicializadas-11-personas-senaladas-de-trafico-local-de-estupefacientes\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/en-isnos-huila-fueron-judicializadas-11-personas-senaladas-de-trafico-local-de-estupefacientes\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/en-isnos-huila-fueron-judicializadas-11-personas-senaladas-de-trafico-local-de-estupefacientes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fiscalia.gov.co\/colombia\/"},{"@type":"ListItem","position":2,"name":"En Isnos (Huila) fueron judicializadas 11 personas se\u00f1aladas de tr\u00e1fico local de estupefacientes"}]},{"@type":"WebSite","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","name":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization","name":"Fiscal\u00eda General de la Naci\u00f3n","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","contentUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","width":300,"height":90,"caption":"Fiscal\u00eda General de la Naci\u00f3n"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FiscaliaCol","https:\/\/x.com\/FiscaliaCol","https:\/\/www.instagram.com\/fiscaliacol","https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/","https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh"]},{"@type":"Person","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/66c172905e0492f1de6bbe5f93c4668f","name":"Paula Andrea Castillo Lenis","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cb060d9561f2947c4102d1825739f868?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cb060d9561f2947c4102d1825739f868?s=96&d=mm&r=g","caption":"Paula Andrea Castillo Lenis"},"url":"https:\/\/www.fiscalia.gov.co\/colombia\/author\/paula-castillo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/363863","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/users\/182"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/comments?post=363863"}],"version-history":[{"count":1,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/363863\/revisions"}],"predecessor-version":[{"id":363865,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/363863\/revisions\/363865"}],"wp:attachment":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/media?parent=363863"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/categories?post=363863"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/tags?post=363863"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}