{"id":363834,"date":"2026-05-13T12:02:42","date_gmt":"2026-05-13T17:02:42","guid":{"rendered":"https:\/\/www.fiscalia.gov.co\/colombia\/?p=363834"},"modified":"2026-05-13T12:02:42","modified_gmt":"2026-05-13T17:02:42","slug":"hombre-que-habria-abusado-sexualmente-de-una-menor-de-edad-en-tumaco-narino-fue-asegurado","status":"publish","type":"post","link":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/hombre-que-habria-abusado-sexualmente-de-una-menor-de-edad-en-tumaco-narino-fue-asegurado\/","title":{"rendered":"Hombre que habr\u00eda abusado sexualmente de una menor de edad en Tumaco (Nari\u00f1o) fue asegurado"},"content":{"rendered":"<p>La <strong>Fiscal\u00eda General de la Naci\u00f3n<\/strong> present\u00f3 ante un juez de control de garant\u00edas a Ariel Antonio Torres Ram\u00edrez, por su presunta responsabilidad en agredir sexualmente a una menor de edad en <strong>Tumaco (Nari\u00f1o).<\/strong><\/p>\n<p>En ese sentido, un fiscal de la <strong>Seccional Nari\u00f1o<\/strong> le imput\u00f3 el delito de acceso carnal abusivo con menor de 14 a\u00f1os. Durante las audiencias concentradas no acept\u00f3 el cargo y le fue impuesta <strong>medida de aseguramiento en centro carcelario.<\/strong><\/p>\n<p>El <strong>material probatorio<\/strong> da cuenta de que el procesado habr\u00eda contactado a la v\u00edctima en el momento que pasaba cerca de su local comercial y mediante enga\u00f1os la hizo entrar al lugar. Bajo el supuesto de darle dinero, presuntamente la someti\u00f3 a vej\u00e1menes sexuales en, al menos, cinco ocasiones en julio de 2025.<\/p>\n<p>Funcionarios del <strong>Cuerpo T\u00e9cnico de Investigaci\u00f3n (CTI)<\/strong> con apoyo de la<strong> Polic\u00eda Nacional<\/strong> capturaron al hombre cuando se movilizaba por el sector Los \u00c1ngeles, cumpliendo una orden judicial.<\/p>\n<p>&nbsp;<\/p>\n<p>JGPV\/AMCJ\/JPGG\/DSN<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><em>La informaci\u00f3n contenida en este bolet\u00edn de prensa corresponde a la narraci\u00f3n de los hechos noticiosos objetivos, suministrados por los funcionarios encargados de adelantar las investigaciones penales al interior de la Fiscal\u00eda General de la Naci\u00f3n. Para el momento de la divulgaci\u00f3n de este comunicado, la situaci\u00f3n jur\u00eddica de la(s) persona(s) relacionada(s) se encuentra pendiente de resolver por la autoridad judicial competente, siempre bajo los preceptos de la presunci\u00f3n de inocencia, consagrados en el art\u00edculo 29 de la Constituci\u00f3n Pol\u00edtica y el art\u00edculo 7\u00ba de la Ley 906 de 2004.<\/em><\/p>\n<p>&nbsp;<\/p>\n\n<div class=\"twitter-share\"><a href=\"https:\/\/twitter.com\/intent\/tweet?via=fiscaliacol\" class=\"twitter-share-button\">Tweet<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La Fiscal\u00eda General de la Naci\u00f3n present\u00f3 ante un juez de control de garant\u00edas a Ariel Antonio Torres Ram\u00edrez, por su presunta responsabilidad en agredir sexualmente a una menor de [&hellip;]<\/p>\n","protected":false},"author":182,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[1,24099],"tags":[801,11941,46901,924,46886,24551,27686,12596,24347,1047,13858,39259,25812,34563,39806,1185,932,10666,24549,558,32205,23867,24468,2299],"class_list":["post-363834","post","type-post","status-publish","format-standard","category-noticias","category-seguridad-territorial","tag-abuso-sexual","tag-acceso-carnal-abusivo-con-menor-de-14-anos","tag-ariel-antonio-torres-ramirez","tag-captura","tag-cargo-no-aceptado","tag-centro-carcelario","tag-control-de-garantias","tag-cuerpo-tecnico-de-investigacion-cti","tag-engano","tag-fiscalia-general-de-la-nacion","tag-imputacion","tag-investigacion-penal","tag-judicializacion","tag-local-comercial","tag-material-probatorio","tag-medida-de-aseguramiento","tag-mensor-de-edad","tag-narino","tag-orden-judicial","tag-policia-nacional","tag-seccional-narino","tag-tumaco","tag-vejamenes-sexuales","tag-violencia-sexual"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fiscal\u00eda General de la Naci\u00f3n<\/title>\n<meta name=\"description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/hombre-que-habria-abusado-sexualmente-de-una-menor-de-edad-en-tumaco-narino-fue-asegurado\/\" \/>\n<meta property=\"og:site_name\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FiscaliaCol\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-13T17:02:42+00:00\" \/>\n<meta name=\"author\" content=\"Paula Andrea Castillo Lenis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:site\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Paula Andrea Castillo Lenis\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/hombre-que-habria-abusado-sexualmente-de-una-menor-de-edad-en-tumaco-narino-fue-asegurado\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/hombre-que-habria-abusado-sexualmente-de-una-menor-de-edad-en-tumaco-narino-fue-asegurado\/\"},\"author\":{\"name\":\"Paula Andrea Castillo Lenis\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/66c172905e0492f1de6bbe5f93c4668f\"},\"headline\":\"Hombre que habr\u00eda abusado sexualmente de una menor de edad en Tumaco (Nari\u00f1o) fue asegurado\",\"datePublished\":\"2026-05-13T17:02:42+00:00\",\"dateModified\":\"2026-05-13T17:02:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/hombre-que-habria-abusado-sexualmente-de-una-menor-de-edad-en-tumaco-narino-fue-asegurado\/\"},\"wordCount\":292,\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"keywords\":[\"Abuso sexual\",\"acceso carnal abusivo con menor de 14 a\u00f1os\",\"Ariel Antonio Torres Ram\u00edrez\",\"Captura\",\"cargo no aceptado\",\"centro carcelario\",\"Control de Garant\u00edas\",\"Cuerpo T\u00e9cnico de Investigaci\u00f3n (CTI)\",\"enga\u00f1o\",\"Fiscal\u00eda General de la Naci\u00f3n\",\"Imputaci\u00f3n\",\"investigaci\u00f3n penal\",\"Judicializaci\u00f3n\",\"local comercial\",\"material probatorio\",\"Medida de aseguramiento\",\"Menor de edad\",\"Nari\u00f1o\",\"orden judicial\",\"Polic\u00eda Nacional\",\"Seccional Nari\u00f1o\",\"Tumaco\",\"vej\u00e1menes sexuales\",\"Violencia sexual\"],\"articleSection\":[\"Noticias\",\"Seguridad territorial\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/hombre-que-habria-abusado-sexualmente-de-una-menor-de-edad-en-tumaco-narino-fue-asegurado\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/hombre-que-habria-abusado-sexualmente-de-una-menor-de-edad-en-tumaco-narino-fue-asegurado\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\"},\"datePublished\":\"2026-05-13T17:02:42+00:00\",\"dateModified\":\"2026-05-13T17:02:42+00:00\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/hombre-que-habria-abusado-sexualmente-de-una-menor-de-edad-en-tumaco-narino-fue-asegurado\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/hombre-que-habria-abusado-sexualmente-de-una-menor-de-edad-en-tumaco-narino-fue-asegurado\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/hombre-que-habria-abusado-sexualmente-de-una-menor-de-edad-en-tumaco-narino-fue-asegurado\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hombre que habr\u00eda abusado sexualmente de una menor de edad en Tumaco (Nari\u00f1o) fue asegurado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"contentUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"width\":300,\"height\":90,\"caption\":\"Fiscal\u00eda General de la Naci\u00f3n\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/FiscaliaCol\",\"https:\/\/x.com\/FiscaliaCol\",\"https:\/\/www.instagram.com\/fiscaliacol\",\"https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/\",\"https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/66c172905e0492f1de6bbe5f93c4668f\",\"name\":\"Paula Andrea Castillo Lenis\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cb060d9561f2947c4102d1825739f868?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cb060d9561f2947c4102d1825739f868?s=96&d=mm&r=g\",\"caption\":\"Paula Andrea Castillo Lenis\"},\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/author\/paula-castillo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Fiscal\u00eda General de la Naci\u00f3n","og_description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","og_url":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/hombre-que-habria-abusado-sexualmente-de-una-menor-de-edad-en-tumaco-narino-fue-asegurado\/","og_site_name":"Fiscal\u00eda General de la Naci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/FiscaliaCol","article_published_time":"2026-05-13T17:02:42+00:00","author":"Paula Andrea Castillo Lenis","twitter_card":"summary_large_image","twitter_creator":"@FiscaliaCol","twitter_site":"@FiscaliaCol","twitter_misc":{"Escrito por":"Paula Andrea Castillo Lenis","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/hombre-que-habria-abusado-sexualmente-de-una-menor-de-edad-en-tumaco-narino-fue-asegurado\/#article","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/hombre-que-habria-abusado-sexualmente-de-una-menor-de-edad-en-tumaco-narino-fue-asegurado\/"},"author":{"name":"Paula Andrea Castillo Lenis","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/66c172905e0492f1de6bbe5f93c4668f"},"headline":"Hombre que habr\u00eda abusado sexualmente de una menor de edad en Tumaco (Nari\u00f1o) fue asegurado","datePublished":"2026-05-13T17:02:42+00:00","dateModified":"2026-05-13T17:02:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/hombre-que-habria-abusado-sexualmente-de-una-menor-de-edad-en-tumaco-narino-fue-asegurado\/"},"wordCount":292,"publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"keywords":["Abuso sexual","acceso carnal abusivo con menor de 14 a\u00f1os","Ariel Antonio Torres Ram\u00edrez","Captura","cargo no aceptado","centro carcelario","Control de Garant\u00edas","Cuerpo T\u00e9cnico de Investigaci\u00f3n (CTI)","enga\u00f1o","Fiscal\u00eda General de la Naci\u00f3n","Imputaci\u00f3n","investigaci\u00f3n penal","Judicializaci\u00f3n","local comercial","material probatorio","Medida de aseguramiento","Menor de edad","Nari\u00f1o","orden judicial","Polic\u00eda Nacional","Seccional Nari\u00f1o","Tumaco","vej\u00e1menes sexuales","Violencia sexual"],"articleSection":["Noticias","Seguridad territorial"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/hombre-que-habria-abusado-sexualmente-de-una-menor-de-edad-en-tumaco-narino-fue-asegurado\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/hombre-que-habria-abusado-sexualmente-de-una-menor-de-edad-en-tumaco-narino-fue-asegurado\/","name":"Fiscal\u00eda General de la Naci\u00f3n","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website"},"datePublished":"2026-05-13T17:02:42+00:00","dateModified":"2026-05-13T17:02:42+00:00","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","breadcrumb":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/hombre-que-habria-abusado-sexualmente-de-una-menor-de-edad-en-tumaco-narino-fue-asegurado\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/hombre-que-habria-abusado-sexualmente-de-una-menor-de-edad-en-tumaco-narino-fue-asegurado\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/hombre-que-habria-abusado-sexualmente-de-una-menor-de-edad-en-tumaco-narino-fue-asegurado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fiscalia.gov.co\/colombia\/"},{"@type":"ListItem","position":2,"name":"Hombre que habr\u00eda abusado sexualmente de una menor de edad en Tumaco (Nari\u00f1o) fue asegurado"}]},{"@type":"WebSite","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","name":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization","name":"Fiscal\u00eda General de la Naci\u00f3n","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","contentUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","width":300,"height":90,"caption":"Fiscal\u00eda General de la Naci\u00f3n"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FiscaliaCol","https:\/\/x.com\/FiscaliaCol","https:\/\/www.instagram.com\/fiscaliacol","https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/","https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh"]},{"@type":"Person","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/66c172905e0492f1de6bbe5f93c4668f","name":"Paula Andrea Castillo Lenis","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cb060d9561f2947c4102d1825739f868?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cb060d9561f2947c4102d1825739f868?s=96&d=mm&r=g","caption":"Paula Andrea Castillo Lenis"},"url":"https:\/\/www.fiscalia.gov.co\/colombia\/author\/paula-castillo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/363834","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/users\/182"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/comments?post=363834"}],"version-history":[{"count":1,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/363834\/revisions"}],"predecessor-version":[{"id":363837,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/363834\/revisions\/363837"}],"wp:attachment":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/media?parent=363834"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/categories?post=363834"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/tags?post=363834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}