{"id":315858,"date":"2025-05-22T09:00:50","date_gmt":"2025-05-22T14:00:50","guid":{"rendered":"https:\/\/www.fiscalia.gov.co\/colombia\/?p=315858"},"modified":"2025-05-22T09:00:50","modified_gmt":"2025-05-22T14:00:50","slug":"judicializado-presunto-responsable-de-extorsionar-a-tres-mujeres-a-cambio-de-no-publicar-material-intimo","status":"publish","type":"post","link":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presunto-responsable-de-extorsionar-a-tres-mujeres-a-cambio-de-no-publicar-material-intimo\/","title":{"rendered":"Judicializado presunto responsable de extorsionar a tres mujeres a cambio de no publicar material \u00edntimo"},"content":{"rendered":"<figure id=\"attachment_315859\" aria-describedby=\"caption-attachment-315859\" style=\"width: 931px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-315859 size-full\" src=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/capturado-.png\" alt=\"Se visualiza al capturado junto a dos uniformados del Gaula de la Polic\u00eda Nacional.  Detr\u00e1s de ellos el banner que identifica a la Polic\u00eda Metropolitana de C\u00facuta.\" width=\"931\" height=\"766\" srcset=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/capturado-.png 931w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/capturado--300x247.png 300w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/capturado--768x632.png 768w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/capturado--510x420.png 510w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/capturado--696x573.png 696w\" sizes=\"auto, (max-width: 931px) 100vw, 931px\" \/><figcaption id=\"caption-attachment-315859\" class=\"wp-caption-text\">Yeiner Arley Gelvez Laguado, alias Pipe G\u00f3mez o Edison, habr\u00eda extorsionado a varias mujeres a cambio de no publicar fotograf\u00edas o videos \u00edntimos.<\/figcaption><\/figure>\n<p><span style=\"font-weight: 400;\">Por solicitud de la <strong>Fiscal\u00eda General de la Naci\u00f3n<\/strong>, un juez de control de garant\u00edas impuso medida de aseguramiento en<strong> establecimiento carcelario<\/strong> a Yeiner Arley Gelvez Laguado, alias Pipe G\u00f3mez o Edison, por su presunta responsabilidad en las <\/span><a href=\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurados-nueve-hombres-que-estarian-extorsionando-a-comerciantes-de-cucuta\/\"><span style=\"font-weight: 400;\">extorsiones<\/span><\/a><span style=\"font-weight: 400;\"> a tres mujeres en hechos ocurridos entre mayo y noviembre de 2024, en <strong>C\u00facuta, Los Patios y Villa Rosario (Norte de Santander).<\/strong><\/span><\/p>\n<p><span style=\"font-weight: 400;\">En ese sentido un fiscal especializado le imput\u00f3 los delitos de extorsi\u00f3n agravada y tentativa de extorsi\u00f3n. En audiencias preliminares el hombre no acept\u00f3 su responsabilidad en los<strong> hechos investigados.<\/strong><\/span><\/p>\n<p><span style=\"font-weight: 400;\">La investigaci\u00f3n da cuenta de que el procesado a trav\u00e9s de redes sociales, al parecer, enga\u00f1\u00f3 a tres mujeres entre los 18 y 20 a\u00f1os con falsas\u00a0 ofertas de trabajo. Posteriormente, tras ganarse su confianza habr\u00eda obtenido<strong> videos \u00edntimos<\/strong> de las afectadas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Despu\u00e9s de la obtenci\u00f3n del material, presuntamente\u00a0 les exigi\u00f3 <\/span><a href=\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/por-intento-de-extorsion-a-una-ciudadana-en-cucuta-fue-asegurado-presunto-responsable\/\"><span style=\"font-weight: 400;\">sumas<\/span><\/a><span style=\"font-weight: 400;\"> de dinero y sostener relaciones \u00edntimas, a cambio de no publicar fotos y videos \u00edntimos. Adem\u00e1s las intimidaba asegurando que ten\u00eda supuestos v\u00ednculos con el<strong> &#8216;Tren de Aragua&#8217;.<\/strong><\/span><\/p>\n<p><span style=\"font-weight: 400;\">El hombre fue capturado mediante orden judicial en el barrio Montevideo de Los Patios (Norte de Santander) por el Gaula de la Polic\u00eda Nacional.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">MPHA\/AMCJ\/ JAAL\/EDBC<\/span><\/p>\n<p><i><span style=\"font-weight: 400;\">La informaci\u00f3n contenida en este bolet\u00edn de prensa corresponde a la narraci\u00f3n de los hechos noticiosos objetivos, suministrados por los funcionarios encargados de adelantar las investigaciones penales al interior de la Fiscal\u00eda General de la Naci\u00f3n. Para el momento de la divulgaci\u00f3n de este comunicado, la situaci\u00f3n jur\u00eddica de la(s) persona(s) relacionada(s) se encuentra pendiente de resolver por la autoridad judicial competente, siempre bajo los preceptos de la presunci\u00f3n de inocencia, consagrados en el art\u00edculo 29 de la Constituci\u00f3n Pol\u00edtica y el art\u00edculo 7\u00ba de la Ley 906 de 2004.\u00a0<\/span><\/i><\/p>\n\n<div class=\"twitter-share\"><a href=\"https:\/\/twitter.com\/intent\/tweet?via=fiscaliacol\" class=\"twitter-share-button\">Tweet<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Por solicitud de la Fiscal\u00eda General de la Naci\u00f3n, un juez de control de garant\u00edas impuso medida de aseguramiento en establecimiento carcelario a Yeiner Arley Gelvez Laguado, alias Pipe G\u00f3mez [&hellip;]<\/p>\n","protected":false},"author":182,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[1],"tags":[41554,41553,3119,12424,23826,2369,24347,24417,871,40811,37492,1047,20,39259,41555,41556,1185,26175,2228,24549,558,3029,3268,30248,25993,36169,41552],"class_list":["post-315858","post","type-post","status-publish","format-standard","category-noticias","tag-alias-edison","tag-alias-pipe-gomez","tag-amenazas","tag-capturado","tag-cucuta","tag-de4litos-sexuales","tag-engano","tag-establecimiento-carcelario","tag-extorion","tag-falsas-ofertas-de-trabajo","tag-fiscal-luz-adriana-camargo","tag-fiscalia-general-de-la-nacion","tag-gaula","tag-investigacion-penal","tag-los-patios","tag-manipulacion-digital","tag-medida-de-aseguramiento","tag-mujeres-victimas","tag-norte-de-santander","tag-orden-judicial","tag-policia-nacional","tag-redes-sociales","tag-tentativa-de-extorsion","tag-tren-de-aragua","tag-videos-intimos","tag-villa-del-rosario","tag-yeiner-arley-gelvez-laguado"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fiscal\u00eda General de la Naci\u00f3n<\/title>\n<meta name=\"description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presunto-responsable-de-extorsionar-a-tres-mujeres-a-cambio-de-no-publicar-material-intimo\/\" \/>\n<meta property=\"og:site_name\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FiscaliaCol\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-22T14:00:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/capturado-.png\" \/>\n\t<meta property=\"og:image:width\" content=\"931\" \/>\n\t<meta property=\"og:image:height\" content=\"766\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Paula Andrea Castillo Lenis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:site\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Paula Andrea Castillo Lenis\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presunto-responsable-de-extorsionar-a-tres-mujeres-a-cambio-de-no-publicar-material-intimo\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presunto-responsable-de-extorsionar-a-tres-mujeres-a-cambio-de-no-publicar-material-intimo\/\"},\"author\":{\"name\":\"Paula Andrea Castillo Lenis\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/66c172905e0492f1de6bbe5f93c4668f\"},\"headline\":\"Judicializado presunto responsable de extorsionar a tres mujeres a cambio de no publicar material \u00edntimo\",\"datePublished\":\"2025-05-22T14:00:50+00:00\",\"dateModified\":\"2025-05-22T14:00:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presunto-responsable-de-extorsionar-a-tres-mujeres-a-cambio-de-no-publicar-material-intimo\/\"},\"wordCount\":363,\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presunto-responsable-de-extorsionar-a-tres-mujeres-a-cambio-de-no-publicar-material-intimo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/capturado-.png\",\"keywords\":[\"alias Edison\",\"alias Pipe G\u00f3mez\",\"Amenazas\",\"Capturado\",\"C\u00facuta\",\"Delitos sexuales\",\"enga\u00f1o\",\"establecimiento carcelario\",\"Extorsi\u00f3n\",\"falsas ofertas de trabajo\",\"Fiscal Luz Adriana Camargo\",\"Fiscal\u00eda General de la Naci\u00f3n\",\"Gaula\",\"investigaci\u00f3n penal\",\"Los Patios\",\"manipulaci\u00f3n digital\",\"Medida de aseguramiento\",\"mujeres v\u00edctimas\",\"Norte de Santander\",\"orden judicial\",\"Polic\u00eda Nacional\",\"Redes sociales\",\"Tentativa de extorsi\u00f3n\",\"Tren de Aragua\",\"videos \u00edntimos\",\"villa del rosario\",\"Yeiner Arley Gelvez Laguado\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presunto-responsable-de-extorsionar-a-tres-mujeres-a-cambio-de-no-publicar-material-intimo\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presunto-responsable-de-extorsionar-a-tres-mujeres-a-cambio-de-no-publicar-material-intimo\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presunto-responsable-de-extorsionar-a-tres-mujeres-a-cambio-de-no-publicar-material-intimo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presunto-responsable-de-extorsionar-a-tres-mujeres-a-cambio-de-no-publicar-material-intimo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/capturado-.png\",\"datePublished\":\"2025-05-22T14:00:50+00:00\",\"dateModified\":\"2025-05-22T14:00:50+00:00\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presunto-responsable-de-extorsionar-a-tres-mujeres-a-cambio-de-no-publicar-material-intimo\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presunto-responsable-de-extorsionar-a-tres-mujeres-a-cambio-de-no-publicar-material-intimo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presunto-responsable-de-extorsionar-a-tres-mujeres-a-cambio-de-no-publicar-material-intimo\/#primaryimage\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/capturado-.png\",\"contentUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/capturado-.png\",\"width\":931,\"height\":766,\"caption\":\"Yeiner Arley Gelvez Laguado, alias Pipe G\u00f3mez o Edison, habr\u00eda extorsionado a varias mujeres a cambio de no publicar fotograf\u00edas o videos \u00edntimos.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presunto-responsable-de-extorsionar-a-tres-mujeres-a-cambio-de-no-publicar-material-intimo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Judicializado presunto responsable de extorsionar a tres mujeres a cambio de no publicar material \u00edntimo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"contentUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"width\":300,\"height\":90,\"caption\":\"Fiscal\u00eda General de la Naci\u00f3n\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/FiscaliaCol\",\"https:\/\/x.com\/FiscaliaCol\",\"https:\/\/www.instagram.com\/fiscaliacol\",\"https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/\",\"https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/66c172905e0492f1de6bbe5f93c4668f\",\"name\":\"Paula Andrea Castillo Lenis\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cb060d9561f2947c4102d1825739f868?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cb060d9561f2947c4102d1825739f868?s=96&d=mm&r=g\",\"caption\":\"Paula Andrea Castillo Lenis\"},\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/author\/paula-castillo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Fiscal\u00eda General de la Naci\u00f3n","og_description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","og_url":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presunto-responsable-de-extorsionar-a-tres-mujeres-a-cambio-de-no-publicar-material-intimo\/","og_site_name":"Fiscal\u00eda General de la Naci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/FiscaliaCol","article_published_time":"2025-05-22T14:00:50+00:00","og_image":[{"width":931,"height":766,"url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/capturado-.png","type":"image\/png"}],"author":"Paula Andrea Castillo Lenis","twitter_card":"summary_large_image","twitter_creator":"@FiscaliaCol","twitter_site":"@FiscaliaCol","twitter_misc":{"Escrito por":"Paula Andrea Castillo Lenis","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presunto-responsable-de-extorsionar-a-tres-mujeres-a-cambio-de-no-publicar-material-intimo\/#article","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presunto-responsable-de-extorsionar-a-tres-mujeres-a-cambio-de-no-publicar-material-intimo\/"},"author":{"name":"Paula Andrea Castillo Lenis","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/66c172905e0492f1de6bbe5f93c4668f"},"headline":"Judicializado presunto responsable de extorsionar a tres mujeres a cambio de no publicar material \u00edntimo","datePublished":"2025-05-22T14:00:50+00:00","dateModified":"2025-05-22T14:00:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presunto-responsable-de-extorsionar-a-tres-mujeres-a-cambio-de-no-publicar-material-intimo\/"},"wordCount":363,"publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presunto-responsable-de-extorsionar-a-tres-mujeres-a-cambio-de-no-publicar-material-intimo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/capturado-.png","keywords":["alias Edison","alias Pipe G\u00f3mez","Amenazas","Capturado","C\u00facuta","Delitos sexuales","enga\u00f1o","establecimiento carcelario","Extorsi\u00f3n","falsas ofertas de trabajo","Fiscal Luz Adriana Camargo","Fiscal\u00eda General de la Naci\u00f3n","Gaula","investigaci\u00f3n penal","Los Patios","manipulaci\u00f3n digital","Medida de aseguramiento","mujeres v\u00edctimas","Norte de Santander","orden judicial","Polic\u00eda Nacional","Redes sociales","Tentativa de extorsi\u00f3n","Tren de Aragua","videos \u00edntimos","villa del rosario","Yeiner Arley Gelvez Laguado"],"articleSection":["Noticias"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presunto-responsable-de-extorsionar-a-tres-mujeres-a-cambio-de-no-publicar-material-intimo\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presunto-responsable-de-extorsionar-a-tres-mujeres-a-cambio-de-no-publicar-material-intimo\/","name":"Fiscal\u00eda General de la Naci\u00f3n","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presunto-responsable-de-extorsionar-a-tres-mujeres-a-cambio-de-no-publicar-material-intimo\/#primaryimage"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presunto-responsable-de-extorsionar-a-tres-mujeres-a-cambio-de-no-publicar-material-intimo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/capturado-.png","datePublished":"2025-05-22T14:00:50+00:00","dateModified":"2025-05-22T14:00:50+00:00","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","breadcrumb":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presunto-responsable-de-extorsionar-a-tres-mujeres-a-cambio-de-no-publicar-material-intimo\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presunto-responsable-de-extorsionar-a-tres-mujeres-a-cambio-de-no-publicar-material-intimo\/"]}]},{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presunto-responsable-de-extorsionar-a-tres-mujeres-a-cambio-de-no-publicar-material-intimo\/#primaryimage","url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/capturado-.png","contentUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/capturado-.png","width":931,"height":766,"caption":"Yeiner Arley Gelvez Laguado, alias Pipe G\u00f3mez o Edison, habr\u00eda extorsionado a varias mujeres a cambio de no publicar fotograf\u00edas o videos \u00edntimos."},{"@type":"BreadcrumbList","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presunto-responsable-de-extorsionar-a-tres-mujeres-a-cambio-de-no-publicar-material-intimo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fiscalia.gov.co\/colombia\/"},{"@type":"ListItem","position":2,"name":"Judicializado presunto responsable de extorsionar a tres mujeres a cambio de no publicar material \u00edntimo"}]},{"@type":"WebSite","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","name":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization","name":"Fiscal\u00eda General de la Naci\u00f3n","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","contentUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","width":300,"height":90,"caption":"Fiscal\u00eda General de la Naci\u00f3n"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FiscaliaCol","https:\/\/x.com\/FiscaliaCol","https:\/\/www.instagram.com\/fiscaliacol","https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/","https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh"]},{"@type":"Person","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/66c172905e0492f1de6bbe5f93c4668f","name":"Paula Andrea Castillo Lenis","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cb060d9561f2947c4102d1825739f868?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cb060d9561f2947c4102d1825739f868?s=96&d=mm&r=g","caption":"Paula Andrea Castillo Lenis"},"url":"https:\/\/www.fiscalia.gov.co\/colombia\/author\/paula-castillo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/315858","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/users\/182"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/comments?post=315858"}],"version-history":[{"count":1,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/315858\/revisions"}],"predecessor-version":[{"id":315860,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/315858\/revisions\/315860"}],"wp:attachment":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/media?parent=315858"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/categories?post=315858"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/tags?post=315858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}