{"id":309009,"date":"2025-01-23T12:12:33","date_gmt":"2025-01-23T17:12:33","guid":{"rendered":"https:\/\/www.fiscalia.gov.co\/colombia\/?p=309009"},"modified":"2025-01-23T12:12:33","modified_gmt":"2025-01-23T17:12:33","slug":"fiscalia-judicializa-a-presunto-responsable-de-extorsiones-a-un-comerciante-en-ocana-norte-de-santander","status":"publish","type":"post","link":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-judicializa-a-presunto-responsable-de-extorsiones-a-un-comerciante-en-ocana-norte-de-santander\/","title":{"rendered":"Fiscal\u00eda judicializa a presunto responsable de extorsiones a un comerciante en Oca\u00f1a (Norte de Santander)"},"content":{"rendered":"<p>La Fiscal\u00eda General de la Naci\u00f3n judicializ\u00f3 a <strong>Eduardo Guti\u00e9rrez, alias Pineda, presunto responsable de realizar exigencias econ\u00f3micas ilegales a un comerciante, en hechos registrados en Oca\u00f1a (Norte de Santander).<\/strong><\/p>\n<figure id=\"attachment_309010\" aria-describedby=\"caption-attachment-309010\" style=\"width: 1600px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-309010\" src=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Eduardo-Gutierrez-alias-Pineda-judicializado-por-su-presunta-responsabilidad-en-extorsion-y-trafico-de-armas-de-fuego.jpeg\" alt=\"En la foto se ven cinco personas, una de ellas el capturado y cuatro uniformados de la Polic\u00eda y el Ej\u00e9rcito Nacional. En la parte posterior se ve un backing de la Polic\u00eda y en el lado derecho otro backing con una l\u00ednea de denuncia de extorsiones del Ej\u00e9rcito. \" width=\"1600\" height=\"1098\" srcset=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Eduardo-Gutierrez-alias-Pineda-judicializado-por-su-presunta-responsabilidad-en-extorsion-y-trafico-de-armas-de-fuego.jpeg 1600w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Eduardo-Gutierrez-alias-Pineda-judicializado-por-su-presunta-responsabilidad-en-extorsion-y-trafico-de-armas-de-fuego-300x206.jpeg 300w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Eduardo-Gutierrez-alias-Pineda-judicializado-por-su-presunta-responsabilidad-en-extorsion-y-trafico-de-armas-de-fuego-1024x703.jpeg 1024w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Eduardo-Gutierrez-alias-Pineda-judicializado-por-su-presunta-responsabilidad-en-extorsion-y-trafico-de-armas-de-fuego-768x527.jpeg 768w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Eduardo-Gutierrez-alias-Pineda-judicializado-por-su-presunta-responsabilidad-en-extorsion-y-trafico-de-armas-de-fuego-1536x1054.jpeg 1536w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Eduardo-Gutierrez-alias-Pineda-judicializado-por-su-presunta-responsabilidad-en-extorsion-y-trafico-de-armas-de-fuego-612x420.jpeg 612w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Eduardo-Gutierrez-alias-Pineda-judicializado-por-su-presunta-responsabilidad-en-extorsion-y-trafico-de-armas-de-fuego-218x150.jpeg 218w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Eduardo-Gutierrez-alias-Pineda-judicializado-por-su-presunta-responsabilidad-en-extorsion-y-trafico-de-armas-de-fuego-696x478.jpeg 696w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Eduardo-Gutierrez-alias-Pineda-judicializado-por-su-presunta-responsabilidad-en-extorsion-y-trafico-de-armas-de-fuego-1068x733.jpeg 1068w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Eduardo-Gutierrez-alias-Pineda-judicializado-por-su-presunta-responsabilidad-en-extorsion-y-trafico-de-armas-de-fuego-100x70.jpeg 100w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><figcaption id=\"caption-attachment-309010\" class=\"wp-caption-text\">Eduardo Guti\u00e9rrez, alias Pineda, fue capturado en flagrancia y judicializado por su presunta responsabilidad en los delitos de extorsi\u00f3n y tr\u00e1fico de armas.<\/figcaption><\/figure>\n<p>Por estos hechos, un <strong>fiscal seccional le imput\u00f3 los delitos de extorsi\u00f3n agravada; y fabricaci\u00f3n, tr\u00e1fico, porte o tenencia de armas de fuego, accesorios, partes o municiones<\/strong>. El procesado no se allan\u00f3 a los cargos y un juez de control de garant\u00edas le impuso medida de aseguramiento privativa de la libertad en establecimiento carcelario.<\/p>\n<p>Seg\u00fan las indagaciones adelantadas por la Fiscal\u00eda <strong>el procesado, entre octubre de 2024 y enero pasado, vendr\u00eda extorsionando al propietario de una bodega utilizada para el acopio y comercializaci\u00f3n de cilindros de gas.<\/strong><\/p>\n<p><strong>A la v\u00edctima le habr\u00eda exigido la suma de 5 millones de pesos mensuales<\/strong> a cambio de no atentar contra su vida, la de su familia y trabajadores, as\u00ed como no atacar los veh\u00edculos transportadores.<\/p>\n<p>La v\u00edctima denunci\u00f3 la situaci\u00f3n y se program\u00f3 una entrega controlada donde personal del Gaula Militar y Polic\u00eda Nacional, logr\u00f3 la captura del presunto responsable en el momento que recib\u00eda el dinero producto de la extorsi\u00f3n.<\/p>\n<p>En el procedimiento judicial le incautaron una pistola, cartuchos, tres\u00a0 celulares, tarjetas sim y una motocicleta.<\/p>\n<p>MPHA\/AMCJ\/OEBR\/EDBC\/DSNS<\/p>\n<p>&nbsp;<\/p>\n<p><em>La informaci\u00f3n contenida en este bolet\u00edn de prensa corresponde a la narraci\u00f3n de los hechos noticiosos objetivos, suministrados por los funcionarios encargados de adelantar las investigaciones penales al interior de la Fiscal\u00eda General de la Naci\u00f3n. Para el momento de la divulgaci\u00f3n de este comunicado, la situaci\u00f3n jur\u00eddica de la(s) persona(s) relacionada(s) se encuentra pendiente de resolver por la autoridad judicial competente, siempre bajo los preceptos de la presunci\u00f3n de inocencia, consagrados en el art\u00edculo 29 de la Constituci\u00f3n Pol\u00edtica y el art\u00edculo 7\u00ba de la Ley 906 de 2004.<\/em><\/p>\n\n<div class=\"twitter-share\"><a href=\"https:\/\/twitter.com\/intent\/tweet?via=fiscaliacol\" class=\"twitter-share-button\">Tweet<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La Fiscal\u00eda General de la Naci\u00f3n judicializ\u00f3 a Eduardo Guti\u00e9rrez, alias Pineda, presunto responsable de realizar exigencias econ\u00f3micas ilegales a un comerciante, en hechos registrados en Oca\u00f1a (Norte de Santander). [&hellip;]<\/p>\n","protected":false},"author":175,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[1,326,24099],"tags":[37491,37514],"class_list":["post-309009","post","type-post","status-publish","format-standard","category-noticias","category-seccional-cucuta","category-seguridad-territorial","tag-fiscal-camargo","tag-fiscal-general-luz-adriana-camargo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fiscal\u00eda General de la Naci\u00f3n<\/title>\n<meta name=\"description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-judicializa-a-presunto-responsable-de-extorsiones-a-un-comerciante-en-ocana-norte-de-santander\/\" \/>\n<meta property=\"og:site_name\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FiscaliaCol\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-23T17:12:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Eduardo-Gutierrez-alias-Pineda-judicializado-por-su-presunta-responsabilidad-en-extorsion-y-trafico-de-armas-de-fuego.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1098\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Katherine Loaiza Mart\u00ednez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:site\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Katherine Loaiza Mart\u00ednez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-judicializa-a-presunto-responsable-de-extorsiones-a-un-comerciante-en-ocana-norte-de-santander\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-judicializa-a-presunto-responsable-de-extorsiones-a-un-comerciante-en-ocana-norte-de-santander\/\"},\"author\":{\"name\":\"Katherine Loaiza Mart\u00ednez\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/2e76b9aba5ecf875ed565ce4de0e0415\"},\"headline\":\"Fiscal\u00eda judicializa a presunto responsable de extorsiones a un comerciante en Oca\u00f1a (Norte de Santander)\",\"datePublished\":\"2025-01-23T17:12:33+00:00\",\"dateModified\":\"2025-01-23T17:12:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-judicializa-a-presunto-responsable-de-extorsiones-a-un-comerciante-en-ocana-norte-de-santander\/\"},\"wordCount\":381,\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-judicializa-a-presunto-responsable-de-extorsiones-a-un-comerciante-en-ocana-norte-de-santander\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Eduardo-Gutierrez-alias-Pineda-judicializado-por-su-presunta-responsabilidad-en-extorsion-y-trafico-de-armas-de-fuego.jpeg\",\"keywords\":[\"fiscal Camargo\",\"Fiscal General Luz Adriana Camargo\"],\"articleSection\":[\"Noticias\",\"Seccional C\u00facuta\",\"Seguridad territorial\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-judicializa-a-presunto-responsable-de-extorsiones-a-un-comerciante-en-ocana-norte-de-santander\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-judicializa-a-presunto-responsable-de-extorsiones-a-un-comerciante-en-ocana-norte-de-santander\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-judicializa-a-presunto-responsable-de-extorsiones-a-un-comerciante-en-ocana-norte-de-santander\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-judicializa-a-presunto-responsable-de-extorsiones-a-un-comerciante-en-ocana-norte-de-santander\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Eduardo-Gutierrez-alias-Pineda-judicializado-por-su-presunta-responsabilidad-en-extorsion-y-trafico-de-armas-de-fuego.jpeg\",\"datePublished\":\"2025-01-23T17:12:33+00:00\",\"dateModified\":\"2025-01-23T17:12:33+00:00\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-judicializa-a-presunto-responsable-de-extorsiones-a-un-comerciante-en-ocana-norte-de-santander\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-judicializa-a-presunto-responsable-de-extorsiones-a-un-comerciante-en-ocana-norte-de-santander\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-judicializa-a-presunto-responsable-de-extorsiones-a-un-comerciante-en-ocana-norte-de-santander\/#primaryimage\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Eduardo-Gutierrez-alias-Pineda-judicializado-por-su-presunta-responsabilidad-en-extorsion-y-trafico-de-armas-de-fuego.jpeg\",\"contentUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Eduardo-Gutierrez-alias-Pineda-judicializado-por-su-presunta-responsabilidad-en-extorsion-y-trafico-de-armas-de-fuego.jpeg\",\"width\":1600,\"height\":1098,\"caption\":\"Eduardo Guti\u00e9rrez, alias Pineda, fue capturado en flagrancia y judicializado por su presunta responsabilidad en los delitos de extorsi\u00f3n y tr\u00e1fico de armas.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-judicializa-a-presunto-responsable-de-extorsiones-a-un-comerciante-en-ocana-norte-de-santander\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fiscal\u00eda judicializa a presunto responsable de extorsiones a un comerciante en Oca\u00f1a (Norte de Santander)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"contentUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"width\":300,\"height\":90,\"caption\":\"Fiscal\u00eda General de la Naci\u00f3n\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/FiscaliaCol\",\"https:\/\/x.com\/FiscaliaCol\",\"https:\/\/www.instagram.com\/fiscaliacol\",\"https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/\",\"https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/2e76b9aba5ecf875ed565ce4de0e0415\",\"name\":\"Katherine Loaiza Mart\u00ednez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ab775a2f394c1b83b6d6f78680e57b50?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ab775a2f394c1b83b6d6f78680e57b50?s=96&d=mm&r=g\",\"caption\":\"Katherine Loaiza Mart\u00ednez\"},\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/author\/kloaiza\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Fiscal\u00eda General de la Naci\u00f3n","og_description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","og_url":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-judicializa-a-presunto-responsable-de-extorsiones-a-un-comerciante-en-ocana-norte-de-santander\/","og_site_name":"Fiscal\u00eda General de la Naci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/FiscaliaCol","article_published_time":"2025-01-23T17:12:33+00:00","og_image":[{"width":1600,"height":1098,"url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Eduardo-Gutierrez-alias-Pineda-judicializado-por-su-presunta-responsabilidad-en-extorsion-y-trafico-de-armas-de-fuego.jpeg","type":"image\/jpeg"}],"author":"Katherine Loaiza Mart\u00ednez","twitter_card":"summary_large_image","twitter_creator":"@FiscaliaCol","twitter_site":"@FiscaliaCol","twitter_misc":{"Escrito por":"Katherine Loaiza Mart\u00ednez","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-judicializa-a-presunto-responsable-de-extorsiones-a-un-comerciante-en-ocana-norte-de-santander\/#article","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-judicializa-a-presunto-responsable-de-extorsiones-a-un-comerciante-en-ocana-norte-de-santander\/"},"author":{"name":"Katherine Loaiza Mart\u00ednez","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/2e76b9aba5ecf875ed565ce4de0e0415"},"headline":"Fiscal\u00eda judicializa a presunto responsable de extorsiones a un comerciante en Oca\u00f1a (Norte de Santander)","datePublished":"2025-01-23T17:12:33+00:00","dateModified":"2025-01-23T17:12:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-judicializa-a-presunto-responsable-de-extorsiones-a-un-comerciante-en-ocana-norte-de-santander\/"},"wordCount":381,"publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-judicializa-a-presunto-responsable-de-extorsiones-a-un-comerciante-en-ocana-norte-de-santander\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Eduardo-Gutierrez-alias-Pineda-judicializado-por-su-presunta-responsabilidad-en-extorsion-y-trafico-de-armas-de-fuego.jpeg","keywords":["fiscal Camargo","Fiscal General Luz Adriana Camargo"],"articleSection":["Noticias","Seccional C\u00facuta","Seguridad territorial"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-judicializa-a-presunto-responsable-de-extorsiones-a-un-comerciante-en-ocana-norte-de-santander\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-judicializa-a-presunto-responsable-de-extorsiones-a-un-comerciante-en-ocana-norte-de-santander\/","name":"Fiscal\u00eda General de la Naci\u00f3n","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-judicializa-a-presunto-responsable-de-extorsiones-a-un-comerciante-en-ocana-norte-de-santander\/#primaryimage"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-judicializa-a-presunto-responsable-de-extorsiones-a-un-comerciante-en-ocana-norte-de-santander\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Eduardo-Gutierrez-alias-Pineda-judicializado-por-su-presunta-responsabilidad-en-extorsion-y-trafico-de-armas-de-fuego.jpeg","datePublished":"2025-01-23T17:12:33+00:00","dateModified":"2025-01-23T17:12:33+00:00","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","breadcrumb":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-judicializa-a-presunto-responsable-de-extorsiones-a-un-comerciante-en-ocana-norte-de-santander\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-judicializa-a-presunto-responsable-de-extorsiones-a-un-comerciante-en-ocana-norte-de-santander\/"]}]},{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-judicializa-a-presunto-responsable-de-extorsiones-a-un-comerciante-en-ocana-norte-de-santander\/#primaryimage","url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Eduardo-Gutierrez-alias-Pineda-judicializado-por-su-presunta-responsabilidad-en-extorsion-y-trafico-de-armas-de-fuego.jpeg","contentUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Eduardo-Gutierrez-alias-Pineda-judicializado-por-su-presunta-responsabilidad-en-extorsion-y-trafico-de-armas-de-fuego.jpeg","width":1600,"height":1098,"caption":"Eduardo Guti\u00e9rrez, alias Pineda, fue capturado en flagrancia y judicializado por su presunta responsabilidad en los delitos de extorsi\u00f3n y tr\u00e1fico de armas."},{"@type":"BreadcrumbList","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-judicializa-a-presunto-responsable-de-extorsiones-a-un-comerciante-en-ocana-norte-de-santander\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fiscalia.gov.co\/colombia\/"},{"@type":"ListItem","position":2,"name":"Fiscal\u00eda judicializa a presunto responsable de extorsiones a un comerciante en Oca\u00f1a (Norte de Santander)"}]},{"@type":"WebSite","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","name":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization","name":"Fiscal\u00eda General de la Naci\u00f3n","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","contentUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","width":300,"height":90,"caption":"Fiscal\u00eda General de la Naci\u00f3n"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FiscaliaCol","https:\/\/x.com\/FiscaliaCol","https:\/\/www.instagram.com\/fiscaliacol","https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/","https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh"]},{"@type":"Person","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/2e76b9aba5ecf875ed565ce4de0e0415","name":"Katherine Loaiza Mart\u00ednez","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ab775a2f394c1b83b6d6f78680e57b50?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ab775a2f394c1b83b6d6f78680e57b50?s=96&d=mm&r=g","caption":"Katherine Loaiza Mart\u00ednez"},"url":"https:\/\/www.fiscalia.gov.co\/colombia\/author\/kloaiza\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/309009","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/users\/175"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/comments?post=309009"}],"version-history":[{"count":1,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/309009\/revisions"}],"predecessor-version":[{"id":309011,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/309009\/revisions\/309011"}],"wp:attachment":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/media?parent=309009"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/categories?post=309009"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/tags?post=309009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}