{"id":300675,"date":"2024-08-27T15:21:39","date_gmt":"2024-08-27T20:21:39","guid":{"rendered":"https:\/\/www.fiscalia.gov.co\/colombia\/?p=300675"},"modified":"2024-08-27T15:21:39","modified_gmt":"2024-08-27T20:21:39","slug":"a-la-carcel-presunto-dinamizador-del-microtrafico-en-leticia","status":"publish","type":"post","link":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-dinamizador-del-microtrafico-en-leticia\/","title":{"rendered":"A la c\u00e1rcel presunto dinamizador del microtr\u00e1fico en Leticia"},"content":{"rendered":"<h4 style=\"text-align: center;\"><strong><em>El procesado <\/em><em>ya ten\u00eda en su contra una condena por el mismo delito; adem\u00e1s de <\/em><em>dos \u00f3rdenes de captura vigentes. <\/em><\/strong><\/h4>\n<p>Ante un juez de garant\u00edas, una fiscal de la Seccional Amazonas judicializ\u00f3 a Juan Pablo Su\u00e1rez Ord\u00f3\u00f1ez como presunto responsable de los delitos de destinaci\u00f3n il\u00edcita de bienes, muebles e inmuebles; y tr\u00e1fico, fabricaci\u00f3n o porte de estupefacientes. <strong>Esta persona ser\u00eda se encargar\u00eda de dinamizar el comercio de estupefacientes en Leticia.<\/strong><\/p>\n<p>Las actividades ilegales ser\u00edan realizadas mediante distintas modalidades de expendio, principalmente desde una vivienda que fue allanada por la Polic\u00eda Nacional. En el lugar fueron encontradas dosis de diferentes estupefacientes listos para ser distribuidos en las denominadas plazas de vicio<strong>. Tambi\u00e9n fue encontrado dinero en efectivo, celulares y elementos para dosificar las sustancias il\u00edcitas.<\/strong><\/p>\n<p>La fiscal\u00eda evidenci\u00f3 que Su\u00e1rez Ord\u00f3\u00f1ez ya hab\u00eda sido condenado por el delito de tr\u00e1fico, fabricaci\u00f3n o porte de estupefacientes y ten\u00eda vigentes dos \u00f3rdenes de captura en su contra. <strong>El procesado fue detenido en flagrancia en el barrio La Esperanza de la capital de Amazonas.<\/strong><\/p>\n<p>El hombre no acept\u00f3 los cargos y fue privado de la libertad en un establecimiento carcelario.<\/p>\n<p>Esta informaci\u00f3n se publica por razones de inter\u00e9s general.<\/p>\n<p>&nbsp;<\/p>\n<p>LMBG\/DOM\/SFA\/MAGA\/<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><em>La informaci\u00f3n contenida en este bolet\u00edn de prensa corresponde a la narraci\u00f3n de los hechos noticiosos objetivos, suministrados por los funcionarios encargados de adelantar las investigaciones penales al interior de la Fiscal\u00eda General de la Naci\u00f3n. Para el momento de la divulgaci\u00f3n de este comunicado, la situaci\u00f3n jur\u00eddica de la(s) persona(s) relacionada(s) se encuentra pendiente de resolver por la autoridad judicial competente, siempre bajo los preceptos de la presunci\u00f3n de inocencia, consagrados en el art\u00edculo 29 de la Constituci\u00f3n Pol\u00edtica y el art\u00edculo 7\u00ba de la Ley 906 de 2004.<\/em><\/p>\n\n<div class=\"twitter-share\"><a href=\"https:\/\/twitter.com\/intent\/tweet?via=fiscaliacol\" class=\"twitter-share-button\">Tweet<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El procesado ya ten\u00eda en su contra una condena por el mismo delito; adem\u00e1s de dos \u00f3rdenes de captura vigentes. Ante un juez de garant\u00edas, una fiscal de la Seccional [&hellip;]<\/p>\n","protected":false},"author":178,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[1,24153,303,24103],"tags":[33862,1047,30239,155],"class_list":["post-300675","post","type-post","status-publish","format-standard","category-noticias","category-seccional-leticia","category-seccionales","category-trafico-de-estupefacientes","tag-bogota-d-c","tag-fiscalia-general-de-la-nacion","tag-seguridad-territorial","tag-trafico-de-estupefacientes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fiscal\u00eda General de la Naci\u00f3n<\/title>\n<meta name=\"description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-dinamizador-del-microtrafico-en-leticia\/\" \/>\n<meta property=\"og:site_name\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FiscaliaCol\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-27T20:21:39+00:00\" \/>\n<meta name=\"author\" content=\"Winnie Geraldine Rodr\u00edguez Navarrete\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:site\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Winnie Geraldine Rodr\u00edguez Navarrete\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-dinamizador-del-microtrafico-en-leticia\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-dinamizador-del-microtrafico-en-leticia\/\"},\"author\":{\"name\":\"Winnie Geraldine Rodr\u00edguez Navarrete\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/176195b99ebab0a52aafa15197e1bf80\"},\"headline\":\"A la c\u00e1rcel presunto dinamizador del microtr\u00e1fico en Leticia\",\"datePublished\":\"2024-08-27T20:21:39+00:00\",\"dateModified\":\"2024-08-27T20:21:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-dinamizador-del-microtrafico-en-leticia\/\"},\"wordCount\":341,\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"keywords\":[\"Bogot\u00e1 D.C.\",\"Fiscal\u00eda General de la Naci\u00f3n\",\"Seguridad territorial\",\"Tr\u00e1fico de estupefacientes\"],\"articleSection\":[\"Noticias\",\"Seccional Leticia\",\"Seccionales\",\"Tr\u00e1fico de estupefacientes\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-dinamizador-del-microtrafico-en-leticia\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-dinamizador-del-microtrafico-en-leticia\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\"},\"datePublished\":\"2024-08-27T20:21:39+00:00\",\"dateModified\":\"2024-08-27T20:21:39+00:00\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-dinamizador-del-microtrafico-en-leticia\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-dinamizador-del-microtrafico-en-leticia\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-dinamizador-del-microtrafico-en-leticia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A la c\u00e1rcel presunto dinamizador del microtr\u00e1fico en Leticia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"contentUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"width\":300,\"height\":90,\"caption\":\"Fiscal\u00eda General de la Naci\u00f3n\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/FiscaliaCol\",\"https:\/\/x.com\/FiscaliaCol\",\"https:\/\/www.instagram.com\/fiscaliacol\",\"https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/\",\"https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/176195b99ebab0a52aafa15197e1bf80\",\"name\":\"Winnie Geraldine Rodr\u00edguez Navarrete\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c24cf8481dc84fa5e8c7b20bc95ab0c6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c24cf8481dc84fa5e8c7b20bc95ab0c6?s=96&d=mm&r=g\",\"caption\":\"Winnie Geraldine Rodr\u00edguez Navarrete\"},\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/author\/winnierodriguez\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Fiscal\u00eda General de la Naci\u00f3n","og_description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","og_url":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-dinamizador-del-microtrafico-en-leticia\/","og_site_name":"Fiscal\u00eda General de la Naci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/FiscaliaCol","article_published_time":"2024-08-27T20:21:39+00:00","author":"Winnie Geraldine Rodr\u00edguez Navarrete","twitter_card":"summary_large_image","twitter_creator":"@FiscaliaCol","twitter_site":"@FiscaliaCol","twitter_misc":{"Escrito por":"Winnie Geraldine Rodr\u00edguez Navarrete","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-dinamizador-del-microtrafico-en-leticia\/#article","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-dinamizador-del-microtrafico-en-leticia\/"},"author":{"name":"Winnie Geraldine Rodr\u00edguez Navarrete","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/176195b99ebab0a52aafa15197e1bf80"},"headline":"A la c\u00e1rcel presunto dinamizador del microtr\u00e1fico en Leticia","datePublished":"2024-08-27T20:21:39+00:00","dateModified":"2024-08-27T20:21:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-dinamizador-del-microtrafico-en-leticia\/"},"wordCount":341,"publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"keywords":["Bogot\u00e1 D.C.","Fiscal\u00eda General de la Naci\u00f3n","Seguridad territorial","Tr\u00e1fico de estupefacientes"],"articleSection":["Noticias","Seccional Leticia","Seccionales","Tr\u00e1fico de estupefacientes"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-dinamizador-del-microtrafico-en-leticia\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-dinamizador-del-microtrafico-en-leticia\/","name":"Fiscal\u00eda General de la Naci\u00f3n","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website"},"datePublished":"2024-08-27T20:21:39+00:00","dateModified":"2024-08-27T20:21:39+00:00","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","breadcrumb":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-dinamizador-del-microtrafico-en-leticia\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-dinamizador-del-microtrafico-en-leticia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-dinamizador-del-microtrafico-en-leticia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fiscalia.gov.co\/colombia\/"},{"@type":"ListItem","position":2,"name":"A la c\u00e1rcel presunto dinamizador del microtr\u00e1fico en Leticia"}]},{"@type":"WebSite","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","name":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization","name":"Fiscal\u00eda General de la Naci\u00f3n","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","contentUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","width":300,"height":90,"caption":"Fiscal\u00eda General de la Naci\u00f3n"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FiscaliaCol","https:\/\/x.com\/FiscaliaCol","https:\/\/www.instagram.com\/fiscaliacol","https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/","https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh"]},{"@type":"Person","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/176195b99ebab0a52aafa15197e1bf80","name":"Winnie Geraldine Rodr\u00edguez Navarrete","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c24cf8481dc84fa5e8c7b20bc95ab0c6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c24cf8481dc84fa5e8c7b20bc95ab0c6?s=96&d=mm&r=g","caption":"Winnie Geraldine Rodr\u00edguez Navarrete"},"url":"https:\/\/www.fiscalia.gov.co\/colombia\/author\/winnierodriguez\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/300675","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/users\/178"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/comments?post=300675"}],"version-history":[{"count":1,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/300675\/revisions"}],"predecessor-version":[{"id":300677,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/300675\/revisions\/300677"}],"wp:attachment":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/media?parent=300675"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/categories?post=300675"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/tags?post=300675"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}