{"id":298294,"date":"2024-07-11T11:18:44","date_gmt":"2024-07-11T16:18:44","guid":{"rendered":"https:\/\/www.fiscalia.gov.co\/colombia\/?p=298294"},"modified":"2024-07-11T11:26:44","modified_gmt":"2024-07-11T16:26:44","slug":"en-risaralda-fue-judicializado-presunto-agresor-sexual-de-cuatro-menores-de-edad","status":"publish","type":"post","link":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/en-risaralda-fue-judicializado-presunto-agresor-sexual-de-cuatro-menores-de-edad\/","title":{"rendered":"En Risaralda fue judicializado presunto agresor sexual de cuatro menores de edad"},"content":{"rendered":"<p>El material probatorio recaudado por la Fiscal\u00eda General de la Naci\u00f3n permiti\u00f3 que un juez de control de garant\u00edas impusiera medida de aseguramiento en centro carcelario contra Alejames Rivera Vinasco, quien habr\u00eda agredido sexualmente a, por lo menos, cuatro menores de edad cuyas edades oscilaban entre 7 y 12 a\u00f1os.<\/p>\n<figure id=\"attachment_298298\" aria-describedby=\"caption-attachment-298298\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-298298\" src=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Alejames-Rivera-Vinasco-1-300x283.jpg\" alt=\"Se observa al capturado de frente y a cada costado un funcionario de Polic\u00eda nacional. Atr\u00e1s, un pend\u00f3n de Polic\u00eda Nacional.\" width=\"300\" height=\"283\" srcset=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Alejames-Rivera-Vinasco-1-300x283.jpg 300w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Alejames-Rivera-Vinasco-1-768x725.jpg 768w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Alejames-Rivera-Vinasco-1-696x657.jpg 696w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Alejames-Rivera-Vinasco-1-445x420.jpg 445w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Alejames-Rivera-Vinasco-1.jpg 953w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-298298\" class=\"wp-caption-text\">Alejames Rivera Vinasco fue privado de la libertad en centro carcelario por su presunta responsabilidad en hechos ocurridos en el municipio de Dosquebradas (Risaralda)<\/figcaption><\/figure>\n<p>Los hechos ocurrieron en la vereda Rivera Baja de Dosquebradas (Risaralda).\u00a0 De acuerdo con la investigaci\u00f3n, el hombre aprovechaba el hecho de contar con internet en su casa para invitar a los estudiantes que no ten\u00edan esa posibilidad a que fueran a su residencia\u00a0 para que pudieran realizar sus trabajos escolares.<\/p>\n<p>Se cree que durante esas visitas Rivera habr\u00eda agredido sexualmente a, por lo menos, cuatro menores de 7, 9, 10 y 12 a\u00f1os, en hechos ocurridos entre el a\u00f1o 2021 y el pasado 4 de abril.<\/p>\n<p>Una fiscal de la Seccional Risaralda le imput\u00f3 el delito de acto sexual con menor de 14 a\u00f1os, cargo que no fue aceptado.<\/p>\n<p>&nbsp;<\/p>\n<p>CLCG\/AMCJ\/MAGA\/CABS\/DSR<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><em>La informaci\u00f3n contenida en este bolet\u00edn de prensa corresponde a la narraci\u00f3n de los hechos noticiosos objetivos, suministrados por los funcionarios encargados de adelantar las investigaciones penales al interior de la Fiscal\u00eda General de la Naci\u00f3n. Para el momento de la divulgaci\u00f3n de este comunicado, la situaci\u00f3n jur\u00eddica de la(s) persona(s) relacionada(s) se encuentra pendiente de resolver por la autoridad judicial competente, siempre bajo los preceptos de la presunci\u00f3n de inocencia, consagrados en el art\u00edculo 29 de la Constituci\u00f3n Pol\u00edtica y el art\u00edculo 7\u00ba de la Ley 906 de 2004.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n\n<div class=\"twitter-share\"><a href=\"https:\/\/twitter.com\/intent\/tweet?via=fiscaliacol\" class=\"twitter-share-button\">Tweet<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El material probatorio recaudado por la Fiscal\u00eda General de la Naci\u00f3n permiti\u00f3 que un juez de control de garant\u00edas impusiera medida de aseguramiento en centro carcelario contra Alejames Rivera Vinasco, [&hellip;]<\/p>\n","protected":false},"author":181,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[1],"tags":[12184,78,37492,4614],"class_list":["post-298294","post","type-post","status-publish","format-standard","category-noticias","tag-fiscal","tag-fiscal-general-de-la-nacion","tag-fiscal-luz-adriana-camargo","tag-fiscalia-2"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fiscal\u00eda General de la Naci\u00f3n<\/title>\n<meta name=\"description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/en-risaralda-fue-judicializado-presunto-agresor-sexual-de-cuatro-menores-de-edad\/\" \/>\n<meta property=\"og:site_name\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FiscaliaCol\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-11T16:18:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-11T16:26:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Alejames-Rivera-Vinasco-1-300x283.jpg\" \/>\n<meta name=\"author\" content=\"Johanna Islenny Prieto Pe\u00f1a\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:site\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Johanna Islenny Prieto Pe\u00f1a\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/en-risaralda-fue-judicializado-presunto-agresor-sexual-de-cuatro-menores-de-edad\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/en-risaralda-fue-judicializado-presunto-agresor-sexual-de-cuatro-menores-de-edad\/\"},\"author\":{\"name\":\"Johanna Islenny Prieto Pe\u00f1a\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/ba9eca435947489fb25117a0cd75bf3e\"},\"headline\":\"En Risaralda fue judicializado presunto agresor sexual de cuatro menores de edad\",\"datePublished\":\"2024-07-11T16:18:44+00:00\",\"dateModified\":\"2024-07-11T16:26:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/en-risaralda-fue-judicializado-presunto-agresor-sexual-de-cuatro-menores-de-edad\/\"},\"wordCount\":319,\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/en-risaralda-fue-judicializado-presunto-agresor-sexual-de-cuatro-menores-de-edad\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Alejames-Rivera-Vinasco-1-300x283.jpg\",\"keywords\":[\"Fiscal\",\"Fiscal General de la Naci\u00f3n\",\"Fiscal Luz Adriana Camargo\",\"Fiscal\u00eda\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/en-risaralda-fue-judicializado-presunto-agresor-sexual-de-cuatro-menores-de-edad\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/en-risaralda-fue-judicializado-presunto-agresor-sexual-de-cuatro-menores-de-edad\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/en-risaralda-fue-judicializado-presunto-agresor-sexual-de-cuatro-menores-de-edad\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/en-risaralda-fue-judicializado-presunto-agresor-sexual-de-cuatro-menores-de-edad\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Alejames-Rivera-Vinasco-1-300x283.jpg\",\"datePublished\":\"2024-07-11T16:18:44+00:00\",\"dateModified\":\"2024-07-11T16:26:44+00:00\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/en-risaralda-fue-judicializado-presunto-agresor-sexual-de-cuatro-menores-de-edad\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/en-risaralda-fue-judicializado-presunto-agresor-sexual-de-cuatro-menores-de-edad\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/en-risaralda-fue-judicializado-presunto-agresor-sexual-de-cuatro-menores-de-edad\/#primaryimage\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Alejames-Rivera-Vinasco-1.jpg\",\"contentUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Alejames-Rivera-Vinasco-1.jpg\",\"width\":953,\"height\":900,\"caption\":\"Alejames Rivera Vinasco fue privado de la libertad en centro carcelario por su presunta responsabilidad en hechos ocurridos en el municipio de Dosquebradas (Risaralda)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/en-risaralda-fue-judicializado-presunto-agresor-sexual-de-cuatro-menores-de-edad\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"En Risaralda fue judicializado presunto agresor sexual de cuatro menores de edad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"contentUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"width\":300,\"height\":90,\"caption\":\"Fiscal\u00eda General de la Naci\u00f3n\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/FiscaliaCol\",\"https:\/\/x.com\/FiscaliaCol\",\"https:\/\/www.instagram.com\/fiscaliacol\",\"https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/\",\"https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/ba9eca435947489fb25117a0cd75bf3e\",\"name\":\"Johanna Islenny Prieto Pe\u00f1a\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/111433fc2acb037ffb768f6a3ca47864?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/111433fc2acb037ffb768f6a3ca47864?s=96&d=mm&r=g\",\"caption\":\"Johanna Islenny Prieto Pe\u00f1a\"},\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/author\/jprietop\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Fiscal\u00eda General de la Naci\u00f3n","og_description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","og_url":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/en-risaralda-fue-judicializado-presunto-agresor-sexual-de-cuatro-menores-de-edad\/","og_site_name":"Fiscal\u00eda General de la Naci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/FiscaliaCol","article_published_time":"2024-07-11T16:18:44+00:00","article_modified_time":"2024-07-11T16:26:44+00:00","og_image":[{"url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Alejames-Rivera-Vinasco-1-300x283.jpg","type":"","width":"","height":""}],"author":"Johanna Islenny Prieto Pe\u00f1a","twitter_card":"summary_large_image","twitter_creator":"@FiscaliaCol","twitter_site":"@FiscaliaCol","twitter_misc":{"Escrito por":"Johanna Islenny Prieto Pe\u00f1a","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/en-risaralda-fue-judicializado-presunto-agresor-sexual-de-cuatro-menores-de-edad\/#article","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/en-risaralda-fue-judicializado-presunto-agresor-sexual-de-cuatro-menores-de-edad\/"},"author":{"name":"Johanna Islenny Prieto Pe\u00f1a","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/ba9eca435947489fb25117a0cd75bf3e"},"headline":"En Risaralda fue judicializado presunto agresor sexual de cuatro menores de edad","datePublished":"2024-07-11T16:18:44+00:00","dateModified":"2024-07-11T16:26:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/en-risaralda-fue-judicializado-presunto-agresor-sexual-de-cuatro-menores-de-edad\/"},"wordCount":319,"publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/en-risaralda-fue-judicializado-presunto-agresor-sexual-de-cuatro-menores-de-edad\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Alejames-Rivera-Vinasco-1-300x283.jpg","keywords":["Fiscal","Fiscal General de la Naci\u00f3n","Fiscal Luz Adriana Camargo","Fiscal\u00eda"],"articleSection":["Noticias"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/en-risaralda-fue-judicializado-presunto-agresor-sexual-de-cuatro-menores-de-edad\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/en-risaralda-fue-judicializado-presunto-agresor-sexual-de-cuatro-menores-de-edad\/","name":"Fiscal\u00eda General de la Naci\u00f3n","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/en-risaralda-fue-judicializado-presunto-agresor-sexual-de-cuatro-menores-de-edad\/#primaryimage"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/en-risaralda-fue-judicializado-presunto-agresor-sexual-de-cuatro-menores-de-edad\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Alejames-Rivera-Vinasco-1-300x283.jpg","datePublished":"2024-07-11T16:18:44+00:00","dateModified":"2024-07-11T16:26:44+00:00","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","breadcrumb":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/en-risaralda-fue-judicializado-presunto-agresor-sexual-de-cuatro-menores-de-edad\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/en-risaralda-fue-judicializado-presunto-agresor-sexual-de-cuatro-menores-de-edad\/"]}]},{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/en-risaralda-fue-judicializado-presunto-agresor-sexual-de-cuatro-menores-de-edad\/#primaryimage","url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Alejames-Rivera-Vinasco-1.jpg","contentUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Alejames-Rivera-Vinasco-1.jpg","width":953,"height":900,"caption":"Alejames Rivera Vinasco fue privado de la libertad en centro carcelario por su presunta responsabilidad en hechos ocurridos en el municipio de Dosquebradas (Risaralda)"},{"@type":"BreadcrumbList","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/en-risaralda-fue-judicializado-presunto-agresor-sexual-de-cuatro-menores-de-edad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fiscalia.gov.co\/colombia\/"},{"@type":"ListItem","position":2,"name":"En Risaralda fue judicializado presunto agresor sexual de cuatro menores de edad"}]},{"@type":"WebSite","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","name":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization","name":"Fiscal\u00eda General de la Naci\u00f3n","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","contentUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","width":300,"height":90,"caption":"Fiscal\u00eda General de la Naci\u00f3n"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FiscaliaCol","https:\/\/x.com\/FiscaliaCol","https:\/\/www.instagram.com\/fiscaliacol","https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/","https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh"]},{"@type":"Person","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/ba9eca435947489fb25117a0cd75bf3e","name":"Johanna Islenny Prieto Pe\u00f1a","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/111433fc2acb037ffb768f6a3ca47864?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/111433fc2acb037ffb768f6a3ca47864?s=96&d=mm&r=g","caption":"Johanna Islenny Prieto Pe\u00f1a"},"url":"https:\/\/www.fiscalia.gov.co\/colombia\/author\/jprietop\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/298294","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/users\/181"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/comments?post=298294"}],"version-history":[{"count":4,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/298294\/revisions"}],"predecessor-version":[{"id":298300,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/298294\/revisions\/298300"}],"wp:attachment":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/media?parent=298294"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/categories?post=298294"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/tags?post=298294"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}