{"id":287756,"date":"2024-02-07T16:13:22","date_gmt":"2024-02-07T21:13:22","guid":{"rendered":"https:\/\/www.fiscalia.gov.co\/colombia\/?p=287756"},"modified":"2024-02-15T09:58:19","modified_gmt":"2024-02-15T14:58:19","slug":"a-la-carcel-presunto-responsable-del-homicidio-de-un-hombre-en-medio-de-un-atraco-en-bucaramanga","status":"publish","type":"post","link":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-responsable-del-homicidio-de-un-hombre-en-medio-de-un-atraco-en-bucaramanga\/","title":{"rendered":"A la c\u00e1rcel presunto responsable del homicidio de un hombre en medio de un atraco en Bucaramanga"},"content":{"rendered":"<p style=\"font-weight: 400;\">Por solicitud de la Fiscal\u00eda un juez con funci\u00f3n de control de garant\u00edas dict\u00f3 medida de aseguramiento en centro carcelario en contra de Rub\u00e9n Guti\u00e9rrez Macareo, por ser el presunto responsable de un homicidio en medio de un atraco.<\/p>\n<figure id=\"attachment_287757\" aria-describedby=\"caption-attachment-287757\" style=\"width: 696px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-287757 size-large\" src=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/RUBEN-GUTIERREZ-MACAREO-1024x704.jpg\" alt=\"en la foto se aprecia a dos miembros de la Polic\u00eda Nacional custodiando al hoy asegurado. \" width=\"696\" height=\"479\" srcset=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/RUBEN-GUTIERREZ-MACAREO-1024x704.jpg 1024w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/RUBEN-GUTIERREZ-MACAREO-300x206.jpg 300w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/RUBEN-GUTIERREZ-MACAREO-768x528.jpg 768w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/RUBEN-GUTIERREZ-MACAREO-1536x1056.jpg 1536w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/RUBEN-GUTIERREZ-MACAREO-218x150.jpg 218w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/RUBEN-GUTIERREZ-MACAREO-696x479.jpg 696w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/RUBEN-GUTIERREZ-MACAREO-1068x734.jpg 1068w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/RUBEN-GUTIERREZ-MACAREO-611x420.jpg 611w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/RUBEN-GUTIERREZ-MACAREO-100x70.jpg 100w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/RUBEN-GUTIERREZ-MACAREO.jpg 1600w\" sizes=\"auto, (max-width: 696px) 100vw, 696px\" \/><figcaption id=\"caption-attachment-287757\" class=\"wp-caption-text\">Rub\u00e9n Guti\u00e9rrez Macareo, fue enviado a prisi\u00f3n por su presunta responsabilidad en los delitos de: homicidio agravado, hurto calificado y agravado en grado de tentativa y uso de menores de edad para la comisi\u00f3n de conductas delictivas<\/figcaption><\/figure>\n<p style=\"font-weight: 400;\">Los hechos ocurrieron el pasado 27 de enero en el barrio La Juventud, en el norte de Bucaramanga, cuando la v\u00edctima estaba esperando el transporte p\u00fablico y fue abordado, al parecer, por el hoy asegurado y un menor de edad para robarle sus pertenencias.<\/p>\n<p style=\"font-weight: 400;\">Tras oponer resistencia Guti\u00e9rrez Macareo lo habr\u00eda atacado con arma blanca.\u00a0El hombre, de 35 a\u00f1os, quien era comunicador social, muri\u00f3 por la gravedad de las heridas.<\/p>\n<p style=\"font-weight: 400;\">A Guti\u00e9rrez Macareo, quien fue capturado por la Polic\u00eda Nacional, la Fiscal\u00eda le imput\u00f3 los delitos de homicidio agravado, hurto calificado y agravado en grado de tentativa y uso de menores de edad para la comisi\u00f3n de conductas delictivas, a los que no se allan\u00f3.<\/p>\n<p><strong><u>La Fiscal\u00eda habla con resultados.<\/u><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"font-weight: 400;\">DRA\/CFG\/MRR\/DSS<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<div class=\"td-post-content tagdiv-type\">\n<div class=\"td-post-content tagdiv-type\">\n<div class=\"td-post-content tagdiv-type\">\n<div class=\"td-post-content tagdiv-type\">\n<div class=\"td-post-content tagdiv-type\">\n<div class=\"td-post-content tagdiv-type\">\n<div class=\"td-post-content tagdiv-type\">\n<p><em>La informaci\u00f3n contenida en este bolet\u00edn de prensa corresponde a la narraci\u00f3n de los hechos noticiosos objetivos, suministrados por los funcionarios encargados de adelantar las investigaciones penales al interior de la Fiscal\u00eda General de la Naci\u00f3n. Para el momento de la divulgaci\u00f3n de este comunicado, la situaci\u00f3n jur\u00eddica de la(s) persona(s) relacionada(s) se encuentra pendiente de resolver por la autoridad judicial competente, siempre bajo los preceptos de la presunci\u00f3n de inocencia, consagrados en el art\u00edculo 29 de la Constituci\u00f3n Pol\u00edtica y el art\u00edculo 7\u00ba de la Ley 906 de 2004.\u00a0<\/em><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<footer>\n<div class=\"td-post-sharing-bottom\"><\/div>\n<\/footer>\n<\/div>\n<\/div>\n\n<div class=\"twitter-share\"><a href=\"https:\/\/twitter.com\/intent\/tweet?via=fiscaliacol\" class=\"twitter-share-button\">Tweet<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Por solicitud de la Fiscal\u00eda un juez con funci\u00f3n de control de garant\u00edas dict\u00f3 medida de aseguramiento en centro carcelario en contra de Rub\u00e9n Guti\u00e9rrez Macareo, por ser el presunto [&hellip;]<\/p>\n","protected":false},"author":177,"featured_media":288283,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[1,322,303,24099],"tags":[4648,24131,24185,1047,409],"class_list":["post-287756","post","type-post","status-publish","format-video","has-post-thumbnail","category-noticias","category-seccional-bucaramanga","category-seccionales","category-seguridad-territorial","tag-atraco","tag-bucaramanga-santander","tag-fiscal-barbosa","tag-fiscalia-general-de-la-nacion","tag-homicidio","post_format-post-format-video"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fiscal\u00eda General de la Naci\u00f3n<\/title>\n<meta name=\"description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-responsable-del-homicidio-de-un-hombre-en-medio-de-un-atraco-en-bucaramanga\/\" \/>\n<meta property=\"og:site_name\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FiscaliaCol\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-07T21:13:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-15T14:58:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/maxresdefault-1393.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jordan Leandro Oviedo Anzola\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:site\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jordan Leandro Oviedo Anzola\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-responsable-del-homicidio-de-un-hombre-en-medio-de-un-atraco-en-bucaramanga\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-responsable-del-homicidio-de-un-hombre-en-medio-de-un-atraco-en-bucaramanga\/\"},\"author\":{\"name\":\"Jordan Leandro Oviedo Anzola\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf84402cf293a5393e9c70b111020b24\"},\"headline\":\"A la c\u00e1rcel presunto responsable del homicidio de un hombre en medio de un atraco en Bucaramanga\",\"datePublished\":\"2024-02-07T21:13:22+00:00\",\"dateModified\":\"2024-02-15T14:58:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-responsable-del-homicidio-de-un-hombre-en-medio-de-un-atraco-en-bucaramanga\/\"},\"wordCount\":357,\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-responsable-del-homicidio-de-un-hombre-en-medio-de-un-atraco-en-bucaramanga\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/maxresdefault-1393.jpg\",\"keywords\":[\"Atraco\",\"Bucaramanga (Santander)\",\"Fiscal Barbosa\",\"Fiscal\u00eda General de la Naci\u00f3n\",\"Homicidio\"],\"articleSection\":[\"Noticias\",\"Seccional Bucaramanga\",\"Seccionales\",\"Seguridad territorial\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-responsable-del-homicidio-de-un-hombre-en-medio-de-un-atraco-en-bucaramanga\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-responsable-del-homicidio-de-un-hombre-en-medio-de-un-atraco-en-bucaramanga\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-responsable-del-homicidio-de-un-hombre-en-medio-de-un-atraco-en-bucaramanga\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-responsable-del-homicidio-de-un-hombre-en-medio-de-un-atraco-en-bucaramanga\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/maxresdefault-1393.jpg\",\"datePublished\":\"2024-02-07T21:13:22+00:00\",\"dateModified\":\"2024-02-15T14:58:19+00:00\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-responsable-del-homicidio-de-un-hombre-en-medio-de-un-atraco-en-bucaramanga\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-responsable-del-homicidio-de-un-hombre-en-medio-de-un-atraco-en-bucaramanga\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-responsable-del-homicidio-de-un-hombre-en-medio-de-un-atraco-en-bucaramanga\/#primaryimage\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/maxresdefault-1393.jpg\",\"contentUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/maxresdefault-1393.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-responsable-del-homicidio-de-un-hombre-en-medio-de-un-atraco-en-bucaramanga\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A la c\u00e1rcel presunto responsable del homicidio de un hombre en medio de un atraco en Bucaramanga\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"contentUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"width\":300,\"height\":90,\"caption\":\"Fiscal\u00eda General de la Naci\u00f3n\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/FiscaliaCol\",\"https:\/\/x.com\/FiscaliaCol\",\"https:\/\/www.instagram.com\/fiscaliacol\",\"https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/\",\"https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf84402cf293a5393e9c70b111020b24\",\"name\":\"Jordan Leandro Oviedo Anzola\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/dabba4346fa9b9207d96adafa8f92721?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/dabba4346fa9b9207d96adafa8f92721?s=96&d=mm&r=g\",\"caption\":\"Jordan Leandro Oviedo Anzola\"},\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/author\/joviedo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Fiscal\u00eda General de la Naci\u00f3n","og_description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","og_url":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-responsable-del-homicidio-de-un-hombre-en-medio-de-un-atraco-en-bucaramanga\/","og_site_name":"Fiscal\u00eda General de la Naci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/FiscaliaCol","article_published_time":"2024-02-07T21:13:22+00:00","article_modified_time":"2024-02-15T14:58:19+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/maxresdefault-1393.jpg","type":"image\/jpeg"}],"author":"Jordan Leandro Oviedo Anzola","twitter_card":"summary_large_image","twitter_creator":"@FiscaliaCol","twitter_site":"@FiscaliaCol","twitter_misc":{"Escrito por":"Jordan Leandro Oviedo Anzola","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-responsable-del-homicidio-de-un-hombre-en-medio-de-un-atraco-en-bucaramanga\/#article","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-responsable-del-homicidio-de-un-hombre-en-medio-de-un-atraco-en-bucaramanga\/"},"author":{"name":"Jordan Leandro Oviedo Anzola","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf84402cf293a5393e9c70b111020b24"},"headline":"A la c\u00e1rcel presunto responsable del homicidio de un hombre en medio de un atraco en Bucaramanga","datePublished":"2024-02-07T21:13:22+00:00","dateModified":"2024-02-15T14:58:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-responsable-del-homicidio-de-un-hombre-en-medio-de-un-atraco-en-bucaramanga\/"},"wordCount":357,"publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-responsable-del-homicidio-de-un-hombre-en-medio-de-un-atraco-en-bucaramanga\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/maxresdefault-1393.jpg","keywords":["Atraco","Bucaramanga (Santander)","Fiscal Barbosa","Fiscal\u00eda General de la Naci\u00f3n","Homicidio"],"articleSection":["Noticias","Seccional Bucaramanga","Seccionales","Seguridad territorial"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-responsable-del-homicidio-de-un-hombre-en-medio-de-un-atraco-en-bucaramanga\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-responsable-del-homicidio-de-un-hombre-en-medio-de-un-atraco-en-bucaramanga\/","name":"Fiscal\u00eda General de la Naci\u00f3n","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-responsable-del-homicidio-de-un-hombre-en-medio-de-un-atraco-en-bucaramanga\/#primaryimage"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-responsable-del-homicidio-de-un-hombre-en-medio-de-un-atraco-en-bucaramanga\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/maxresdefault-1393.jpg","datePublished":"2024-02-07T21:13:22+00:00","dateModified":"2024-02-15T14:58:19+00:00","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","breadcrumb":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-responsable-del-homicidio-de-un-hombre-en-medio-de-un-atraco-en-bucaramanga\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-responsable-del-homicidio-de-un-hombre-en-medio-de-un-atraco-en-bucaramanga\/"]}]},{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-responsable-del-homicidio-de-un-hombre-en-medio-de-un-atraco-en-bucaramanga\/#primaryimage","url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/maxresdefault-1393.jpg","contentUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/maxresdefault-1393.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-responsable-del-homicidio-de-un-hombre-en-medio-de-un-atraco-en-bucaramanga\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fiscalia.gov.co\/colombia\/"},{"@type":"ListItem","position":2,"name":"A la c\u00e1rcel presunto responsable del homicidio de un hombre en medio de un atraco en Bucaramanga"}]},{"@type":"WebSite","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","name":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization","name":"Fiscal\u00eda General de la Naci\u00f3n","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","contentUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","width":300,"height":90,"caption":"Fiscal\u00eda General de la Naci\u00f3n"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FiscaliaCol","https:\/\/x.com\/FiscaliaCol","https:\/\/www.instagram.com\/fiscaliacol","https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/","https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh"]},{"@type":"Person","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf84402cf293a5393e9c70b111020b24","name":"Jordan Leandro Oviedo Anzola","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/dabba4346fa9b9207d96adafa8f92721?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dabba4346fa9b9207d96adafa8f92721?s=96&d=mm&r=g","caption":"Jordan Leandro Oviedo Anzola"},"url":"https:\/\/www.fiscalia.gov.co\/colombia\/author\/joviedo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/287756","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/users\/177"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/comments?post=287756"}],"version-history":[{"count":1,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/287756\/revisions"}],"predecessor-version":[{"id":287758,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/287756\/revisions\/287758"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/media\/288283"}],"wp:attachment":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/media?parent=287756"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/categories?post=287756"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/tags?post=287756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}