{"id":285022,"date":"2023-12-15T11:27:22","date_gmt":"2023-12-15T16:27:22","guid":{"rendered":"https:\/\/www.fiscalia.gov.co\/colombia\/?p=285022"},"modified":"2023-12-15T11:27:22","modified_gmt":"2023-12-15T16:27:22","slug":"cifras-historicas-en-la-lucha-contra-la-criminalidad-arrojo-la-seccional-santander-durante-el-periodo-2020-2023","status":"publish","type":"post","link":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/cifras-historicas-en-la-lucha-contra-la-criminalidad-arrojo-la-seccional-santander-durante-el-periodo-2020-2023\/","title":{"rendered":"Cifras hist\u00f3ricas en la lucha contra la criminalidad arroj\u00f3 la seccional Santander durante el periodo 2020 &#8211; 2023"},"content":{"rendered":"<h4 style=\"font-weight: 400;\"><strong><em>La Fiscal\u00eda en Santander desarticul\u00f3 268 organizaciones criminales, ocup\u00f3 los primeros puestos en esclarecimiento en delitos como el feminicidio y homicidio, fortaleci\u00f3 la atenci\u00f3n de v\u00edctimas de violencia de g\u00e9nero y ampli\u00f3 su presencia en el departamento.<\/em><\/strong><\/h4>\n<p style=\"font-weight: 400;\">Atendiendo las directrices impartidas por el se\u00f1or fiscal general de la Naci\u00f3n, Francisco Barbosa, y articulada con el Cuerpo T\u00e9cnico de Investigaci\u00f3n, la Polic\u00eda Nacional, el Ej\u00e9rcito Nacional y autoridades administrativas de los \u00f3rdenes municipal y departamental, la Seccional Santander arroj\u00f3 importantes resultados en la lucha contra la criminalidad en este departamento entre 2020 y 2023.<\/p>\n<p style=\"font-weight: 400;\"><strong>Desarticulaci\u00f3n de bandas<\/strong><\/p>\n<p style=\"font-weight: 400;\">Durante este periodo se impactaron 268 organizaciones delincuenciales que afectan la seguridad ciudadana en diferentes municipios santandereanos. Mediante la aplicaci\u00f3n exitosa de t\u00e9cnicas de investigaci\u00f3n se logr\u00f3 la captura de 1.469 personas dedicadas a la comisi\u00f3n de delitos como el tr\u00e1fico de estupefacientes, hurto calificado y agravado, extorsi\u00f3n, homicidio y tr\u00e1fico de migrantes, entre otros, logrando la imposici\u00f3n de 1.263 medidas de aseguramiento con un 82.57% por ciento de efectividad.<\/p>\n<p style=\"font-weight: 400;\">De hecho, la medalla al m\u00e9rito Enrique Low Murtra fue concedida a un fiscal de esta seccional en 2022, destacando la labor acuciosa realizada por ese gran equipo de trabajo que permiti\u00f3 la desarticulaci\u00f3n de la banda Los Coyotes, dedicada al tr\u00e1fico de migrantes, quienes facilitaban el ingreso y salida de extranjeros por territorio colombiano a trav\u00e9s de trochas y pasos fronterizos con Ecuador y Venezuela, permitiendo su paso hacia pa\u00edses de centro y Suram\u00e9rica.<\/p>\n<p style=\"font-weight: 400;\">En el 2023 una fiscal recibi\u00f3 menci\u00f3n de honor Enrique Low Murtra en reconocimiento a la labor adelantada al impactar la banda Luz de Salvaci\u00f3n, logrando el esclarecimiento de 16 homicidios ocurridos en el \u00c1rea Metropolitana de Bucaramanga.<\/p>\n<figure id=\"attachment_285026\" aria-describedby=\"caption-attachment-285026\" style=\"width: 410px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-285026\" src=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/DIRECTORA-DE-FISCALIAS-DE-SANTANDER-2023-300x226.jpg\" alt=\"En la foto aparece la Directora Seccional realizando la presentaci\u00f3n del balance de gesti\u00f3n.\" width=\"410\" height=\"309\" srcset=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/DIRECTORA-DE-FISCALIAS-DE-SANTANDER-2023-300x226.jpg 300w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/DIRECTORA-DE-FISCALIAS-DE-SANTANDER-2023-1024x771.jpg 1024w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/DIRECTORA-DE-FISCALIAS-DE-SANTANDER-2023-768x578.jpg 768w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/DIRECTORA-DE-FISCALIAS-DE-SANTANDER-2023-1536x1157.jpg 1536w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/DIRECTORA-DE-FISCALIAS-DE-SANTANDER-2023-696x524.jpg 696w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/DIRECTORA-DE-FISCALIAS-DE-SANTANDER-2023-1068x804.jpg 1068w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/DIRECTORA-DE-FISCALIAS-DE-SANTANDER-2023-558x420.jpg 558w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/DIRECTORA-DE-FISCALIAS-DE-SANTANDER-2023-80x60.jpg 80w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/DIRECTORA-DE-FISCALIAS-DE-SANTANDER-2023.jpg 1600w\" sizes=\"auto, (max-width: 410px) 100vw, 410px\" \/><figcaption id=\"caption-attachment-285026\" class=\"wp-caption-text\">En rueda de prensa la directora de la Seccional Santander, Marisol Ram\u00edrez Rodr\u00edguez, dio a conocer el balance de la gesti\u00f3n.<\/figcaption><\/figure>\n<p style=\"font-weight: 400;\"><strong>Delitos priorizados<\/strong><\/p>\n<p style=\"font-weight: 400;\">En cuanto a delitos priorizados se logr\u00f3 el incremento significativo en sus resultados que superan las cifras de periodos anteriores. En casos de homicidios se logr\u00f3 un esclarecimiento del 69%, en feminicidios del 100%, en violencia sexual un 67%, en violencia intrafamiliar un 91% y en homicidios en donde las v\u00edctimas son mujeres un 85%.<\/p>\n<p style=\"font-weight: 400;\"><strong>Atenci\u00f3n diferencial<\/strong><\/p>\n<p style=\"font-weight: 400;\">Con la creaci\u00f3n de rutas itinerantes para impulsar actividades investigativas en torno a casos de violencia intrafamiliar y violencia sexual en los que aparecen como v\u00edctimas ni\u00f1os, ni\u00f1as y adolescentes, se atendieron alrededor de 5.000 personas en los municipios de Bucaramanga, Gir\u00f3n, Piedecuesta, Floridablanca, V\u00e9lez y Barbosa.<\/p>\n<p style=\"font-weight: 400;\">Y se continu\u00f3 fortaleciendo la prevenci\u00f3n del delito a trav\u00e9s del programa Futuro Colombia, orientando a 29.313\u00a0 estudiantes, docentes y padres de familia en establecimientos educativos de Santander.<\/p>\n<p style=\"font-weight: 400;\">Y en un trabajo interinstitucional con el comit\u00e9 seccional de G\u00e9nero de Bucaramanga se puso en marcha el proyecto piloto denominado Ventanilla Violeta, liderado por la Seccional Santander, que cuenta con el apoyo de profesionales especializados ubicados en lugares adecuados y cuyo objetivo es brindar un nuevo canal de atenci\u00f3n especializada a aquellas personas que son v\u00edctimas de violencia de g\u00e9nero.<\/p>\n<p style=\"font-weight: 400;\"><strong>Ampliaci\u00f3n de presencia institucional en el territorio<\/strong><\/p>\n<p style=\"font-weight: 400;\">Para ampliar el \u00e1rea de cobertura de atenci\u00f3n, tal y como lo dispone el Direccionamiento Estrat\u00e9gico del se\u00f1or fiscal general, se crearon 17 puntos de atenci\u00f3n de la Fiscal\u00eda (PAF), ampliando de esta manera los mecanismos de contacto y respuesta en lugares donde no existe presencia f\u00edsica del ente acusador.<\/p>\n<p style=\"font-weight: 400;\">Con el fin de afianzar la aplicaci\u00f3n de modelos de justicia restaurativa, fueron habilitados los respectivos centros en San Gil y Socorro, municipios en donde se propende dar soluciones a conflictos por fuera del \u00e1mbito penal.<\/p>\n<p style=\"font-weight: 400;\">Sobre la organizaci\u00f3n de sedes, se concret\u00f3 la construcci\u00f3n del b\u00fanker en el municipio de Floridablanca, contando para ello con una inversi\u00f3n millonaria que permitir\u00e1 no solo el bienestar de los servidores de la Fiscal\u00eda, sino el mejoramiento de la infraestructura para mayor comodidad de nuestros usuarios y v\u00edctimas en general.<\/p>\n<p style=\"font-weight: 400;\"><strong>Compromiso laboral\u00a0<\/strong><\/p>\n<p style=\"font-weight: 400;\">El trabajo en equipo realizado por los fiscales adscritos a esta Seccional con el apoyo de la Direcci\u00f3n de Atenci\u00f3n al Usuario, Intervenci\u00f3n Temprana y Asignaciones, Dauita, en materia de descongesti\u00f3n, qued\u00f3 evidenciado en cifras. Para febrero de 2020 se contaba con una carga de congesti\u00f3n del 35.02%, a diciembre de 2023 se cuenta con una descongesti\u00f3n del 24.80%.<\/p>\n<p style=\"font-weight: 400;\">Todas estas acciones cuya materializaci\u00f3n se observa en los logros se\u00f1alados, son la respuesta al gran compromiso demostrado por esta Seccional frente a las tareas encomendadas por el se\u00f1or fiscal general al disponer la garant\u00eda de un derecho al acceso a la justicia de manera eficiente y oportuna.<\/p>\n<p><strong><u>La Fiscal\u00eda habla con resultados.<\/u><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"font-weight: 400;\">DRA\/ CFG\/MRR\/DSS<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">\n<p>&nbsp;<\/p>\n<p><em>La informaci\u00f3n contenida en este bolet\u00edn de prensa corresponde a la narraci\u00f3n de los hechos noticiosos objetivos, suministrados por los funcionarios encargados de adelantar las investigaciones penales al interior de la Fiscal\u00eda General de la Naci\u00f3n. Para el momento de la divulgaci\u00f3n de este comunicado, la situaci\u00f3n jur\u00eddica de la(s) persona(s) relacionada(s) se encuentra pendiente de resolver por la autoridad\u00a0judicial competente, siempre bajo los preceptos de la presunci\u00f3n de inocencia, consagrados en el art\u00edculo 29 de la Constituci\u00f3n Pol\u00edtica y el art\u00edculo 7\u00ba de la Ley 906 de 2004.\u00a0<\/em><\/p>\n\n<div class=\"twitter-share\"><a href=\"https:\/\/twitter.com\/intent\/tweet?via=fiscaliacol\" class=\"twitter-share-button\">Tweet<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La Fiscal\u00eda en Santander desarticul\u00f3 268 organizaciones criminales, ocup\u00f3 los primeros puestos en esclarecimiento en delitos como el feminicidio y homicidio, fortaleci\u00f3 la atenci\u00f3n de v\u00edctimas de violencia de g\u00e9nero [&hellip;]<\/p>\n","protected":false},"author":178,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[1,322,303],"tags":[33535,1561],"class_list":["post-285022","post","type-post","status-publish","format-standard","category-noticias","category-seccional-bucaramanga","category-seccionales","tag-balance-de-gestion","tag-santander"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fiscal\u00eda General de la Naci\u00f3n<\/title>\n<meta name=\"description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/cifras-historicas-en-la-lucha-contra-la-criminalidad-arrojo-la-seccional-santander-durante-el-periodo-2020-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FiscaliaCol\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-15T16:27:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/DIRECTORA-DE-FISCALIAS-DE-SANTANDER-2023-300x226.jpg\" \/>\n<meta name=\"author\" content=\"Winnie Geraldine Rodr\u00edguez Navarrete\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:site\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Winnie Geraldine Rodr\u00edguez Navarrete\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/cifras-historicas-en-la-lucha-contra-la-criminalidad-arrojo-la-seccional-santander-durante-el-periodo-2020-2023\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/cifras-historicas-en-la-lucha-contra-la-criminalidad-arrojo-la-seccional-santander-durante-el-periodo-2020-2023\/\"},\"author\":{\"name\":\"Winnie Geraldine Rodr\u00edguez Navarrete\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/176195b99ebab0a52aafa15197e1bf80\"},\"headline\":\"Cifras hist\u00f3ricas en la lucha contra la criminalidad arroj\u00f3 la seccional Santander durante el periodo 2020 &#8211; 2023\",\"datePublished\":\"2023-12-15T16:27:22+00:00\",\"dateModified\":\"2023-12-15T16:27:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/cifras-historicas-en-la-lucha-contra-la-criminalidad-arrojo-la-seccional-santander-durante-el-periodo-2020-2023\/\"},\"wordCount\":934,\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/cifras-historicas-en-la-lucha-contra-la-criminalidad-arrojo-la-seccional-santander-durante-el-periodo-2020-2023\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/DIRECTORA-DE-FISCALIAS-DE-SANTANDER-2023-300x226.jpg\",\"keywords\":[\"balance de gesti\u00f3n\",\"Santander\"],\"articleSection\":[\"Noticias\",\"Seccional Bucaramanga\",\"Seccionales\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/cifras-historicas-en-la-lucha-contra-la-criminalidad-arrojo-la-seccional-santander-durante-el-periodo-2020-2023\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/cifras-historicas-en-la-lucha-contra-la-criminalidad-arrojo-la-seccional-santander-durante-el-periodo-2020-2023\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/cifras-historicas-en-la-lucha-contra-la-criminalidad-arrojo-la-seccional-santander-durante-el-periodo-2020-2023\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/cifras-historicas-en-la-lucha-contra-la-criminalidad-arrojo-la-seccional-santander-durante-el-periodo-2020-2023\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/DIRECTORA-DE-FISCALIAS-DE-SANTANDER-2023-300x226.jpg\",\"datePublished\":\"2023-12-15T16:27:22+00:00\",\"dateModified\":\"2023-12-15T16:27:22+00:00\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/cifras-historicas-en-la-lucha-contra-la-criminalidad-arrojo-la-seccional-santander-durante-el-periodo-2020-2023\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/cifras-historicas-en-la-lucha-contra-la-criminalidad-arrojo-la-seccional-santander-durante-el-periodo-2020-2023\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/cifras-historicas-en-la-lucha-contra-la-criminalidad-arrojo-la-seccional-santander-durante-el-periodo-2020-2023\/#primaryimage\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/DIRECTORA-DE-FISCALIAS-DE-SANTANDER-2023.jpg\",\"contentUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/DIRECTORA-DE-FISCALIAS-DE-SANTANDER-2023.jpg\",\"width\":1600,\"height\":1205,\"caption\":\"En rueda de prensa la directora de la Seccional Santander, Marisol Ram\u00edrez Rodr\u00edguez, dio a conocer el balance de la gesti\u00f3n.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/cifras-historicas-en-la-lucha-contra-la-criminalidad-arrojo-la-seccional-santander-durante-el-periodo-2020-2023\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cifras hist\u00f3ricas en la lucha contra la criminalidad arroj\u00f3 la seccional Santander durante el periodo 2020 &#8211; 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"contentUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"width\":300,\"height\":90,\"caption\":\"Fiscal\u00eda General de la Naci\u00f3n\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/FiscaliaCol\",\"https:\/\/x.com\/FiscaliaCol\",\"https:\/\/www.instagram.com\/fiscaliacol\",\"https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/\",\"https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/176195b99ebab0a52aafa15197e1bf80\",\"name\":\"Winnie Geraldine Rodr\u00edguez Navarrete\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c24cf8481dc84fa5e8c7b20bc95ab0c6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c24cf8481dc84fa5e8c7b20bc95ab0c6?s=96&d=mm&r=g\",\"caption\":\"Winnie Geraldine Rodr\u00edguez Navarrete\"},\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/author\/winnierodriguez\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Fiscal\u00eda General de la Naci\u00f3n","og_description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","og_url":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/cifras-historicas-en-la-lucha-contra-la-criminalidad-arrojo-la-seccional-santander-durante-el-periodo-2020-2023\/","og_site_name":"Fiscal\u00eda General de la Naci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/FiscaliaCol","article_published_time":"2023-12-15T16:27:22+00:00","og_image":[{"url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/DIRECTORA-DE-FISCALIAS-DE-SANTANDER-2023-300x226.jpg","type":"","width":"","height":""}],"author":"Winnie Geraldine Rodr\u00edguez Navarrete","twitter_card":"summary_large_image","twitter_creator":"@FiscaliaCol","twitter_site":"@FiscaliaCol","twitter_misc":{"Escrito por":"Winnie Geraldine Rodr\u00edguez Navarrete","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/cifras-historicas-en-la-lucha-contra-la-criminalidad-arrojo-la-seccional-santander-durante-el-periodo-2020-2023\/#article","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/cifras-historicas-en-la-lucha-contra-la-criminalidad-arrojo-la-seccional-santander-durante-el-periodo-2020-2023\/"},"author":{"name":"Winnie Geraldine Rodr\u00edguez Navarrete","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/176195b99ebab0a52aafa15197e1bf80"},"headline":"Cifras hist\u00f3ricas en la lucha contra la criminalidad arroj\u00f3 la seccional Santander durante el periodo 2020 &#8211; 2023","datePublished":"2023-12-15T16:27:22+00:00","dateModified":"2023-12-15T16:27:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/cifras-historicas-en-la-lucha-contra-la-criminalidad-arrojo-la-seccional-santander-durante-el-periodo-2020-2023\/"},"wordCount":934,"publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/cifras-historicas-en-la-lucha-contra-la-criminalidad-arrojo-la-seccional-santander-durante-el-periodo-2020-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/DIRECTORA-DE-FISCALIAS-DE-SANTANDER-2023-300x226.jpg","keywords":["balance de gesti\u00f3n","Santander"],"articleSection":["Noticias","Seccional Bucaramanga","Seccionales"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/cifras-historicas-en-la-lucha-contra-la-criminalidad-arrojo-la-seccional-santander-durante-el-periodo-2020-2023\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/cifras-historicas-en-la-lucha-contra-la-criminalidad-arrojo-la-seccional-santander-durante-el-periodo-2020-2023\/","name":"Fiscal\u00eda General de la Naci\u00f3n","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/cifras-historicas-en-la-lucha-contra-la-criminalidad-arrojo-la-seccional-santander-durante-el-periodo-2020-2023\/#primaryimage"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/cifras-historicas-en-la-lucha-contra-la-criminalidad-arrojo-la-seccional-santander-durante-el-periodo-2020-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/DIRECTORA-DE-FISCALIAS-DE-SANTANDER-2023-300x226.jpg","datePublished":"2023-12-15T16:27:22+00:00","dateModified":"2023-12-15T16:27:22+00:00","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","breadcrumb":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/cifras-historicas-en-la-lucha-contra-la-criminalidad-arrojo-la-seccional-santander-durante-el-periodo-2020-2023\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/cifras-historicas-en-la-lucha-contra-la-criminalidad-arrojo-la-seccional-santander-durante-el-periodo-2020-2023\/"]}]},{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/cifras-historicas-en-la-lucha-contra-la-criminalidad-arrojo-la-seccional-santander-durante-el-periodo-2020-2023\/#primaryimage","url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/DIRECTORA-DE-FISCALIAS-DE-SANTANDER-2023.jpg","contentUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/DIRECTORA-DE-FISCALIAS-DE-SANTANDER-2023.jpg","width":1600,"height":1205,"caption":"En rueda de prensa la directora de la Seccional Santander, Marisol Ram\u00edrez Rodr\u00edguez, dio a conocer el balance de la gesti\u00f3n."},{"@type":"BreadcrumbList","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/cifras-historicas-en-la-lucha-contra-la-criminalidad-arrojo-la-seccional-santander-durante-el-periodo-2020-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fiscalia.gov.co\/colombia\/"},{"@type":"ListItem","position":2,"name":"Cifras hist\u00f3ricas en la lucha contra la criminalidad arroj\u00f3 la seccional Santander durante el periodo 2020 &#8211; 2023"}]},{"@type":"WebSite","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","name":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization","name":"Fiscal\u00eda General de la Naci\u00f3n","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","contentUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","width":300,"height":90,"caption":"Fiscal\u00eda General de la Naci\u00f3n"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FiscaliaCol","https:\/\/x.com\/FiscaliaCol","https:\/\/www.instagram.com\/fiscaliacol","https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/","https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh"]},{"@type":"Person","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/176195b99ebab0a52aafa15197e1bf80","name":"Winnie Geraldine Rodr\u00edguez Navarrete","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c24cf8481dc84fa5e8c7b20bc95ab0c6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c24cf8481dc84fa5e8c7b20bc95ab0c6?s=96&d=mm&r=g","caption":"Winnie Geraldine Rodr\u00edguez Navarrete"},"url":"https:\/\/www.fiscalia.gov.co\/colombia\/author\/winnierodriguez\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/285022","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/users\/178"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/comments?post=285022"}],"version-history":[{"count":2,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/285022\/revisions"}],"predecessor-version":[{"id":285027,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/285022\/revisions\/285027"}],"wp:attachment":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/media?parent=285022"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/categories?post=285022"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/tags?post=285022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}