{"id":281631,"date":"2023-10-17T11:46:54","date_gmt":"2023-10-17T16:46:54","guid":{"rendered":"https:\/\/www.fiscalia.gov.co\/colombia\/?p=281631"},"modified":"2023-10-23T15:23:23","modified_gmt":"2023-10-23T20:23:23","slug":"a-la-carcel-ciudadano-extranjero-que-es-senalado-de-asesinar-a-un-hombre-en-itsmina-choco","status":"publish","type":"post","link":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-ciudadano-extranjero-que-es-senalado-de-asesinar-a-un-hombre-en-itsmina-choco\/","title":{"rendered":"A la c\u00e1rcel ciudadano extranjero que es se\u00f1alado de asesinar a un hombre en Itsmina, Choc\u00f3"},"content":{"rendered":"<p>Funcionarios del Cuerpo T\u00e9cnico de Investigaci\u00f3n (CTI) de la Fiscal\u00eda en coordinaci\u00f3n con la Polic\u00eda Nacional capturaron a Gelcinei Soares de Oliveira, alias Yeo o Brasil, para que responda por el asesinato de Darwin Rene Mosquera Lozano.<\/p>\n<p>La Fiscal\u00eda le imput\u00f3 los delitos de homicidio, tentativa de homicidio y fabricaci\u00f3n, porte y tr\u00e1fico de armas de fuego. Y aunque no se allan\u00f3 a los cargos, una juez de control de garant\u00edas lo cobij\u00f3 con medida de aseguramiento intramuros.<\/p>\n<figure id=\"attachment_281632\" aria-describedby=\"caption-attachment-281632\" style=\"width: 383px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-281632\" src=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/WhatsApp-Image-2023-10-17-at-11.28.28-AM-300x174.jpeg\" alt=\"En la foto aparece Gelcinei Soares de Oliveira, alias Yeo o Brasil, a sus lados est\u00e1n dos funcionarios, uno del CTI de la Fiscal\u00eda y otro de la Polic\u00eda Nacional, atr\u00e1s el pend\u00f3n con con logos de la Fiscal\u00eda.\" width=\"383\" height=\"222\" srcset=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/WhatsApp-Image-2023-10-17-at-11.28.28-AM-300x174.jpeg 300w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/WhatsApp-Image-2023-10-17-at-11.28.28-AM-1024x593.jpeg 1024w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/WhatsApp-Image-2023-10-17-at-11.28.28-AM-768x445.jpeg 768w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/WhatsApp-Image-2023-10-17-at-11.28.28-AM-696x403.jpeg 696w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/WhatsApp-Image-2023-10-17-at-11.28.28-AM-1068x618.jpeg 1068w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/WhatsApp-Image-2023-10-17-at-11.28.28-AM-726x420.jpeg 726w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/WhatsApp-Image-2023-10-17-at-11.28.28-AM.jpeg 1263w\" sizes=\"auto, (max-width: 383px) 100vw, 383px\" \/><figcaption id=\"caption-attachment-281632\" class=\"wp-caption-text\">Gelcinei Soares de Oliveira, alias Yeo o Brasil, fue capturado para que responda por el asesinato de Darwin Rene Mosquera Lozano el pasado 6 de octubre en Itsmina (Choc\u00f3).<\/figcaption><\/figure>\n<p>De acuerdo con el material probatorio, el detenido, el pasado viernes 6 de octubre, al parecer, cit\u00f3 a Mosquera Lozano, a quien le deb\u00eda 130 millones de pesos, presuntamente para pagarle la deuda.<\/p>\n<p>D\u00edas atr\u00e1s, de acuerdo con los testimonios, Soares de Oliveira le pidi\u00f3 a Mosquera Lozano que empe\u00f1ara su camioneta y le prestara el dinero, as\u00ed que presuntamente, lo hicieron. De ese monto el procesado se habr\u00eda quedado con 70 millones de pesos, pero le asegur\u00f3 que el pagar\u00eda 130 millones de pesos, de intereses y la deuda y que en un mes se lo devolver\u00eda.<\/p>\n<p>Pas\u00f3 el tiempo, y al parecer, no le pag\u00f3, pero le dijo que har\u00eda un negocio con otras personas para librar la camioneta, de esta manera ese d\u00eda lo cit\u00f3 a la entrada del corregimiento de San Antonio de Itsmina a las 7:00 p.m., por lo que al cerrar el negocio que ten\u00eda le dijo a su esposa que lo acompa\u00f1ara.<\/p>\n<p>Presuntamente llegaron y el indiciado ya estaba en el sitio, pero en la declaraci\u00f3n la mujer asegur\u00f3 que el procesado estuvo muy distante de ellos, situaci\u00f3n que no le pareci\u00f3 normal. Agreg\u00f3 que de un momento a otro comenzaron a dispararles. Ella result\u00f3 herida con cinco tiros y su esposo fue trasladado a un centro asistencial de Quibd\u00f3 (Choc\u00f3), pero muri\u00f3 en el camino.<\/p>\n<p>Soares de Oliveira, fue capturado en el barrio Cubis de Itsmina.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>La Fiscal\u00eda habla con resultados.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>JLH\/DSCH\/FAGH<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><i>La informaci\u00f3n contenida en este bolet\u00edn de prensa corresponde a la narraci\u00f3n de los hechos noticiosos objetivos, suministrados por los funcionarios encargados de adelantar las investigaciones penales al interior de la Fiscal\u00eda General de la Naci\u00f3n. Para el momento de la divulgaci\u00f3n de este comunicado, la situaci\u00f3n jur\u00eddica de la(s) persona(s) relacionada(s) se encuentra pendiente de resolver por la autoridad judicial competente, siempre bajo los preceptos de la presunci\u00f3n de inocencia, consagrados en el art\u00edculo 29 de la Constituci\u00f3n Pol\u00edtica y el art\u00edculo 7\u00ba de la Ley 906 de 2004.\u00a0<\/i><\/p>\n\n<div class=\"twitter-share\"><a href=\"https:\/\/twitter.com\/intent\/tweet?via=fiscaliacol\" class=\"twitter-share-button\">Tweet<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Funcionarios del Cuerpo T\u00e9cnico de Investigaci\u00f3n (CTI) de la Fiscal\u00eda en coordinaci\u00f3n con la Polic\u00eda Nacional capturaron a Gelcinei Soares de Oliveira, alias Yeo o Brasil, para que responda por [&hellip;]<\/p>\n","protected":false},"author":179,"featured_media":282066,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[1,2336,303,24099],"tags":[35912,35917,35916,28027,35913,24185,1047,35911,409,558,35915,25613,35914],"class_list":["post-281631","post","type-post","status-publish","format-video","has-post-thumbnail","category-noticias","category-seccional-quibdo","category-seccionales","category-seguridad-territorial","tag-alias-yeo-o-brasil","tag-barrio-cubis-de-itsmina","tag-corregimiento-de-san-antonio-de-itsmina","tag-cuerpo-tecnico-de-investigacion-cti-de-la-fiscalia","tag-darwin-rene-mosquera-lozano","tag-fiscal-barbosa","tag-fiscalia-general-de-la-nacion","tag-gelcinei-soares-de-oliveira","tag-homicidio","tag-policia-nacional","tag-porte-y-trafico-de-armas-de-fuego","tag-quibdo-choco","tag-tentativa-de-homicidio-y-fabricacion","post_format-post-format-video"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fiscal\u00eda General de la Naci\u00f3n<\/title>\n<meta name=\"description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-ciudadano-extranjero-que-es-senalado-de-asesinar-a-un-hombre-en-itsmina-choco\/\" \/>\n<meta property=\"og:site_name\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FiscaliaCol\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-17T16:46:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-23T20:23:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/maxresdefault-1230.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lesly Katherine Segura Camargo.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:site\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lesly Katherine Segura Camargo.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-ciudadano-extranjero-que-es-senalado-de-asesinar-a-un-hombre-en-itsmina-choco\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-ciudadano-extranjero-que-es-senalado-de-asesinar-a-un-hombre-en-itsmina-choco\/\"},\"author\":{\"name\":\"Lesly Katherine Segura Camargo.\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/6be81acb78add0abcbda2c598c1d53e1\"},\"headline\":\"A la c\u00e1rcel ciudadano extranjero que es se\u00f1alado de asesinar a un hombre en Itsmina, Choc\u00f3\",\"datePublished\":\"2023-10-17T16:46:54+00:00\",\"dateModified\":\"2023-10-23T20:23:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-ciudadano-extranjero-que-es-senalado-de-asesinar-a-un-hombre-en-itsmina-choco\/\"},\"wordCount\":501,\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-ciudadano-extranjero-que-es-senalado-de-asesinar-a-un-hombre-en-itsmina-choco\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/maxresdefault-1230.jpg\",\"keywords\":[\"alias Yeo o Brasil\",\"barrio Cubis de Itsmina.\",\"corregimiento de San Antonio de Itsmina\",\"Cuerpo T\u00e9cnico de Investigaci\u00f3n (CTI) de la Fiscal\u00eda\",\"Darwin Rene Mosquera Lozano\",\"Fiscal Barbosa\",\"Fiscal\u00eda General de la Naci\u00f3n\",\"Gelcinei Soares de Oliveira\",\"Homicidio\",\"Polic\u00eda Nacional\",\"porte y tr\u00e1fico de armas de fuego\",\"QUIBD\u00d3-CHOC\u00d3\",\"tentativa de homicidio y fabricaci\u00f3n\"],\"articleSection\":[\"Noticias\",\"Seccional Quibd\u00f3\",\"Seccionales\",\"Seguridad territorial\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-ciudadano-extranjero-que-es-senalado-de-asesinar-a-un-hombre-en-itsmina-choco\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-ciudadano-extranjero-que-es-senalado-de-asesinar-a-un-hombre-en-itsmina-choco\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-ciudadano-extranjero-que-es-senalado-de-asesinar-a-un-hombre-en-itsmina-choco\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-ciudadano-extranjero-que-es-senalado-de-asesinar-a-un-hombre-en-itsmina-choco\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/maxresdefault-1230.jpg\",\"datePublished\":\"2023-10-17T16:46:54+00:00\",\"dateModified\":\"2023-10-23T20:23:23+00:00\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-ciudadano-extranjero-que-es-senalado-de-asesinar-a-un-hombre-en-itsmina-choco\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-ciudadano-extranjero-que-es-senalado-de-asesinar-a-un-hombre-en-itsmina-choco\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-ciudadano-extranjero-que-es-senalado-de-asesinar-a-un-hombre-en-itsmina-choco\/#primaryimage\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/maxresdefault-1230.jpg\",\"contentUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/maxresdefault-1230.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-ciudadano-extranjero-que-es-senalado-de-asesinar-a-un-hombre-en-itsmina-choco\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A la c\u00e1rcel ciudadano extranjero que es se\u00f1alado de asesinar a un hombre en Itsmina, Choc\u00f3\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"contentUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"width\":300,\"height\":90,\"caption\":\"Fiscal\u00eda General de la Naci\u00f3n\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/FiscaliaCol\",\"https:\/\/x.com\/FiscaliaCol\",\"https:\/\/www.instagram.com\/fiscaliacol\",\"https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/\",\"https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/6be81acb78add0abcbda2c598c1d53e1\",\"name\":\"Lesly Katherine Segura Camargo.\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1892091c53ef3b9c2fcb37ca6066e439?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1892091c53ef3b9c2fcb37ca6066e439?s=96&d=mm&r=g\",\"caption\":\"Lesly Katherine Segura Camargo.\"},\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/author\/lesly-segura\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Fiscal\u00eda General de la Naci\u00f3n","og_description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","og_url":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-ciudadano-extranjero-que-es-senalado-de-asesinar-a-un-hombre-en-itsmina-choco\/","og_site_name":"Fiscal\u00eda General de la Naci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/FiscaliaCol","article_published_time":"2023-10-17T16:46:54+00:00","article_modified_time":"2023-10-23T20:23:23+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/maxresdefault-1230.jpg","type":"image\/jpeg"}],"author":"Lesly Katherine Segura Camargo.","twitter_card":"summary_large_image","twitter_creator":"@FiscaliaCol","twitter_site":"@FiscaliaCol","twitter_misc":{"Escrito por":"Lesly Katherine Segura Camargo.","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-ciudadano-extranjero-que-es-senalado-de-asesinar-a-un-hombre-en-itsmina-choco\/#article","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-ciudadano-extranjero-que-es-senalado-de-asesinar-a-un-hombre-en-itsmina-choco\/"},"author":{"name":"Lesly Katherine Segura Camargo.","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/6be81acb78add0abcbda2c598c1d53e1"},"headline":"A la c\u00e1rcel ciudadano extranjero que es se\u00f1alado de asesinar a un hombre en Itsmina, Choc\u00f3","datePublished":"2023-10-17T16:46:54+00:00","dateModified":"2023-10-23T20:23:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-ciudadano-extranjero-que-es-senalado-de-asesinar-a-un-hombre-en-itsmina-choco\/"},"wordCount":501,"publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-ciudadano-extranjero-que-es-senalado-de-asesinar-a-un-hombre-en-itsmina-choco\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/maxresdefault-1230.jpg","keywords":["alias Yeo o Brasil","barrio Cubis de Itsmina.","corregimiento de San Antonio de Itsmina","Cuerpo T\u00e9cnico de Investigaci\u00f3n (CTI) de la Fiscal\u00eda","Darwin Rene Mosquera Lozano","Fiscal Barbosa","Fiscal\u00eda General de la Naci\u00f3n","Gelcinei Soares de Oliveira","Homicidio","Polic\u00eda Nacional","porte y tr\u00e1fico de armas de fuego","QUIBD\u00d3-CHOC\u00d3","tentativa de homicidio y fabricaci\u00f3n"],"articleSection":["Noticias","Seccional Quibd\u00f3","Seccionales","Seguridad territorial"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-ciudadano-extranjero-que-es-senalado-de-asesinar-a-un-hombre-en-itsmina-choco\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-ciudadano-extranjero-que-es-senalado-de-asesinar-a-un-hombre-en-itsmina-choco\/","name":"Fiscal\u00eda General de la Naci\u00f3n","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-ciudadano-extranjero-que-es-senalado-de-asesinar-a-un-hombre-en-itsmina-choco\/#primaryimage"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-ciudadano-extranjero-que-es-senalado-de-asesinar-a-un-hombre-en-itsmina-choco\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/maxresdefault-1230.jpg","datePublished":"2023-10-17T16:46:54+00:00","dateModified":"2023-10-23T20:23:23+00:00","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","breadcrumb":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-ciudadano-extranjero-que-es-senalado-de-asesinar-a-un-hombre-en-itsmina-choco\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-ciudadano-extranjero-que-es-senalado-de-asesinar-a-un-hombre-en-itsmina-choco\/"]}]},{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-ciudadano-extranjero-que-es-senalado-de-asesinar-a-un-hombre-en-itsmina-choco\/#primaryimage","url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/maxresdefault-1230.jpg","contentUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/maxresdefault-1230.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-ciudadano-extranjero-que-es-senalado-de-asesinar-a-un-hombre-en-itsmina-choco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fiscalia.gov.co\/colombia\/"},{"@type":"ListItem","position":2,"name":"A la c\u00e1rcel ciudadano extranjero que es se\u00f1alado de asesinar a un hombre en Itsmina, Choc\u00f3"}]},{"@type":"WebSite","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","name":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization","name":"Fiscal\u00eda General de la Naci\u00f3n","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","contentUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","width":300,"height":90,"caption":"Fiscal\u00eda General de la Naci\u00f3n"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FiscaliaCol","https:\/\/x.com\/FiscaliaCol","https:\/\/www.instagram.com\/fiscaliacol","https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/","https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh"]},{"@type":"Person","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/6be81acb78add0abcbda2c598c1d53e1","name":"Lesly Katherine Segura Camargo.","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1892091c53ef3b9c2fcb37ca6066e439?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1892091c53ef3b9c2fcb37ca6066e439?s=96&d=mm&r=g","caption":"Lesly Katherine Segura Camargo."},"url":"https:\/\/www.fiscalia.gov.co\/colombia\/author\/lesly-segura\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/281631","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/users\/179"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/comments?post=281631"}],"version-history":[{"count":2,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/281631\/revisions"}],"predecessor-version":[{"id":282068,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/281631\/revisions\/282068"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/media\/282066"}],"wp:attachment":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/media?parent=281631"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/categories?post=281631"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/tags?post=281631"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}