{"id":277484,"date":"2023-08-25T08:29:16","date_gmt":"2023-08-25T13:29:16","guid":{"rendered":"https:\/\/www.fiscalia.gov.co\/colombia\/?p=277484"},"modified":"2023-08-25T08:36:03","modified_gmt":"2023-08-25T13:36:03","slug":"carcel-para-presunto-integrante-de-una-red-delictiva-que-estaria-involucrada-en-el-hurto-y-posterior-asesinato-de-la-gerente-de-una-reconocida-empresa-de-estetica","status":"publish","type":"post","link":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/carcel-para-presunto-integrante-de-una-red-delictiva-que-estaria-involucrada-en-el-hurto-y-posterior-asesinato-de-la-gerente-de-una-reconocida-empresa-de-estetica\/","title":{"rendered":"C\u00e1rcel para presunto integrante de una red delictiva que estar\u00eda involucrada en el hurto y posterior asesinato de la gerente de una reconocida empresa de est\u00e9tica"},"content":{"rendered":"<p><strong><em>El investigado habr\u00eda participado en varios asaltos ocurridos en ciudades de la Costa Atl\u00e1ntica.<\/em><\/strong><\/p>\n<figure id=\"attachment_277485\" aria-describedby=\"caption-attachment-277485\" style=\"width: 696px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-277485\" src=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/WhatsApp-Image-2023-08-24-at-8.03.14-PM-1-1024x693.jpeg\" alt=\"El procesado se encuentras custodiado por dos uniformados de la Polic\u00edas Nacional, quienes tienen chaquetas verdes. \" width=\"696\" height=\"471\" srcset=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/WhatsApp-Image-2023-08-24-at-8.03.14-PM-1-1024x693.jpeg 1024w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/WhatsApp-Image-2023-08-24-at-8.03.14-PM-1-300x203.jpeg 300w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/WhatsApp-Image-2023-08-24-at-8.03.14-PM-1-768x520.jpeg 768w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/WhatsApp-Image-2023-08-24-at-8.03.14-PM-1-1536x1040.jpeg 1536w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/WhatsApp-Image-2023-08-24-at-8.03.14-PM-1-696x471.jpeg 696w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/WhatsApp-Image-2023-08-24-at-8.03.14-PM-1-1068x723.jpeg 1068w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/WhatsApp-Image-2023-08-24-at-8.03.14-PM-1-620x420.jpeg 620w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/WhatsApp-Image-2023-08-24-at-8.03.14-PM-1.jpeg 1600w\" sizes=\"auto, (max-width: 696px) 100vw, 696px\" \/><figcaption id=\"caption-attachment-277485\" class=\"wp-caption-text\">El imputado fue capturado en Momp\u00f3s, Bol\u00edvar.<\/figcaption><\/figure>\n<p>Luego de valorar los elementos de prueba aportados por la Fiscal\u00eda General de la Naci\u00f3n, un juez de control de garant\u00edas impuso medida de aseguramiento en centro carcelario a Germ\u00e1n Andr\u00e9s Espa\u00f1a \u00c1lvarez, presunto integrante de una red delincuencial responsable de m\u00faltiples hurtos ocurridos en Bol\u00edvar, C\u00f3rdoba, Sucre, Atl\u00e1ntico y Magdalena.<\/p>\n<p>A este grupo ilegal se le atribuye el asalto y posterior asesinato de Mar\u00eda Mercedes Garc\u00eda Rodr\u00edguez, gerente y propietaria de una reconocida empresa de est\u00e9tica facial y corporal, en hechos ocurridos el 28 de diciembre de 2022, en Tol\u00fa (Sucre).<\/p>\n<p>De acuerdo con la investigaci\u00f3n liderada por una fiscal de la Estructura de Apoyo (EDA) de la Seccional Sucre, Espa\u00f1a \u00c1lvarez estar\u00eda involucrado en dos robos sucedidos en febrero y agosto del a\u00f1o en curso, en Lorica (C\u00f3rdoba) y Mompox (Bol\u00edvar),respectivamente.<\/p>\n<p>En el evento m\u00e1s reciente habr\u00eda amordazado a una de las v\u00edctimas y arrebatado m\u00e1s de 150 millones de pesos.<\/p>\n<p>Adicionalmente, se verifica la posible participaci\u00f3n de este hombre en un homicidio registrado en Cartagena (Bol\u00edvar), en febrero pasado.<\/p>\n<p>La Fiscal\u00eda imput\u00f3 a Germ\u00e1n Andr\u00e9s Espa\u00f1a \u00c1lvarez los delitos de hurto calificado y concierto para delinquir. Los cargos no fueron aceptados.<\/p>\n<p>El procesado, de 33 a\u00f1os, fue capturado en una acci\u00f3n conjunta de la Fiscal\u00eda y la SIJIN de la Polic\u00eda Nacional, en Mompox.<\/p>\n<p>En los registros oficiales presenta varias anotaciones por fabricaci\u00f3n, tr\u00e1fico o porte de armas de fuego; homicidio, receptaci\u00f3n y violencia intrafamiliar.<\/p>\n<p><strong>La Fiscal\u00eda habla con resultados.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>VHGB\/MASR\/FSJ\/DSS\/JARG\/<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<div class=\"td-post-content tagdiv-type\">\n<div class=\"td-post-content tagdiv-type\">\n<p><i>La informaci\u00f3n contenida en este bolet\u00edn de prensa corresponde a la narraci\u00f3n de los hechos noticiosos objetivos, suministrados por los funcionarios encargados de adelantar las investigaciones penales al interior de la Fiscal\u00eda General de la Naci\u00f3n. Para el momento de la divulgaci\u00f3n de este comunicado, la situaci\u00f3n jur\u00eddica de la(s) persona(s) relacionada(s) se encuentra pendiente de resolver por la autoridad judicial competente, siempre bajo los preceptos de la presunci\u00f3n de inocencia, consagrados en el art\u00edculo 29 de la Constituci\u00f3n Pol\u00edtica y el art\u00edculo 7\u00ba de la Ley 906 de 2004.<\/i><\/p>\n<\/div>\n<\/div>\n<footer>\n<div class=\"td-post-source-tags\"><\/div>\n<div class=\"td-post-sharing-bottom\"><\/div>\n<\/footer>\n<p>&nbsp;<\/p>\n\n<div class=\"twitter-share\"><a href=\"https:\/\/twitter.com\/intent\/tweet?via=fiscaliacol\" class=\"twitter-share-button\">Tweet<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El investigado habr\u00eda participado en varios asaltos ocurridos en ciudades de la Costa Atl\u00e1ntica. Luego de valorar los elementos de prueba aportados por la Fiscal\u00eda General de la Naci\u00f3n, un [&hellip;]<\/p>\n","protected":false},"author":177,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[1,340,12641,303,24099],"tags":[35426,24185,1047,409,23960,32324,29313],"class_list":["post-277484","post","type-post","status-publish","format-standard","category-noticias","category-seccional-sincelejo","category-seccional-sucre","category-seccionales","category-seguridad-territorial","tag-clinica-estetica","tag-fiscal-barbosa","tag-fiscalia-general-de-la-nacion","tag-homicidio","tag-hurto","tag-red-delictiva","tag-sincelejo-sucre"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fiscal\u00eda General de la Naci\u00f3n<\/title>\n<meta name=\"description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/carcel-para-presunto-integrante-de-una-red-delictiva-que-estaria-involucrada-en-el-hurto-y-posterior-asesinato-de-la-gerente-de-una-reconocida-empresa-de-estetica\/\" \/>\n<meta property=\"og:site_name\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FiscaliaCol\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-25T13:29:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-25T13:36:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/WhatsApp-Image-2023-08-24-at-8.03.14-PM-1-1024x693.jpeg\" \/>\n<meta name=\"author\" content=\"Jordan Leandro Oviedo Anzola\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:site\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jordan Leandro Oviedo Anzola\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/carcel-para-presunto-integrante-de-una-red-delictiva-que-estaria-involucrada-en-el-hurto-y-posterior-asesinato-de-la-gerente-de-una-reconocida-empresa-de-estetica\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/carcel-para-presunto-integrante-de-una-red-delictiva-que-estaria-involucrada-en-el-hurto-y-posterior-asesinato-de-la-gerente-de-una-reconocida-empresa-de-estetica\/\"},\"author\":{\"name\":\"Jordan Leandro Oviedo Anzola\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf84402cf293a5393e9c70b111020b24\"},\"headline\":\"C\u00e1rcel para presunto integrante de una red delictiva que estar\u00eda involucrada en el hurto y posterior asesinato de la gerente de una reconocida empresa de est\u00e9tica\",\"datePublished\":\"2023-08-25T13:29:16+00:00\",\"dateModified\":\"2023-08-25T13:36:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/carcel-para-presunto-integrante-de-una-red-delictiva-que-estaria-involucrada-en-el-hurto-y-posterior-asesinato-de-la-gerente-de-una-reconocida-empresa-de-estetica\/\"},\"wordCount\":458,\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/carcel-para-presunto-integrante-de-una-red-delictiva-que-estaria-involucrada-en-el-hurto-y-posterior-asesinato-de-la-gerente-de-una-reconocida-empresa-de-estetica\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/WhatsApp-Image-2023-08-24-at-8.03.14-PM-1-1024x693.jpeg\",\"keywords\":[\"clinica estetica\",\"Fiscal Barbosa\",\"Fiscal\u00eda General de la Naci\u00f3n\",\"Homicidio\",\"Hurto\",\"red delictiva\",\"Sincelejo (Sucre)\"],\"articleSection\":[\"Noticias\",\"Seccional Sincelejo\",\"Seccional Sucre\",\"Seccionales\",\"Seguridad territorial\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/carcel-para-presunto-integrante-de-una-red-delictiva-que-estaria-involucrada-en-el-hurto-y-posterior-asesinato-de-la-gerente-de-una-reconocida-empresa-de-estetica\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/carcel-para-presunto-integrante-de-una-red-delictiva-que-estaria-involucrada-en-el-hurto-y-posterior-asesinato-de-la-gerente-de-una-reconocida-empresa-de-estetica\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/carcel-para-presunto-integrante-de-una-red-delictiva-que-estaria-involucrada-en-el-hurto-y-posterior-asesinato-de-la-gerente-de-una-reconocida-empresa-de-estetica\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/carcel-para-presunto-integrante-de-una-red-delictiva-que-estaria-involucrada-en-el-hurto-y-posterior-asesinato-de-la-gerente-de-una-reconocida-empresa-de-estetica\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/WhatsApp-Image-2023-08-24-at-8.03.14-PM-1-1024x693.jpeg\",\"datePublished\":\"2023-08-25T13:29:16+00:00\",\"dateModified\":\"2023-08-25T13:36:03+00:00\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/carcel-para-presunto-integrante-de-una-red-delictiva-que-estaria-involucrada-en-el-hurto-y-posterior-asesinato-de-la-gerente-de-una-reconocida-empresa-de-estetica\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/carcel-para-presunto-integrante-de-una-red-delictiva-que-estaria-involucrada-en-el-hurto-y-posterior-asesinato-de-la-gerente-de-una-reconocida-empresa-de-estetica\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/carcel-para-presunto-integrante-de-una-red-delictiva-que-estaria-involucrada-en-el-hurto-y-posterior-asesinato-de-la-gerente-de-una-reconocida-empresa-de-estetica\/#primaryimage\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/WhatsApp-Image-2023-08-24-at-8.03.14-PM-1-1024x693.jpeg\",\"contentUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/WhatsApp-Image-2023-08-24-at-8.03.14-PM-1-1024x693.jpeg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/carcel-para-presunto-integrante-de-una-red-delictiva-que-estaria-involucrada-en-el-hurto-y-posterior-asesinato-de-la-gerente-de-una-reconocida-empresa-de-estetica\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"C\u00e1rcel para presunto integrante de una red delictiva que estar\u00eda involucrada en el hurto y posterior asesinato de la gerente de una reconocida empresa de est\u00e9tica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"contentUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"width\":300,\"height\":90,\"caption\":\"Fiscal\u00eda General de la Naci\u00f3n\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/FiscaliaCol\",\"https:\/\/x.com\/FiscaliaCol\",\"https:\/\/www.instagram.com\/fiscaliacol\",\"https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/\",\"https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf84402cf293a5393e9c70b111020b24\",\"name\":\"Jordan Leandro Oviedo Anzola\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/dabba4346fa9b9207d96adafa8f92721?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/dabba4346fa9b9207d96adafa8f92721?s=96&d=mm&r=g\",\"caption\":\"Jordan Leandro Oviedo Anzola\"},\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/author\/joviedo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Fiscal\u00eda General de la Naci\u00f3n","og_description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","og_url":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/carcel-para-presunto-integrante-de-una-red-delictiva-que-estaria-involucrada-en-el-hurto-y-posterior-asesinato-de-la-gerente-de-una-reconocida-empresa-de-estetica\/","og_site_name":"Fiscal\u00eda General de la Naci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/FiscaliaCol","article_published_time":"2023-08-25T13:29:16+00:00","article_modified_time":"2023-08-25T13:36:03+00:00","og_image":[{"url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/WhatsApp-Image-2023-08-24-at-8.03.14-PM-1-1024x693.jpeg","type":"","width":"","height":""}],"author":"Jordan Leandro Oviedo Anzola","twitter_card":"summary_large_image","twitter_creator":"@FiscaliaCol","twitter_site":"@FiscaliaCol","twitter_misc":{"Escrito por":"Jordan Leandro Oviedo Anzola","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/carcel-para-presunto-integrante-de-una-red-delictiva-que-estaria-involucrada-en-el-hurto-y-posterior-asesinato-de-la-gerente-de-una-reconocida-empresa-de-estetica\/#article","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/carcel-para-presunto-integrante-de-una-red-delictiva-que-estaria-involucrada-en-el-hurto-y-posterior-asesinato-de-la-gerente-de-una-reconocida-empresa-de-estetica\/"},"author":{"name":"Jordan Leandro Oviedo Anzola","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf84402cf293a5393e9c70b111020b24"},"headline":"C\u00e1rcel para presunto integrante de una red delictiva que estar\u00eda involucrada en el hurto y posterior asesinato de la gerente de una reconocida empresa de est\u00e9tica","datePublished":"2023-08-25T13:29:16+00:00","dateModified":"2023-08-25T13:36:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/carcel-para-presunto-integrante-de-una-red-delictiva-que-estaria-involucrada-en-el-hurto-y-posterior-asesinato-de-la-gerente-de-una-reconocida-empresa-de-estetica\/"},"wordCount":458,"publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/carcel-para-presunto-integrante-de-una-red-delictiva-que-estaria-involucrada-en-el-hurto-y-posterior-asesinato-de-la-gerente-de-una-reconocida-empresa-de-estetica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/WhatsApp-Image-2023-08-24-at-8.03.14-PM-1-1024x693.jpeg","keywords":["clinica estetica","Fiscal Barbosa","Fiscal\u00eda General de la Naci\u00f3n","Homicidio","Hurto","red delictiva","Sincelejo (Sucre)"],"articleSection":["Noticias","Seccional Sincelejo","Seccional Sucre","Seccionales","Seguridad territorial"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/carcel-para-presunto-integrante-de-una-red-delictiva-que-estaria-involucrada-en-el-hurto-y-posterior-asesinato-de-la-gerente-de-una-reconocida-empresa-de-estetica\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/carcel-para-presunto-integrante-de-una-red-delictiva-que-estaria-involucrada-en-el-hurto-y-posterior-asesinato-de-la-gerente-de-una-reconocida-empresa-de-estetica\/","name":"Fiscal\u00eda General de la Naci\u00f3n","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/carcel-para-presunto-integrante-de-una-red-delictiva-que-estaria-involucrada-en-el-hurto-y-posterior-asesinato-de-la-gerente-de-una-reconocida-empresa-de-estetica\/#primaryimage"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/carcel-para-presunto-integrante-de-una-red-delictiva-que-estaria-involucrada-en-el-hurto-y-posterior-asesinato-de-la-gerente-de-una-reconocida-empresa-de-estetica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/WhatsApp-Image-2023-08-24-at-8.03.14-PM-1-1024x693.jpeg","datePublished":"2023-08-25T13:29:16+00:00","dateModified":"2023-08-25T13:36:03+00:00","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","breadcrumb":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/carcel-para-presunto-integrante-de-una-red-delictiva-que-estaria-involucrada-en-el-hurto-y-posterior-asesinato-de-la-gerente-de-una-reconocida-empresa-de-estetica\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/carcel-para-presunto-integrante-de-una-red-delictiva-que-estaria-involucrada-en-el-hurto-y-posterior-asesinato-de-la-gerente-de-una-reconocida-empresa-de-estetica\/"]}]},{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/carcel-para-presunto-integrante-de-una-red-delictiva-que-estaria-involucrada-en-el-hurto-y-posterior-asesinato-de-la-gerente-de-una-reconocida-empresa-de-estetica\/#primaryimage","url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/WhatsApp-Image-2023-08-24-at-8.03.14-PM-1-1024x693.jpeg","contentUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/WhatsApp-Image-2023-08-24-at-8.03.14-PM-1-1024x693.jpeg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/carcel-para-presunto-integrante-de-una-red-delictiva-que-estaria-involucrada-en-el-hurto-y-posterior-asesinato-de-la-gerente-de-una-reconocida-empresa-de-estetica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fiscalia.gov.co\/colombia\/"},{"@type":"ListItem","position":2,"name":"C\u00e1rcel para presunto integrante de una red delictiva que estar\u00eda involucrada en el hurto y posterior asesinato de la gerente de una reconocida empresa de est\u00e9tica"}]},{"@type":"WebSite","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","name":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization","name":"Fiscal\u00eda General de la Naci\u00f3n","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","contentUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","width":300,"height":90,"caption":"Fiscal\u00eda General de la Naci\u00f3n"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FiscaliaCol","https:\/\/x.com\/FiscaliaCol","https:\/\/www.instagram.com\/fiscaliacol","https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/","https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh"]},{"@type":"Person","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf84402cf293a5393e9c70b111020b24","name":"Jordan Leandro Oviedo Anzola","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/dabba4346fa9b9207d96adafa8f92721?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dabba4346fa9b9207d96adafa8f92721?s=96&d=mm&r=g","caption":"Jordan Leandro Oviedo Anzola"},"url":"https:\/\/www.fiscalia.gov.co\/colombia\/author\/joviedo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/277484","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/users\/177"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/comments?post=277484"}],"version-history":[{"count":4,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/277484\/revisions"}],"predecessor-version":[{"id":277491,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/277484\/revisions\/277491"}],"wp:attachment":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/media?parent=277484"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/categories?post=277484"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/tags?post=277484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}