{"id":277341,"date":"2023-08-23T15:38:29","date_gmt":"2023-08-23T20:38:29","guid":{"rendered":"https:\/\/www.fiscalia.gov.co\/colombia\/?p=277341"},"modified":"2023-08-23T15:38:29","modified_gmt":"2023-08-23T20:38:29","slug":"fiscalia-obtiene-medidas-cautelares-sobre-derechos-fiduciarios-de-un-bien-presuntamente-de-propiedad-de-memo-fantasma-y-del-bloque-central-bolivar-de-las-auc","status":"publish","type":"post","link":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-obtiene-medidas-cautelares-sobre-derechos-fiduciarios-de-un-bien-presuntamente-de-propiedad-de-memo-fantasma-y-del-bloque-central-bolivar-de-las-auc\/","title":{"rendered":"Fiscal\u00eda obtiene medidas cautelares sobre derechos fiduciarios de un bien, presuntamente de propiedad de \u2018Memo Fantasma\u2019 y del Bloque Central Bol\u00edvar de las AUC"},"content":{"rendered":"<h4><strong><em>Se trata de un piso de 3.233 metros cuadrados, ubicado en el norte de Bogot\u00e1, sobre el cual se impusieron medidas cautelares de <\/em><em>embargo, secuestro y suspensi\u00f3n del poder dispositivo.<\/em><\/strong><\/h4>\n<p>Por solicitud de la Fiscal\u00eda General de la Naci\u00f3n, la Sala de Control de Garant\u00edas de Justicia y Paz del Tribunal Superior de Bucaramanga (Santander), impuso medidas cautelares sobre los derechos fiduciarios de un bien que ser\u00eda propiedad de Guillermo Le\u00f3n Acevedo, alias Memo Fantasma, y del Bloque Central Bol\u00edvar (BCB) de las extintas autodefensas.<\/p>\n<p>Se trata de los derechos fiduciarios sobre el piso 28 de una torre de oficinas ubicada en la carrera 7 con calle 100 en el norte de Bogot\u00e1. La extensi\u00f3n del predio alcanzar\u00eda los 3.233 metros cuadrados y su valor preliminar superar\u00eda los 38.805 millones de pesos.<\/p>\n<p>Las labores investigativas adelantadas por el Grupo de Persecuci\u00f3n de Bienes de la Direcci\u00f3n de Justicia Transicional evidenciaron que los derechos fiduciarios est\u00e1n a nombre de una empresa creada por Guillermo Le\u00f3n Acevedo, alias Memo Fantasma.<\/p>\n<p>Igualmente, se demostr\u00f3 que la constituci\u00f3n de derechos fiduciarios en proyectos inmobiliarios por parte de Guillermo Le\u00f3n Acevedo corresponder\u00eda a una estrategia de ocultamiento del patrimonio il\u00edcito. Se han afectado con medidas cautelares de embargo, secuestro y suspensi\u00f3n del poder dispositivo derechos fiduciarios sobre dos proyectos inmobiliarios avaluados en m\u00e1s de 59.884 millones de pesos.<\/p>\n<p>Estos ser\u00e1n puestos a disposici\u00f3n del Fondo para la Reparaci\u00f3n a las V\u00edctimas para su administraci\u00f3n.<\/p>\n<p><strong>Resultados 2020 &#8211; 2023<\/strong><\/p>\n<p>En tres a\u00f1os y medio, se han decretado por parte de la Magistratura medidas cautelares de embargo, secuestro y suspensi\u00f3n del poder dispositivo, sobre 115 bienes relacionados con Guillermo Le\u00f3n Acevedo, alias Memo Fantasma, avaluados en m\u00e1s de 173.000 millones de pesos.<\/p>\n<p>En el mismo periodo, la Direcci\u00f3n de Justicia Transicional ha puesto a disposici\u00f3n del Fondo para la Reparaci\u00f3n a las V\u00edctimas 103 bienes relacionados con Guillermo Le\u00f3n Acevedo, alias Memo Fantasma. El valor de estos activos supera los 95.000 millones de pesos.<\/p>\n<p>Esta informaci\u00f3n se publica por razones de inter\u00e9s general.<\/p>\n<p><strong><u>La Fiscal\u00eda habla con resultados.<\/u><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>LMFO\/MAGA\/SSR\/DJT\/MRC\/<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<div class=\"td-post-content tagdiv-type\">\n<div class=\"td-post-content tagdiv-type\">\n<div class=\"td-post-content tagdiv-type\">\n<p><i><span lang=\"ES\">La informaci\u00f3n contenida en este bolet\u00edn de prensa corresponde a la narraci\u00f3n de los hechos noticiosos objetivos, suministrados por los funcionarios encargados de adelantar las investigaciones penales al interior de la Fiscal\u00eda General de la Naci\u00f3n. Para el momento de la divulgaci\u00f3n de este comunicado, la situaci\u00f3n jur\u00eddica de la(s) persona(s) relacionada(s) se encuentra pendiente de resolver por la autoridad judicial competente, siempre bajo los preceptos de la presunci\u00f3n de inocencia, consagrados en el art\u00edculo 29 de la Constituci\u00f3n Pol\u00edtica y el art\u00edculo 7\u00ba de la Ley 906 de 2004.\u00a0<\/span><\/i><\/p>\n<\/div>\n<\/div>\n<\/div>\n\n<div class=\"twitter-share\"><a href=\"https:\/\/twitter.com\/intent\/tweet?via=fiscaliacol\" class=\"twitter-share-button\">Tweet<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Se trata de un piso de 3.233 metros cuadrados, ubicado en el norte de Bogot\u00e1, sobre el cual se impusieron medidas cautelares de embargo, secuestro y suspensi\u00f3n del poder dispositivo. [&hellip;]<\/p>\n","protected":false},"author":177,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[24101,1],"tags":[35409,24185,1047,518,28719],"class_list":["post-277341","post","type-post","status-publish","format-standard","category-justicia-transicional","category-noticias","tag-derechos-fiduciarios","tag-fiscal-barbosa","tag-fiscalia-general-de-la-nacion","tag-justicia-transicional","tag-memo-fantasma"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fiscal\u00eda General de la Naci\u00f3n<\/title>\n<meta name=\"description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-obtiene-medidas-cautelares-sobre-derechos-fiduciarios-de-un-bien-presuntamente-de-propiedad-de-memo-fantasma-y-del-bloque-central-bolivar-de-las-auc\/\" \/>\n<meta property=\"og:site_name\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FiscaliaCol\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-23T20:38:29+00:00\" \/>\n<meta name=\"author\" content=\"Jordan Leandro Oviedo Anzola\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:site\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jordan Leandro Oviedo Anzola\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-obtiene-medidas-cautelares-sobre-derechos-fiduciarios-de-un-bien-presuntamente-de-propiedad-de-memo-fantasma-y-del-bloque-central-bolivar-de-las-auc\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-obtiene-medidas-cautelares-sobre-derechos-fiduciarios-de-un-bien-presuntamente-de-propiedad-de-memo-fantasma-y-del-bloque-central-bolivar-de-las-auc\/\"},\"author\":{\"name\":\"Jordan Leandro Oviedo Anzola\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf84402cf293a5393e9c70b111020b24\"},\"headline\":\"Fiscal\u00eda obtiene medidas cautelares sobre derechos fiduciarios de un bien, presuntamente de propiedad de \u2018Memo Fantasma\u2019 y del Bloque Central Bol\u00edvar de las AUC\",\"datePublished\":\"2023-08-23T20:38:29+00:00\",\"dateModified\":\"2023-08-23T20:38:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-obtiene-medidas-cautelares-sobre-derechos-fiduciarios-de-un-bien-presuntamente-de-propiedad-de-memo-fantasma-y-del-bloque-central-bolivar-de-las-auc\/\"},\"wordCount\":509,\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"keywords\":[\"derechos fiduciarios\",\"Fiscal Barbosa\",\"Fiscal\u00eda General de la Naci\u00f3n\",\"Justicia transicional\",\"Memo Fantasma\"],\"articleSection\":[\"Justicia Transicional\",\"Noticias\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-obtiene-medidas-cautelares-sobre-derechos-fiduciarios-de-un-bien-presuntamente-de-propiedad-de-memo-fantasma-y-del-bloque-central-bolivar-de-las-auc\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-obtiene-medidas-cautelares-sobre-derechos-fiduciarios-de-un-bien-presuntamente-de-propiedad-de-memo-fantasma-y-del-bloque-central-bolivar-de-las-auc\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\"},\"datePublished\":\"2023-08-23T20:38:29+00:00\",\"dateModified\":\"2023-08-23T20:38:29+00:00\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-obtiene-medidas-cautelares-sobre-derechos-fiduciarios-de-un-bien-presuntamente-de-propiedad-de-memo-fantasma-y-del-bloque-central-bolivar-de-las-auc\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-obtiene-medidas-cautelares-sobre-derechos-fiduciarios-de-un-bien-presuntamente-de-propiedad-de-memo-fantasma-y-del-bloque-central-bolivar-de-las-auc\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-obtiene-medidas-cautelares-sobre-derechos-fiduciarios-de-un-bien-presuntamente-de-propiedad-de-memo-fantasma-y-del-bloque-central-bolivar-de-las-auc\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fiscal\u00eda obtiene medidas cautelares sobre derechos fiduciarios de un bien, presuntamente de propiedad de \u2018Memo Fantasma\u2019 y del Bloque Central Bol\u00edvar de las AUC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"contentUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"width\":300,\"height\":90,\"caption\":\"Fiscal\u00eda General de la Naci\u00f3n\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/FiscaliaCol\",\"https:\/\/x.com\/FiscaliaCol\",\"https:\/\/www.instagram.com\/fiscaliacol\",\"https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/\",\"https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf84402cf293a5393e9c70b111020b24\",\"name\":\"Jordan Leandro Oviedo Anzola\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/dabba4346fa9b9207d96adafa8f92721?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/dabba4346fa9b9207d96adafa8f92721?s=96&d=mm&r=g\",\"caption\":\"Jordan Leandro Oviedo Anzola\"},\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/author\/joviedo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Fiscal\u00eda General de la Naci\u00f3n","og_description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","og_url":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-obtiene-medidas-cautelares-sobre-derechos-fiduciarios-de-un-bien-presuntamente-de-propiedad-de-memo-fantasma-y-del-bloque-central-bolivar-de-las-auc\/","og_site_name":"Fiscal\u00eda General de la Naci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/FiscaliaCol","article_published_time":"2023-08-23T20:38:29+00:00","author":"Jordan Leandro Oviedo Anzola","twitter_card":"summary_large_image","twitter_creator":"@FiscaliaCol","twitter_site":"@FiscaliaCol","twitter_misc":{"Escrito por":"Jordan Leandro Oviedo Anzola","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-obtiene-medidas-cautelares-sobre-derechos-fiduciarios-de-un-bien-presuntamente-de-propiedad-de-memo-fantasma-y-del-bloque-central-bolivar-de-las-auc\/#article","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-obtiene-medidas-cautelares-sobre-derechos-fiduciarios-de-un-bien-presuntamente-de-propiedad-de-memo-fantasma-y-del-bloque-central-bolivar-de-las-auc\/"},"author":{"name":"Jordan Leandro Oviedo Anzola","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf84402cf293a5393e9c70b111020b24"},"headline":"Fiscal\u00eda obtiene medidas cautelares sobre derechos fiduciarios de un bien, presuntamente de propiedad de \u2018Memo Fantasma\u2019 y del Bloque Central Bol\u00edvar de las AUC","datePublished":"2023-08-23T20:38:29+00:00","dateModified":"2023-08-23T20:38:29+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-obtiene-medidas-cautelares-sobre-derechos-fiduciarios-de-un-bien-presuntamente-de-propiedad-de-memo-fantasma-y-del-bloque-central-bolivar-de-las-auc\/"},"wordCount":509,"publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"keywords":["derechos fiduciarios","Fiscal Barbosa","Fiscal\u00eda General de la Naci\u00f3n","Justicia transicional","Memo Fantasma"],"articleSection":["Justicia Transicional","Noticias"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-obtiene-medidas-cautelares-sobre-derechos-fiduciarios-de-un-bien-presuntamente-de-propiedad-de-memo-fantasma-y-del-bloque-central-bolivar-de-las-auc\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-obtiene-medidas-cautelares-sobre-derechos-fiduciarios-de-un-bien-presuntamente-de-propiedad-de-memo-fantasma-y-del-bloque-central-bolivar-de-las-auc\/","name":"Fiscal\u00eda General de la Naci\u00f3n","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website"},"datePublished":"2023-08-23T20:38:29+00:00","dateModified":"2023-08-23T20:38:29+00:00","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","breadcrumb":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-obtiene-medidas-cautelares-sobre-derechos-fiduciarios-de-un-bien-presuntamente-de-propiedad-de-memo-fantasma-y-del-bloque-central-bolivar-de-las-auc\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-obtiene-medidas-cautelares-sobre-derechos-fiduciarios-de-un-bien-presuntamente-de-propiedad-de-memo-fantasma-y-del-bloque-central-bolivar-de-las-auc\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-obtiene-medidas-cautelares-sobre-derechos-fiduciarios-de-un-bien-presuntamente-de-propiedad-de-memo-fantasma-y-del-bloque-central-bolivar-de-las-auc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fiscalia.gov.co\/colombia\/"},{"@type":"ListItem","position":2,"name":"Fiscal\u00eda obtiene medidas cautelares sobre derechos fiduciarios de un bien, presuntamente de propiedad de \u2018Memo Fantasma\u2019 y del Bloque Central Bol\u00edvar de las AUC"}]},{"@type":"WebSite","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","name":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization","name":"Fiscal\u00eda General de la Naci\u00f3n","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","contentUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","width":300,"height":90,"caption":"Fiscal\u00eda General de la Naci\u00f3n"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FiscaliaCol","https:\/\/x.com\/FiscaliaCol","https:\/\/www.instagram.com\/fiscaliacol","https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/","https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh"]},{"@type":"Person","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf84402cf293a5393e9c70b111020b24","name":"Jordan Leandro Oviedo Anzola","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/dabba4346fa9b9207d96adafa8f92721?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dabba4346fa9b9207d96adafa8f92721?s=96&d=mm&r=g","caption":"Jordan Leandro Oviedo Anzola"},"url":"https:\/\/www.fiscalia.gov.co\/colombia\/author\/joviedo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/277341","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/users\/177"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/comments?post=277341"}],"version-history":[{"count":1,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/277341\/revisions"}],"predecessor-version":[{"id":277367,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/277341\/revisions\/277367"}],"wp:attachment":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/media?parent=277341"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/categories?post=277341"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/tags?post=277341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}