{"id":277148,"date":"2023-08-18T14:52:16","date_gmt":"2023-08-18T19:52:16","guid":{"rendered":"https:\/\/www.fiscalia.gov.co\/colombia\/?p=277148"},"modified":"2023-08-18T14:52:16","modified_gmt":"2023-08-18T19:52:16","slug":"a-la-carcel-presunto-responsable-de-tentativa-de-feminicidio-contra-su-pareja-sentimental","status":"publish","type":"post","link":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-responsable-de-tentativa-de-feminicidio-contra-su-pareja-sentimental\/","title":{"rendered":"A la c\u00e1rcel presunto responsable de tentativa de feminicidio contra su pareja sentimental"},"content":{"rendered":"<h4><strong><i>El hombre se entreg\u00f3 ante la Fiscal\u00eda al conocer de la orden de captura que pesaba en su contra.\u00a0<\/i>\u00a0<\/strong><\/h4>\n<figure id=\"attachment_277152\" aria-describedby=\"caption-attachment-277152\" style=\"width: 696px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-277152\" src=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/feminicidio-agravado-tentado-ibague-1024x928.jpeg\" alt=\"en la imagen se ve una persona detenida en custodia de un investigador del CTI. Detr\u00e1s suyo un backing de la Fiscal\u00eda. \" width=\"696\" height=\"631\" srcset=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/feminicidio-agravado-tentado-ibague-1024x928.jpeg 1024w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/feminicidio-agravado-tentado-ibague-300x272.jpeg 300w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/feminicidio-agravado-tentado-ibague-768x696.jpeg 768w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/feminicidio-agravado-tentado-ibague-696x631.jpeg 696w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/feminicidio-agravado-tentado-ibague-1068x968.jpeg 1068w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/feminicidio-agravado-tentado-ibague-463x420.jpeg 463w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/feminicidio-agravado-tentado-ibague.jpeg 1178w\" sizes=\"auto, (max-width: 696px) 100vw, 696px\" \/><figcaption id=\"caption-attachment-277152\" class=\"wp-caption-text\">El hombre se entreg\u00f3 ante el despacho fiscal de la Unidad de Vida que lo requer\u00eda por tentativa de feminicidio agravado. Fue enviado a la c\u00e1rcel como medida de aseguramiento preventiva.<\/figcaption><\/figure>\n<p>Jos\u00e9 William Rodr\u00edguez Grisales, de 55 a\u00f1os de edad, fue afectado con medida de aseguramiento en centro carcelario por su presunta responsabilidad en el delito de feminicidio agravado tentado.<\/p>\n<p>Personal del Cuerpo T\u00e9cnico de Investigaci\u00f3n (CTI) adscrito el grupo investigativo de vida e integridad personal de la Seccional Tolima materializ\u00f3 su captura este 16 de agosto en las instalaciones del B\u00fanker de la Fiscal\u00eda en Ibagu\u00e9 (Tolima), tras presentarse voluntariamente luego de conocer la orden judicial que pesaba en su contra.<\/p>\n<p>Los hechos por los cuales est\u00e1 siendo investigado ocurrieron el 16 de julio de este a\u00f1o en el barrio Galarza de la capital tolimense, cuando presuntamente, en un ataque de celos,\u00a0 le ocasion\u00f3 seis heridas con un machete en la cara y el cuello a su compa\u00f1era sentimental\u00a0 de 46 a\u00f1os de edad.<\/p>\n<p>Seg\u00fan las indagaciones del ente acusador, todo se habr\u00eda dado en un contexto de violencia de g\u00e9nero al que vendr\u00eda siendo sometida la mujer por m\u00e1s de 35 a\u00f1os.<\/p>\n<p>Durante las audiencias concentradas el presunto agresor no se allan\u00f3 a los cargos imputados.<\/p>\n<p><b><u>La Fiscal\u00eda habla con resultados.<\/u><\/b><b><u>\u00a0<\/u><\/b><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>PAAM\/ LFML\/GPST\/AMBV\/DST<\/p>\n<p>&nbsp;<\/p>\n<p align=\"center\">\n<p><span lang=\"ES-TRAD\">\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<div class=\"td-post-content tagdiv-type\">\n<div class=\"td-post-content tagdiv-type\">\n<div class=\"td-post-content tagdiv-type\">\n<div class=\"td-post-content tagdiv-type\">\n<div dir=\"ltr\">\n<p><em>La informaci\u00f3n contenida en este bolet\u00edn de prensa corresponde a la narraci\u00f3n de los hechos noticiosos objetivos, y las investigaciones penales al interior de la Fiscal\u00eda General de la Naci\u00f3n. Para el momento de la divulgaci\u00f3n de este comunicado, la situaci\u00f3n jur\u00eddica de la(s) persona(s) relacionada(s) se encuentra pendiente de resolver por la autoridad judicial competente, siempre bajo los preceptos de la presunci\u00f3n de inocencia, consagrados en el art\u00edculo 29 de la Constituci\u00f3n Pol\u00edtica y el art\u00edculo 7\u00ba de la Ley 906 de 2004.<\/em><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n<div class=\"twitter-share\"><a href=\"https:\/\/twitter.com\/intent\/tweet?via=fiscaliacol\" class=\"twitter-share-button\">Tweet<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El hombre se entreg\u00f3 ante la Fiscal\u00eda al conocer de la orden de captura que pesaba en su contra.\u00a0\u00a0 Jos\u00e9 William Rodr\u00edguez Grisales, de 55 a\u00f1os de edad, fue afectado [&hellip;]<\/p>\n","protected":false},"author":177,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[1,329,303,24127],"tags":[13442,24185,1047,23990,27437],"class_list":["post-277148","post","type-post","status-publish","format-standard","category-noticias","category-seccional-ibague","category-seccionales","category-violencia-sexual-e-intrafamiliar","tag-feminicidio","tag-fiscal-barbosa","tag-fiscalia-general-de-la-nacion","tag-ibague-tolima","tag-pareja-sentimental"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fiscal\u00eda General de la Naci\u00f3n<\/title>\n<meta name=\"description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-responsable-de-tentativa-de-feminicidio-contra-su-pareja-sentimental\/\" \/>\n<meta property=\"og:site_name\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FiscaliaCol\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-18T19:52:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/feminicidio-agravado-tentado-ibague-1024x928.jpeg\" \/>\n<meta name=\"author\" content=\"Jordan Leandro Oviedo Anzola\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:site\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jordan Leandro Oviedo Anzola\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-responsable-de-tentativa-de-feminicidio-contra-su-pareja-sentimental\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-responsable-de-tentativa-de-feminicidio-contra-su-pareja-sentimental\/\"},\"author\":{\"name\":\"Jordan Leandro Oviedo Anzola\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf84402cf293a5393e9c70b111020b24\"},\"headline\":\"A la c\u00e1rcel presunto responsable de tentativa de feminicidio contra su pareja sentimental\",\"datePublished\":\"2023-08-18T19:52:16+00:00\",\"dateModified\":\"2023-08-18T19:52:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-responsable-de-tentativa-de-feminicidio-contra-su-pareja-sentimental\/\"},\"wordCount\":376,\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-responsable-de-tentativa-de-feminicidio-contra-su-pareja-sentimental\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/feminicidio-agravado-tentado-ibague-1024x928.jpeg\",\"keywords\":[\"Feminicidio\",\"Fiscal Barbosa\",\"Fiscal\u00eda General de la Naci\u00f3n\",\"Ibagu\u00e9 (Tolima)\",\"pareja sentimental\"],\"articleSection\":[\"Noticias\",\"Seccional Ibagu\u00e9\",\"Seccionales\",\"Violencia sexual e intrafamiliar\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-responsable-de-tentativa-de-feminicidio-contra-su-pareja-sentimental\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-responsable-de-tentativa-de-feminicidio-contra-su-pareja-sentimental\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-responsable-de-tentativa-de-feminicidio-contra-su-pareja-sentimental\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-responsable-de-tentativa-de-feminicidio-contra-su-pareja-sentimental\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/feminicidio-agravado-tentado-ibague-1024x928.jpeg\",\"datePublished\":\"2023-08-18T19:52:16+00:00\",\"dateModified\":\"2023-08-18T19:52:16+00:00\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-responsable-de-tentativa-de-feminicidio-contra-su-pareja-sentimental\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-responsable-de-tentativa-de-feminicidio-contra-su-pareja-sentimental\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-responsable-de-tentativa-de-feminicidio-contra-su-pareja-sentimental\/#primaryimage\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/feminicidio-agravado-tentado-ibague-1024x928.jpeg\",\"contentUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/feminicidio-agravado-tentado-ibague-1024x928.jpeg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-responsable-de-tentativa-de-feminicidio-contra-su-pareja-sentimental\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A la c\u00e1rcel presunto responsable de tentativa de feminicidio contra su pareja sentimental\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"contentUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"width\":300,\"height\":90,\"caption\":\"Fiscal\u00eda General de la Naci\u00f3n\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/FiscaliaCol\",\"https:\/\/x.com\/FiscaliaCol\",\"https:\/\/www.instagram.com\/fiscaliacol\",\"https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/\",\"https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf84402cf293a5393e9c70b111020b24\",\"name\":\"Jordan Leandro Oviedo Anzola\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/dabba4346fa9b9207d96adafa8f92721?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/dabba4346fa9b9207d96adafa8f92721?s=96&d=mm&r=g\",\"caption\":\"Jordan Leandro Oviedo Anzola\"},\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/author\/joviedo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Fiscal\u00eda General de la Naci\u00f3n","og_description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","og_url":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-responsable-de-tentativa-de-feminicidio-contra-su-pareja-sentimental\/","og_site_name":"Fiscal\u00eda General de la Naci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/FiscaliaCol","article_published_time":"2023-08-18T19:52:16+00:00","og_image":[{"url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/feminicidio-agravado-tentado-ibague-1024x928.jpeg","type":"","width":"","height":""}],"author":"Jordan Leandro Oviedo Anzola","twitter_card":"summary_large_image","twitter_creator":"@FiscaliaCol","twitter_site":"@FiscaliaCol","twitter_misc":{"Escrito por":"Jordan Leandro Oviedo Anzola","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-responsable-de-tentativa-de-feminicidio-contra-su-pareja-sentimental\/#article","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-responsable-de-tentativa-de-feminicidio-contra-su-pareja-sentimental\/"},"author":{"name":"Jordan Leandro Oviedo Anzola","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf84402cf293a5393e9c70b111020b24"},"headline":"A la c\u00e1rcel presunto responsable de tentativa de feminicidio contra su pareja sentimental","datePublished":"2023-08-18T19:52:16+00:00","dateModified":"2023-08-18T19:52:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-responsable-de-tentativa-de-feminicidio-contra-su-pareja-sentimental\/"},"wordCount":376,"publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-responsable-de-tentativa-de-feminicidio-contra-su-pareja-sentimental\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/feminicidio-agravado-tentado-ibague-1024x928.jpeg","keywords":["Feminicidio","Fiscal Barbosa","Fiscal\u00eda General de la Naci\u00f3n","Ibagu\u00e9 (Tolima)","pareja sentimental"],"articleSection":["Noticias","Seccional Ibagu\u00e9","Seccionales","Violencia sexual e intrafamiliar"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-responsable-de-tentativa-de-feminicidio-contra-su-pareja-sentimental\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-responsable-de-tentativa-de-feminicidio-contra-su-pareja-sentimental\/","name":"Fiscal\u00eda General de la Naci\u00f3n","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-responsable-de-tentativa-de-feminicidio-contra-su-pareja-sentimental\/#primaryimage"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-responsable-de-tentativa-de-feminicidio-contra-su-pareja-sentimental\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/feminicidio-agravado-tentado-ibague-1024x928.jpeg","datePublished":"2023-08-18T19:52:16+00:00","dateModified":"2023-08-18T19:52:16+00:00","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","breadcrumb":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-responsable-de-tentativa-de-feminicidio-contra-su-pareja-sentimental\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-responsable-de-tentativa-de-feminicidio-contra-su-pareja-sentimental\/"]}]},{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-responsable-de-tentativa-de-feminicidio-contra-su-pareja-sentimental\/#primaryimage","url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/feminicidio-agravado-tentado-ibague-1024x928.jpeg","contentUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/feminicidio-agravado-tentado-ibague-1024x928.jpeg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-responsable-de-tentativa-de-feminicidio-contra-su-pareja-sentimental\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fiscalia.gov.co\/colombia\/"},{"@type":"ListItem","position":2,"name":"A la c\u00e1rcel presunto responsable de tentativa de feminicidio contra su pareja sentimental"}]},{"@type":"WebSite","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","name":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization","name":"Fiscal\u00eda General de la Naci\u00f3n","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","contentUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","width":300,"height":90,"caption":"Fiscal\u00eda General de la Naci\u00f3n"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FiscaliaCol","https:\/\/x.com\/FiscaliaCol","https:\/\/www.instagram.com\/fiscaliacol","https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/","https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh"]},{"@type":"Person","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf84402cf293a5393e9c70b111020b24","name":"Jordan Leandro Oviedo Anzola","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/dabba4346fa9b9207d96adafa8f92721?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dabba4346fa9b9207d96adafa8f92721?s=96&d=mm&r=g","caption":"Jordan Leandro Oviedo Anzola"},"url":"https:\/\/www.fiscalia.gov.co\/colombia\/author\/joviedo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/277148","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/users\/177"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/comments?post=277148"}],"version-history":[{"count":1,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/277148\/revisions"}],"predecessor-version":[{"id":277153,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/277148\/revisions\/277153"}],"wp:attachment":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/media?parent=277148"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/categories?post=277148"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/tags?post=277148"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}