{"id":264340,"date":"2023-01-19T11:13:50","date_gmt":"2023-01-19T16:13:50","guid":{"rendered":"https:\/\/www.fiscalia.gov.co\/colombia\/?p=264340"},"modified":"2023-01-19T11:13:50","modified_gmt":"2023-01-19T16:13:50","slug":"asegurado-en-centro-carcelario-presunto-responsable-de-feminicidio-tentado-contra-excompanera-sentimental","status":"publish","type":"post","link":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurado-en-centro-carcelario-presunto-responsable-de-feminicidio-tentado-contra-excompanera-sentimental\/","title":{"rendered":"Asegurado en centro carcelario presunto responsable de feminicidio tentado contra excompa\u00f1era sentimental"},"content":{"rendered":"<p style=\"font-weight: 400;\">Ante la contundencia y el material probatorio presentado por un fiscal Local, un juez penal de control de garant\u00edas dict\u00f3 medida de aseguramiento contra Dilan Camilo Cadavid Pe\u00f1a en centro carcelario.<\/p>\n<figure id=\"attachment_264341\" aria-describedby=\"caption-attachment-264341\" style=\"width: 696px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-264341\" src=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/FOTO-CAPTURADO-POR-FEMINICIDIO-1024x784.jpeg\" alt=\"En la fotograf\u00eda aparece el capturado junto a un servidor del CTI y a un agente de la Polic\u00eda Nacional. En la parte superior se observa un banner de la Fiscal\u00eda General de la Naci\u00f3n.\" width=\"696\" height=\"533\" srcset=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/FOTO-CAPTURADO-POR-FEMINICIDIO-1024x784.jpeg 1024w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/FOTO-CAPTURADO-POR-FEMINICIDIO-300x230.jpeg 300w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/FOTO-CAPTURADO-POR-FEMINICIDIO-768x588.jpeg 768w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/FOTO-CAPTURADO-POR-FEMINICIDIO-696x533.jpeg 696w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/FOTO-CAPTURADO-POR-FEMINICIDIO-1068x818.jpeg 1068w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/FOTO-CAPTURADO-POR-FEMINICIDIO-549x420.jpeg 549w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/FOTO-CAPTURADO-POR-FEMINICIDIO-80x60.jpeg 80w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/FOTO-CAPTURADO-POR-FEMINICIDIO.jpeg 1280w\" sizes=\"auto, (max-width: 696px) 100vw, 696px\" \/><figcaption id=\"caption-attachment-264341\" class=\"wp-caption-text\">Dilan Camilo Cadavid fue privado de la libertad en centro de reclusi\u00f3n como presunto autor de feminicidio tentado.<\/figcaption><\/figure>\n<p style=\"font-weight: 400;\">Un fiscal local imput\u00f3 cargos al hombre como presunto autor material del delito de\u00a0<a href=\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-responsable-del-feminicidio-de-su-companera-sentimental-en-el-barrio-moravia\/\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-presunto-responsable-del-feminicidio-de-su-companera-sentimental-en-el-barrio-moravia\/&amp;source=gmail&amp;ust=1674230308686000&amp;usg=AOvVaw3ywDGyUmuPKqn32EVRn6uD\">feminicidio<\/a>\u00a0en grado de tentativa.<\/p>\n<p style=\"font-weight: 400;\">Los hechos por los que Cadavid Pe\u00f1a es procesado se registraron el 17 de diciembre de 2022, en el barrio Villa Nancy de este municipio del oriente vallecaucano, cuando el hombre se acerc\u00f3 a su excompa\u00f1era sentimental, de 20 a\u00f1os, quien se movilizaba en una motocicleta con una amiga y seg\u00fan la investigaci\u00f3n, el asegurado la lanz\u00f3 al suelo y presuntamente le propin\u00f3\u00a0pu\u00f1os y patadas en su cuerpo, rostro y cabeza lo que le hizo perder la conciencia.<\/p>\n<p style=\"font-weight: 400;\">Amigos y vecinos del sector trasladaron a la mujer a un centro asistencial, donde la valoraci\u00f3n m\u00e9dica detall\u00f3 los traumas con hematomas en su rostro y cabeza, sangrado por su nariz y lesiones en sus brazos, t\u00f3rax y piernas.<\/p>\n<p style=\"font-weight: 400;\">Instaurada la denuncia en la URI de la Fiscal\u00eda, un juez penal emiti\u00f3 una orden de captura contra el presunto agresor, quien fue capturado por servidores del CTI, junto con agentes de la Polic\u00eda Nacional.<\/p>\n<p style=\"font-weight: 400;\">El hombre no acept\u00f3 el cargo imputado por la Fiscal\u00eda.<\/p>\n<p style=\"font-weight: 400;\">Esta informaci\u00f3n se publica por razones de inter\u00e9s general.<\/p>\n<p style=\"font-weight: 400;\"><strong>La Fiscal\u00eda habla con resultados.\u00a0<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"font-weight: 400;\">JGP\/LYBT\/DP\/DSC<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<div class=\"td-post-content tagdiv-type\">\n<p><i>La informaci\u00f3n contenida en este bolet\u00edn de prensa corresponde a la narraci\u00f3n de los hechos noticiosos objetivos, y las investigaciones penales al interior de la Fiscal\u00eda General de la Naci\u00f3n. Para el momento de la divulgaci\u00f3n de este comunicado, la situaci\u00f3n jur\u00eddica de la(s) persona(s) relacionada(s) se encuentra pendiente de resolver por la autoridad judicial competente, siempre bajo los preceptos de la presunci\u00f3n de inocencia, consagrados en el art\u00edculo 29 de la Constituci\u00f3n Pol\u00edtica y el art\u00edculo 7\u00ba de la Ley 906 de 2004.<\/i><\/p>\n<\/div>\n<footer>\n<div class=\"td-post-sharing-bottom\"><\/div>\n<\/footer>\n\n<div class=\"twitter-share\"><a href=\"https:\/\/twitter.com\/intent\/tweet?via=fiscaliacol\" class=\"twitter-share-button\">Tweet<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ante la contundencia y el material probatorio presentado por un fiscal Local, un juez penal de control de garant\u00edas dict\u00f3 medida de aseguramiento contra Dilan Camilo Cadavid Pe\u00f1a en centro [&hellip;]<\/p>\n","protected":false},"author":177,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[1,324,303,24099],"tags":[13442,24526,24481,1047,32270,28247],"class_list":["post-264340","post","type-post","status-publish","format-standard","category-noticias","category-seccional-cali","category-seccionales","category-seguridad-territorial","tag-feminicidio","tag-fiscal-general-francisco-barbosa-delgado","tag-fiscalia-de-colombia","tag-fiscalia-general-de-la-nacion","tag-florida-valle-del-cauca","tag-punos-y-patadas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fiscal\u00eda General de la Naci\u00f3n<\/title>\n<meta name=\"description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurado-en-centro-carcelario-presunto-responsable-de-feminicidio-tentado-contra-excompanera-sentimental\/\" \/>\n<meta property=\"og:site_name\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FiscaliaCol\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-19T16:13:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/FOTO-CAPTURADO-POR-FEMINICIDIO-1024x784.jpeg\" \/>\n<meta name=\"author\" content=\"Jordan Leandro Oviedo Anzola\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:site\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jordan Leandro Oviedo Anzola\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurado-en-centro-carcelario-presunto-responsable-de-feminicidio-tentado-contra-excompanera-sentimental\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurado-en-centro-carcelario-presunto-responsable-de-feminicidio-tentado-contra-excompanera-sentimental\/\"},\"author\":{\"name\":\"Jordan Leandro Oviedo Anzola\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf84402cf293a5393e9c70b111020b24\"},\"headline\":\"Asegurado en centro carcelario presunto responsable de feminicidio tentado contra excompa\u00f1era sentimental\",\"datePublished\":\"2023-01-19T16:13:50+00:00\",\"dateModified\":\"2023-01-19T16:13:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurado-en-centro-carcelario-presunto-responsable-de-feminicidio-tentado-contra-excompanera-sentimental\/\"},\"wordCount\":390,\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurado-en-centro-carcelario-presunto-responsable-de-feminicidio-tentado-contra-excompanera-sentimental\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/FOTO-CAPTURADO-POR-FEMINICIDIO-1024x784.jpeg\",\"keywords\":[\"Feminicidio\",\"Fiscal General Francisco Barbosa Delgado\",\"Fiscal\u00eda de Colombia\",\"Fiscal\u00eda General de la Naci\u00f3n\",\"Florida (Valle del Cauca)\",\"pu\u00f1os y patadas\"],\"articleSection\":[\"Noticias\",\"Seccional Cali\",\"Seccionales\",\"Seguridad territorial\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurado-en-centro-carcelario-presunto-responsable-de-feminicidio-tentado-contra-excompanera-sentimental\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurado-en-centro-carcelario-presunto-responsable-de-feminicidio-tentado-contra-excompanera-sentimental\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurado-en-centro-carcelario-presunto-responsable-de-feminicidio-tentado-contra-excompanera-sentimental\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurado-en-centro-carcelario-presunto-responsable-de-feminicidio-tentado-contra-excompanera-sentimental\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/FOTO-CAPTURADO-POR-FEMINICIDIO-1024x784.jpeg\",\"datePublished\":\"2023-01-19T16:13:50+00:00\",\"dateModified\":\"2023-01-19T16:13:50+00:00\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurado-en-centro-carcelario-presunto-responsable-de-feminicidio-tentado-contra-excompanera-sentimental\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurado-en-centro-carcelario-presunto-responsable-de-feminicidio-tentado-contra-excompanera-sentimental\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurado-en-centro-carcelario-presunto-responsable-de-feminicidio-tentado-contra-excompanera-sentimental\/#primaryimage\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/FOTO-CAPTURADO-POR-FEMINICIDIO-1024x784.jpeg\",\"contentUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/FOTO-CAPTURADO-POR-FEMINICIDIO-1024x784.jpeg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurado-en-centro-carcelario-presunto-responsable-de-feminicidio-tentado-contra-excompanera-sentimental\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Asegurado en centro carcelario presunto responsable de feminicidio tentado contra excompa\u00f1era sentimental\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"contentUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"width\":300,\"height\":90,\"caption\":\"Fiscal\u00eda General de la Naci\u00f3n\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/FiscaliaCol\",\"https:\/\/x.com\/FiscaliaCol\",\"https:\/\/www.instagram.com\/fiscaliacol\",\"https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/\",\"https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf84402cf293a5393e9c70b111020b24\",\"name\":\"Jordan Leandro Oviedo Anzola\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/dabba4346fa9b9207d96adafa8f92721?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/dabba4346fa9b9207d96adafa8f92721?s=96&d=mm&r=g\",\"caption\":\"Jordan Leandro Oviedo Anzola\"},\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/author\/joviedo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Fiscal\u00eda General de la Naci\u00f3n","og_description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","og_url":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurado-en-centro-carcelario-presunto-responsable-de-feminicidio-tentado-contra-excompanera-sentimental\/","og_site_name":"Fiscal\u00eda General de la Naci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/FiscaliaCol","article_published_time":"2023-01-19T16:13:50+00:00","og_image":[{"url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/FOTO-CAPTURADO-POR-FEMINICIDIO-1024x784.jpeg","type":"","width":"","height":""}],"author":"Jordan Leandro Oviedo Anzola","twitter_card":"summary_large_image","twitter_creator":"@FiscaliaCol","twitter_site":"@FiscaliaCol","twitter_misc":{"Escrito por":"Jordan Leandro Oviedo Anzola","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurado-en-centro-carcelario-presunto-responsable-de-feminicidio-tentado-contra-excompanera-sentimental\/#article","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurado-en-centro-carcelario-presunto-responsable-de-feminicidio-tentado-contra-excompanera-sentimental\/"},"author":{"name":"Jordan Leandro Oviedo Anzola","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf84402cf293a5393e9c70b111020b24"},"headline":"Asegurado en centro carcelario presunto responsable de feminicidio tentado contra excompa\u00f1era sentimental","datePublished":"2023-01-19T16:13:50+00:00","dateModified":"2023-01-19T16:13:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurado-en-centro-carcelario-presunto-responsable-de-feminicidio-tentado-contra-excompanera-sentimental\/"},"wordCount":390,"publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurado-en-centro-carcelario-presunto-responsable-de-feminicidio-tentado-contra-excompanera-sentimental\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/FOTO-CAPTURADO-POR-FEMINICIDIO-1024x784.jpeg","keywords":["Feminicidio","Fiscal General Francisco Barbosa Delgado","Fiscal\u00eda de Colombia","Fiscal\u00eda General de la Naci\u00f3n","Florida (Valle del Cauca)","pu\u00f1os y patadas"],"articleSection":["Noticias","Seccional Cali","Seccionales","Seguridad territorial"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurado-en-centro-carcelario-presunto-responsable-de-feminicidio-tentado-contra-excompanera-sentimental\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurado-en-centro-carcelario-presunto-responsable-de-feminicidio-tentado-contra-excompanera-sentimental\/","name":"Fiscal\u00eda General de la Naci\u00f3n","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurado-en-centro-carcelario-presunto-responsable-de-feminicidio-tentado-contra-excompanera-sentimental\/#primaryimage"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurado-en-centro-carcelario-presunto-responsable-de-feminicidio-tentado-contra-excompanera-sentimental\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/FOTO-CAPTURADO-POR-FEMINICIDIO-1024x784.jpeg","datePublished":"2023-01-19T16:13:50+00:00","dateModified":"2023-01-19T16:13:50+00:00","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","breadcrumb":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurado-en-centro-carcelario-presunto-responsable-de-feminicidio-tentado-contra-excompanera-sentimental\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurado-en-centro-carcelario-presunto-responsable-de-feminicidio-tentado-contra-excompanera-sentimental\/"]}]},{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurado-en-centro-carcelario-presunto-responsable-de-feminicidio-tentado-contra-excompanera-sentimental\/#primaryimage","url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/FOTO-CAPTURADO-POR-FEMINICIDIO-1024x784.jpeg","contentUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/FOTO-CAPTURADO-POR-FEMINICIDIO-1024x784.jpeg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurado-en-centro-carcelario-presunto-responsable-de-feminicidio-tentado-contra-excompanera-sentimental\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fiscalia.gov.co\/colombia\/"},{"@type":"ListItem","position":2,"name":"Asegurado en centro carcelario presunto responsable de feminicidio tentado contra excompa\u00f1era sentimental"}]},{"@type":"WebSite","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","name":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization","name":"Fiscal\u00eda General de la Naci\u00f3n","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","contentUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","width":300,"height":90,"caption":"Fiscal\u00eda General de la Naci\u00f3n"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FiscaliaCol","https:\/\/x.com\/FiscaliaCol","https:\/\/www.instagram.com\/fiscaliacol","https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/","https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh"]},{"@type":"Person","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf84402cf293a5393e9c70b111020b24","name":"Jordan Leandro Oviedo Anzola","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/dabba4346fa9b9207d96adafa8f92721?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dabba4346fa9b9207d96adafa8f92721?s=96&d=mm&r=g","caption":"Jordan Leandro Oviedo Anzola"},"url":"https:\/\/www.fiscalia.gov.co\/colombia\/author\/joviedo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/264340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/users\/177"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/comments?post=264340"}],"version-history":[{"count":2,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/264340\/revisions"}],"predecessor-version":[{"id":264343,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/264340\/revisions\/264343"}],"wp:attachment":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/media?parent=264340"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/categories?post=264340"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/tags?post=264340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}