{"id":263554,"date":"2022-12-28T10:52:01","date_gmt":"2022-12-28T15:52:01","guid":{"rendered":"https:\/\/www.fiscalia.gov.co\/colombia\/?p=263554"},"modified":"2022-12-28T10:52:01","modified_gmt":"2022-12-28T15:52:01","slug":"a-la-carcel-dos-presuntos-miembros-de-las-disidencias-quienes-portaban-armas-de-uso-restringido-y-explosivos-artesanales","status":"publish","type":"post","link":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-dos-presuntos-miembros-de-las-disidencias-quienes-portaban-armas-de-uso-restringido-y-explosivos-artesanales\/","title":{"rendered":"A la c\u00e1rcel dos presuntos miembros de las disidencias quienes portaban armas de uso restringido y explosivos artesanales"},"content":{"rendered":"<p style=\"font-weight: 400;\">Los dos presuntos integrantes de las disidencias residuales Rafael Aguilera y <a href=\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-ibague\/asegurados-en-centro-carcelario-tres-presuntos-integrantes-de-la-comision-de-finanzas-del-frente-alfonso-cano-de-las-disidencias-de-las-farc\/\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-ibague\/asegurados-en-centro-carcelario-tres-presuntos-integrantes-de-la-comision-de-finanzas-del-frente-alfonso-cano-de-las-disidencias-de-las-farc\/&amp;source=gmail&amp;ust=1672328451516000&amp;usg=AOvVaw1FI8LAfmobWrhJF6IgbSfm\">Alfonso Cano<\/a>\u00a0fueron capturados durante operativos de patrullaje y control en el municipio de El Charco (Nari\u00f1o), cuando se encontraban en una cancha de f\u00fatbol del barrio El Porvenir.<\/p>\n<figure id=\"attachment_263556\" aria-describedby=\"caption-attachment-263556\" style=\"width: 696px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-263556\" src=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/IMG-20221228-WA0022-1024x740.jpg\" alt=\"En la fotograf\u00eda aparecen los dos capturados junto a dos agentes de la Polic\u00eda Nacional, un infante de marina y un soldado del Ej\u00e9rcito Nacional. En la parte posterior se observa una mesa con armas de fuego, municiones, explosivos artesanales y una mochila. \" width=\"696\" height=\"503\" srcset=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/IMG-20221228-WA0022-1024x740.jpg 1024w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/IMG-20221228-WA0022-300x217.jpg 300w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/IMG-20221228-WA0022-768x555.jpg 768w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/IMG-20221228-WA0022-696x503.jpg 696w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/IMG-20221228-WA0022-1068x772.jpg 1068w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/IMG-20221228-WA0022-581x420.jpg 581w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/IMG-20221228-WA0022-324x235.jpg 324w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/IMG-20221228-WA0022.jpg 1280w\" sizes=\"auto, (max-width: 696px) 100vw, 696px\" \/><figcaption id=\"caption-attachment-263556\" class=\"wp-caption-text\">A dos presuntos miembros de las disidencias la Fiscal\u00eda los imput\u00f3 por porte ilegal de armas de fuego y fueron enviados a la c\u00e1rcel por un juez penal de Tumaco (Nari\u00f1o).<\/figcaption><\/figure>\n<p style=\"font-weight: 400;\">Milton Solarte Perea y Luis Alberto Viafara Sinisterra estar\u00edan reunidos con varios hombres, quienes portaban armas de largo y corto alcance cuando llegaron unidades de la Infanter\u00eda de Marina de la Armada, el Ej\u00e9rcito y la Polic\u00eda Nacional, inici\u00e1ndose un enfrentamiento armado.<\/p>\n<p style=\"font-weight: 400;\">Durante los combates los dos hombres fueron detenidos por infantes de marina a quienes les incautaron un fusil con dos proveedores, un rev\u00f3lver, cuatro pistolas\u00a0calibre 9 mil\u00edmetros con sus proveedores, dos explosivos artesanales, un escopeta con tres cartuchos y una mochila.<\/p>\n<p style=\"font-weight: 400;\">Durante las audiencias concentradas un fiscal de Tumaco (Nari\u00f1o)\u00a0les imput\u00f3 cargos como presuntos autores de los delitos de fabricaci\u00f3n, tr\u00e1fico y porte de armas de fuego y municiones de\u00a0<a href=\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurados-4-presuntos-responsables-de-porte-ilegal-de-armas-de-uso-privativos-y-otros-elementos-en-barbacoas-narino\/\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurados-4-presuntos-responsables-de-porte-ilegal-de-armas-de-uso-privativos-y-otros-elementos-en-barbacoas-narino\/&amp;source=gmail&amp;ust=1672328451516000&amp;usg=AOvVaw0NJVK7UX10wAGkRiyEzhnP\">uso privativo<\/a>\u00a0de las Fuerzas Armadas o explosivos agravado.<\/p>\n<p style=\"font-weight: 400;\">Solarte Perea y Vi\u00e1fara Sinisterra no aceptaron los cargos.<\/p>\n<p style=\"font-weight: 400;\">Un juez penal de Tumaco dict\u00f3 medida de aseguramiento contra los dos hombres consistente en detenci\u00f3n preventiva en establecimiento carcelario.<\/p>\n<p style=\"font-weight: 400;\">Esta informaci\u00f3n se publica por razones de inter\u00e9s general<\/p>\n<p style=\"font-weight: 400;\"><strong>La Fiscal\u00eda habla con resultados\u00a0<\/strong><\/p>\n<p>Le puede interesar:\u00a0<a href=\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurados-6-presuntos-miembros-de-la-disidencia-residual-alfonso-cano-capturados-con-armas-y-municion-de-uso-privativo\/\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurados-6-presuntos-miembros-de-la-disidencia-residual-alfonso-cano-capturados-con-armas-y-municion-de-uso-privativo\/&amp;source=gmail&amp;ust=1672328451516000&amp;usg=AOvVaw2kgDJCBxnoHYmvuPT4cEL2\">Asegurados 6 presuntos miembros de la disidencia residual Alfonso Cano, capturados con armas y munici\u00f3n de uso privativo<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"font-weight: 400;\">JGP\/CFG\/LVB\/DSN<\/p>\n<p>&nbsp;<\/p>\n<p style=\"font-weight: 400;\">\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<div class=\"td-post-content tagdiv-type\">\n<div class=\"td-post-content tagdiv-type\">\n<div class=\"td-post-content tagdiv-type\">\n<div class=\"td-post-content tagdiv-type\">\n<div class=\"td-post-content tagdiv-type\">\n<div class=\"td-post-content tagdiv-type\">\n<div class=\"td-post-content tagdiv-type\">\n<div class=\"td-post-content tagdiv-type\">\n<div class=\"td-post-content tagdiv-type\">\n<div class=\"td-post-content tagdiv-type\">\n<div class=\"td-post-content tagdiv-type\">\n<div class=\"td-post-content tagdiv-type\">\n<div class=\"td-post-content tagdiv-type\">\n<div class=\"td-post-content tagdiv-type\">\n<div class=\"td-post-content tagdiv-type\">\n<div class=\"td-post-content tagdiv-type\">\n<div class=\"td-post-content tagdiv-type\">\n<div class=\"td-post-content tagdiv-type\">\n<div class=\"td-post-content tagdiv-type\">\n<div class=\"td-post-content tagdiv-type\">\n<div class=\"td-post-content tagdiv-type\">\n<div class=\"td-post-content tagdiv-type\">\n<div class=\"td-post-content tagdiv-type\">\n<div class=\"td-post-content tagdiv-type\">\n<div class=\"td-post-content tagdiv-type\">\n<div class=\"td-post-content tagdiv-type\">\n<div class=\"td-post-content tagdiv-type\">\n<p><em>La informaci\u00f3n contenida en este bolet\u00edn de prensa corresponde a la narraci\u00f3n de los hechos noticiosos objetivos, suministrados por los funcionarios encargados de adelantar las investigaciones penales al interior de la Fiscal\u00eda General de la Naci\u00f3n. Para el momento de la divulgaci\u00f3n de este comunicado, la situaci\u00f3n jur\u00eddica de la(s) persona(s) relacionada(s) se encuentra pendiente de resolver por la autoridad judicial competente, siempre bajo los preceptos de la presunci\u00f3n de inocencia, consagrados en el art\u00edculo 29 de la Constituci\u00f3n Pol\u00edtica y el art\u00edculo 7\u00ba de la Ley 906 de 2004.<\/em><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n<div class=\"twitter-share\"><a href=\"https:\/\/twitter.com\/intent\/tweet?via=fiscaliacol\" class=\"twitter-share-button\">Tweet<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Los dos presuntos integrantes de las disidencias residuales Rafael Aguilera y Alfonso Cano\u00a0fueron capturados durante operativos de patrullaje y control en el municipio de El Charco (Nari\u00f1o), cuando se encontraban [&hellip;]<\/p>\n","protected":false},"author":177,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[1,334,303,24099],"tags":[3223,24526,24481,1047,24037,11515],"class_list":["post-263554","post","type-post","status-publish","format-standard","category-noticias","category-seccional-pasto","category-seccionales","category-seguridad-territorial","tag-alfonso-cano","tag-fiscal-general-francisco-barbosa-delgado","tag-fiscalia-de-colombia","tag-fiscalia-general-de-la-nacion","tag-tumaco-narino","tag-uso-privativo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fiscal\u00eda General de la Naci\u00f3n<\/title>\n<meta name=\"description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-dos-presuntos-miembros-de-las-disidencias-quienes-portaban-armas-de-uso-restringido-y-explosivos-artesanales\/\" \/>\n<meta property=\"og:site_name\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FiscaliaCol\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-28T15:52:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/IMG-20221228-WA0022-1024x740.jpg\" \/>\n<meta name=\"author\" content=\"Jordan Leandro Oviedo Anzola\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:site\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jordan Leandro Oviedo Anzola\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-dos-presuntos-miembros-de-las-disidencias-quienes-portaban-armas-de-uso-restringido-y-explosivos-artesanales\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-dos-presuntos-miembros-de-las-disidencias-quienes-portaban-armas-de-uso-restringido-y-explosivos-artesanales\/\"},\"author\":{\"name\":\"Jordan Leandro Oviedo Anzola\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf84402cf293a5393e9c70b111020b24\"},\"headline\":\"A la c\u00e1rcel dos presuntos miembros de las disidencias quienes portaban armas de uso restringido y explosivos artesanales\",\"datePublished\":\"2022-12-28T15:52:01+00:00\",\"dateModified\":\"2022-12-28T15:52:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-dos-presuntos-miembros-de-las-disidencias-quienes-portaban-armas-de-uso-restringido-y-explosivos-artesanales\/\"},\"wordCount\":419,\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-dos-presuntos-miembros-de-las-disidencias-quienes-portaban-armas-de-uso-restringido-y-explosivos-artesanales\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/IMG-20221228-WA0022-1024x740.jpg\",\"keywords\":[\"Alfonso Cano\",\"Fiscal General Francisco Barbosa Delgado\",\"Fiscal\u00eda de Colombia\",\"Fiscal\u00eda General de la Naci\u00f3n\",\"Tumaco (Nari\u00f1o)\",\"Uso privativo\"],\"articleSection\":[\"Noticias\",\"Seccional Pasto\",\"Seccionales\",\"Seguridad territorial\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-dos-presuntos-miembros-de-las-disidencias-quienes-portaban-armas-de-uso-restringido-y-explosivos-artesanales\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-dos-presuntos-miembros-de-las-disidencias-quienes-portaban-armas-de-uso-restringido-y-explosivos-artesanales\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-dos-presuntos-miembros-de-las-disidencias-quienes-portaban-armas-de-uso-restringido-y-explosivos-artesanales\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-dos-presuntos-miembros-de-las-disidencias-quienes-portaban-armas-de-uso-restringido-y-explosivos-artesanales\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/IMG-20221228-WA0022-1024x740.jpg\",\"datePublished\":\"2022-12-28T15:52:01+00:00\",\"dateModified\":\"2022-12-28T15:52:01+00:00\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-dos-presuntos-miembros-de-las-disidencias-quienes-portaban-armas-de-uso-restringido-y-explosivos-artesanales\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-dos-presuntos-miembros-de-las-disidencias-quienes-portaban-armas-de-uso-restringido-y-explosivos-artesanales\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-dos-presuntos-miembros-de-las-disidencias-quienes-portaban-armas-de-uso-restringido-y-explosivos-artesanales\/#primaryimage\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/IMG-20221228-WA0022.jpg\",\"contentUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/IMG-20221228-WA0022.jpg\",\"width\":1280,\"height\":925,\"caption\":\"A dos presuntos miembros de las disidencias la Fiscal\u00eda los imput\u00f3 por porte ilegal de armas de fuego y fueron enviados a la c\u00e1rcel por un juez penal de Tumaco (Nari\u00f1o).\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-dos-presuntos-miembros-de-las-disidencias-quienes-portaban-armas-de-uso-restringido-y-explosivos-artesanales\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A la c\u00e1rcel dos presuntos miembros de las disidencias quienes portaban armas de uso restringido y explosivos artesanales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"contentUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"width\":300,\"height\":90,\"caption\":\"Fiscal\u00eda General de la Naci\u00f3n\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/FiscaliaCol\",\"https:\/\/x.com\/FiscaliaCol\",\"https:\/\/www.instagram.com\/fiscaliacol\",\"https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/\",\"https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf84402cf293a5393e9c70b111020b24\",\"name\":\"Jordan Leandro Oviedo Anzola\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/dabba4346fa9b9207d96adafa8f92721?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/dabba4346fa9b9207d96adafa8f92721?s=96&d=mm&r=g\",\"caption\":\"Jordan Leandro Oviedo Anzola\"},\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/author\/joviedo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Fiscal\u00eda General de la Naci\u00f3n","og_description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","og_url":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-dos-presuntos-miembros-de-las-disidencias-quienes-portaban-armas-de-uso-restringido-y-explosivos-artesanales\/","og_site_name":"Fiscal\u00eda General de la Naci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/FiscaliaCol","article_published_time":"2022-12-28T15:52:01+00:00","og_image":[{"url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/IMG-20221228-WA0022-1024x740.jpg","type":"","width":"","height":""}],"author":"Jordan Leandro Oviedo Anzola","twitter_card":"summary_large_image","twitter_creator":"@FiscaliaCol","twitter_site":"@FiscaliaCol","twitter_misc":{"Escrito por":"Jordan Leandro Oviedo Anzola","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-dos-presuntos-miembros-de-las-disidencias-quienes-portaban-armas-de-uso-restringido-y-explosivos-artesanales\/#article","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-dos-presuntos-miembros-de-las-disidencias-quienes-portaban-armas-de-uso-restringido-y-explosivos-artesanales\/"},"author":{"name":"Jordan Leandro Oviedo Anzola","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf84402cf293a5393e9c70b111020b24"},"headline":"A la c\u00e1rcel dos presuntos miembros de las disidencias quienes portaban armas de uso restringido y explosivos artesanales","datePublished":"2022-12-28T15:52:01+00:00","dateModified":"2022-12-28T15:52:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-dos-presuntos-miembros-de-las-disidencias-quienes-portaban-armas-de-uso-restringido-y-explosivos-artesanales\/"},"wordCount":419,"publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-dos-presuntos-miembros-de-las-disidencias-quienes-portaban-armas-de-uso-restringido-y-explosivos-artesanales\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/IMG-20221228-WA0022-1024x740.jpg","keywords":["Alfonso Cano","Fiscal General Francisco Barbosa Delgado","Fiscal\u00eda de Colombia","Fiscal\u00eda General de la Naci\u00f3n","Tumaco (Nari\u00f1o)","Uso privativo"],"articleSection":["Noticias","Seccional Pasto","Seccionales","Seguridad territorial"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-dos-presuntos-miembros-de-las-disidencias-quienes-portaban-armas-de-uso-restringido-y-explosivos-artesanales\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-dos-presuntos-miembros-de-las-disidencias-quienes-portaban-armas-de-uso-restringido-y-explosivos-artesanales\/","name":"Fiscal\u00eda General de la Naci\u00f3n","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-dos-presuntos-miembros-de-las-disidencias-quienes-portaban-armas-de-uso-restringido-y-explosivos-artesanales\/#primaryimage"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-dos-presuntos-miembros-de-las-disidencias-quienes-portaban-armas-de-uso-restringido-y-explosivos-artesanales\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/IMG-20221228-WA0022-1024x740.jpg","datePublished":"2022-12-28T15:52:01+00:00","dateModified":"2022-12-28T15:52:01+00:00","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","breadcrumb":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-dos-presuntos-miembros-de-las-disidencias-quienes-portaban-armas-de-uso-restringido-y-explosivos-artesanales\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-dos-presuntos-miembros-de-las-disidencias-quienes-portaban-armas-de-uso-restringido-y-explosivos-artesanales\/"]}]},{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-dos-presuntos-miembros-de-las-disidencias-quienes-portaban-armas-de-uso-restringido-y-explosivos-artesanales\/#primaryimage","url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/IMG-20221228-WA0022.jpg","contentUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/IMG-20221228-WA0022.jpg","width":1280,"height":925,"caption":"A dos presuntos miembros de las disidencias la Fiscal\u00eda los imput\u00f3 por porte ilegal de armas de fuego y fueron enviados a la c\u00e1rcel por un juez penal de Tumaco (Nari\u00f1o)."},{"@type":"BreadcrumbList","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-dos-presuntos-miembros-de-las-disidencias-quienes-portaban-armas-de-uso-restringido-y-explosivos-artesanales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fiscalia.gov.co\/colombia\/"},{"@type":"ListItem","position":2,"name":"A la c\u00e1rcel dos presuntos miembros de las disidencias quienes portaban armas de uso restringido y explosivos artesanales"}]},{"@type":"WebSite","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","name":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization","name":"Fiscal\u00eda General de la Naci\u00f3n","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","contentUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","width":300,"height":90,"caption":"Fiscal\u00eda General de la Naci\u00f3n"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FiscaliaCol","https:\/\/x.com\/FiscaliaCol","https:\/\/www.instagram.com\/fiscaliacol","https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/","https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh"]},{"@type":"Person","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf84402cf293a5393e9c70b111020b24","name":"Jordan Leandro Oviedo Anzola","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/dabba4346fa9b9207d96adafa8f92721?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dabba4346fa9b9207d96adafa8f92721?s=96&d=mm&r=g","caption":"Jordan Leandro Oviedo Anzola"},"url":"https:\/\/www.fiscalia.gov.co\/colombia\/author\/joviedo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/263554","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/users\/177"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/comments?post=263554"}],"version-history":[{"count":3,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/263554\/revisions"}],"predecessor-version":[{"id":263558,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/263554\/revisions\/263558"}],"wp:attachment":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/media?parent=263554"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/categories?post=263554"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/tags?post=263554"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}