{"id":260060,"date":"2022-10-28T11:26:07","date_gmt":"2022-10-28T16:26:07","guid":{"rendered":"https:\/\/www.fiscalia.gov.co\/colombia\/?p=260060"},"modified":"2022-11-03T15:57:09","modified_gmt":"2022-11-03T20:57:09","slug":"fiscalia-en-amazonas-esclarece-delitos-sexuales-contra-menores-de-edad","status":"publish","type":"post","link":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-en-amazonas-esclarece-delitos-sexuales-contra-menores-de-edad\/","title":{"rendered":"Fiscal\u00eda en Amazonas esclarece delitos sexuales contra menores de edad"},"content":{"rendered":"<p>La Fiscal\u00eda General <a href=\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-impacto-a-los-del-puerto-integrantes-de-una-familia-que-estarian-a-cargo-del-negocio-de-estupefacientes-en-amazonas\/\">seccional Amazonas<\/a>, en un trabajo articulado con su polic\u00eda judicial CTI y la polic\u00eda de infancia y adolescencia, <strong>logr\u00f3 la judicializaci\u00f3n de 3 personas vinculadas presuntamente con cometer \u00a0delitos sexuales en contra de menores de edad.<\/strong><\/p>\n<p>Uno de los casos investigados en Leticia se logr\u00f3 el esclarecimiento de un abuso sexual presuntamente cometido por un <strong>profesor de ciencias naturales contra una ni\u00f1a de 8 a\u00f1os.<\/strong><\/p>\n<p>La investigaci\u00f3n indica que el 11 de noviembre \u00faltimo, la ni\u00f1a se acerc\u00f3 al escritorio del docente a presentarle un trabajo, <strong>luego el agresor la habr\u00eda halado y realizado\u00a0 tocamientos encima de la ropa en sus partes \u00edntimas.<\/strong><\/p>\n<p>En el segundo caso esclarecido, fue enviado a la c\u00e1rcel el padrastro de una menor de edad quien la habr\u00eda abusado desde los 10 a los 12 a\u00f1os, en el barrio Victoria Regia, Leticia (Amazonas<strong>). Ante el abundante material probatorio el imputado acept\u00f3 los cargos.<\/strong><strong>\u00a0<\/strong><\/p>\n<p>Por \u00faltimo, fue asegurado intramuros el profesor de un plantel escolar, quien cit\u00f3 en su casa a una alumna de 12 a\u00f1os para que la entrega de un trabajo que ten\u00eda pendiente<strong>.\u00a0 En este lugar la habr\u00eda tocado y abusado sexualmente<\/strong>.\u00a0 Los hechos ocurrieron en Puerto Nari\u00f1o (Amazonas) el 6 de septiembre de 2021.<\/p>\n<p>La delegada fiscal en actos urgentes, indagaci\u00f3n, investigaci\u00f3n, conocimiento y descongesti\u00f3n de delitos sexuales en Amazonas, <strong>les imput\u00f3 los delitos de acceso carnal abusivo con menor de catorce a\u00f1os agravado o actos sexuales con menor de catorce a\u00f1os agravado.<\/strong><\/p>\n<p><strong>La Fiscal\u00eda habla con resultados<\/strong><\/p>\n<p>CMRM\/DOPM\/FAGH<\/p>\n<p><em>La informaci\u00f3n contenida en este bolet\u00edn de prensa corresponde a la narraci\u00f3n de los hechos noticiosos objetivos, suministrados por los funcionarios encargados de adelantar las investigaciones penales al interior de la Fiscal\u00eda General de la Naci\u00f3n. Para el momento de la divulgaci\u00f3n de este comunicado, la situaci\u00f3n jur\u00eddica de la(s) persona(s) relacionada(s) se encuentra pendiente de resolver por la autoridad judicial competente, siempre bajo los preceptos de la presunci\u00f3n de inocencia, consagrados en el art\u00edculo 29 de la Constituci\u00f3n Pol\u00edtica\u00a0y\u00a0el art\u00edculo 7\u00ba de la Ley 906 de 2004.\u00a0<\/em><\/p>\n\n<div class=\"twitter-share\"><a href=\"https:\/\/twitter.com\/intent\/tweet?via=fiscaliacol\" class=\"twitter-share-button\">Tweet<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La Fiscal\u00eda General seccional Amazonas, en un trabajo articulado con su polic\u00eda judicial CTI y la polic\u00eda de infancia y adolescencia, logr\u00f3 la judicializaci\u00f3n de 3 personas vinculadas presuntamente con [&hellip;]<\/p>\n","protected":false},"author":175,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[1,24153,24127],"tags":[24189,24526],"class_list":["post-260060","post","type-post","status-publish","format-video","category-noticias","category-seccional-leticia","category-violencia-sexual-e-intrafamiliar","tag-fiscal-francisco-barbosa-delgado","tag-fiscal-general-francisco-barbosa-delgado","post_format-post-format-video"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fiscal\u00eda General de la Naci\u00f3n<\/title>\n<meta name=\"description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-en-amazonas-esclarece-delitos-sexuales-contra-menores-de-edad\/\" \/>\n<meta property=\"og:site_name\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FiscaliaCol\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-28T16:26:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-03T20:57:09+00:00\" \/>\n<meta name=\"author\" content=\"Katherine Loaiza Mart\u00ednez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:site\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Katherine Loaiza Mart\u00ednez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-en-amazonas-esclarece-delitos-sexuales-contra-menores-de-edad\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-en-amazonas-esclarece-delitos-sexuales-contra-menores-de-edad\/\"},\"author\":{\"name\":\"Katherine Loaiza Mart\u00ednez\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/2e76b9aba5ecf875ed565ce4de0e0415\"},\"headline\":\"Fiscal\u00eda en Amazonas esclarece delitos sexuales contra menores de edad\",\"datePublished\":\"2022-10-28T16:26:07+00:00\",\"dateModified\":\"2022-11-03T20:57:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-en-amazonas-esclarece-delitos-sexuales-contra-menores-de-edad\/\"},\"wordCount\":379,\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"keywords\":[\"Fiscal Francisco Barbosa Delgado\",\"Fiscal General Francisco Barbosa Delgado\"],\"articleSection\":[\"Noticias\",\"Seccional Leticia\",\"Violencia sexual e intrafamiliar\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-en-amazonas-esclarece-delitos-sexuales-contra-menores-de-edad\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-en-amazonas-esclarece-delitos-sexuales-contra-menores-de-edad\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\"},\"datePublished\":\"2022-10-28T16:26:07+00:00\",\"dateModified\":\"2022-11-03T20:57:09+00:00\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-en-amazonas-esclarece-delitos-sexuales-contra-menores-de-edad\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-en-amazonas-esclarece-delitos-sexuales-contra-menores-de-edad\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-en-amazonas-esclarece-delitos-sexuales-contra-menores-de-edad\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fiscal\u00eda en Amazonas esclarece delitos sexuales contra menores de edad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"contentUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"width\":300,\"height\":90,\"caption\":\"Fiscal\u00eda General de la Naci\u00f3n\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/FiscaliaCol\",\"https:\/\/x.com\/FiscaliaCol\",\"https:\/\/www.instagram.com\/fiscaliacol\",\"https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/\",\"https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/2e76b9aba5ecf875ed565ce4de0e0415\",\"name\":\"Katherine Loaiza Mart\u00ednez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ab775a2f394c1b83b6d6f78680e57b50?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ab775a2f394c1b83b6d6f78680e57b50?s=96&d=mm&r=g\",\"caption\":\"Katherine Loaiza Mart\u00ednez\"},\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/author\/kloaiza\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Fiscal\u00eda General de la Naci\u00f3n","og_description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","og_url":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-en-amazonas-esclarece-delitos-sexuales-contra-menores-de-edad\/","og_site_name":"Fiscal\u00eda General de la Naci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/FiscaliaCol","article_published_time":"2022-10-28T16:26:07+00:00","article_modified_time":"2022-11-03T20:57:09+00:00","author":"Katherine Loaiza Mart\u00ednez","twitter_card":"summary_large_image","twitter_creator":"@FiscaliaCol","twitter_site":"@FiscaliaCol","twitter_misc":{"Escrito por":"Katherine Loaiza Mart\u00ednez","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-en-amazonas-esclarece-delitos-sexuales-contra-menores-de-edad\/#article","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-en-amazonas-esclarece-delitos-sexuales-contra-menores-de-edad\/"},"author":{"name":"Katherine Loaiza Mart\u00ednez","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/2e76b9aba5ecf875ed565ce4de0e0415"},"headline":"Fiscal\u00eda en Amazonas esclarece delitos sexuales contra menores de edad","datePublished":"2022-10-28T16:26:07+00:00","dateModified":"2022-11-03T20:57:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-en-amazonas-esclarece-delitos-sexuales-contra-menores-de-edad\/"},"wordCount":379,"publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"keywords":["Fiscal Francisco Barbosa Delgado","Fiscal General Francisco Barbosa Delgado"],"articleSection":["Noticias","Seccional Leticia","Violencia sexual e intrafamiliar"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-en-amazonas-esclarece-delitos-sexuales-contra-menores-de-edad\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-en-amazonas-esclarece-delitos-sexuales-contra-menores-de-edad\/","name":"Fiscal\u00eda General de la Naci\u00f3n","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website"},"datePublished":"2022-10-28T16:26:07+00:00","dateModified":"2022-11-03T20:57:09+00:00","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","breadcrumb":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-en-amazonas-esclarece-delitos-sexuales-contra-menores-de-edad\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-en-amazonas-esclarece-delitos-sexuales-contra-menores-de-edad\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-en-amazonas-esclarece-delitos-sexuales-contra-menores-de-edad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fiscalia.gov.co\/colombia\/"},{"@type":"ListItem","position":2,"name":"Fiscal\u00eda en Amazonas esclarece delitos sexuales contra menores de edad"}]},{"@type":"WebSite","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","name":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization","name":"Fiscal\u00eda General de la Naci\u00f3n","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","contentUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","width":300,"height":90,"caption":"Fiscal\u00eda General de la Naci\u00f3n"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FiscaliaCol","https:\/\/x.com\/FiscaliaCol","https:\/\/www.instagram.com\/fiscaliacol","https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/","https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh"]},{"@type":"Person","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/2e76b9aba5ecf875ed565ce4de0e0415","name":"Katherine Loaiza Mart\u00ednez","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ab775a2f394c1b83b6d6f78680e57b50?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ab775a2f394c1b83b6d6f78680e57b50?s=96&d=mm&r=g","caption":"Katherine Loaiza Mart\u00ednez"},"url":"https:\/\/www.fiscalia.gov.co\/colombia\/author\/kloaiza\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/260060","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/users\/175"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/comments?post=260060"}],"version-history":[{"count":1,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/260060\/revisions"}],"predecessor-version":[{"id":260061,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/260060\/revisions\/260061"}],"wp:attachment":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/media?parent=260060"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/categories?post=260060"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/tags?post=260060"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}