{"id":245616,"date":"2022-04-07T12:51:25","date_gmt":"2022-04-07T17:51:25","guid":{"rendered":"https:\/\/www.fiscalia.gov.co\/colombia\/?p=245616"},"modified":"2022-04-07T12:51:25","modified_gmt":"2022-04-07T17:51:25","slug":"a-la-carcel-un-hombre-que-habria-exhibido-sus-partes-intimas-a-una-sobrina-menor-de-edad","status":"publish","type":"post","link":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-un-hombre-que-habria-exhibido-sus-partes-intimas-a-una-sobrina-menor-de-edad\/","title":{"rendered":"A la c\u00e1rcel un hombre que habr\u00eda exhibido sus partes \u00edntimas a una sobrina, menor de edad\u00a0"},"content":{"rendered":"<p style=\"font-weight: 400;\">Como presunto responsable del delito de actos sexuales con menor de 14 a\u00f1os de edad agravado, la Fiscal\u00eda General de la Naci\u00f3n obtuvo medida de aseguramiento en centro carcelario contra un hombre de 44 a\u00f1os de edad.<\/p>\n<p style=\"font-weight: 400;\">Los hechos investigados habr\u00edan ocurrido en zona rural del municipio de Barbosa (Antioquia) en enero pasado cuando el hombre, al parecer, exhibi\u00f3 sus genitales frente a su sobrina, una menor de 9 a\u00f1os de edad. Seg\u00fan la denuncia, esta conducta delictiva, habr\u00eda sido cometida por el procesado, al menos, en cuatro oportunidades.<\/p>\n<p style=\"font-weight: 400;\">El procesado fue capturado el pasado 5 de abril por servidores del Cuerpo T\u00e9cnico de Investigaci\u00f3n (CTI) y no se allan\u00f3 a los cargos imputados.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"font-weight: 400;\">LFML\/OG\/MAGA<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\"><em>La informaci\u00f3n contenida en este bolet\u00edn de prensa corresponde a la narraci\u00f3n de los hechos noticiosos objetivos, suministrados por los funcionarios encargados de adelantar las investigaciones penales al interior de la Fiscal\u00eda General de la Naci\u00f3n. Para el momento de la divulgaci\u00f3n de este comunicado, la situaci\u00f3n jur\u00eddica de la(s) persona(s) relacionada(s) se encuentra pendiente de resolver por la autoridad judicial competente, siempre bajo los preceptos de la presunci\u00f3n de inocencia, consagrados en el art\u00edculo 29 de la Constituci\u00f3n Pol\u00edtica y el art\u00edculo 7\u00ba de la Ley 906 de 2004.<\/em><strong>\u00a0<\/strong><\/p>\n\n<div class=\"twitter-share\"><a href=\"https:\/\/twitter.com\/intent\/tweet?via=fiscaliacol\" class=\"twitter-share-button\">Tweet<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Como presunto responsable del delito de actos sexuales con menor de 14 a\u00f1os de edad agravado, la Fiscal\u00eda General de la Naci\u00f3n obtuvo medida de aseguramiento en centro carcelario contra [&hellip;]<\/p>\n","protected":false},"author":177,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[1,318,303,24127],"tags":[20254,45,25012,31221,24185,31220],"class_list":["post-245616","post","type-post","status-publish","format-standard","category-noticias","category-seccional-antioquia","category-seccionales","category-violencia-sexual-e-intrafamiliar","tag-actos-sexuales-con-menor-de-14-anos-agravado","tag-cti","tag-cuerpo-tecnico-de-investigacion","tag-el-hombre-habria-exhibido-y-manipulado-su-miembro-viril-delante-de-su-sobrina","tag-fiscal-barbosa","tag-zona-rural-del-municipio-de-barbosa-antioquia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fiscal\u00eda General de la Naci\u00f3n<\/title>\n<meta name=\"description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-un-hombre-que-habria-exhibido-sus-partes-intimas-a-una-sobrina-menor-de-edad\/\" \/>\n<meta property=\"og:site_name\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FiscaliaCol\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-07T17:51:25+00:00\" \/>\n<meta name=\"author\" content=\"Jordan Leandro Oviedo Anzola\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:site\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jordan Leandro Oviedo Anzola\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-un-hombre-que-habria-exhibido-sus-partes-intimas-a-una-sobrina-menor-de-edad\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-un-hombre-que-habria-exhibido-sus-partes-intimas-a-una-sobrina-menor-de-edad\/\"},\"author\":{\"name\":\"Jordan Leandro Oviedo Anzola\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf84402cf293a5393e9c70b111020b24\"},\"headline\":\"A la c\u00e1rcel un hombre que habr\u00eda exhibido sus partes \u00edntimas a una sobrina, menor de edad\u00a0\",\"datePublished\":\"2022-04-07T17:51:25+00:00\",\"dateModified\":\"2022-04-07T17:51:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-un-hombre-que-habria-exhibido-sus-partes-intimas-a-una-sobrina-menor-de-edad\/\"},\"wordCount\":246,\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"keywords\":[\"actos sexuales con menor de 14 a\u00f1os agravado\",\"CTI\",\"cuerpo t\u00e9cnico de investigaci\u00f3n\",\"el hombre habr\u00eda exhibido y manipulado su miembro viril delante de su sobrina\",\"Fiscal Barbosa\",\"zona rural del municipio de Barbosa (Antioquia)\"],\"articleSection\":[\"Noticias\",\"Seccional Antioquia\",\"Seccionales\",\"Violencia sexual e intrafamiliar\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-un-hombre-que-habria-exhibido-sus-partes-intimas-a-una-sobrina-menor-de-edad\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-un-hombre-que-habria-exhibido-sus-partes-intimas-a-una-sobrina-menor-de-edad\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\"},\"datePublished\":\"2022-04-07T17:51:25+00:00\",\"dateModified\":\"2022-04-07T17:51:25+00:00\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-un-hombre-que-habria-exhibido-sus-partes-intimas-a-una-sobrina-menor-de-edad\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-un-hombre-que-habria-exhibido-sus-partes-intimas-a-una-sobrina-menor-de-edad\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-un-hombre-que-habria-exhibido-sus-partes-intimas-a-una-sobrina-menor-de-edad\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A la c\u00e1rcel un hombre que habr\u00eda exhibido sus partes \u00edntimas a una sobrina, menor de edad\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"contentUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"width\":300,\"height\":90,\"caption\":\"Fiscal\u00eda General de la Naci\u00f3n\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/FiscaliaCol\",\"https:\/\/x.com\/FiscaliaCol\",\"https:\/\/www.instagram.com\/fiscaliacol\",\"https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/\",\"https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf84402cf293a5393e9c70b111020b24\",\"name\":\"Jordan Leandro Oviedo Anzola\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/dabba4346fa9b9207d96adafa8f92721?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/dabba4346fa9b9207d96adafa8f92721?s=96&d=mm&r=g\",\"caption\":\"Jordan Leandro Oviedo Anzola\"},\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/author\/joviedo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Fiscal\u00eda General de la Naci\u00f3n","og_description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","og_url":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-un-hombre-que-habria-exhibido-sus-partes-intimas-a-una-sobrina-menor-de-edad\/","og_site_name":"Fiscal\u00eda General de la Naci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/FiscaliaCol","article_published_time":"2022-04-07T17:51:25+00:00","author":"Jordan Leandro Oviedo Anzola","twitter_card":"summary_large_image","twitter_creator":"@FiscaliaCol","twitter_site":"@FiscaliaCol","twitter_misc":{"Escrito por":"Jordan Leandro Oviedo Anzola","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-un-hombre-que-habria-exhibido-sus-partes-intimas-a-una-sobrina-menor-de-edad\/#article","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-un-hombre-que-habria-exhibido-sus-partes-intimas-a-una-sobrina-menor-de-edad\/"},"author":{"name":"Jordan Leandro Oviedo Anzola","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf84402cf293a5393e9c70b111020b24"},"headline":"A la c\u00e1rcel un hombre que habr\u00eda exhibido sus partes \u00edntimas a una sobrina, menor de edad\u00a0","datePublished":"2022-04-07T17:51:25+00:00","dateModified":"2022-04-07T17:51:25+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-un-hombre-que-habria-exhibido-sus-partes-intimas-a-una-sobrina-menor-de-edad\/"},"wordCount":246,"publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"keywords":["actos sexuales con menor de 14 a\u00f1os agravado","CTI","cuerpo t\u00e9cnico de investigaci\u00f3n","el hombre habr\u00eda exhibido y manipulado su miembro viril delante de su sobrina","Fiscal Barbosa","zona rural del municipio de Barbosa (Antioquia)"],"articleSection":["Noticias","Seccional Antioquia","Seccionales","Violencia sexual e intrafamiliar"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-un-hombre-que-habria-exhibido-sus-partes-intimas-a-una-sobrina-menor-de-edad\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-un-hombre-que-habria-exhibido-sus-partes-intimas-a-una-sobrina-menor-de-edad\/","name":"Fiscal\u00eda General de la Naci\u00f3n","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website"},"datePublished":"2022-04-07T17:51:25+00:00","dateModified":"2022-04-07T17:51:25+00:00","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","breadcrumb":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-un-hombre-que-habria-exhibido-sus-partes-intimas-a-una-sobrina-menor-de-edad\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-un-hombre-que-habria-exhibido-sus-partes-intimas-a-una-sobrina-menor-de-edad\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-un-hombre-que-habria-exhibido-sus-partes-intimas-a-una-sobrina-menor-de-edad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fiscalia.gov.co\/colombia\/"},{"@type":"ListItem","position":2,"name":"A la c\u00e1rcel un hombre que habr\u00eda exhibido sus partes \u00edntimas a una sobrina, menor de edad\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","name":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization","name":"Fiscal\u00eda General de la Naci\u00f3n","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","contentUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","width":300,"height":90,"caption":"Fiscal\u00eda General de la Naci\u00f3n"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FiscaliaCol","https:\/\/x.com\/FiscaliaCol","https:\/\/www.instagram.com\/fiscaliacol","https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/","https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh"]},{"@type":"Person","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf84402cf293a5393e9c70b111020b24","name":"Jordan Leandro Oviedo Anzola","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/dabba4346fa9b9207d96adafa8f92721?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dabba4346fa9b9207d96adafa8f92721?s=96&d=mm&r=g","caption":"Jordan Leandro Oviedo Anzola"},"url":"https:\/\/www.fiscalia.gov.co\/colombia\/author\/joviedo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/245616","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/users\/177"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/comments?post=245616"}],"version-history":[{"count":1,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/245616\/revisions"}],"predecessor-version":[{"id":245617,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/245616\/revisions\/245617"}],"wp:attachment":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/media?parent=245616"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/categories?post=245616"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/tags?post=245616"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}