{"id":245095,"date":"2022-04-01T16:20:23","date_gmt":"2022-04-01T21:20:23","guid":{"rendered":"https:\/\/www.fiscalia.gov.co\/colombia\/?p=245095"},"modified":"2022-04-01T16:20:23","modified_gmt":"2022-04-01T21:20:23","slug":"un-hombre-fue-privado-de-la-libertad-por-presuntas-agresiones-fisicas-y-verbales-a-su-ex-pareja-sentimental","status":"publish","type":"post","link":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/un-hombre-fue-privado-de-la-libertad-por-presuntas-agresiones-fisicas-y-verbales-a-su-ex-pareja-sentimental\/","title":{"rendered":"Un hombre fue privado de la libertad por presuntas agresiones f\u00edsicas y verbales a su ex pareja sentimental"},"content":{"rendered":"<p style=\"font-weight: 400;\">Acogiendo la solicitud de un fiscal del Centro de Atenci\u00f3n a V\u00edctimas de Violencia Intrafamiliar, un juez de garant\u00edas impuso <strong>medida restrictiva de la libertad en centro de reclusi\u00f3n<\/strong>\u00a0contra Jorge Alberto Morales \u00d1uste, de 23 a\u00f1os de edad.<\/p>\n<figure id=\"attachment_245096\" aria-describedby=\"caption-attachment-245096\" style=\"width: 696px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-245096\" src=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Fiscal-Francisco-Barbosa_Jorge-Alberto-Morales-N\u00deuste-1024x927.jpeg\" alt=\"\" width=\"696\" height=\"630\" srcset=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Fiscal-Francisco-Barbosa_Jorge-Alberto-Morales-N\u00deuste-1024x927.jpeg 1024w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Fiscal-Francisco-Barbosa_Jorge-Alberto-Morales-N\u00deuste-300x272.jpeg 300w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Fiscal-Francisco-Barbosa_Jorge-Alberto-Morales-N\u00deuste-768x695.jpeg 768w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Fiscal-Francisco-Barbosa_Jorge-Alberto-Morales-N\u00deuste-696x630.jpeg 696w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Fiscal-Francisco-Barbosa_Jorge-Alberto-Morales-N\u00deuste-1068x967.jpeg 1068w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Fiscal-Francisco-Barbosa_Jorge-Alberto-Morales-N\u00deuste-464x420.jpeg 464w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Fiscal-Francisco-Barbosa_Jorge-Alberto-Morales-N\u00deuste.jpeg 1280w\" sizes=\"auto, (max-width: 696px) 100vw, 696px\" \/><figcaption id=\"caption-attachment-245096\" class=\"wp-caption-text\">El procesado le habr\u00eda\u00a0 causado una fractura nasal a la v\u00edctima, quien\u00a0recibi\u00f3 incapacidad de 25 d\u00edas\u00a0por fractura nasal\u00a0con\u00a0riesgo extremo.<\/figcaption><\/figure>\n<p style=\"font-weight: 400;\">El 6 de octubre de 2021, al parecer\u00a0<strong>agredi\u00f3 de manera\u00a0f\u00edsica y verbal a su ex pareja sentimental<\/strong>\u00a0en un establecimiento comercial en el barrio Santa In\u00e9s de Neiva.<\/p>\n<p style=\"font-weight: 400;\">Luego de que un amigo del acusado le preguntara por la v\u00edctima, el indiciado se habr\u00eda\u00a0<strong>acercado a la mujer a pegarle<\/strong>.<\/p>\n<p style=\"font-weight: 400;\">Despu\u00e9s la habr\u00eda seguido agrediendo\u00a0<strong>m\u00e1s de cuatro veces\u00a0el mismo d\u00eda<\/strong>, propin\u00e1ndole pu\u00f1os, patadas, mordiscos,\u00a0<strong>caus\u00e1ndole\u00a0 hemorragia conjuntiva en el ojo izquierdo y hematomas.\u00a0\u00a0<\/strong><\/p>\n<p style=\"font-weight: 400;\">Ese d\u00eda el agresor al parecer se\u00a0<strong>apropi\u00f3 de algunas de sus pertenencias<\/strong>, entre esas las llaves de la casa de la afectada,\u00a0\u00a0pero unas personas que\u00a0\u00a0se bajaron de un taxi,\u00a0\u00a0la auxiliaron por lo que tuvo que devolv\u00e9rselas junto con un dinero que le hab\u00eda hurtado.<\/p>\n<p style=\"font-weight: 400;\">La v\u00edctima fue valorada por Medicina Legal que\u00a0le dictamin\u00f3 una incapacidad de 20 d\u00edas. Dentro de una nueva agresi\u00f3n, la v\u00edctima fue valorada nuevamente y se\u00a0<strong>dictamin\u00f3\u00a0incapacidad provisional de 25 d\u00edas\u00a0por fractura nasal\u00a0con\u00a0riesgo extremo<\/strong>\u00a0de sufrir lesiones muy graves o incluso la muerte.<\/p>\n<p style=\"font-weight: 400;\">La Fiscal\u00eda lo acus\u00f3 por el delito de\u00a0<strong>violencia intrafamiliar agravada en concurso homog\u00e9neo y sucesivo. No acept\u00f3 cargos.\u00a0\u00a0<\/strong><\/p>\n<p style=\"font-weight: 400;\">La captura de Morales \u00d1uste\u00a0la efectu\u00f3 personal del CTI en conjunto con Polic\u00eda Nacional y Gaula Militar en v\u00eda p\u00fablica del barrio Los Guaduales de Neiva(Huila) el pasado 30 de marzo.<\/p>\n<p style=\"font-weight: 400;\">La Fiscal\u00eda publica esta informaci\u00f3n por razones de inter\u00e9s general.<\/p>\n<p style=\"font-weight: 400;\">\n<p>&nbsp;<\/p>\n<p style=\"font-weight: 400;\">DSH\/LMGM\/CFG\/DSPB<\/p>\n<p style=\"font-weight: 400;\">\n<p>&nbsp;<\/p>\n<p style=\"font-weight: 400;\"><em>La informaci\u00f3n contenida en este bolet\u00edn\u00a0de\u00a0prensa corresponde a la narraci\u00f3n\u00a0de\u00a0los hechos noticiosos objetivos, suministrados por los funcionarios encargados\u00a0de\u00a0adelantar las investigaciones penales al interior\u00a0de\u00a0la Fiscal\u00eda General\u00a0de\u00a0la Naci\u00f3n. Para el momento\u00a0de\u00a0la divulgaci\u00f3n\u00a0de\u00a0este comunicado, la situaci\u00f3n jur\u00eddica\u00a0de\u00a0la(s) persona(s) relacionada(s) se encuentra pendiente\u00a0de\u00a0resolver por la autoridad judicial competente, siempre bajo los preceptos\u00a0de\u00a0la presunci\u00f3n\u00a0de\u00a0inocencia, consagrados en el art\u00edculo 29\u00a0de\u00a0la Constituci\u00f3n Pol\u00edtica y el art\u00edculo 7\u00ba\u00a0de\u00a0la Ley 906\u00a0de\u00a02004.<\/em><\/p>\n\n<div class=\"twitter-share\"><a href=\"https:\/\/twitter.com\/intent\/tweet?via=fiscaliacol\" class=\"twitter-share-button\">Tweet<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Acogiendo la solicitud de un fiscal del Centro de Atenci\u00f3n a V\u00edctimas de Violencia Intrafamiliar, un juez de garant\u00edas impuso medida restrictiva de la libertad en centro de reclusi\u00f3n\u00a0contra Jorge [&hellip;]<\/p>\n","protected":false},"author":177,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[1,333,303,24127],"tags":[25068,24185,31116,1064,31115,16,27851,23833,31117,682],"class_list":["post-245095","post","type-post","status-publish","format-standard","category-noticias","category-seccional-neiva","category-seccionales","category-violencia-sexual-e-intrafamiliar","tag-ex-pareja-sentimental","tag-fiscal-barbosa","tag-fractura-nasal","tag-golpes","tag-hematomas","tag-huila","tag-incapacidad-medico-legal","tag-neiva","tag-riesgo-extremo","tag-violencia-intrafamiliar"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fiscal\u00eda General de la Naci\u00f3n<\/title>\n<meta name=\"description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/un-hombre-fue-privado-de-la-libertad-por-presuntas-agresiones-fisicas-y-verbales-a-su-ex-pareja-sentimental\/\" \/>\n<meta property=\"og:site_name\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FiscaliaCol\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-01T21:20:23+00:00\" \/>\n<meta name=\"author\" content=\"Jordan Leandro Oviedo Anzola\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:site\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jordan Leandro Oviedo Anzola\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/un-hombre-fue-privado-de-la-libertad-por-presuntas-agresiones-fisicas-y-verbales-a-su-ex-pareja-sentimental\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/un-hombre-fue-privado-de-la-libertad-por-presuntas-agresiones-fisicas-y-verbales-a-su-ex-pareja-sentimental\/\"},\"author\":{\"name\":\"Jordan Leandro Oviedo Anzola\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf84402cf293a5393e9c70b111020b24\"},\"headline\":\"Un hombre fue privado de la libertad por presuntas agresiones f\u00edsicas y verbales a su ex pareja sentimental\",\"datePublished\":\"2022-04-01T21:20:23+00:00\",\"dateModified\":\"2022-04-01T21:20:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/un-hombre-fue-privado-de-la-libertad-por-presuntas-agresiones-fisicas-y-verbales-a-su-ex-pareja-sentimental\/\"},\"wordCount\":459,\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"keywords\":[\"ex pareja sentimental\",\"Fiscal Barbosa\",\"fractura nasal\",\"Golpes\",\"hematomas\",\"Huila\",\"incapacidad m\u00e9dico legal\",\"Neiva\",\"riesgo extremo\",\"Violencia intrafamiliar\"],\"articleSection\":[\"Noticias\",\"Seccional Neiva\",\"Seccionales\",\"Violencia sexual e intrafamiliar\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/un-hombre-fue-privado-de-la-libertad-por-presuntas-agresiones-fisicas-y-verbales-a-su-ex-pareja-sentimental\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/un-hombre-fue-privado-de-la-libertad-por-presuntas-agresiones-fisicas-y-verbales-a-su-ex-pareja-sentimental\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\"},\"datePublished\":\"2022-04-01T21:20:23+00:00\",\"dateModified\":\"2022-04-01T21:20:23+00:00\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/un-hombre-fue-privado-de-la-libertad-por-presuntas-agresiones-fisicas-y-verbales-a-su-ex-pareja-sentimental\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/un-hombre-fue-privado-de-la-libertad-por-presuntas-agresiones-fisicas-y-verbales-a-su-ex-pareja-sentimental\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/un-hombre-fue-privado-de-la-libertad-por-presuntas-agresiones-fisicas-y-verbales-a-su-ex-pareja-sentimental\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un hombre fue privado de la libertad por presuntas agresiones f\u00edsicas y verbales a su ex pareja sentimental\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"contentUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"width\":300,\"height\":90,\"caption\":\"Fiscal\u00eda General de la Naci\u00f3n\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/FiscaliaCol\",\"https:\/\/x.com\/FiscaliaCol\",\"https:\/\/www.instagram.com\/fiscaliacol\",\"https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/\",\"https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf84402cf293a5393e9c70b111020b24\",\"name\":\"Jordan Leandro Oviedo Anzola\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/dabba4346fa9b9207d96adafa8f92721?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/dabba4346fa9b9207d96adafa8f92721?s=96&d=mm&r=g\",\"caption\":\"Jordan Leandro Oviedo Anzola\"},\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/author\/joviedo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Fiscal\u00eda General de la Naci\u00f3n","og_description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","og_url":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/un-hombre-fue-privado-de-la-libertad-por-presuntas-agresiones-fisicas-y-verbales-a-su-ex-pareja-sentimental\/","og_site_name":"Fiscal\u00eda General de la Naci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/FiscaliaCol","article_published_time":"2022-04-01T21:20:23+00:00","author":"Jordan Leandro Oviedo Anzola","twitter_card":"summary_large_image","twitter_creator":"@FiscaliaCol","twitter_site":"@FiscaliaCol","twitter_misc":{"Escrito por":"Jordan Leandro Oviedo Anzola","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/un-hombre-fue-privado-de-la-libertad-por-presuntas-agresiones-fisicas-y-verbales-a-su-ex-pareja-sentimental\/#article","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/un-hombre-fue-privado-de-la-libertad-por-presuntas-agresiones-fisicas-y-verbales-a-su-ex-pareja-sentimental\/"},"author":{"name":"Jordan Leandro Oviedo Anzola","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf84402cf293a5393e9c70b111020b24"},"headline":"Un hombre fue privado de la libertad por presuntas agresiones f\u00edsicas y verbales a su ex pareja sentimental","datePublished":"2022-04-01T21:20:23+00:00","dateModified":"2022-04-01T21:20:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/un-hombre-fue-privado-de-la-libertad-por-presuntas-agresiones-fisicas-y-verbales-a-su-ex-pareja-sentimental\/"},"wordCount":459,"publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"keywords":["ex pareja sentimental","Fiscal Barbosa","fractura nasal","Golpes","hematomas","Huila","incapacidad m\u00e9dico legal","Neiva","riesgo extremo","Violencia intrafamiliar"],"articleSection":["Noticias","Seccional Neiva","Seccionales","Violencia sexual e intrafamiliar"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/un-hombre-fue-privado-de-la-libertad-por-presuntas-agresiones-fisicas-y-verbales-a-su-ex-pareja-sentimental\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/un-hombre-fue-privado-de-la-libertad-por-presuntas-agresiones-fisicas-y-verbales-a-su-ex-pareja-sentimental\/","name":"Fiscal\u00eda General de la Naci\u00f3n","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website"},"datePublished":"2022-04-01T21:20:23+00:00","dateModified":"2022-04-01T21:20:23+00:00","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","breadcrumb":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/un-hombre-fue-privado-de-la-libertad-por-presuntas-agresiones-fisicas-y-verbales-a-su-ex-pareja-sentimental\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/un-hombre-fue-privado-de-la-libertad-por-presuntas-agresiones-fisicas-y-verbales-a-su-ex-pareja-sentimental\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/un-hombre-fue-privado-de-la-libertad-por-presuntas-agresiones-fisicas-y-verbales-a-su-ex-pareja-sentimental\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fiscalia.gov.co\/colombia\/"},{"@type":"ListItem","position":2,"name":"Un hombre fue privado de la libertad por presuntas agresiones f\u00edsicas y verbales a su ex pareja sentimental"}]},{"@type":"WebSite","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","name":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization","name":"Fiscal\u00eda General de la Naci\u00f3n","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","contentUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","width":300,"height":90,"caption":"Fiscal\u00eda General de la Naci\u00f3n"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FiscaliaCol","https:\/\/x.com\/FiscaliaCol","https:\/\/www.instagram.com\/fiscaliacol","https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/","https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh"]},{"@type":"Person","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf84402cf293a5393e9c70b111020b24","name":"Jordan Leandro Oviedo Anzola","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/dabba4346fa9b9207d96adafa8f92721?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dabba4346fa9b9207d96adafa8f92721?s=96&d=mm&r=g","caption":"Jordan Leandro Oviedo Anzola"},"url":"https:\/\/www.fiscalia.gov.co\/colombia\/author\/joviedo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/245095","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/users\/177"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/comments?post=245095"}],"version-history":[{"count":1,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/245095\/revisions"}],"predecessor-version":[{"id":245097,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/245095\/revisions\/245097"}],"wp:attachment":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/media?parent=245095"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/categories?post=245095"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/tags?post=245095"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}