{"id":244854,"date":"2022-03-30T15:00:24","date_gmt":"2022-03-30T20:00:24","guid":{"rendered":"https:\/\/www.fiscalia.gov.co\/colombia\/?p=244854"},"modified":"2022-03-30T15:00:24","modified_gmt":"2022-03-30T20:00:24","slug":"asegurados-presuntos-integrantes-de-los-centrales-por-venta-de-estupefacientes-en-dos-municipios-de-putumayo","status":"publish","type":"post","link":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurados-presuntos-integrantes-de-los-centrales-por-venta-de-estupefacientes-en-dos-municipios-de-putumayo\/","title":{"rendered":"Asegurados presuntos integrantes de Los Centrales por venta de estupefacientes en dos municipios de Putumayo"},"content":{"rendered":"<p>La Fiscal\u00eda present\u00f3 ante un juez con funci\u00f3n de control de garant\u00edas a siete personas que integrar\u00edan el\u00a0<strong>grupo delincuencial Los Centrales<\/strong>, quienes fueron aseguradas con\u00a0<strong>medida privativa de la libertad<\/strong>\u00a0como presuntos responsables del delito de\u00a0<strong>tr\u00e1fico, fabricaci\u00f3n o porte de estupefacientes.\u00a0\u00a0<\/strong><\/p>\n<figure id=\"attachment_244855\" aria-describedby=\"caption-attachment-244855\" style=\"width: 696px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-244855\" src=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Fiscal-Francisco-Barbosa-_Los-capturados-al-parecer-comercializaban-sustancias-estupefacientes-a-domicilio-desde-distintos-barrios-de-los-municipios-de-San-Miguel-y-Valle-del-Guamuez-Putumayo.-1024x661.jpeg\" alt=\"\" width=\"696\" height=\"449\" srcset=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Fiscal-Francisco-Barbosa-_Los-capturados-al-parecer-comercializaban-sustancias-estupefacientes-a-domicilio-desde-distintos-barrios-de-los-municipios-de-San-Miguel-y-Valle-del-Guamuez-Putumayo.-1024x661.jpeg 1024w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Fiscal-Francisco-Barbosa-_Los-capturados-al-parecer-comercializaban-sustancias-estupefacientes-a-domicilio-desde-distintos-barrios-de-los-municipios-de-San-Miguel-y-Valle-del-Guamuez-Putumayo.-300x194.jpeg 300w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Fiscal-Francisco-Barbosa-_Los-capturados-al-parecer-comercializaban-sustancias-estupefacientes-a-domicilio-desde-distintos-barrios-de-los-municipios-de-San-Miguel-y-Valle-del-Guamuez-Putumayo.-768x496.jpeg 768w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Fiscal-Francisco-Barbosa-_Los-capturados-al-parecer-comercializaban-sustancias-estupefacientes-a-domicilio-desde-distintos-barrios-de-los-municipios-de-San-Miguel-y-Valle-del-Guamuez-Putumayo.-696x449.jpeg 696w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Fiscal-Francisco-Barbosa-_Los-capturados-al-parecer-comercializaban-sustancias-estupefacientes-a-domicilio-desde-distintos-barrios-de-los-municipios-de-San-Miguel-y-Valle-del-Guamuez-Putumayo.-1068x689.jpeg 1068w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Fiscal-Francisco-Barbosa-_Los-capturados-al-parecer-comercializaban-sustancias-estupefacientes-a-domicilio-desde-distintos-barrios-de-los-municipios-de-San-Miguel-y-Valle-del-Guamuez-Putumayo.-651x420.jpeg 651w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Fiscal-Francisco-Barbosa-_Los-capturados-al-parecer-comercializaban-sustancias-estupefacientes-a-domicilio-desde-distintos-barrios-de-los-municipios-de-San-Miguel-y-Valle-del-Guamuez-Putumayo..jpeg 1280w\" sizes=\"auto, (max-width: 696px) 100vw, 696px\" \/><figcaption id=\"caption-attachment-244855\" class=\"wp-caption-text\">Los capturados al parecer comercializaban sustancias estupefacientes a domicilio desde distintos barrios de los municipios de San Miguel y Valle del Guamuez (Putumayo).<\/figcaption><\/figure>\n<p>La investigaci\u00f3n da cuenta que desde 2020, los judicializados estar\u00edan\u00a0<strong>dedicados a la comercializaci\u00f3n\u00a0\u00a0de\u00a0\u00a0sustancias de estupefacientes,<\/strong>\u00a0\u00a0que al parecer expenden\u00a0<strong>desde sus lugares de residencia y a domicilio<\/strong>\u00a0en diferentes barrios de San Miguel y Valle del Guamuez (Putumayo).<\/p>\n<p>Miembros de la Sij\u00edn\u00a0\u00a0realizaron\u00a0<strong>cuatro diligencias de allanamiento y registro<\/strong>\u00a0en los inmuebles donde se materializaron las capturas de los procesados en los barrios\u00a0<strong>Central en\u00a0el municipio de San Miguel y Divino Ni\u00f1o, 30 de Octubre y Las Am\u00e9ricas<\/strong>\u00a0<strong>en Valle del Guamuez (Putumayo)<\/strong>. All\u00ed se encontraron sustancias estupefacientes como marihuana, coca\u00edna y dinero en efectivo.<\/p>\n<p><strong>Los judicializados:\u00a0<\/strong><\/p>\n<p><strong>Con medida en centro carcelario\u00a0\u00a0<\/strong><\/p>\n<p>Arley Alejandro Guerra David<\/p>\n<p>Jaunier Alberto L\u00f3pez Valencia<\/p>\n<p>H\u00e9ctor Andr\u00e9s Londo\u00f1o Ram\u00edrez<\/p>\n<p>Carlos Edilson Calder\u00f3n Cuar\u00e1n<\/p>\n<p>Mauricio Renter\u00eda Renter\u00eda<\/p>\n<p><strong>Con medida en lugar de residencia\u00a0<\/strong><\/p>\n<p>Aura Estela Villamar\u00edn Villacorte (\u00fanica que acept\u00f3 cargos)<\/p>\n<p>Carlos Arturo Villota Erazo<\/p>\n<p>La Fiscal\u00eda publica esta informaci\u00f3n por razones de inter\u00e9s general.<\/p>\n<p><strong>Tambi\u00e9n le puede interesar:\u00a0\u00a0\u00a0<\/strong><strong><a href=\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-judicializo-a-11-presuntos-integrantes-de-la-banda-los-topos-al-parecer-esponsable-de-homicidios-tentativas-de-homicidio-y-comercializacion-de-estupefacientes\/\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-judicializo-a-11-presuntos-integrantes-de-la-banda-los-topos-al-parecer-esponsable-de-homicidios-tentativas-de-homicidio-y-comercializacion-de-estupefacientes\/&amp;source=gmail&amp;ust=1648756473274000&amp;usg=AOvVaw2mQFnMUNmU0RfzEGXU_VGF\">Fiscal\u00eda judicializ\u00f3 a 11 presuntos integrantes de la banda Los Topos, al parecer responsable de homicidios, tentativas de homicidio y comercializaci\u00f3n de estupefacientes<\/a><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>DSP\/LMGM\/CFG\/GRM<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><em>La informaci\u00f3n contenida en este bolet\u00edn de prensa corresponde a la narraci\u00f3n de los hechos noticiosos objetivos, suministrados por los funcionarios encargados de adelantar las investigaciones penales al interior de la Fiscal\u00eda General de la Naci\u00f3n. Para el momento de la divulgaci\u00f3n de este comunicado, la situaci\u00f3n jur\u00eddica de la(s) persona(s) relacionada(s) se encuentra pendiente de resolver por la autoridad judicial competente, siempre bajo los preceptos de la presunci\u00f3n de inocencia, consagrados en el art\u00edculo 29 de la Constituci\u00f3n Pol\u00edtica y el art\u00edculo 7\u00ba de la Ley 906 de 2004.\u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/em><\/p>\n\n<div class=\"twitter-share\"><a href=\"https:\/\/twitter.com\/intent\/tweet?via=fiscaliacol\" class=\"twitter-share-button\">Tweet<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La Fiscal\u00eda present\u00f3 ante un juez con funci\u00f3n de control de garant\u00edas a siete personas que integrar\u00edan el\u00a0grupo delincuencial Los Centrales, quienes fueron aseguradas con\u00a0medida privativa de la libertad\u00a0como presuntos [&hellip;]<\/p>\n","protected":false},"author":177,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[1,2910,303,24103],"tags":[19,12799,26474,1264,674,2279,28952,11101,27867],"class_list":["post-244854","post","type-post","status-publish","format-standard","category-noticias","category-seccional-mocoa","category-seccionales","category-trafico-de-estupefacientes","tag-cocaina","tag-comercializacion","tag-domicilio","tag-marihuana","tag-microtrafico","tag-putumayo","tag-san-miguel","tag-seguridad-ciudadana","tag-valle-del-guamuez"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fiscal\u00eda General de la Naci\u00f3n<\/title>\n<meta name=\"description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurados-presuntos-integrantes-de-los-centrales-por-venta-de-estupefacientes-en-dos-municipios-de-putumayo\/\" \/>\n<meta property=\"og:site_name\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FiscaliaCol\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-30T20:00:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Fiscal-Francisco-Barbosa-_Los-capturados-al-parecer-comercializaban-sustancias-estupefacientes-a-domicilio-desde-distintos-barrios-de-los-municipios-de-San-Miguel-y-Valle-del-Guamuez-Putumayo.-1024x661.jpeg\" \/>\n<meta name=\"author\" content=\"Jordan Leandro Oviedo Anzola\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:site\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jordan Leandro Oviedo Anzola\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurados-presuntos-integrantes-de-los-centrales-por-venta-de-estupefacientes-en-dos-municipios-de-putumayo\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurados-presuntos-integrantes-de-los-centrales-por-venta-de-estupefacientes-en-dos-municipios-de-putumayo\/\"},\"author\":{\"name\":\"Jordan Leandro Oviedo Anzola\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf84402cf293a5393e9c70b111020b24\"},\"headline\":\"Asegurados presuntos integrantes de Los Centrales por venta de estupefacientes en dos municipios de Putumayo\",\"datePublished\":\"2022-03-30T20:00:24+00:00\",\"dateModified\":\"2022-03-30T20:00:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurados-presuntos-integrantes-de-los-centrales-por-venta-de-estupefacientes-en-dos-municipios-de-putumayo\/\"},\"wordCount\":404,\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurados-presuntos-integrantes-de-los-centrales-por-venta-de-estupefacientes-en-dos-municipios-de-putumayo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Fiscal-Francisco-Barbosa-_Los-capturados-al-parecer-comercializaban-sustancias-estupefacientes-a-domicilio-desde-distintos-barrios-de-los-municipios-de-San-Miguel-y-Valle-del-Guamuez-Putumayo.-1024x661.jpeg\",\"keywords\":[\"Coca\u00edna\",\"Comercializaci\u00f3n\",\"domicilio\",\"Marihuana\",\"Microtr\u00e1fico\",\"Putumayo\",\"San Miguel\",\"Seguridad ciudadana\",\"Valle del Guamuez\"],\"articleSection\":[\"Noticias\",\"Seccional Mocoa\",\"Seccionales\",\"Tr\u00e1fico de estupefacientes\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurados-presuntos-integrantes-de-los-centrales-por-venta-de-estupefacientes-en-dos-municipios-de-putumayo\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurados-presuntos-integrantes-de-los-centrales-por-venta-de-estupefacientes-en-dos-municipios-de-putumayo\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurados-presuntos-integrantes-de-los-centrales-por-venta-de-estupefacientes-en-dos-municipios-de-putumayo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurados-presuntos-integrantes-de-los-centrales-por-venta-de-estupefacientes-en-dos-municipios-de-putumayo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Fiscal-Francisco-Barbosa-_Los-capturados-al-parecer-comercializaban-sustancias-estupefacientes-a-domicilio-desde-distintos-barrios-de-los-municipios-de-San-Miguel-y-Valle-del-Guamuez-Putumayo.-1024x661.jpeg\",\"datePublished\":\"2022-03-30T20:00:24+00:00\",\"dateModified\":\"2022-03-30T20:00:24+00:00\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurados-presuntos-integrantes-de-los-centrales-por-venta-de-estupefacientes-en-dos-municipios-de-putumayo\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurados-presuntos-integrantes-de-los-centrales-por-venta-de-estupefacientes-en-dos-municipios-de-putumayo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurados-presuntos-integrantes-de-los-centrales-por-venta-de-estupefacientes-en-dos-municipios-de-putumayo\/#primaryimage\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Fiscal-Francisco-Barbosa-_Los-capturados-al-parecer-comercializaban-sustancias-estupefacientes-a-domicilio-desde-distintos-barrios-de-los-municipios-de-San-Miguel-y-Valle-del-Guamuez-Putumayo.-1024x661.jpeg\",\"contentUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Fiscal-Francisco-Barbosa-_Los-capturados-al-parecer-comercializaban-sustancias-estupefacientes-a-domicilio-desde-distintos-barrios-de-los-municipios-de-San-Miguel-y-Valle-del-Guamuez-Putumayo.-1024x661.jpeg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurados-presuntos-integrantes-de-los-centrales-por-venta-de-estupefacientes-en-dos-municipios-de-putumayo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Asegurados presuntos integrantes de Los Centrales por venta de estupefacientes en dos municipios de Putumayo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"contentUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"width\":300,\"height\":90,\"caption\":\"Fiscal\u00eda General de la Naci\u00f3n\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/FiscaliaCol\",\"https:\/\/x.com\/FiscaliaCol\",\"https:\/\/www.instagram.com\/fiscaliacol\",\"https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/\",\"https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf84402cf293a5393e9c70b111020b24\",\"name\":\"Jordan Leandro Oviedo Anzola\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/dabba4346fa9b9207d96adafa8f92721?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/dabba4346fa9b9207d96adafa8f92721?s=96&d=mm&r=g\",\"caption\":\"Jordan Leandro Oviedo Anzola\"},\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/author\/joviedo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Fiscal\u00eda General de la Naci\u00f3n","og_description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","og_url":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurados-presuntos-integrantes-de-los-centrales-por-venta-de-estupefacientes-en-dos-municipios-de-putumayo\/","og_site_name":"Fiscal\u00eda General de la Naci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/FiscaliaCol","article_published_time":"2022-03-30T20:00:24+00:00","og_image":[{"url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Fiscal-Francisco-Barbosa-_Los-capturados-al-parecer-comercializaban-sustancias-estupefacientes-a-domicilio-desde-distintos-barrios-de-los-municipios-de-San-Miguel-y-Valle-del-Guamuez-Putumayo.-1024x661.jpeg","type":"","width":"","height":""}],"author":"Jordan Leandro Oviedo Anzola","twitter_card":"summary_large_image","twitter_creator":"@FiscaliaCol","twitter_site":"@FiscaliaCol","twitter_misc":{"Escrito por":"Jordan Leandro Oviedo Anzola","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurados-presuntos-integrantes-de-los-centrales-por-venta-de-estupefacientes-en-dos-municipios-de-putumayo\/#article","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurados-presuntos-integrantes-de-los-centrales-por-venta-de-estupefacientes-en-dos-municipios-de-putumayo\/"},"author":{"name":"Jordan Leandro Oviedo Anzola","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf84402cf293a5393e9c70b111020b24"},"headline":"Asegurados presuntos integrantes de Los Centrales por venta de estupefacientes en dos municipios de Putumayo","datePublished":"2022-03-30T20:00:24+00:00","dateModified":"2022-03-30T20:00:24+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurados-presuntos-integrantes-de-los-centrales-por-venta-de-estupefacientes-en-dos-municipios-de-putumayo\/"},"wordCount":404,"publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurados-presuntos-integrantes-de-los-centrales-por-venta-de-estupefacientes-en-dos-municipios-de-putumayo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Fiscal-Francisco-Barbosa-_Los-capturados-al-parecer-comercializaban-sustancias-estupefacientes-a-domicilio-desde-distintos-barrios-de-los-municipios-de-San-Miguel-y-Valle-del-Guamuez-Putumayo.-1024x661.jpeg","keywords":["Coca\u00edna","Comercializaci\u00f3n","domicilio","Marihuana","Microtr\u00e1fico","Putumayo","San Miguel","Seguridad ciudadana","Valle del Guamuez"],"articleSection":["Noticias","Seccional Mocoa","Seccionales","Tr\u00e1fico de estupefacientes"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurados-presuntos-integrantes-de-los-centrales-por-venta-de-estupefacientes-en-dos-municipios-de-putumayo\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurados-presuntos-integrantes-de-los-centrales-por-venta-de-estupefacientes-en-dos-municipios-de-putumayo\/","name":"Fiscal\u00eda General de la Naci\u00f3n","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurados-presuntos-integrantes-de-los-centrales-por-venta-de-estupefacientes-en-dos-municipios-de-putumayo\/#primaryimage"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurados-presuntos-integrantes-de-los-centrales-por-venta-de-estupefacientes-en-dos-municipios-de-putumayo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Fiscal-Francisco-Barbosa-_Los-capturados-al-parecer-comercializaban-sustancias-estupefacientes-a-domicilio-desde-distintos-barrios-de-los-municipios-de-San-Miguel-y-Valle-del-Guamuez-Putumayo.-1024x661.jpeg","datePublished":"2022-03-30T20:00:24+00:00","dateModified":"2022-03-30T20:00:24+00:00","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","breadcrumb":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurados-presuntos-integrantes-de-los-centrales-por-venta-de-estupefacientes-en-dos-municipios-de-putumayo\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurados-presuntos-integrantes-de-los-centrales-por-venta-de-estupefacientes-en-dos-municipios-de-putumayo\/"]}]},{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurados-presuntos-integrantes-de-los-centrales-por-venta-de-estupefacientes-en-dos-municipios-de-putumayo\/#primaryimage","url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Fiscal-Francisco-Barbosa-_Los-capturados-al-parecer-comercializaban-sustancias-estupefacientes-a-domicilio-desde-distintos-barrios-de-los-municipios-de-San-Miguel-y-Valle-del-Guamuez-Putumayo.-1024x661.jpeg","contentUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Fiscal-Francisco-Barbosa-_Los-capturados-al-parecer-comercializaban-sustancias-estupefacientes-a-domicilio-desde-distintos-barrios-de-los-municipios-de-San-Miguel-y-Valle-del-Guamuez-Putumayo.-1024x661.jpeg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/asegurados-presuntos-integrantes-de-los-centrales-por-venta-de-estupefacientes-en-dos-municipios-de-putumayo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fiscalia.gov.co\/colombia\/"},{"@type":"ListItem","position":2,"name":"Asegurados presuntos integrantes de Los Centrales por venta de estupefacientes en dos municipios de Putumayo"}]},{"@type":"WebSite","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","name":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization","name":"Fiscal\u00eda General de la Naci\u00f3n","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","contentUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","width":300,"height":90,"caption":"Fiscal\u00eda General de la Naci\u00f3n"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FiscaliaCol","https:\/\/x.com\/FiscaliaCol","https:\/\/www.instagram.com\/fiscaliacol","https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/","https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh"]},{"@type":"Person","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf84402cf293a5393e9c70b111020b24","name":"Jordan Leandro Oviedo Anzola","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/dabba4346fa9b9207d96adafa8f92721?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dabba4346fa9b9207d96adafa8f92721?s=96&d=mm&r=g","caption":"Jordan Leandro Oviedo Anzola"},"url":"https:\/\/www.fiscalia.gov.co\/colombia\/author\/joviedo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/244854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/users\/177"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/comments?post=244854"}],"version-history":[{"count":1,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/244854\/revisions"}],"predecessor-version":[{"id":244856,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/244854\/revisions\/244856"}],"wp:attachment":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/media?parent=244854"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/categories?post=244854"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/tags?post=244854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}