{"id":244607,"date":"2022-03-28T15:34:52","date_gmt":"2022-03-28T20:34:52","guid":{"rendered":"https:\/\/www.fiscalia.gov.co\/colombia\/?p=244607"},"modified":"2022-03-28T15:34:52","modified_gmt":"2022-03-28T20:34:52","slug":"a-19-anos-de-prision-fue-condenado-un-hombre-que-abuso-sexualmente-de-dos-menores-de-edad","status":"publish","type":"post","link":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-19-anos-de-prision-fue-condenado-un-hombre-que-abuso-sexualmente-de-dos-menores-de-edad\/","title":{"rendered":"A 19 a\u00f1os de prisi\u00f3n fue condenado un hombre que abus\u00f3 sexualmente de dos menores de edad"},"content":{"rendered":"<h4 style=\"font-weight: 400;\"><strong><em>El sentenciado entregaba a las v\u00edctimas celulares o dinero en efectivo para que sostuvieran relaciones \u00edntimas con \u00e9l.<\/em><\/strong><\/h4>\n<p style=\"font-weight: 400;\">Por solicitud de la Fiscal\u00eda General de la Naci\u00f3n, un juez penal del circuito de Itag\u00fc\u00ed (Antioquia) conden\u00f3 a 19 a\u00f1os de prisi\u00f3n a David Augusto Hurtado Suaza, de 50 a\u00f1os de edad, responsable de incurrir en los delitos de acceso carnal abusivo con menor de 14 a\u00f1os, actos sexuales con menor de 14 a\u00f1os, demanda de explotaci\u00f3n sexual comercial con personas menores de 18 a\u00f1os y utilizaci\u00f3n de menores, todas las conductas en concurso homog\u00e9neo y sucesivo.<\/p>\n<p style=\"font-weight: 400;\">De acuerdo con la investigaci\u00f3n, adelantada por un fiscal del Centro de Atenci\u00f3n Integral a V\u00edctimas de Abuso Sexual (Caivas), entre el 20 de diciembre de 2019 y el 19 de enero de 2020 el procesado abus\u00f3 sexualmente de dos menores de 12 a\u00f1os en su casa, ubicada en la vereda Los G\u00f3mez del municipio de Itag\u00fc\u00ed, sur del Valle de Aburr\u00e1.<\/p>\n<p style=\"font-weight: 400;\">Seg\u00fan las indagaciones adelantadas, el implicado manipul\u00f3 a los menores de edad con la entrega de regalos como celulares y sumas de dinero en efectivo que oscilaban entre\u00a0\u00a0200 y 450 mil pesos, para que sostuvieran relaciones sexuales.<\/p>\n<p style=\"font-weight: 400;\">En desarrollo de las investigaciones se comprob\u00f3 que el hombre instrumentalizaba a una menor para que convenciera a otras ni\u00f1as de sostener encuentros \u00edntimos con \u00e9l.<\/p>\n<p style=\"font-weight: 400;\"><strong>La Fiscal\u00eda habla con resultados.<\/strong><\/p>\n<p style=\"font-weight: 400;\">\n<p>&nbsp;<\/p>\n<p style=\"font-weight: 400;\">LFML\/MAGA\/MVS.<\/p>\n<p style=\"font-weight: 400;\">\n<p>&nbsp;<\/p>\n<div class=\"td-post-content tagdiv-type\">\n<p><i><span lang=\"ES\">La informaci\u00f3n contenida en este bolet\u00edn de prensa corresponde a la narraci\u00f3n de los hechos noticiosos objetivos, suministrados por los funcionarios encargados de adelantar las investigaciones penales al interior de la Fiscal\u00eda General de la Naci\u00f3n. Para el momento de la divulgaci\u00f3n de este comunicado, la situaci\u00f3n jur\u00eddica de la(s) persona(s) relacionada(s) se encuentra pendiente de resolver por la autoridad judicial competente, siempre bajo los preceptos de la presunci\u00f3n de inocencia, consagrados en el art\u00edculo 29 de la Constituci\u00f3n Pol\u00edtica y el art\u00edculo 7\u00ba de la Ley 906 de 2004.<\/span><\/i><\/p>\n<\/div>\n\n<div class=\"twitter-share\"><a href=\"https:\/\/twitter.com\/intent\/tweet?via=fiscaliacol\" class=\"twitter-share-button\">Tweet<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El sentenciado entregaba a las v\u00edctimas celulares o dinero en efectivo para que sostuvieran relaciones \u00edntimas con \u00e9l. Por solicitud de la Fiscal\u00eda General de la Naci\u00f3n, un juez penal [&hellip;]<\/p>\n","protected":false},"author":177,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[1,318,303,24127],"tags":[11941,12642,31023,31024,31022,26604,24185,1047,25600],"class_list":["post-244607","post","type-post","status-publish","format-standard","category-noticias","category-seccional-antioquia","category-seccionales","category-violencia-sexual-e-intrafamiliar","tag-acceso-carnal-abusivo-con-menor-de-14-anos","tag-actos-sexuales-con-menor-de-14-anos","tag-administrador-de-empresas","tag-celulares-o-dinero-en-efectivo-a-cambio-de-favores-sexuales","tag-condenado-a-19-anos-de-prision","tag-demanda-de-explotacion-sexual-comercial","tag-fiscal-barbosa","tag-fiscalia-general-de-la-nacion","tag-itagui-antioquia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fiscal\u00eda General de la Naci\u00f3n<\/title>\n<meta name=\"description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-19-anos-de-prision-fue-condenado-un-hombre-que-abuso-sexualmente-de-dos-menores-de-edad\/\" \/>\n<meta property=\"og:site_name\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FiscaliaCol\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-28T20:34:52+00:00\" \/>\n<meta name=\"author\" content=\"Jordan Leandro Oviedo Anzola\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:site\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jordan Leandro Oviedo Anzola\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-19-anos-de-prision-fue-condenado-un-hombre-que-abuso-sexualmente-de-dos-menores-de-edad\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-19-anos-de-prision-fue-condenado-un-hombre-que-abuso-sexualmente-de-dos-menores-de-edad\/\"},\"author\":{\"name\":\"Jordan Leandro Oviedo Anzola\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf84402cf293a5393e9c70b111020b24\"},\"headline\":\"A 19 a\u00f1os de prisi\u00f3n fue condenado un hombre que abus\u00f3 sexualmente de dos menores de edad\",\"datePublished\":\"2022-03-28T20:34:52+00:00\",\"dateModified\":\"2022-03-28T20:34:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-19-anos-de-prision-fue-condenado-un-hombre-que-abuso-sexualmente-de-dos-menores-de-edad\/\"},\"wordCount\":360,\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"keywords\":[\"acceso carnal abusivo con menor de 14 a\u00f1os\",\"actos sexuales con menor de 14 a\u00f1os\",\"administrador de empresas\",\"celulares o dinero en efectivo a cambio de favores sexuales\",\"Condenado a 19 a\u00f1os de prisi\u00f3n\",\"DEMANDA DE EXPLOTACI\u00d2N SEXUAL COMERCIAL\",\"Fiscal Barbosa\",\"Fiscal\u00eda General de la Naci\u00f3n\",\"ITAG\u00dc\u00cd -ANTIOQUIA\"],\"articleSection\":[\"Noticias\",\"Seccional Antioquia\",\"Seccionales\",\"Violencia sexual e intrafamiliar\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-19-anos-de-prision-fue-condenado-un-hombre-que-abuso-sexualmente-de-dos-menores-de-edad\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-19-anos-de-prision-fue-condenado-un-hombre-que-abuso-sexualmente-de-dos-menores-de-edad\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\"},\"datePublished\":\"2022-03-28T20:34:52+00:00\",\"dateModified\":\"2022-03-28T20:34:52+00:00\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-19-anos-de-prision-fue-condenado-un-hombre-que-abuso-sexualmente-de-dos-menores-de-edad\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-19-anos-de-prision-fue-condenado-un-hombre-que-abuso-sexualmente-de-dos-menores-de-edad\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-19-anos-de-prision-fue-condenado-un-hombre-que-abuso-sexualmente-de-dos-menores-de-edad\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A 19 a\u00f1os de prisi\u00f3n fue condenado un hombre que abus\u00f3 sexualmente de dos menores de edad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"contentUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"width\":300,\"height\":90,\"caption\":\"Fiscal\u00eda General de la Naci\u00f3n\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/FiscaliaCol\",\"https:\/\/x.com\/FiscaliaCol\",\"https:\/\/www.instagram.com\/fiscaliacol\",\"https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/\",\"https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf84402cf293a5393e9c70b111020b24\",\"name\":\"Jordan Leandro Oviedo Anzola\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/dabba4346fa9b9207d96adafa8f92721?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/dabba4346fa9b9207d96adafa8f92721?s=96&d=mm&r=g\",\"caption\":\"Jordan Leandro Oviedo Anzola\"},\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/author\/joviedo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Fiscal\u00eda General de la Naci\u00f3n","og_description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","og_url":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-19-anos-de-prision-fue-condenado-un-hombre-que-abuso-sexualmente-de-dos-menores-de-edad\/","og_site_name":"Fiscal\u00eda General de la Naci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/FiscaliaCol","article_published_time":"2022-03-28T20:34:52+00:00","author":"Jordan Leandro Oviedo Anzola","twitter_card":"summary_large_image","twitter_creator":"@FiscaliaCol","twitter_site":"@FiscaliaCol","twitter_misc":{"Escrito por":"Jordan Leandro Oviedo Anzola","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-19-anos-de-prision-fue-condenado-un-hombre-que-abuso-sexualmente-de-dos-menores-de-edad\/#article","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-19-anos-de-prision-fue-condenado-un-hombre-que-abuso-sexualmente-de-dos-menores-de-edad\/"},"author":{"name":"Jordan Leandro Oviedo Anzola","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf84402cf293a5393e9c70b111020b24"},"headline":"A 19 a\u00f1os de prisi\u00f3n fue condenado un hombre que abus\u00f3 sexualmente de dos menores de edad","datePublished":"2022-03-28T20:34:52+00:00","dateModified":"2022-03-28T20:34:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-19-anos-de-prision-fue-condenado-un-hombre-que-abuso-sexualmente-de-dos-menores-de-edad\/"},"wordCount":360,"publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"keywords":["acceso carnal abusivo con menor de 14 a\u00f1os","actos sexuales con menor de 14 a\u00f1os","administrador de empresas","celulares o dinero en efectivo a cambio de favores sexuales","Condenado a 19 a\u00f1os de prisi\u00f3n","DEMANDA DE EXPLOTACI\u00d2N SEXUAL COMERCIAL","Fiscal Barbosa","Fiscal\u00eda General de la Naci\u00f3n","ITAG\u00dc\u00cd -ANTIOQUIA"],"articleSection":["Noticias","Seccional Antioquia","Seccionales","Violencia sexual e intrafamiliar"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-19-anos-de-prision-fue-condenado-un-hombre-que-abuso-sexualmente-de-dos-menores-de-edad\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-19-anos-de-prision-fue-condenado-un-hombre-que-abuso-sexualmente-de-dos-menores-de-edad\/","name":"Fiscal\u00eda General de la Naci\u00f3n","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website"},"datePublished":"2022-03-28T20:34:52+00:00","dateModified":"2022-03-28T20:34:52+00:00","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","breadcrumb":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-19-anos-de-prision-fue-condenado-un-hombre-que-abuso-sexualmente-de-dos-menores-de-edad\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-19-anos-de-prision-fue-condenado-un-hombre-que-abuso-sexualmente-de-dos-menores-de-edad\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-19-anos-de-prision-fue-condenado-un-hombre-que-abuso-sexualmente-de-dos-menores-de-edad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fiscalia.gov.co\/colombia\/"},{"@type":"ListItem","position":2,"name":"A 19 a\u00f1os de prisi\u00f3n fue condenado un hombre que abus\u00f3 sexualmente de dos menores de edad"}]},{"@type":"WebSite","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","name":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization","name":"Fiscal\u00eda General de la Naci\u00f3n","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","contentUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","width":300,"height":90,"caption":"Fiscal\u00eda General de la Naci\u00f3n"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FiscaliaCol","https:\/\/x.com\/FiscaliaCol","https:\/\/www.instagram.com\/fiscaliacol","https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/","https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh"]},{"@type":"Person","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf84402cf293a5393e9c70b111020b24","name":"Jordan Leandro Oviedo Anzola","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/dabba4346fa9b9207d96adafa8f92721?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dabba4346fa9b9207d96adafa8f92721?s=96&d=mm&r=g","caption":"Jordan Leandro Oviedo Anzola"},"url":"https:\/\/www.fiscalia.gov.co\/colombia\/author\/joviedo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/244607","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/users\/177"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/comments?post=244607"}],"version-history":[{"count":1,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/244607\/revisions"}],"predecessor-version":[{"id":244608,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/244607\/revisions\/244608"}],"wp:attachment":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/media?parent=244607"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/categories?post=244607"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/tags?post=244607"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}