{"id":243067,"date":"2022-03-10T11:30:15","date_gmt":"2022-03-10T16:30:15","guid":{"rendered":"https:\/\/www.fiscalia.gov.co\/colombia\/?p=243067"},"modified":"2022-03-10T11:30:15","modified_gmt":"2022-03-10T16:30:15","slug":"privado-de-la-libertad-supuesto-medico-naturalista-que-agredio-sexualmente-a-una-menor","status":"publish","type":"post","link":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/privado-de-la-libertad-supuesto-medico-naturalista-que-agredio-sexualmente-a-una-menor\/","title":{"rendered":"Privado de la libertad supuesto m\u00e9dico naturalista que agredi\u00f3 sexualmente a una menor"},"content":{"rendered":"<p>Como presunto responsable del delito de\u00a0<strong>acto sexual violento<\/strong>, la Fiscal\u00eda General de La Naci\u00f3n judicializ\u00f3 a\u00a0\u00a0\u00c1lvaro S\u00e1enz\u00a0porque al parecer le hizo\u00a0<strong style=\"font-style: inherit;\">tocamientos \u00edntimos a una menor de 14 a\u00f1os.<\/strong><\/p>\n<figure id=\"attachment_243068\" aria-describedby=\"caption-attachment-243068\" style=\"width: 696px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-243068\" src=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Fiscal-Francisco-Barbosa_\u00c1lvaro-S\u00e1enz-1024x672.jpeg\" alt=\"\" width=\"696\" height=\"457\" srcset=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Fiscal-Francisco-Barbosa_\u00c1lvaro-S\u00e1enz-1024x672.jpeg 1024w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Fiscal-Francisco-Barbosa_\u00c1lvaro-S\u00e1enz-300x197.jpeg 300w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Fiscal-Francisco-Barbosa_\u00c1lvaro-S\u00e1enz-768x504.jpeg 768w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Fiscal-Francisco-Barbosa_\u00c1lvaro-S\u00e1enz-696x457.jpeg 696w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Fiscal-Francisco-Barbosa_\u00c1lvaro-S\u00e1enz-1068x701.jpeg 1068w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Fiscal-Francisco-Barbosa_\u00c1lvaro-S\u00e1enz-640x420.jpeg 640w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Fiscal-Francisco-Barbosa_\u00c1lvaro-S\u00e1enz-741x486.jpeg 741w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Fiscal-Francisco-Barbosa_\u00c1lvaro-S\u00e1enz.jpeg 1280w\" sizes=\"auto, (max-width: 696px) 100vw, 696px\" \/><figcaption id=\"caption-attachment-243068\" class=\"wp-caption-text\">\u00c1lvaro S\u00e1enz no acept\u00f3 su responsabilidad en el delito de acto sexual violento<\/figcaption><\/figure>\n<p>Seg\u00fan la investigaci\u00f3n, el pasado 19 de enero el procesado habr\u00eda llegado a una casa en la vereda Puerto Rosario, en Puerto Guzm\u00e1n,\u00a0<strong>ofreciendo masajes para el estr\u00e9s en calidad\u00a0\u00a0de m\u00e9dico naturista<\/strong>.<\/p>\n<p>El hombre, aprovechando que la menor se encontraba sola, le hizo quitar la blusa para\u00a0<strong>presuntamente propinarle tocamientos \u00edntimos<\/strong>, hechos por los que la v\u00edctima sinti\u00f3 temor y dolor, siendo\u00a0<strong>afectada psicol\u00f3gicamente.<\/strong><\/p>\n<p>Su captura por orden judicial la realizaron uniformados de CTI en coordinaci\u00f3n con Polic\u00eda de Infancia y Adolescencia en Mocoa (Putumayo). No hubo aceptaci\u00f3n de cargos.<\/p>\n<p>La Fiscal\u00eda publica esta informaci\u00f3n por razones de inter\u00e9s general.<\/p>\n<p>Tambi\u00e9n le puede interesar:\u00a0\u00a0<a href=\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-fue-enviado-un-hombre-como-presunto-responsable-del-delito-de-acceso-carnal-violento-contra-una-joven-que-luego-se-quito-la-vida\/\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-la-carcel-fue-enviado-un-hombre-como-presunto-responsable-del-delito-de-acceso-carnal-violento-contra-una-joven-que-luego-se-quito-la-vida\/&amp;source=gmail&amp;ust=1647004604820000&amp;usg=AOvVaw0w_b958QSszFxIgE8O8RNb\">A la c\u00e1rcel fue enviado un hombre como presunto responsable\u00a0del delito de acceso carnal violento contra una joven que luego se quit\u00f3 la vida<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>LMGM\/CFG\/GRM<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><em>La informaci\u00f3n contenida en este bolet\u00edn de prensa corresponde a la narraci\u00f3n de los hechos noticiosos objetivos, suministrados por los funcionarios encargados de adelantar las investigaciones penales al interior de la Fiscal\u00eda General de la Naci\u00f3n. Para el momento de la divulgaci\u00f3n de este comunicado, la situaci\u00f3n jur\u00eddica de la(s) persona(s) relacionada(s) se encuentra pendiente de resolver por la autoridad judicial competente, siempre bajo los preceptos de la presunci\u00f3n de inocencia, consagrados en el art\u00edculo 29 de la Constituci\u00f3n Pol\u00edtica y el art\u00edculo 7\u00ba de la Ley 906 de 2004.<\/em><\/p>\n\n<div class=\"twitter-share\"><a href=\"https:\/\/twitter.com\/intent\/tweet?via=fiscaliacol\" class=\"twitter-share-button\">Tweet<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Como presunto responsable del delito de\u00a0acto sexual violento, la Fiscal\u00eda General de La Naci\u00f3n judicializ\u00f3 a\u00a0\u00a0\u00c1lvaro S\u00e1enz\u00a0porque al parecer le hizo\u00a0tocamientos \u00edntimos a una menor de 14 a\u00f1os. Seg\u00fan la [&hellip;]<\/p>\n","protected":false},"author":177,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[1,2910,303,24127],"tags":[17825,24185,24188,1047,30782,30781,28156,2279],"class_list":["post-243067","post","type-post","status-publish","format-standard","category-noticias","category-seccional-mocoa","category-seccionales","category-violencia-sexual-e-intrafamiliar","tag-acto-sexual-violento","tag-fiscal-barbosa","tag-fiscal-francisco-barbosa","tag-fiscalia-general-de-la-nacion","tag-masajes","tag-medico-naturista","tag-puerto-guzman","tag-putumayo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fiscal\u00eda General de la Naci\u00f3n<\/title>\n<meta name=\"description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/privado-de-la-libertad-supuesto-medico-naturalista-que-agredio-sexualmente-a-una-menor\/\" \/>\n<meta property=\"og:site_name\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FiscaliaCol\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-10T16:30:15+00:00\" \/>\n<meta name=\"author\" content=\"Jordan Leandro Oviedo Anzola\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:site\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jordan Leandro Oviedo Anzola\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/privado-de-la-libertad-supuesto-medico-naturalista-que-agredio-sexualmente-a-una-menor\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/privado-de-la-libertad-supuesto-medico-naturalista-que-agredio-sexualmente-a-una-menor\/\"},\"author\":{\"name\":\"Jordan Leandro Oviedo Anzola\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf84402cf293a5393e9c70b111020b24\"},\"headline\":\"Privado de la libertad supuesto m\u00e9dico naturalista que agredi\u00f3 sexualmente a una menor\",\"datePublished\":\"2022-03-10T16:30:15+00:00\",\"dateModified\":\"2022-03-10T16:30:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/privado-de-la-libertad-supuesto-medico-naturalista-que-agredio-sexualmente-a-una-menor\/\"},\"wordCount\":324,\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"keywords\":[\"acto sexual violento\",\"Fiscal Barbosa\",\"Fiscal Francisco Barbosa\",\"Fiscal\u00eda General de la Naci\u00f3n\",\"masajes\",\"m\u00e9dico naturista\",\"Puerto Guzm\u00e1n\",\"Putumayo\"],\"articleSection\":[\"Noticias\",\"Seccional Mocoa\",\"Seccionales\",\"Violencia sexual e intrafamiliar\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/privado-de-la-libertad-supuesto-medico-naturalista-que-agredio-sexualmente-a-una-menor\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/privado-de-la-libertad-supuesto-medico-naturalista-que-agredio-sexualmente-a-una-menor\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\"},\"datePublished\":\"2022-03-10T16:30:15+00:00\",\"dateModified\":\"2022-03-10T16:30:15+00:00\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/privado-de-la-libertad-supuesto-medico-naturalista-que-agredio-sexualmente-a-una-menor\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/privado-de-la-libertad-supuesto-medico-naturalista-que-agredio-sexualmente-a-una-menor\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/privado-de-la-libertad-supuesto-medico-naturalista-que-agredio-sexualmente-a-una-menor\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Privado de la libertad supuesto m\u00e9dico naturalista que agredi\u00f3 sexualmente a una menor\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"contentUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"width\":300,\"height\":90,\"caption\":\"Fiscal\u00eda General de la Naci\u00f3n\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/FiscaliaCol\",\"https:\/\/x.com\/FiscaliaCol\",\"https:\/\/www.instagram.com\/fiscaliacol\",\"https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/\",\"https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf84402cf293a5393e9c70b111020b24\",\"name\":\"Jordan Leandro Oviedo Anzola\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/dabba4346fa9b9207d96adafa8f92721?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/dabba4346fa9b9207d96adafa8f92721?s=96&d=mm&r=g\",\"caption\":\"Jordan Leandro Oviedo Anzola\"},\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/author\/joviedo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Fiscal\u00eda General de la Naci\u00f3n","og_description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","og_url":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/privado-de-la-libertad-supuesto-medico-naturalista-que-agredio-sexualmente-a-una-menor\/","og_site_name":"Fiscal\u00eda General de la Naci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/FiscaliaCol","article_published_time":"2022-03-10T16:30:15+00:00","author":"Jordan Leandro Oviedo Anzola","twitter_card":"summary_large_image","twitter_creator":"@FiscaliaCol","twitter_site":"@FiscaliaCol","twitter_misc":{"Escrito por":"Jordan Leandro Oviedo Anzola","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/privado-de-la-libertad-supuesto-medico-naturalista-que-agredio-sexualmente-a-una-menor\/#article","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/privado-de-la-libertad-supuesto-medico-naturalista-que-agredio-sexualmente-a-una-menor\/"},"author":{"name":"Jordan Leandro Oviedo Anzola","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf84402cf293a5393e9c70b111020b24"},"headline":"Privado de la libertad supuesto m\u00e9dico naturalista que agredi\u00f3 sexualmente a una menor","datePublished":"2022-03-10T16:30:15+00:00","dateModified":"2022-03-10T16:30:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/privado-de-la-libertad-supuesto-medico-naturalista-que-agredio-sexualmente-a-una-menor\/"},"wordCount":324,"publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"keywords":["acto sexual violento","Fiscal Barbosa","Fiscal Francisco Barbosa","Fiscal\u00eda General de la Naci\u00f3n","masajes","m\u00e9dico naturista","Puerto Guzm\u00e1n","Putumayo"],"articleSection":["Noticias","Seccional Mocoa","Seccionales","Violencia sexual e intrafamiliar"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/privado-de-la-libertad-supuesto-medico-naturalista-que-agredio-sexualmente-a-una-menor\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/privado-de-la-libertad-supuesto-medico-naturalista-que-agredio-sexualmente-a-una-menor\/","name":"Fiscal\u00eda General de la Naci\u00f3n","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website"},"datePublished":"2022-03-10T16:30:15+00:00","dateModified":"2022-03-10T16:30:15+00:00","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","breadcrumb":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/privado-de-la-libertad-supuesto-medico-naturalista-que-agredio-sexualmente-a-una-menor\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/privado-de-la-libertad-supuesto-medico-naturalista-que-agredio-sexualmente-a-una-menor\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/privado-de-la-libertad-supuesto-medico-naturalista-que-agredio-sexualmente-a-una-menor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fiscalia.gov.co\/colombia\/"},{"@type":"ListItem","position":2,"name":"Privado de la libertad supuesto m\u00e9dico naturalista que agredi\u00f3 sexualmente a una menor"}]},{"@type":"WebSite","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","name":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization","name":"Fiscal\u00eda General de la Naci\u00f3n","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","contentUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","width":300,"height":90,"caption":"Fiscal\u00eda General de la Naci\u00f3n"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FiscaliaCol","https:\/\/x.com\/FiscaliaCol","https:\/\/www.instagram.com\/fiscaliacol","https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/","https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh"]},{"@type":"Person","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf84402cf293a5393e9c70b111020b24","name":"Jordan Leandro Oviedo Anzola","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/dabba4346fa9b9207d96adafa8f92721?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dabba4346fa9b9207d96adafa8f92721?s=96&d=mm&r=g","caption":"Jordan Leandro Oviedo Anzola"},"url":"https:\/\/www.fiscalia.gov.co\/colombia\/author\/joviedo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/243067","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/users\/177"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/comments?post=243067"}],"version-history":[{"count":1,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/243067\/revisions"}],"predecessor-version":[{"id":243069,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/243067\/revisions\/243069"}],"wp:attachment":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/media?parent=243067"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/categories?post=243067"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/tags?post=243067"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}