{"id":240091,"date":"2022-02-06T10:24:33","date_gmt":"2022-02-06T15:24:33","guid":{"rendered":"https:\/\/www.fiscalia.gov.co\/colombia\/?p=240091"},"modified":"2022-02-12T19:32:32","modified_gmt":"2022-02-13T00:32:32","slug":"cae-don-rafa-supuesto-cabecilla-de-una-estructura-narcotraficante-senalada-de-sacar-cocaina-por-la-alta-guajira","status":"publish","type":"post","link":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/cae-don-rafa-supuesto-cabecilla-de-una-estructura-narcotraficante-senalada-de-sacar-cocaina-por-la-alta-guajira\/","title":{"rendered":"Cae \u2018Don Rafa\u2019, supuesto cabecilla de una estructura narcotraficante se\u00f1alada de sacar coca\u00edna por la Alta Guajira"},"content":{"rendered":"<blockquote class=\"td_quote_box td_box_center\">\n<h4 style=\"text-align: left;\"><strong><em>Este hombre fue capturado con fines de extradici\u00f3n. Una Corte Distrital de Estados Unidos lo requiere por cuatro cargos relacionados con narcotr\u00e1fico.<\/em><\/strong><\/h4>\n<\/blockquote>\n<p>En atenci\u00f3n a una orden de captura con fines de extradici\u00f3n expedida por la Fiscal\u00eda General de la Naci\u00f3n, la Direcci\u00f3n Especializada contra el Narcotr\u00e1fico, en un trabajo articulado con la Polic\u00eda Nacional y las agencias estadounidenses, ubic\u00f3 a Rafael Valdeblanquez Jusayu, alias Don Rafa o T\u00edo Rafa, supuesto m\u00e1ximo cabecilla de una estructura dedicada al env\u00edo de toneladas de coca\u00edna por las costas de la Alta Guajira.<\/p>\n<p>Esta persona fue detenida en una diligencia de registro y allanamiento realizada en un inmueble de Maicao (La Guajira).<\/p>\n<p>Una Corte Distrital de Estados Unidos para el distrito sur de La Florida requiere a \u2018Don Rafa\u2019 para que responda en juicio por cuatro cargos distintos relacionados con tr\u00e1fico de estupefacientes. De acuerdo con el requerimiento internacional, ser\u00eda el responsable de sacar la mayor cantidad de estupefacientes por las costas del extremo norte de Colombia y uno de los principales aliados narcotraficantes del ELN.<\/p>\n<p>Las investigaciones dan cuenta de que la red de este hombre, al parecer, adquir\u00eda el clorhidrato de coca\u00edna en el Catatumbo (Norte de Santander), a trav\u00e9s de las distintas estructuras del ELN que delinquen en la regi\u00f3n. Posteriormente, trasladaba los cargamentos a la Alta Guajira y all\u00ed los almacenaba durante algunos d\u00edas.<\/p>\n<p>Finalmente, y con apoyo de una red de lancheros, los alijos sal\u00edan en embarcaciones tipo \u2018go fast\u2019 desde embarcaderos clandestinos ubicados en Parajimaruhu y Puerto Ingl\u00e9s, en la Alta Guajira, hacia Aruba, Honduras, Rep\u00fablica Dominicana, Puerto Rico y otros pa\u00edses del Caribe y Centroam\u00e9rica.<\/p>\n<p>La Direcci\u00f3n de Asuntos Internacionales de la Fiscal\u00eda, por conducto del Ministerio de Relaciones Exteriores, comunicar\u00e1 sobre esta captura a la Embajada de Estados Unidos en Colombia para que se surtan los tr\u00e1mites de extradici\u00f3n dentro de los t\u00e9rminos de ley.<\/p>\n<p>Esta informaci\u00f3n se publica por razones de inter\u00e9s general.<\/p>\n<p>LMBG\/JARG\/DECN\/MRC.<\/p>\n<p><strong>La Fiscal\u00eda habla con resultados.<\/strong><\/p>\n<div class=\"td-post-content tagdiv-type\">\n<p><em>La informaci\u00f3n contenida en este bolet\u00edn\u00a0de\u00a0prensa corresponde a la narraci\u00f3n\u00a0de\u00a0los hechos noticiosos objetivos, suministrados por los funcionarios encargados\u00a0de\u00a0adelantar las investigaciones penales al interior\u00a0de\u00a0la Fiscal\u00eda General\u00a0de\u00a0la Naci\u00f3n. Para el momento\u00a0de\u00a0la divulgaci\u00f3n\u00a0de\u00a0este comunicado, la situaci\u00f3n jur\u00eddica\u00a0de\u00a0la(s) persona(s) relacionada(s) se encuentra pendiente\u00a0de\u00a0resolver por la autoridad judicial competente, siempre bajo los preceptos\u00a0de\u00a0la presunci\u00f3n\u00a0de\u00a0inocencia, consagrados en el art\u00edculo 29\u00a0de\u00a0la Constituci\u00f3n Pol\u00edtica y el art\u00edculo 7\u00ba\u00a0de\u00a0la Ley 906\u00a0de\u00a02004.\u00a0<\/em><\/p>\n<\/div>\n<footer>\n<div class=\"td-post-sharing-bottom\"><\/div>\n<\/footer>\n\n<div class=\"twitter-share\"><a href=\"https:\/\/twitter.com\/intent\/tweet?via=fiscaliacol\" class=\"twitter-share-button\">Tweet<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Este hombre fue capturado con fines de extradici\u00f3n. Una Corte Distrital de Estados Unidos lo requiere por cuatro cargos relacionados con narcotr\u00e1fico. En atenci\u00f3n a una orden de captura con [&hellip;]<\/p>\n","protected":false},"author":162,"featured_media":240835,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[24115,1],"tags":[30310,2663,2300,148],"class_list":["post-240091","post","type-post","status-publish","format-video","has-post-thumbnail","category-narcotrafico","category-noticias","tag-don-rafa","tag-estados-unidos","tag-extradicion","tag-narcotrafico","post_format-post-format-video"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fiscal\u00eda General de la Naci\u00f3n<\/title>\n<meta name=\"description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/cae-don-rafa-supuesto-cabecilla-de-una-estructura-narcotraficante-senalada-de-sacar-cocaina-por-la-alta-guajira\/\" \/>\n<meta property=\"og:site_name\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FiscaliaCol\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-06T15:24:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-13T00:32:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/maxresdefault-340.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:site\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/cae-don-rafa-supuesto-cabecilla-de-una-estructura-narcotraficante-senalada-de-sacar-cocaina-por-la-alta-guajira\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/cae-don-rafa-supuesto-cabecilla-de-una-estructura-narcotraficante-senalada-de-sacar-cocaina-por-la-alta-guajira\/\"},\"author\":{\"name\":\"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf28d8ae7f1b287bbe3af484b04f43ea\"},\"headline\":\"Cae \u2018Don Rafa\u2019, supuesto cabecilla de una estructura narcotraficante se\u00f1alada de sacar coca\u00edna por la Alta Guajira\",\"datePublished\":\"2022-02-06T15:24:33+00:00\",\"dateModified\":\"2022-02-13T00:32:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/cae-don-rafa-supuesto-cabecilla-de-una-estructura-narcotraficante-senalada-de-sacar-cocaina-por-la-alta-guajira\/\"},\"wordCount\":482,\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/cae-don-rafa-supuesto-cabecilla-de-una-estructura-narcotraficante-senalada-de-sacar-cocaina-por-la-alta-guajira\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/maxresdefault-340.jpg\",\"keywords\":[\"Don Rafa\",\"Estados Unidos\",\"Extradici\u00f3n\",\"Narcotr\u00e1fico\"],\"articleSection\":[\"Narcotr\u00e1fico\",\"Noticias\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/cae-don-rafa-supuesto-cabecilla-de-una-estructura-narcotraficante-senalada-de-sacar-cocaina-por-la-alta-guajira\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/cae-don-rafa-supuesto-cabecilla-de-una-estructura-narcotraficante-senalada-de-sacar-cocaina-por-la-alta-guajira\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/cae-don-rafa-supuesto-cabecilla-de-una-estructura-narcotraficante-senalada-de-sacar-cocaina-por-la-alta-guajira\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/cae-don-rafa-supuesto-cabecilla-de-una-estructura-narcotraficante-senalada-de-sacar-cocaina-por-la-alta-guajira\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/maxresdefault-340.jpg\",\"datePublished\":\"2022-02-06T15:24:33+00:00\",\"dateModified\":\"2022-02-13T00:32:32+00:00\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/cae-don-rafa-supuesto-cabecilla-de-una-estructura-narcotraficante-senalada-de-sacar-cocaina-por-la-alta-guajira\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/cae-don-rafa-supuesto-cabecilla-de-una-estructura-narcotraficante-senalada-de-sacar-cocaina-por-la-alta-guajira\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/cae-don-rafa-supuesto-cabecilla-de-una-estructura-narcotraficante-senalada-de-sacar-cocaina-por-la-alta-guajira\/#primaryimage\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/maxresdefault-340.jpg\",\"contentUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/maxresdefault-340.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/cae-don-rafa-supuesto-cabecilla-de-una-estructura-narcotraficante-senalada-de-sacar-cocaina-por-la-alta-guajira\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cae \u2018Don Rafa\u2019, supuesto cabecilla de una estructura narcotraficante se\u00f1alada de sacar coca\u00edna por la Alta Guajira\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"contentUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"width\":300,\"height\":90,\"caption\":\"Fiscal\u00eda General de la Naci\u00f3n\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/FiscaliaCol\",\"https:\/\/x.com\/FiscaliaCol\",\"https:\/\/www.instagram.com\/fiscaliacol\",\"https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/\",\"https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf28d8ae7f1b287bbe3af484b04f43ea\",\"name\":\"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9d55ae161d32da16dbdd0b380c080a5f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9d55ae161d32da16dbdd0b380c080a5f?s=96&d=mm&r=g\",\"caption\":\"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n\"},\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/author\/kbonilla\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Fiscal\u00eda General de la Naci\u00f3n","og_description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","og_url":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/cae-don-rafa-supuesto-cabecilla-de-una-estructura-narcotraficante-senalada-de-sacar-cocaina-por-la-alta-guajira\/","og_site_name":"Fiscal\u00eda General de la Naci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/FiscaliaCol","article_published_time":"2022-02-06T15:24:33+00:00","article_modified_time":"2022-02-13T00:32:32+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/maxresdefault-340.jpg","type":"image\/jpeg"}],"author":"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@FiscaliaCol","twitter_site":"@FiscaliaCol","twitter_misc":{"Escrito por":"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/cae-don-rafa-supuesto-cabecilla-de-una-estructura-narcotraficante-senalada-de-sacar-cocaina-por-la-alta-guajira\/#article","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/cae-don-rafa-supuesto-cabecilla-de-una-estructura-narcotraficante-senalada-de-sacar-cocaina-por-la-alta-guajira\/"},"author":{"name":"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf28d8ae7f1b287bbe3af484b04f43ea"},"headline":"Cae \u2018Don Rafa\u2019, supuesto cabecilla de una estructura narcotraficante se\u00f1alada de sacar coca\u00edna por la Alta Guajira","datePublished":"2022-02-06T15:24:33+00:00","dateModified":"2022-02-13T00:32:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/cae-don-rafa-supuesto-cabecilla-de-una-estructura-narcotraficante-senalada-de-sacar-cocaina-por-la-alta-guajira\/"},"wordCount":482,"publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/cae-don-rafa-supuesto-cabecilla-de-una-estructura-narcotraficante-senalada-de-sacar-cocaina-por-la-alta-guajira\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/maxresdefault-340.jpg","keywords":["Don Rafa","Estados Unidos","Extradici\u00f3n","Narcotr\u00e1fico"],"articleSection":["Narcotr\u00e1fico","Noticias"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/cae-don-rafa-supuesto-cabecilla-de-una-estructura-narcotraficante-senalada-de-sacar-cocaina-por-la-alta-guajira\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/cae-don-rafa-supuesto-cabecilla-de-una-estructura-narcotraficante-senalada-de-sacar-cocaina-por-la-alta-guajira\/","name":"Fiscal\u00eda General de la Naci\u00f3n","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/cae-don-rafa-supuesto-cabecilla-de-una-estructura-narcotraficante-senalada-de-sacar-cocaina-por-la-alta-guajira\/#primaryimage"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/cae-don-rafa-supuesto-cabecilla-de-una-estructura-narcotraficante-senalada-de-sacar-cocaina-por-la-alta-guajira\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/maxresdefault-340.jpg","datePublished":"2022-02-06T15:24:33+00:00","dateModified":"2022-02-13T00:32:32+00:00","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","breadcrumb":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/cae-don-rafa-supuesto-cabecilla-de-una-estructura-narcotraficante-senalada-de-sacar-cocaina-por-la-alta-guajira\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/cae-don-rafa-supuesto-cabecilla-de-una-estructura-narcotraficante-senalada-de-sacar-cocaina-por-la-alta-guajira\/"]}]},{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/cae-don-rafa-supuesto-cabecilla-de-una-estructura-narcotraficante-senalada-de-sacar-cocaina-por-la-alta-guajira\/#primaryimage","url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/maxresdefault-340.jpg","contentUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/maxresdefault-340.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/cae-don-rafa-supuesto-cabecilla-de-una-estructura-narcotraficante-senalada-de-sacar-cocaina-por-la-alta-guajira\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fiscalia.gov.co\/colombia\/"},{"@type":"ListItem","position":2,"name":"Cae \u2018Don Rafa\u2019, supuesto cabecilla de una estructura narcotraficante se\u00f1alada de sacar coca\u00edna por la Alta Guajira"}]},{"@type":"WebSite","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","name":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization","name":"Fiscal\u00eda General de la Naci\u00f3n","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","contentUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","width":300,"height":90,"caption":"Fiscal\u00eda General de la Naci\u00f3n"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FiscaliaCol","https:\/\/x.com\/FiscaliaCol","https:\/\/www.instagram.com\/fiscaliacol","https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/","https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh"]},{"@type":"Person","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf28d8ae7f1b287bbe3af484b04f43ea","name":"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9d55ae161d32da16dbdd0b380c080a5f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9d55ae161d32da16dbdd0b380c080a5f?s=96&d=mm&r=g","caption":"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n"},"url":"https:\/\/www.fiscalia.gov.co\/colombia\/author\/kbonilla\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/240091","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/users\/162"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/comments?post=240091"}],"version-history":[{"count":1,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/240091\/revisions"}],"predecessor-version":[{"id":240092,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/240091\/revisions\/240092"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/media\/240835"}],"wp:attachment":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/media?parent=240091"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/categories?post=240091"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/tags?post=240091"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}