{"id":240079,"date":"2022-02-05T14:00:45","date_gmt":"2022-02-05T19:00:45","guid":{"rendered":"https:\/\/www.fiscalia.gov.co\/colombia\/?p=240079"},"modified":"2022-02-12T10:44:36","modified_gmt":"2022-02-12T15:44:36","slug":"judicializado-presuntos-integrantes-de-red-delincuencial-senalada-de-sacrificar-caballos-para-vender-las-carne-clandestinamente-en-la-costa-atlantica","status":"publish","type":"post","link":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presuntos-integrantes-de-red-delincuencial-senalada-de-sacrificar-caballos-para-vender-las-carne-clandestinamente-en-la-costa-atlantica\/","title":{"rendered":"Judicializados presuntos integrantes de red delincuencial se\u00f1alada de sacrificar caballos para vender las carne clandestinamente en la Costa Atl\u00e1ntica"},"content":{"rendered":"<blockquote class=\"td_quote_box td_box_center\">\n<h4 style=\"text-align: left;\"><strong><i><span lang=\"ES-CO\">Entre los procesados hay dos integrantes de la Polic\u00eda Nacional que habr\u00edan permitido que esta actividad ilegal se realizara.\u00a0<\/span><\/i><\/strong><\/h4>\n<\/blockquote>\n<p><span lang=\"ES-CO\">Al atender la solicitud de la Fiscal\u00eda General de la Naci\u00f3n, un juez de control de garant\u00edas impuso medida de aseguramiento privativa de la libertad en centro de reclusi\u00f3n a seis presuntos integrantes de \u2018Los Percherones\u2019, una\u00a0<a href=\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presunto-responsable-de-matadero-ilegal-de-carne-de-caballo-y-de-burro\/\" target=\"_blank\" rel=\"noopener noreferrer\" data-auth=\"NotApplicable\" data-linkindex=\"0\">red delictiva que estar\u00eda dedicada al sacrificio de caballos y la comercializaci\u00f3n ilegal de su\u00a0\u00a0carne en Atl\u00e1ntico y otros departamentos de la Costa Atl\u00e1ntica.<\/a>\u00a0<\/span><\/p>\n<figure id=\"attachment_240080\" aria-describedby=\"caption-attachment-240080\" style=\"width: 1024px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-240080\" src=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Foto-1-5.jpg\" alt=\"\" width=\"1024\" height=\"789\" srcset=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Foto-1-5.jpg 1024w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Foto-1-5-300x231.jpg 300w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Foto-1-5-768x592.jpg 768w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Foto-1-5-696x536.jpg 696w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Foto-1-5-545x420.jpg 545w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption id=\"caption-attachment-240080\" class=\"wp-caption-text\"><strong>En el lugar se encontraron 70 kilogramos de piel de caballo y burro y cerca de 100 kilogramos de carne y v\u00edsceras de equino.<\/strong><\/figcaption><\/figure>\n<p><span lang=\"ES-CO\">De acuerdo con la investigaci\u00f3n, equinos y burros en mal estado, muchos de estos enfermos, eran llevados a un inmueble del barrio Rebolo, en Barranquilla, donde habr\u00edan estado sometidos a condiciones de maltrato.\u00a0<b>En este lugar, la organizaci\u00f3n despostaba a los animales sin ninguna medida de salubridad; mientras que las carnes y las v\u00edsceras las almacenaban, sin conservar la cadena de fr\u00edo, para ser vendidas, posteriormente, en establecimientos de comercio.\u00a0<\/b><\/span><\/p>\n<p><span lang=\"ES-CO\">En distintas inspecciones realizadas, se constat\u00f3 que los residuos l\u00edquidos eran vertidos indiscriminadamente al alcantarillado; mientras que los desechos s\u00f3lidos no recib\u00edan un tratamiento adecuado. Esta actuaci\u00f3n representaba grave riesgo la salud de la ciudadan\u00eda.\u00a0<\/span><\/p>\n<p><span lang=\"ES-CO\">La Fiscal\u00eda y la Sijin de la Polic\u00eda Nacional, con apoyo de las autoridades ambientales de la Alcald\u00eda de Barranquilla, hicieron efectiva una orden de registro y allanamiento en el inmueble.\u00a0<b>En el lugar se encontraron 70 kilogramos de piel de caballo y burro, adem\u00e1s dos congeladores en p\u00e9simas condiciones con cerca de 100 kilogramos de carne y v\u00edsceras de equino.\u00a0<\/b><\/span><\/p>\n<p><span lang=\"ES-CO\">Simult\u00e1neamente, fueron capturadas seis personas, quienes estar\u00edan involucradas en el andamiaje ilegal de sacrificio y comercializaci\u00f3n.\u00a0<b>Dos de los detenidos son integrantes de la Polic\u00eda Nacional que, seg\u00fan los elementos de prueba, omitieron sus funciones y permitieron el desarrollo de estas actividades il\u00edcitas.\u00a0<\/b><\/span><\/p>\n<p><span lang=\"ES-CO\">La Fiscal\u00eda imput\u00f3 a los capturados delitos como: maltrato animal, concierto para delinquir, contaminaci\u00f3n ambiental, cohecho por dar u ofrecer; corrupci\u00f3n de alimentos, productos m\u00e9dicos y material profil\u00e1ctico; tr\u00e1fico de influencia de particular, y tr\u00e1fico de influencias a servidor p\u00fablico.\u00a0<\/span><\/p>\n<p><span lang=\"ES-CO\">Los procesados son: Elvira Contreras Salcedo, Hip\u00f3lito Meri\u00f1o Ortega, Roberto Enrique Meri\u00f1o Contreras, Jhonny Mart\u00edn Hern\u00e1ndez, y los patrulleros de la Polic\u00eda Germ\u00e1n Eduardo P\u00e9rez Mart\u00ednez y Jaison Manuel Bola\u00f1os Pardo.\u00a0\u00a0<\/span><\/p>\n<p><span lang=\"ES-CO\">Al t\u00e9rmino de las audiencias preliminares la defensa apel\u00f3 la decisi\u00f3n del juez de garant\u00edas.\u00a0<\/span><\/p>\n<p><span lang=\"ES-CO\">AMCJ\/JARG\/AG\/MCRC\/<\/span><span lang=\"ES-CO\">\u00a0<\/span><\/p>\n<p align=\"center\"><b><span lang=\"ES-CO\">La Fiscal\u00eda habla con resultados\u00a0<\/span><\/b><\/p>\n<p><em>La informaci\u00f3n contenida en este bolet\u00edn\u00a0de\u00a0prensa corresponde a la narraci\u00f3n\u00a0de\u00a0los hechos noticiosos objetivos, suministrados por los funcionarios encargados\u00a0de\u00a0adelantar las investigaciones penales al interior\u00a0de\u00a0la Fiscal\u00eda General\u00a0de\u00a0la Naci\u00f3n. Para el momento\u00a0de\u00a0la divulgaci\u00f3n\u00a0de\u00a0este comunicado, la situaci\u00f3n jur\u00eddica\u00a0de\u00a0la(s) persona(s) relacionada(s) se encuentra pendiente\u00a0de\u00a0resolver por la autoridad judicial competente, siempre bajo los preceptos\u00a0de\u00a0la presunci\u00f3n\u00a0de\u00a0inocencia, consagrados en el art\u00edculo 29\u00a0de\u00a0la Constituci\u00f3n Pol\u00edtica y el art\u00edculo 7\u00ba\u00a0de\u00a0la Ley 906\u00a0de\u00a02004.\u00a0<\/em><\/p>\n\n<div class=\"twitter-share\"><a href=\"https:\/\/twitter.com\/intent\/tweet?via=fiscaliacol\" class=\"twitter-share-button\">Tweet<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Entre los procesados hay dos integrantes de la Polic\u00eda Nacional que habr\u00edan permitido que esta actividad ilegal se realizara.\u00a0 Al atender la solicitud de la Fiscal\u00eda General de la Naci\u00f3n, [&hellip;]<\/p>\n","protected":false},"author":162,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[1],"tags":[14083,30239],"class_list":["post-240079","post","type-post","status-publish","format-video","category-noticias","tag-atlantico","tag-seguridad-territorial","post_format-post-format-video"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fiscal\u00eda General de la Naci\u00f3n<\/title>\n<meta name=\"description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presuntos-integrantes-de-red-delincuencial-senalada-de-sacrificar-caballos-para-vender-las-carne-clandestinamente-en-la-costa-atlantica\/\" \/>\n<meta property=\"og:site_name\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FiscaliaCol\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-05T19:00:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-12T15:44:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Foto-1-5.jpg\" \/>\n<meta name=\"author\" content=\"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:site\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presuntos-integrantes-de-red-delincuencial-senalada-de-sacrificar-caballos-para-vender-las-carne-clandestinamente-en-la-costa-atlantica\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presuntos-integrantes-de-red-delincuencial-senalada-de-sacrificar-caballos-para-vender-las-carne-clandestinamente-en-la-costa-atlantica\/\"},\"author\":{\"name\":\"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf28d8ae7f1b287bbe3af484b04f43ea\"},\"headline\":\"Judicializados presuntos integrantes de red delincuencial se\u00f1alada de sacrificar caballos para vender las carne clandestinamente en la Costa Atl\u00e1ntica\",\"datePublished\":\"2022-02-05T19:00:45+00:00\",\"dateModified\":\"2022-02-12T15:44:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presuntos-integrantes-de-red-delincuencial-senalada-de-sacrificar-caballos-para-vender-las-carne-clandestinamente-en-la-costa-atlantica\/\"},\"wordCount\":590,\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presuntos-integrantes-de-red-delincuencial-senalada-de-sacrificar-caballos-para-vender-las-carne-clandestinamente-en-la-costa-atlantica\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Foto-1-5.jpg\",\"keywords\":[\"Atl\u00e1ntico\",\"Seguridad territorial\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presuntos-integrantes-de-red-delincuencial-senalada-de-sacrificar-caballos-para-vender-las-carne-clandestinamente-en-la-costa-atlantica\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presuntos-integrantes-de-red-delincuencial-senalada-de-sacrificar-caballos-para-vender-las-carne-clandestinamente-en-la-costa-atlantica\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presuntos-integrantes-de-red-delincuencial-senalada-de-sacrificar-caballos-para-vender-las-carne-clandestinamente-en-la-costa-atlantica\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presuntos-integrantes-de-red-delincuencial-senalada-de-sacrificar-caballos-para-vender-las-carne-clandestinamente-en-la-costa-atlantica\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Foto-1-5.jpg\",\"datePublished\":\"2022-02-05T19:00:45+00:00\",\"dateModified\":\"2022-02-12T15:44:36+00:00\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presuntos-integrantes-de-red-delincuencial-senalada-de-sacrificar-caballos-para-vender-las-carne-clandestinamente-en-la-costa-atlantica\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presuntos-integrantes-de-red-delincuencial-senalada-de-sacrificar-caballos-para-vender-las-carne-clandestinamente-en-la-costa-atlantica\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presuntos-integrantes-de-red-delincuencial-senalada-de-sacrificar-caballos-para-vender-las-carne-clandestinamente-en-la-costa-atlantica\/#primaryimage\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Foto-1-5.jpg\",\"contentUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Foto-1-5.jpg\",\"width\":1024,\"height\":789,\"caption\":\"En el lugar se encontraron 70 kilogramos de piel de caballo y burro y cerca de 100 kilogramos de carne y v\u00edsceras de equino.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presuntos-integrantes-de-red-delincuencial-senalada-de-sacrificar-caballos-para-vender-las-carne-clandestinamente-en-la-costa-atlantica\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Judicializados presuntos integrantes de red delincuencial se\u00f1alada de sacrificar caballos para vender las carne clandestinamente en la Costa Atl\u00e1ntica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"contentUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"width\":300,\"height\":90,\"caption\":\"Fiscal\u00eda General de la Naci\u00f3n\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/FiscaliaCol\",\"https:\/\/x.com\/FiscaliaCol\",\"https:\/\/www.instagram.com\/fiscaliacol\",\"https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/\",\"https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf28d8ae7f1b287bbe3af484b04f43ea\",\"name\":\"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9d55ae161d32da16dbdd0b380c080a5f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9d55ae161d32da16dbdd0b380c080a5f?s=96&d=mm&r=g\",\"caption\":\"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n\"},\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/author\/kbonilla\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Fiscal\u00eda General de la Naci\u00f3n","og_description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","og_url":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presuntos-integrantes-de-red-delincuencial-senalada-de-sacrificar-caballos-para-vender-las-carne-clandestinamente-en-la-costa-atlantica\/","og_site_name":"Fiscal\u00eda General de la Naci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/FiscaliaCol","article_published_time":"2022-02-05T19:00:45+00:00","article_modified_time":"2022-02-12T15:44:36+00:00","og_image":[{"url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Foto-1-5.jpg","type":"","width":"","height":""}],"author":"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@FiscaliaCol","twitter_site":"@FiscaliaCol","twitter_misc":{"Escrito por":"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presuntos-integrantes-de-red-delincuencial-senalada-de-sacrificar-caballos-para-vender-las-carne-clandestinamente-en-la-costa-atlantica\/#article","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presuntos-integrantes-de-red-delincuencial-senalada-de-sacrificar-caballos-para-vender-las-carne-clandestinamente-en-la-costa-atlantica\/"},"author":{"name":"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf28d8ae7f1b287bbe3af484b04f43ea"},"headline":"Judicializados presuntos integrantes de red delincuencial se\u00f1alada de sacrificar caballos para vender las carne clandestinamente en la Costa Atl\u00e1ntica","datePublished":"2022-02-05T19:00:45+00:00","dateModified":"2022-02-12T15:44:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presuntos-integrantes-de-red-delincuencial-senalada-de-sacrificar-caballos-para-vender-las-carne-clandestinamente-en-la-costa-atlantica\/"},"wordCount":590,"publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presuntos-integrantes-de-red-delincuencial-senalada-de-sacrificar-caballos-para-vender-las-carne-clandestinamente-en-la-costa-atlantica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Foto-1-5.jpg","keywords":["Atl\u00e1ntico","Seguridad territorial"],"articleSection":["Noticias"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presuntos-integrantes-de-red-delincuencial-senalada-de-sacrificar-caballos-para-vender-las-carne-clandestinamente-en-la-costa-atlantica\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presuntos-integrantes-de-red-delincuencial-senalada-de-sacrificar-caballos-para-vender-las-carne-clandestinamente-en-la-costa-atlantica\/","name":"Fiscal\u00eda General de la Naci\u00f3n","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presuntos-integrantes-de-red-delincuencial-senalada-de-sacrificar-caballos-para-vender-las-carne-clandestinamente-en-la-costa-atlantica\/#primaryimage"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presuntos-integrantes-de-red-delincuencial-senalada-de-sacrificar-caballos-para-vender-las-carne-clandestinamente-en-la-costa-atlantica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Foto-1-5.jpg","datePublished":"2022-02-05T19:00:45+00:00","dateModified":"2022-02-12T15:44:36+00:00","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","breadcrumb":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presuntos-integrantes-de-red-delincuencial-senalada-de-sacrificar-caballos-para-vender-las-carne-clandestinamente-en-la-costa-atlantica\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presuntos-integrantes-de-red-delincuencial-senalada-de-sacrificar-caballos-para-vender-las-carne-clandestinamente-en-la-costa-atlantica\/"]}]},{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presuntos-integrantes-de-red-delincuencial-senalada-de-sacrificar-caballos-para-vender-las-carne-clandestinamente-en-la-costa-atlantica\/#primaryimage","url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Foto-1-5.jpg","contentUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Foto-1-5.jpg","width":1024,"height":789,"caption":"En el lugar se encontraron 70 kilogramos de piel de caballo y burro y cerca de 100 kilogramos de carne y v\u00edsceras de equino."},{"@type":"BreadcrumbList","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presuntos-integrantes-de-red-delincuencial-senalada-de-sacrificar-caballos-para-vender-las-carne-clandestinamente-en-la-costa-atlantica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fiscalia.gov.co\/colombia\/"},{"@type":"ListItem","position":2,"name":"Judicializados presuntos integrantes de red delincuencial se\u00f1alada de sacrificar caballos para vender las carne clandestinamente en la Costa Atl\u00e1ntica"}]},{"@type":"WebSite","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","name":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization","name":"Fiscal\u00eda General de la Naci\u00f3n","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","contentUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","width":300,"height":90,"caption":"Fiscal\u00eda General de la Naci\u00f3n"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FiscaliaCol","https:\/\/x.com\/FiscaliaCol","https:\/\/www.instagram.com\/fiscaliacol","https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/","https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh"]},{"@type":"Person","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf28d8ae7f1b287bbe3af484b04f43ea","name":"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9d55ae161d32da16dbdd0b380c080a5f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9d55ae161d32da16dbdd0b380c080a5f?s=96&d=mm&r=g","caption":"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n"},"url":"https:\/\/www.fiscalia.gov.co\/colombia\/author\/kbonilla\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/240079","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/users\/162"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/comments?post=240079"}],"version-history":[{"count":2,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/240079\/revisions"}],"predecessor-version":[{"id":240082,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/240079\/revisions\/240082"}],"wp:attachment":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/media?parent=240079"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/categories?post=240079"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/tags?post=240079"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}