{"id":236143,"date":"2021-12-02T10:18:42","date_gmt":"2021-12-02T15:18:42","guid":{"rendered":"https:\/\/www.fiscalia.gov.co\/colombia\/?p=236143"},"modified":"2021-12-02T10:18:42","modified_gmt":"2021-12-02T15:18:42","slug":"fiscalia-presento-contundentes-resultados-en-la-lucha-contra-la-violencia-y-de-genero","status":"publish","type":"post","link":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-presento-contundentes-resultados-en-la-lucha-contra-la-violencia-y-de-genero\/","title":{"rendered":"Fiscal\u00eda present\u00f3 contundentes resultados en la lucha contra la violencia y de g\u00e9nero"},"content":{"rendered":"<p>En el marco\u00a0de las actividades programadas para la lucha contra la violencia de la mujer\u00a0en el departamento\u00a0de La Guajira\u00a0se desarroll\u00f3 la campa\u00f1a \u00danete para Ponerle\u00a0Fin a la\u00a0 Violencia Contra la Mujer Ya.<\/p>\n<p>En \u00e9se sentido la Fiscal\u00eda General de la Naci\u00f3n como miembro activo del comit\u00e9 articulador para el abordaje integral de las violencias por razones sexo y g\u00e9nero, de las mujeres, ni\u00f1os, ni\u00f1as y adolescentes\u00a0ha\u00a0priorizado proteger la vida e integridad de las mujeres en Colombia.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-236144\" src=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/IMG-20211202-WA0044.jpg\" alt=\"\" width=\"1545\" height=\"914\" srcset=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/IMG-20211202-WA0044.jpg 1545w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/IMG-20211202-WA0044-300x177.jpg 300w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/IMG-20211202-WA0044-1024x606.jpg 1024w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/IMG-20211202-WA0044-768x454.jpg 768w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/IMG-20211202-WA0044-1536x909.jpg 1536w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/IMG-20211202-WA0044-696x412.jpg 696w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/IMG-20211202-WA0044-1068x632.jpg 1068w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/IMG-20211202-WA0044-710x420.jpg 710w\" sizes=\"auto, (max-width: 1545px) 100vw, 1545px\" \/><\/p>\n<p>Con estos lineamientos la entidad ha logrado importantes resultados en la seccional\u00a0de la Guajira durante el\u00a0 \u00a0periodo correspondiente al a\u00f1o 2021.<\/p>\n<p>Balance de violencia de g\u00e9nero<\/p>\n<ul>\n<li><strong>Feminicidio<\/strong><\/li>\n<\/ul>\n<p>La entidad logr\u00f3 en el \u00faltimo a\u00f1o un porcentaje del 100 % en esclarecimiento de feminicidios con 5 casos registrados.\u00a0\u00a0 En 2020, no se registraron v\u00edctimas por este delito y, para el mismo per\u00edodo comprendido entre el 1 de enero y el 31 de diciembre en 2019 se registr\u00f3 1 caso, lo que represent\u00f3 un avance del 100 %.<\/p>\n<ul>\n<li><strong>Violencia intrafamiliar \u00a0<\/strong><\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-236145\" src=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/IMG-20211202-WA0045.jpg\" alt=\"\" width=\"1289\" height=\"906\" srcset=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/IMG-20211202-WA0045.jpg 1289w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/IMG-20211202-WA0045-300x211.jpg 300w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/IMG-20211202-WA0045-1024x720.jpg 1024w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/IMG-20211202-WA0045-768x540.jpg 768w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/IMG-20211202-WA0045-696x489.jpg 696w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/IMG-20211202-WA0045-1068x751.jpg 1068w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/IMG-20211202-WA0045-598x420.jpg 598w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/IMG-20211202-WA0045-100x70.jpg 100w\" sizes=\"auto, (max-width: 1289px) 100vw, 1289px\" \/><\/p>\n<p>Se identific\u00f3 que el delito de violencia intrafamiliar es la segunda conducta m\u00e1s denunciada.\u00a0 En 2019 se registraron\u00a0141 casos de los cuales se avanz\u00f3 en 38,\u00a0lo que equivale a un 18.88 %, en el 2020 se evidenciaron 467 casos con avances\u00a0de 156,\u00a0lo que corresponde a un\u00a032, 55 %, en el\u00a02021 se registraron 525 casos logrado un avance en 332 equivalente al 63%.<\/p>\n<ul>\n<li><strong>Violencia sexual<\/strong><\/li>\n<\/ul>\n<p>Por otra parte, por delitos sexuales, en 2019 se registraron 143 casos, logrando un avance en 27,\u00a0lo que corresponde al 18.88 %,\u00a0mientras que en el\u00a02020 se registraron 278 alcanzando\u00a0un\u00a0avance en 41 de ellos, lo que equivaldr\u00eda al 14, 86, finalmente en el\u00a02021 se registraron 266 casos de estos en 119 se logr\u00f3 avances lo corresponde al 30, 57 %.<\/p>\n<ul>\n<li><strong>Homicidio<\/strong><\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-236146\" src=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/IMG-20211202-WA0046.jpg\" alt=\"\" width=\"1600\" height=\"737\" srcset=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/IMG-20211202-WA0046.jpg 1600w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/IMG-20211202-WA0046-300x138.jpg 300w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/IMG-20211202-WA0046-1024x472.jpg 1024w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/IMG-20211202-WA0046-768x354.jpg 768w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/IMG-20211202-WA0046-1536x708.jpg 1536w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/IMG-20211202-WA0046-696x321.jpg 696w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/IMG-20211202-WA0046-1068x492.jpg 1068w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/IMG-20211202-WA0046-912x420.jpg 912w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><\/p>\n<p>Durante el 2019 se registraron 102 casos con un avance en 27,\u00a0lo que correspondi\u00f3 a un 23, 53%, en el 2020 fueron reportados 186 casos sobre los que se avanz\u00f3 en 37,\u00a0arrojando un porcentaje del 23, 72%, mientras que en el 2021 se registraron 165 casos avanzando en 60 lo que equivale al 36, 36 %.<\/p>\n<p>La Fiscal\u00eda General de la Naci\u00f3n publica la presente informaci\u00f3n por considerarla de inter\u00e9s general.<\/p>\n<p>La Fiscal\u00eda habla con resultados.<\/p>\n<p>REDH\/FAGH\/DFHI<\/p>\n\n<div class=\"twitter-share\"><a href=\"https:\/\/twitter.com\/intent\/tweet?via=fiscaliacol\" class=\"twitter-share-button\">Tweet<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>En el marco\u00a0de las actividades programadas para la lucha contra la violencia de la mujer\u00a0en el departamento\u00a0de La Guajira\u00a0se desarroll\u00f3 la campa\u00f1a \u00danete para Ponerle\u00a0Fin a la\u00a0 Violencia Contra la [&hellip;]<\/p>\n","protected":false},"author":176,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[1,797,303],"tags":[24189,78,24526,4614,24481],"class_list":["post-236143","post","type-post","status-publish","format-standard","category-noticias","category-seccional-riohacha","category-seccionales","tag-fiscal-francisco-barbosa-delgado","tag-fiscal-general-de-la-nacion","tag-fiscal-general-francisco-barbosa-delgado","tag-fiscalia-2","tag-fiscalia-de-colombia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fiscal\u00eda General de la Naci\u00f3n<\/title>\n<meta name=\"description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-presento-contundentes-resultados-en-la-lucha-contra-la-violencia-y-de-genero\/\" \/>\n<meta property=\"og:site_name\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FiscaliaCol\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-02T15:18:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/IMG-20211202-WA0044.jpg\" \/>\n<meta name=\"author\" content=\"Johanna Black Prieto Pe\u00f1a\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:site\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Johanna Black Prieto Pe\u00f1a\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-presento-contundentes-resultados-en-la-lucha-contra-la-violencia-y-de-genero\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-presento-contundentes-resultados-en-la-lucha-contra-la-violencia-y-de-genero\/\"},\"author\":{\"name\":\"Johanna Black Prieto Pe\u00f1a\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/b19b49f26569f91393176a2b3d13a0e5\"},\"headline\":\"Fiscal\u00eda present\u00f3 contundentes resultados en la lucha contra la violencia y de g\u00e9nero\",\"datePublished\":\"2021-12-02T15:18:42+00:00\",\"dateModified\":\"2021-12-02T15:18:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-presento-contundentes-resultados-en-la-lucha-contra-la-violencia-y-de-genero\/\"},\"wordCount\":364,\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-presento-contundentes-resultados-en-la-lucha-contra-la-violencia-y-de-genero\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/IMG-20211202-WA0044.jpg\",\"keywords\":[\"Fiscal Francisco Barbosa Delgado\",\"Fiscal General de la Naci\u00f3n\",\"Fiscal General Francisco Barbosa Delgado\",\"Fiscal\u00eda\",\"Fiscal\u00eda de Colombia\"],\"articleSection\":[\"Noticias\",\"Seccional Riohacha\",\"Seccionales\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-presento-contundentes-resultados-en-la-lucha-contra-la-violencia-y-de-genero\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-presento-contundentes-resultados-en-la-lucha-contra-la-violencia-y-de-genero\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-presento-contundentes-resultados-en-la-lucha-contra-la-violencia-y-de-genero\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-presento-contundentes-resultados-en-la-lucha-contra-la-violencia-y-de-genero\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/IMG-20211202-WA0044.jpg\",\"datePublished\":\"2021-12-02T15:18:42+00:00\",\"dateModified\":\"2021-12-02T15:18:42+00:00\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-presento-contundentes-resultados-en-la-lucha-contra-la-violencia-y-de-genero\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-presento-contundentes-resultados-en-la-lucha-contra-la-violencia-y-de-genero\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-presento-contundentes-resultados-en-la-lucha-contra-la-violencia-y-de-genero\/#primaryimage\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/IMG-20211202-WA0044.jpg\",\"contentUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/IMG-20211202-WA0044.jpg\",\"width\":1545,\"height\":914},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-presento-contundentes-resultados-en-la-lucha-contra-la-violencia-y-de-genero\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fiscal\u00eda present\u00f3 contundentes resultados en la lucha contra la violencia y de g\u00e9nero\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"contentUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"width\":300,\"height\":90,\"caption\":\"Fiscal\u00eda General de la Naci\u00f3n\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/FiscaliaCol\",\"https:\/\/x.com\/FiscaliaCol\",\"https:\/\/www.instagram.com\/fiscaliacol\",\"https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/\",\"https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/b19b49f26569f91393176a2b3d13a0e5\",\"name\":\"Johanna Black Prieto Pe\u00f1a\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7f04518e1774335e76d761d76f04003e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7f04518e1774335e76d761d76f04003e?s=96&d=mm&r=g\",\"caption\":\"Johanna Black Prieto Pe\u00f1a\"},\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/author\/jprieto\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Fiscal\u00eda General de la Naci\u00f3n","og_description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","og_url":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-presento-contundentes-resultados-en-la-lucha-contra-la-violencia-y-de-genero\/","og_site_name":"Fiscal\u00eda General de la Naci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/FiscaliaCol","article_published_time":"2021-12-02T15:18:42+00:00","og_image":[{"url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/IMG-20211202-WA0044.jpg","type":"","width":"","height":""}],"author":"Johanna Black Prieto Pe\u00f1a","twitter_card":"summary_large_image","twitter_creator":"@FiscaliaCol","twitter_site":"@FiscaliaCol","twitter_misc":{"Escrito por":"Johanna Black Prieto Pe\u00f1a","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-presento-contundentes-resultados-en-la-lucha-contra-la-violencia-y-de-genero\/#article","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-presento-contundentes-resultados-en-la-lucha-contra-la-violencia-y-de-genero\/"},"author":{"name":"Johanna Black Prieto Pe\u00f1a","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/b19b49f26569f91393176a2b3d13a0e5"},"headline":"Fiscal\u00eda present\u00f3 contundentes resultados en la lucha contra la violencia y de g\u00e9nero","datePublished":"2021-12-02T15:18:42+00:00","dateModified":"2021-12-02T15:18:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-presento-contundentes-resultados-en-la-lucha-contra-la-violencia-y-de-genero\/"},"wordCount":364,"publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-presento-contundentes-resultados-en-la-lucha-contra-la-violencia-y-de-genero\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/IMG-20211202-WA0044.jpg","keywords":["Fiscal Francisco Barbosa Delgado","Fiscal General de la Naci\u00f3n","Fiscal General Francisco Barbosa Delgado","Fiscal\u00eda","Fiscal\u00eda de Colombia"],"articleSection":["Noticias","Seccional Riohacha","Seccionales"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-presento-contundentes-resultados-en-la-lucha-contra-la-violencia-y-de-genero\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-presento-contundentes-resultados-en-la-lucha-contra-la-violencia-y-de-genero\/","name":"Fiscal\u00eda General de la Naci\u00f3n","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-presento-contundentes-resultados-en-la-lucha-contra-la-violencia-y-de-genero\/#primaryimage"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-presento-contundentes-resultados-en-la-lucha-contra-la-violencia-y-de-genero\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/IMG-20211202-WA0044.jpg","datePublished":"2021-12-02T15:18:42+00:00","dateModified":"2021-12-02T15:18:42+00:00","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","breadcrumb":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-presento-contundentes-resultados-en-la-lucha-contra-la-violencia-y-de-genero\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-presento-contundentes-resultados-en-la-lucha-contra-la-violencia-y-de-genero\/"]}]},{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-presento-contundentes-resultados-en-la-lucha-contra-la-violencia-y-de-genero\/#primaryimage","url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/IMG-20211202-WA0044.jpg","contentUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/IMG-20211202-WA0044.jpg","width":1545,"height":914},{"@type":"BreadcrumbList","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/fiscalia-presento-contundentes-resultados-en-la-lucha-contra-la-violencia-y-de-genero\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fiscalia.gov.co\/colombia\/"},{"@type":"ListItem","position":2,"name":"Fiscal\u00eda present\u00f3 contundentes resultados en la lucha contra la violencia y de g\u00e9nero"}]},{"@type":"WebSite","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","name":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization","name":"Fiscal\u00eda General de la Naci\u00f3n","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","contentUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","width":300,"height":90,"caption":"Fiscal\u00eda General de la Naci\u00f3n"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FiscaliaCol","https:\/\/x.com\/FiscaliaCol","https:\/\/www.instagram.com\/fiscaliacol","https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/","https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh"]},{"@type":"Person","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/b19b49f26569f91393176a2b3d13a0e5","name":"Johanna Black Prieto Pe\u00f1a","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7f04518e1774335e76d761d76f04003e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7f04518e1774335e76d761d76f04003e?s=96&d=mm&r=g","caption":"Johanna Black Prieto Pe\u00f1a"},"url":"https:\/\/www.fiscalia.gov.co\/colombia\/author\/jprieto\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/236143","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/users\/176"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/comments?post=236143"}],"version-history":[{"count":1,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/236143\/revisions"}],"predecessor-version":[{"id":236147,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/236143\/revisions\/236147"}],"wp:attachment":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/media?parent=236143"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/categories?post=236143"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/tags?post=236143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}