{"id":235745,"date":"2021-11-27T09:28:35","date_gmt":"2021-11-27T14:28:35","guid":{"rendered":"https:\/\/www.fiscalia.gov.co\/colombia\/?p=235745"},"modified":"2021-12-07T16:31:29","modified_gmt":"2021-12-07T21:31:29","slug":"judicializado-presunto-responsable-de-matadero-ilegal-de-carne-de-caballo-y-de-burro","status":"publish","type":"post","link":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presunto-responsable-de-matadero-ilegal-de-carne-de-caballo-y-de-burro\/","title":{"rendered":"Judicializado presunto responsable de matadero ilegal de carne de caballo y de burro"},"content":{"rendered":"<h4 dir=\"ltr\"><i><span lang=\"ES\">En un inmueble del barrio Rebolo de Barranquilla fueron encontradas evidencias sobre el sacrificio de animales para su posterior comercializaci\u00f3n.<u><\/u>\u00a0<\/span><\/i><\/h4>\n<p dir=\"ltr\"><span lang=\"ES\">La Fiscal\u00eda General de la Naci\u00f3n logr\u00f3 la judicializaci\u00f3n de Hip\u00f3lito Enrique Meri\u00f1o, quien estar\u00eda <a href=\"https:\/\/www.fiscalia.gov.co\/colombia\/dano-al-medio-ambiente\/fiscalia-pone-al-descubierto-red-delictiva-senalada-de-auspiciar-la-caza-ilegal-de-chiguiro-y-la-comercializacion-de-su-carne\/\" target=\"_blank\" rel=\"noopener noreferrer\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.fiscalia.gov.co\/colombia\/dano-al-medio-ambiente\/fiscalia-pone-al-descubierto-red-delictiva-senalada-de-auspiciar-la-caza-ilegal-de-chiguiro-y-la-comercializacion-de-su-carne\/&amp;source=gmail&amp;ust=1638109533392000&amp;usg=AOvVaw2Pe9ihl0jILm1jGs_nluL5\">involucrado en el sacrificio de caballos y burros, y la posterior comercializaci\u00f3n de la carne en Barranquilla y otros municipios de Atl\u00e1ntico.<\/a><\/span><span lang=\"ES\"><u><\/u>\u00a0<\/span><\/p>\n<div dir=\"ltr\">\n<figure id=\"attachment_235746\" aria-describedby=\"caption-attachment-235746\" style=\"width: 1280px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-235746\" src=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Foto-1-4.jpg\" alt=\"\" width=\"1280\" height=\"720\" srcset=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Foto-1-4.jpg 1280w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Foto-1-4-300x169.jpg 300w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Foto-1-4-1024x576.jpg 1024w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Foto-1-4-768x432.jpg 768w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Foto-1-4-696x392.jpg 696w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Foto-1-4-1068x601.jpg 1068w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Foto-1-4-747x420.jpg 747w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><figcaption id=\"caption-attachment-235746\" class=\"wp-caption-text\"><br \/>Foto 1: Se\u00a0encontraron 14 animales en pie, seis m\u00e1s muertos y partes de otros almacenadas en un refrigerador.<\/figcaption><\/figure>\n<p><span lang=\"ES\">En diligencia de registro y allanamiento realizada en un inmueble ubicado en el barrio Rebolo,\u00a0<\/span><b><span lang=\"ES\">se encontraron 14 animales en pie, seis m\u00e1s muertos y partes de otros almacenadas en un refrigerador.\u00a0<\/span><\/b><span lang=\"ES\">Adem\u00e1s, fueron hallados libros de contabilidad con registros de la venta de carne y de los dineros obtenidos por esta actividad.\u00a0<\/span><span lang=\"ES\"><u><\/u>\u00a0<u><\/u><\/span><\/p>\n<p><span lang=\"ES\">El procedimiento cont\u00f3 con el acompa\u00f1amiento de un veterinario de la Secretar\u00eda de Salud de Barranquilla.\u00a0<\/span><b><span lang=\"ES\">El experto dictamin\u00f3 que los burros y caballos vivos estaban en mal estado f\u00edsico y presentaban graves lesiones.\u00a0<\/span><\/b><b><span lang=\"ES\"><u><\/u>\u00a0<u><\/u><\/span><\/b><\/p>\n<p><span lang=\"ES\">Durante las verificaciones la autoridad ambiental indic\u00f3 que la vivienda y la persona que la ocupaba no ten\u00edan permisos para el sacrificio de equinos y burros. Adem\u00e1s,\u00a0<\/span><b><span lang=\"ES\">constat\u00f3 vertimientos de l\u00edquidos y residuos a las fuentes h\u00eddricas aleda\u00f1as y al suelo, situaci\u00f3n que representa grave riesgo para la salud.<\/span><\/b><b><span lang=\"ES\"><u><\/u>\u00a0<u><\/u><\/span><\/b><\/p>\n<p><span lang=\"ES\">Por su presunta responsabilidad en estos hechos, Hip\u00f3lito Enrique Meri\u00f1o fue imputado por los delitos de maltrato animal; corrupci\u00f3n de alimentos, productos m\u00e9dicos o material profil\u00e1ctico; y contaminaci\u00f3n ambiental.\u00a0<\/span><b><span lang=\"ES\">Por disposici\u00f3n de un juez de control de garant\u00edas, deber\u00e1 cumplir medida de aseguramiento privativa de la libertad en su lugar de residencia.<\/span><\/b><b><span lang=\"ES\"><u><\/u>\u00a0<u><\/u><\/span><\/b><\/p>\n<p><span lang=\"ES\">AMCJ\/JARG\/MCR\/<u><\/u>\u00a0<u><\/u><\/span><\/p>\n<p style=\"text-align: left;\" align=\"center\"><b><span lang=\"ES\">La Fiscal\u00eda habla con resultados<\/span><\/b><b><span lang=\"ES-CO\"><u><\/u>\u00a0<u><\/u><\/span><\/b><\/p>\n<p dir=\"ltr\" style=\"text-align: left;\" align=\"center\"><i>La informaci\u00f3n contenida en este bolet\u00edn de prensa corresponde a la narraci\u00f3n de los hechos noticiosos objetivos, suministrados por los funcionarios encargados de adelantar las investigaciones penales al interior de la Fiscal\u00eda General de la Naci\u00f3n. Para el momento de la divulgaci\u00f3n de este comunicado, la situaci\u00f3n jur\u00eddica de la(s) persona(s) relacionada(s) se encuentra pendiente de resolver por la autoridad judicial competente, siempre bajo los preceptos de la presunci\u00f3n de inocencia, consagrados en el art\u00edculo 29 de la Constituci\u00f3n Pol\u00edtica y el art\u00edculo 7\u00ba de la Ley 906 de 2004.<\/i><\/p>\n<\/div>\n\n<div class=\"twitter-share\"><a href=\"https:\/\/twitter.com\/intent\/tweet?via=fiscaliacol\" class=\"twitter-share-button\">Tweet<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>En un inmueble del barrio Rebolo de Barranquilla fueron encontradas evidencias sobre el sacrificio de animales para su posterior comercializaci\u00f3n.\u00a0 La Fiscal\u00eda General de la Naci\u00f3n logr\u00f3 la judicializaci\u00f3n de [&hellip;]<\/p>\n","protected":false},"author":176,"featured_media":236549,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[1,320,303],"tags":[14083,21553,18566],"class_list":["post-235745","post","type-post","status-publish","format-video","has-post-thumbnail","category-noticias","category-seccional-barranquilla","category-seccionales","tag-atlantico","tag-dano-al-medio-ambiente","tag-maltrato-animal","post_format-post-format-video"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fiscal\u00eda General de la Naci\u00f3n<\/title>\n<meta name=\"description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presunto-responsable-de-matadero-ilegal-de-carne-de-caballo-y-de-burro\/\" \/>\n<meta property=\"og:site_name\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FiscaliaCol\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-27T14:28:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-07T21:31:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/maxresdefault-239.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Johanna Black Prieto Pe\u00f1a\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:site\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Johanna Black Prieto Pe\u00f1a\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presunto-responsable-de-matadero-ilegal-de-carne-de-caballo-y-de-burro\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presunto-responsable-de-matadero-ilegal-de-carne-de-caballo-y-de-burro\/\"},\"author\":{\"name\":\"Johanna Black Prieto Pe\u00f1a\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/b19b49f26569f91393176a2b3d13a0e5\"},\"headline\":\"Judicializado presunto responsable de matadero ilegal de carne de caballo y de burro\",\"datePublished\":\"2021-11-27T14:28:35+00:00\",\"dateModified\":\"2021-12-07T21:31:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presunto-responsable-de-matadero-ilegal-de-carne-de-caballo-y-de-burro\/\"},\"wordCount\":421,\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presunto-responsable-de-matadero-ilegal-de-carne-de-caballo-y-de-burro\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/maxresdefault-239.jpg\",\"keywords\":[\"Atl\u00e1ntico\",\"Da\u00f1o al medio ambiente\",\"Maltrato animal\"],\"articleSection\":[\"Noticias\",\"Seccional Barranquilla\",\"Seccionales\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presunto-responsable-de-matadero-ilegal-de-carne-de-caballo-y-de-burro\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presunto-responsable-de-matadero-ilegal-de-carne-de-caballo-y-de-burro\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presunto-responsable-de-matadero-ilegal-de-carne-de-caballo-y-de-burro\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presunto-responsable-de-matadero-ilegal-de-carne-de-caballo-y-de-burro\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/maxresdefault-239.jpg\",\"datePublished\":\"2021-11-27T14:28:35+00:00\",\"dateModified\":\"2021-12-07T21:31:29+00:00\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presunto-responsable-de-matadero-ilegal-de-carne-de-caballo-y-de-burro\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presunto-responsable-de-matadero-ilegal-de-carne-de-caballo-y-de-burro\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presunto-responsable-de-matadero-ilegal-de-carne-de-caballo-y-de-burro\/#primaryimage\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/maxresdefault-239.jpg\",\"contentUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/maxresdefault-239.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presunto-responsable-de-matadero-ilegal-de-carne-de-caballo-y-de-burro\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Judicializado presunto responsable de matadero ilegal de carne de caballo y de burro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"contentUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"width\":300,\"height\":90,\"caption\":\"Fiscal\u00eda General de la Naci\u00f3n\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/FiscaliaCol\",\"https:\/\/x.com\/FiscaliaCol\",\"https:\/\/www.instagram.com\/fiscaliacol\",\"https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/\",\"https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/b19b49f26569f91393176a2b3d13a0e5\",\"name\":\"Johanna Black Prieto Pe\u00f1a\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7f04518e1774335e76d761d76f04003e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7f04518e1774335e76d761d76f04003e?s=96&d=mm&r=g\",\"caption\":\"Johanna Black Prieto Pe\u00f1a\"},\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/author\/jprieto\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Fiscal\u00eda General de la Naci\u00f3n","og_description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","og_url":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presunto-responsable-de-matadero-ilegal-de-carne-de-caballo-y-de-burro\/","og_site_name":"Fiscal\u00eda General de la Naci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/FiscaliaCol","article_published_time":"2021-11-27T14:28:35+00:00","article_modified_time":"2021-12-07T21:31:29+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/maxresdefault-239.jpg","type":"image\/jpeg"}],"author":"Johanna Black Prieto Pe\u00f1a","twitter_card":"summary_large_image","twitter_creator":"@FiscaliaCol","twitter_site":"@FiscaliaCol","twitter_misc":{"Escrito por":"Johanna Black Prieto Pe\u00f1a","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presunto-responsable-de-matadero-ilegal-de-carne-de-caballo-y-de-burro\/#article","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presunto-responsable-de-matadero-ilegal-de-carne-de-caballo-y-de-burro\/"},"author":{"name":"Johanna Black Prieto Pe\u00f1a","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/b19b49f26569f91393176a2b3d13a0e5"},"headline":"Judicializado presunto responsable de matadero ilegal de carne de caballo y de burro","datePublished":"2021-11-27T14:28:35+00:00","dateModified":"2021-12-07T21:31:29+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presunto-responsable-de-matadero-ilegal-de-carne-de-caballo-y-de-burro\/"},"wordCount":421,"publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presunto-responsable-de-matadero-ilegal-de-carne-de-caballo-y-de-burro\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/maxresdefault-239.jpg","keywords":["Atl\u00e1ntico","Da\u00f1o al medio ambiente","Maltrato animal"],"articleSection":["Noticias","Seccional Barranquilla","Seccionales"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presunto-responsable-de-matadero-ilegal-de-carne-de-caballo-y-de-burro\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presunto-responsable-de-matadero-ilegal-de-carne-de-caballo-y-de-burro\/","name":"Fiscal\u00eda General de la Naci\u00f3n","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presunto-responsable-de-matadero-ilegal-de-carne-de-caballo-y-de-burro\/#primaryimage"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presunto-responsable-de-matadero-ilegal-de-carne-de-caballo-y-de-burro\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/maxresdefault-239.jpg","datePublished":"2021-11-27T14:28:35+00:00","dateModified":"2021-12-07T21:31:29+00:00","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","breadcrumb":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presunto-responsable-de-matadero-ilegal-de-carne-de-caballo-y-de-burro\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presunto-responsable-de-matadero-ilegal-de-carne-de-caballo-y-de-burro\/"]}]},{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presunto-responsable-de-matadero-ilegal-de-carne-de-caballo-y-de-burro\/#primaryimage","url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/maxresdefault-239.jpg","contentUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/maxresdefault-239.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/judicializado-presunto-responsable-de-matadero-ilegal-de-carne-de-caballo-y-de-burro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fiscalia.gov.co\/colombia\/"},{"@type":"ListItem","position":2,"name":"Judicializado presunto responsable de matadero ilegal de carne de caballo y de burro"}]},{"@type":"WebSite","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","name":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization","name":"Fiscal\u00eda General de la Naci\u00f3n","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","contentUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","width":300,"height":90,"caption":"Fiscal\u00eda General de la Naci\u00f3n"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FiscaliaCol","https:\/\/x.com\/FiscaliaCol","https:\/\/www.instagram.com\/fiscaliacol","https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/","https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh"]},{"@type":"Person","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/b19b49f26569f91393176a2b3d13a0e5","name":"Johanna Black Prieto Pe\u00f1a","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7f04518e1774335e76d761d76f04003e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7f04518e1774335e76d761d76f04003e?s=96&d=mm&r=g","caption":"Johanna Black Prieto Pe\u00f1a"},"url":"https:\/\/www.fiscalia.gov.co\/colombia\/author\/jprieto\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/235745","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/users\/176"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/comments?post=235745"}],"version-history":[{"count":1,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/235745\/revisions"}],"predecessor-version":[{"id":235747,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/235745\/revisions\/235747"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/media\/236549"}],"wp:attachment":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/media?parent=235745"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/categories?post=235745"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/tags?post=235745"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}