{"id":230168,"date":"2021-09-19T17:55:32","date_gmt":"2021-09-19T22:55:32","guid":{"rendered":"https:\/\/www.fiscalia.gov.co\/colombia\/?p=230168"},"modified":"2021-09-19T18:11:56","modified_gmt":"2021-09-19T23:11:56","slug":"tras-apelacion-de-la-fiscalia-tio-politico-de-joven-desaparecida-en-corregimiento-de-cartagena-fue-enviado-a-prision","status":"publish","type":"post","link":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/tras-apelacion-de-la-fiscalia-tio-politico-de-joven-desaparecida-en-corregimiento-de-cartagena-fue-enviado-a-prision\/","title":{"rendered":"Tras apelaci\u00f3n de la Fiscal\u00eda, t\u00edo pol\u00edtico de joven desaparecida en corregimiento de Cartagena fue enviado a prisi\u00f3n"},"content":{"rendered":"<h4><strong><em>V\u00edctima de 15 a\u00f1os fue vista por \u00faltima vez el pasado 19 de marzo, cuando sali\u00f3 de su casa en compa\u00f1\u00eda del hoy procesado.<\/em><\/strong><\/h4>\n<p>&nbsp;<\/p>\n<p>Al resolver en favor de la Fiscal\u00eda el recurso de apelaci\u00f3n interpuesto el pasado 30 de julio, el juez quinto penal del circuito de Cartagena \u2500en segunda instancia\u2500 revoc\u00f3 la decisi\u00f3n del Juzgado Cuarto Penal Municipal de Control de Garant\u00edas de esa ciudad que se abstuvo de imponer medida de aseguramiento en contra de un hombre se\u00f1alado como presunto responsable de la desaparici\u00f3n de su sobrina pol\u00edtica de 15 a\u00f1os.<\/p>\n<figure id=\"attachment_230172\" aria-describedby=\"caption-attachment-230172\" style=\"width: 892px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-230172\" src=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Wainer-Ayola-caso-desaparecida.jpg\" alt=\"\" width=\"892\" height=\"1146\" srcset=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Wainer-Ayola-caso-desaparecida.jpg 892w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Wainer-Ayola-caso-desaparecida-234x300.jpg 234w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Wainer-Ayola-caso-desaparecida-797x1024.jpg 797w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Wainer-Ayola-caso-desaparecida-768x987.jpg 768w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Wainer-Ayola-caso-desaparecida-696x894.jpg 696w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Wainer-Ayola-caso-desaparecida-327x420.jpg 327w\" sizes=\"auto, (max-width: 892px) 100vw, 892px\" \/><figcaption id=\"caption-attachment-230172\" class=\"wp-caption-text\">El procesado se present\u00f3 de forma voluntaria ante las autoridades.<\/figcaption><\/figure>\n<p>En consecuencia, el despacho impuso medida de aseguramiento en centro de reclusi\u00f3n para el procesado, por el delito de desaparici\u00f3n forzada agravada que le endilg\u00f3 el ente acusador en su momento.<\/p>\n<p>&nbsp;<\/p>\n<p>El presunto implicado fue detenido mediante orden judicial este 18 de septiembre, luego de que se presentara de forma voluntaria en la estaci\u00f3n Los Caracoles de Cartagena.<\/p>\n<p>&nbsp;<\/p>\n<p>La investigaci\u00f3n se relaciona con los hechos ocurridos el 19 de marzo \u00faltimo, cuando la adolescente desapareci\u00f3 en el sector Punta Canoa, luego de salir de su vivienda, en el corregimiento Bayunca de la capital de Bol\u00edvar, en compa\u00f1\u00eda de su t\u00edo pol\u00edtico.<\/p>\n<p>&nbsp;<\/p>\n<p>La Fiscal\u00eda General de la Naci\u00f3n habla con resultados.<\/p>\n<p>&nbsp;<\/p>\n<p>VHGB\/DLBM\/OA<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><em>La informaci\u00f3n contenida en este bolet\u00edn de prensa corresponde a la narraci\u00f3n de los hechos noticiosos objetivos, suministrados por los funcionarios encargados de adelantar las investigaciones penales al interior de la Fiscal\u00eda General de la Naci\u00f3n. Para el momento de la divulgaci\u00f3n de este comunicado, la situaci\u00f3n jur\u00eddica de la(s) persona(s) relacionada(s) se encuentra pendiente de resolver por la autoridad judicial competente, siempre bajo los preceptos de la presunci\u00f3n de inocencia, consagrados en el art\u00edculo 29 de la Constituci\u00f3n Pol\u00edtica y el art\u00edculo 7\u00ba de la Ley 906 de 2004.<\/em><\/p>\n\n<div class=\"twitter-share\"><a href=\"https:\/\/twitter.com\/intent\/tweet?via=fiscaliacol\" class=\"twitter-share-button\">Tweet<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>V\u00edctima de 15 a\u00f1os fue vista por \u00faltima vez el pasado 19 de marzo, cuando sali\u00f3 de su casa en compa\u00f1\u00eda del hoy procesado. &nbsp; Al resolver en favor de [&hellip;]<\/p>\n","protected":false},"author":175,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[1,325,24099],"tags":[363,24185,24187,1047,1185,558],"class_list":["post-230168","post","type-post","status-publish","format-standard","category-noticias","category-seccional-cartagena","category-seguridad-territorial","tag-desaparicion-forzada","tag-fiscal-barbosa","tag-fiscalia-colombia","tag-fiscalia-general-de-la-nacion","tag-medida-de-aseguramiento","tag-policia-nacional"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fiscal\u00eda General de la Naci\u00f3n<\/title>\n<meta name=\"description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/tras-apelacion-de-la-fiscalia-tio-politico-de-joven-desaparecida-en-corregimiento-de-cartagena-fue-enviado-a-prision\/\" \/>\n<meta property=\"og:site_name\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FiscaliaCol\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-19T22:55:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-19T23:11:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Wainer-Ayola-caso-desaparecida.jpg\" \/>\n<meta name=\"author\" content=\"Katherine Loaiza Mart\u00ednez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:site\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Katherine Loaiza Mart\u00ednez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/tras-apelacion-de-la-fiscalia-tio-politico-de-joven-desaparecida-en-corregimiento-de-cartagena-fue-enviado-a-prision\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/tras-apelacion-de-la-fiscalia-tio-politico-de-joven-desaparecida-en-corregimiento-de-cartagena-fue-enviado-a-prision\/\"},\"author\":{\"name\":\"Katherine Loaiza Mart\u00ednez\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/2e76b9aba5ecf875ed565ce4de0e0415\"},\"headline\":\"Tras apelaci\u00f3n de la Fiscal\u00eda, t\u00edo pol\u00edtico de joven desaparecida en corregimiento de Cartagena fue enviado a prisi\u00f3n\",\"datePublished\":\"2021-09-19T22:55:32+00:00\",\"dateModified\":\"2021-09-19T23:11:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/tras-apelacion-de-la-fiscalia-tio-politico-de-joven-desaparecida-en-corregimiento-de-cartagena-fue-enviado-a-prision\/\"},\"wordCount\":372,\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/tras-apelacion-de-la-fiscalia-tio-politico-de-joven-desaparecida-en-corregimiento-de-cartagena-fue-enviado-a-prision\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Wainer-Ayola-caso-desaparecida.jpg\",\"keywords\":[\"Desaparici\u00f3n forzada\",\"Fiscal Barbosa\",\"Fiscal\u00eda Colombia\",\"Fiscal\u00eda General de la Naci\u00f3n\",\"Medida de aseguramiento\",\"Polic\u00eda Nacional\"],\"articleSection\":[\"Noticias\",\"Seccional Cartagena\",\"Seguridad territorial\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/tras-apelacion-de-la-fiscalia-tio-politico-de-joven-desaparecida-en-corregimiento-de-cartagena-fue-enviado-a-prision\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/tras-apelacion-de-la-fiscalia-tio-politico-de-joven-desaparecida-en-corregimiento-de-cartagena-fue-enviado-a-prision\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/tras-apelacion-de-la-fiscalia-tio-politico-de-joven-desaparecida-en-corregimiento-de-cartagena-fue-enviado-a-prision\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/tras-apelacion-de-la-fiscalia-tio-politico-de-joven-desaparecida-en-corregimiento-de-cartagena-fue-enviado-a-prision\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Wainer-Ayola-caso-desaparecida.jpg\",\"datePublished\":\"2021-09-19T22:55:32+00:00\",\"dateModified\":\"2021-09-19T23:11:56+00:00\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/tras-apelacion-de-la-fiscalia-tio-politico-de-joven-desaparecida-en-corregimiento-de-cartagena-fue-enviado-a-prision\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/tras-apelacion-de-la-fiscalia-tio-politico-de-joven-desaparecida-en-corregimiento-de-cartagena-fue-enviado-a-prision\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/tras-apelacion-de-la-fiscalia-tio-politico-de-joven-desaparecida-en-corregimiento-de-cartagena-fue-enviado-a-prision\/#primaryimage\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Wainer-Ayola-caso-desaparecida.jpg\",\"contentUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Wainer-Ayola-caso-desaparecida.jpg\",\"width\":892,\"height\":1146,\"caption\":\"El procesado se present\u00f3 de forma voluntaria ante las autoridades.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/tras-apelacion-de-la-fiscalia-tio-politico-de-joven-desaparecida-en-corregimiento-de-cartagena-fue-enviado-a-prision\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tras apelaci\u00f3n de la Fiscal\u00eda, t\u00edo pol\u00edtico de joven desaparecida en corregimiento de Cartagena fue enviado a prisi\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"contentUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"width\":300,\"height\":90,\"caption\":\"Fiscal\u00eda General de la Naci\u00f3n\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/FiscaliaCol\",\"https:\/\/x.com\/FiscaliaCol\",\"https:\/\/www.instagram.com\/fiscaliacol\",\"https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/\",\"https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/2e76b9aba5ecf875ed565ce4de0e0415\",\"name\":\"Katherine Loaiza Mart\u00ednez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ab775a2f394c1b83b6d6f78680e57b50?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ab775a2f394c1b83b6d6f78680e57b50?s=96&d=mm&r=g\",\"caption\":\"Katherine Loaiza Mart\u00ednez\"},\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/author\/kloaiza\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Fiscal\u00eda General de la Naci\u00f3n","og_description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","og_url":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/tras-apelacion-de-la-fiscalia-tio-politico-de-joven-desaparecida-en-corregimiento-de-cartagena-fue-enviado-a-prision\/","og_site_name":"Fiscal\u00eda General de la Naci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/FiscaliaCol","article_published_time":"2021-09-19T22:55:32+00:00","article_modified_time":"2021-09-19T23:11:56+00:00","og_image":[{"url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Wainer-Ayola-caso-desaparecida.jpg","type":"","width":"","height":""}],"author":"Katherine Loaiza Mart\u00ednez","twitter_card":"summary_large_image","twitter_creator":"@FiscaliaCol","twitter_site":"@FiscaliaCol","twitter_misc":{"Escrito por":"Katherine Loaiza Mart\u00ednez","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/tras-apelacion-de-la-fiscalia-tio-politico-de-joven-desaparecida-en-corregimiento-de-cartagena-fue-enviado-a-prision\/#article","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/tras-apelacion-de-la-fiscalia-tio-politico-de-joven-desaparecida-en-corregimiento-de-cartagena-fue-enviado-a-prision\/"},"author":{"name":"Katherine Loaiza Mart\u00ednez","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/2e76b9aba5ecf875ed565ce4de0e0415"},"headline":"Tras apelaci\u00f3n de la Fiscal\u00eda, t\u00edo pol\u00edtico de joven desaparecida en corregimiento de Cartagena fue enviado a prisi\u00f3n","datePublished":"2021-09-19T22:55:32+00:00","dateModified":"2021-09-19T23:11:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/tras-apelacion-de-la-fiscalia-tio-politico-de-joven-desaparecida-en-corregimiento-de-cartagena-fue-enviado-a-prision\/"},"wordCount":372,"publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/tras-apelacion-de-la-fiscalia-tio-politico-de-joven-desaparecida-en-corregimiento-de-cartagena-fue-enviado-a-prision\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Wainer-Ayola-caso-desaparecida.jpg","keywords":["Desaparici\u00f3n forzada","Fiscal Barbosa","Fiscal\u00eda Colombia","Fiscal\u00eda General de la Naci\u00f3n","Medida de aseguramiento","Polic\u00eda Nacional"],"articleSection":["Noticias","Seccional Cartagena","Seguridad territorial"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/tras-apelacion-de-la-fiscalia-tio-politico-de-joven-desaparecida-en-corregimiento-de-cartagena-fue-enviado-a-prision\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/tras-apelacion-de-la-fiscalia-tio-politico-de-joven-desaparecida-en-corregimiento-de-cartagena-fue-enviado-a-prision\/","name":"Fiscal\u00eda General de la Naci\u00f3n","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/tras-apelacion-de-la-fiscalia-tio-politico-de-joven-desaparecida-en-corregimiento-de-cartagena-fue-enviado-a-prision\/#primaryimage"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/tras-apelacion-de-la-fiscalia-tio-politico-de-joven-desaparecida-en-corregimiento-de-cartagena-fue-enviado-a-prision\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Wainer-Ayola-caso-desaparecida.jpg","datePublished":"2021-09-19T22:55:32+00:00","dateModified":"2021-09-19T23:11:56+00:00","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","breadcrumb":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/tras-apelacion-de-la-fiscalia-tio-politico-de-joven-desaparecida-en-corregimiento-de-cartagena-fue-enviado-a-prision\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/tras-apelacion-de-la-fiscalia-tio-politico-de-joven-desaparecida-en-corregimiento-de-cartagena-fue-enviado-a-prision\/"]}]},{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/tras-apelacion-de-la-fiscalia-tio-politico-de-joven-desaparecida-en-corregimiento-de-cartagena-fue-enviado-a-prision\/#primaryimage","url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Wainer-Ayola-caso-desaparecida.jpg","contentUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Wainer-Ayola-caso-desaparecida.jpg","width":892,"height":1146,"caption":"El procesado se present\u00f3 de forma voluntaria ante las autoridades."},{"@type":"BreadcrumbList","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/tras-apelacion-de-la-fiscalia-tio-politico-de-joven-desaparecida-en-corregimiento-de-cartagena-fue-enviado-a-prision\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fiscalia.gov.co\/colombia\/"},{"@type":"ListItem","position":2,"name":"Tras apelaci\u00f3n de la Fiscal\u00eda, t\u00edo pol\u00edtico de joven desaparecida en corregimiento de Cartagena fue enviado a prisi\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","name":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization","name":"Fiscal\u00eda General de la Naci\u00f3n","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","contentUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","width":300,"height":90,"caption":"Fiscal\u00eda General de la Naci\u00f3n"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FiscaliaCol","https:\/\/x.com\/FiscaliaCol","https:\/\/www.instagram.com\/fiscaliacol","https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/","https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh"]},{"@type":"Person","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/2e76b9aba5ecf875ed565ce4de0e0415","name":"Katherine Loaiza Mart\u00ednez","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ab775a2f394c1b83b6d6f78680e57b50?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ab775a2f394c1b83b6d6f78680e57b50?s=96&d=mm&r=g","caption":"Katherine Loaiza Mart\u00ednez"},"url":"https:\/\/www.fiscalia.gov.co\/colombia\/author\/kloaiza\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/230168","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/users\/175"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/comments?post=230168"}],"version-history":[{"count":4,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/230168\/revisions"}],"predecessor-version":[{"id":230173,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/230168\/revisions\/230173"}],"wp:attachment":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/media?parent=230168"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/categories?post=230168"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/tags?post=230168"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}