{"id":229741,"date":"2021-09-14T08:00:57","date_gmt":"2021-09-14T13:00:57","guid":{"rendered":"https:\/\/www.fiscalia.gov.co\/colombia\/?p=229741"},"modified":"2021-09-14T08:00:57","modified_gmt":"2021-09-14T13:00:57","slug":"medida-de-internamiento-para-joven-que-habria-abusado-sexualmente-de-una-nina-de-8-anos-en-casanare","status":"publish","type":"post","link":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/medida-de-internamiento-para-joven-que-habria-abusado-sexualmente-de-una-nina-de-8-anos-en-casanare\/","title":{"rendered":"Medida de internamiento para joven que habr\u00eda abusado sexualmente de una ni\u00f1a de 8 a\u00f1os en Casanare\u00a0"},"content":{"rendered":"<p><span lang=\"ES-MX\">Una fiscal de la\u00a0<b>Unidad de Responsabilidad Penal para Adolescentes (Urpa)<\/b>\u00a0de Paz de Ariporo (Casanare), en coordinaci\u00f3n con la Polic\u00eda Nacional, logr\u00f3 la captura de un joven de 18 a\u00f1os, el pasado 8 de septiembre, se\u00f1alado como presunto responsable del\u00a0<b>abuso sexual<\/b>\u00a0de una ni\u00f1a de 8 a\u00f1os.\u00a0<\/span><\/p>\n<p><span lang=\"ES-MX\">Tras la legalizaci\u00f3n del procedimiento ordenado por el Juzgado Promiscuo Municipal de La Salina (Casanare), el ente investigador le formul\u00f3 cargos al detenido por los delitos de\u00a0<\/span><a href=\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/medida-de-internamiento-preventivo-para-un-adolescente-por-feminicidio-agravado-y-acceso-carnal-abusivo-con-menor-de-14-anos\/\" target=\"_blank\" rel=\"noopener noreferrer\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/medida-de-internamiento-preventivo-para-un-adolescente-por-feminicidio-agravado-y-acceso-carnal-abusivo-con-menor-de-14-anos\/&amp;source=gmail&amp;ust=1631660881595000&amp;usg=AFQjCNFu1L-7i_8bpBtY2VvDz4WjY8Wv5A\"><b><span lang=\"ES-MX\">acceso carnal abusivo con menor de 14 a\u00f1os<\/span><\/b><\/a><span lang=\"ES\">\u00a0en concurso heterog\u00e9neo con\u00a0<a href=\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/medida-de-internamiento-preventivo-para-un-adolescente-por-feminicidio-agravado-y-acceso-carnal-abusivo-con-menor-de-14-anos\/\" target=\"_blank\" rel=\"noopener noreferrer\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/medida-de-internamiento-preventivo-para-un-adolescente-por-feminicidio-agravado-y-acceso-carnal-abusivo-con-menor-de-14-anos\/&amp;source=gmail&amp;ust=1631660881595000&amp;usg=AFQjCNFu1L-7i_8bpBtY2VvDz4WjY8Wv5A\"><b><span lang=\"ES-MX\">actos sexuales abusivos con menor de 14 a\u00f1os<\/span><\/b><\/a>\u00a0en concurso homog\u00e9neo.\u00a0<\/span><\/p>\n<p><span lang=\"ES-MX\">La investigaci\u00f3n se deriva de los hechos ocurridos en enero de 2019 en esa poblaci\u00f3n casanare\u00f1a, donde el procesado, quien para ese momento ten\u00eda 16 a\u00f1os, aparentemente someti\u00f3 a vej\u00e1menes sexuales a la v\u00edctima en reiteradas ocasiones, aprovechando que era conocido de la familia y lleg\u00f3 a la vivienda a quedarse una temporada.\u00a0<\/span><\/p>\n<p><span lang=\"ES-MX\">El presunto infractor, judicializado mediante la Ley de Infancia y Adolescencia, fue afectado con\u00a0<b>medida de internamiento preventivo<\/b>\u00a0en centro especializado.\u00a0<\/span><\/p>\n<p><span lang=\"ES-MX\">La Fiscal\u00eda habla con resultados.\u00a0<\/span><\/p>\n<p><span lang=\"ES-MX\">LAZL\/DLBM\/ELB<\/span><span lang=\"ES-MX\">\u00a0<\/span><\/p>\n<p><span lang=\"ES-MX\">\u00a0<\/span><span lang=\"ES\">\u00a0<\/span><\/p>\n<p><i><span lang=\"ES-MX\">La informaci\u00f3n contenida en este bolet\u00edn de prensa corresponde a la narraci\u00f3n de los hechos noticiosos objetivos, suministrados por los funcionarios encargados de adelantar las investigaciones penales al interior de la Fiscal\u00eda General de la Naci\u00f3n.\u00a0<\/span><\/i><i><span lang=\"ES\">Para el momento de la divulgaci\u00f3n de este comunicado, la situaci\u00f3n jur\u00eddica de la(s) persona(s) relacionada(s) se encuentra pendiente de resolver por la autoridad judicial competente, siempre bajo los preceptos de la presunci\u00f3n de inocencia, consagrados en el art\u00edculo 29 de la Constituci\u00f3n Pol\u00edtica y el art\u00edculo 7\u00ba de la Ley 906 de 2004.<\/span><\/i><span lang=\"ES\">\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n\n<div class=\"twitter-share\"><a href=\"https:\/\/twitter.com\/intent\/tweet?via=fiscaliacol\" class=\"twitter-share-button\">Tweet<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Una fiscal de la\u00a0Unidad de Responsabilidad Penal para Adolescentes (Urpa)\u00a0de Paz de Ariporo (Casanare), en coordinaci\u00f3n con la Polic\u00eda Nacional, logr\u00f3 la captura de un joven de 18 a\u00f1os, el [&hellip;]<\/p>\n","protected":false},"author":175,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[1,16751,24127],"tags":[11941,8759,924,24401,24189,1047,25192],"class_list":["post-229741","post","type-post","status-publish","format-standard","category-noticias","category-seccional-casanare","category-violencia-sexual-e-intrafamiliar","tag-acceso-carnal-abusivo-con-menor-de-14-anos","tag-actos-sexuales-abusivos-con-menor-de-14-anos","tag-captura","tag-fiscal-barbosa-delgado","tag-fiscal-francisco-barbosa-delgado","tag-fiscalia-general-de-la-nacion","tag-medida-de-internamiento-preventivo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fiscal\u00eda General de la Naci\u00f3n<\/title>\n<meta name=\"description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/medida-de-internamiento-para-joven-que-habria-abusado-sexualmente-de-una-nina-de-8-anos-en-casanare\/\" \/>\n<meta property=\"og:site_name\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FiscaliaCol\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-14T13:00:57+00:00\" \/>\n<meta name=\"author\" content=\"Katherine Loaiza Mart\u00ednez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:site\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Katherine Loaiza Mart\u00ednez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/medida-de-internamiento-para-joven-que-habria-abusado-sexualmente-de-una-nina-de-8-anos-en-casanare\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/medida-de-internamiento-para-joven-que-habria-abusado-sexualmente-de-una-nina-de-8-anos-en-casanare\/\"},\"author\":{\"name\":\"Katherine Loaiza Mart\u00ednez\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/2e76b9aba5ecf875ed565ce4de0e0415\"},\"headline\":\"Medida de internamiento para joven que habr\u00eda abusado sexualmente de una ni\u00f1a de 8 a\u00f1os en Casanare\u00a0\",\"datePublished\":\"2021-09-14T13:00:57+00:00\",\"dateModified\":\"2021-09-14T13:00:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/medida-de-internamiento-para-joven-que-habria-abusado-sexualmente-de-una-nina-de-8-anos-en-casanare\/\"},\"wordCount\":315,\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"keywords\":[\"acceso carnal abusivo con menor de 14 a\u00f1os\",\"actos sexuales abusivos con menor de 14 a\u00f1os\",\"Captura\",\"Fiscal Barbosa Delgado\",\"Fiscal Francisco Barbosa Delgado\",\"Fiscal\u00eda General de la Naci\u00f3n\",\"medida de internamiento preventivo\"],\"articleSection\":[\"Noticias\",\"Seccional Casanare\",\"Violencia sexual e intrafamiliar\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/medida-de-internamiento-para-joven-que-habria-abusado-sexualmente-de-una-nina-de-8-anos-en-casanare\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/medida-de-internamiento-para-joven-que-habria-abusado-sexualmente-de-una-nina-de-8-anos-en-casanare\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\"},\"datePublished\":\"2021-09-14T13:00:57+00:00\",\"dateModified\":\"2021-09-14T13:00:57+00:00\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/medida-de-internamiento-para-joven-que-habria-abusado-sexualmente-de-una-nina-de-8-anos-en-casanare\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/medida-de-internamiento-para-joven-que-habria-abusado-sexualmente-de-una-nina-de-8-anos-en-casanare\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/medida-de-internamiento-para-joven-que-habria-abusado-sexualmente-de-una-nina-de-8-anos-en-casanare\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Medida de internamiento para joven que habr\u00eda abusado sexualmente de una ni\u00f1a de 8 a\u00f1os en Casanare\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"contentUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"width\":300,\"height\":90,\"caption\":\"Fiscal\u00eda General de la Naci\u00f3n\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/FiscaliaCol\",\"https:\/\/x.com\/FiscaliaCol\",\"https:\/\/www.instagram.com\/fiscaliacol\",\"https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/\",\"https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/2e76b9aba5ecf875ed565ce4de0e0415\",\"name\":\"Katherine Loaiza Mart\u00ednez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ab775a2f394c1b83b6d6f78680e57b50?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ab775a2f394c1b83b6d6f78680e57b50?s=96&d=mm&r=g\",\"caption\":\"Katherine Loaiza Mart\u00ednez\"},\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/author\/kloaiza\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Fiscal\u00eda General de la Naci\u00f3n","og_description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","og_url":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/medida-de-internamiento-para-joven-que-habria-abusado-sexualmente-de-una-nina-de-8-anos-en-casanare\/","og_site_name":"Fiscal\u00eda General de la Naci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/FiscaliaCol","article_published_time":"2021-09-14T13:00:57+00:00","author":"Katherine Loaiza Mart\u00ednez","twitter_card":"summary_large_image","twitter_creator":"@FiscaliaCol","twitter_site":"@FiscaliaCol","twitter_misc":{"Escrito por":"Katherine Loaiza Mart\u00ednez","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/medida-de-internamiento-para-joven-que-habria-abusado-sexualmente-de-una-nina-de-8-anos-en-casanare\/#article","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/medida-de-internamiento-para-joven-que-habria-abusado-sexualmente-de-una-nina-de-8-anos-en-casanare\/"},"author":{"name":"Katherine Loaiza Mart\u00ednez","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/2e76b9aba5ecf875ed565ce4de0e0415"},"headline":"Medida de internamiento para joven que habr\u00eda abusado sexualmente de una ni\u00f1a de 8 a\u00f1os en Casanare\u00a0","datePublished":"2021-09-14T13:00:57+00:00","dateModified":"2021-09-14T13:00:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/medida-de-internamiento-para-joven-que-habria-abusado-sexualmente-de-una-nina-de-8-anos-en-casanare\/"},"wordCount":315,"publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"keywords":["acceso carnal abusivo con menor de 14 a\u00f1os","actos sexuales abusivos con menor de 14 a\u00f1os","Captura","Fiscal Barbosa Delgado","Fiscal Francisco Barbosa Delgado","Fiscal\u00eda General de la Naci\u00f3n","medida de internamiento preventivo"],"articleSection":["Noticias","Seccional Casanare","Violencia sexual e intrafamiliar"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/medida-de-internamiento-para-joven-que-habria-abusado-sexualmente-de-una-nina-de-8-anos-en-casanare\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/medida-de-internamiento-para-joven-que-habria-abusado-sexualmente-de-una-nina-de-8-anos-en-casanare\/","name":"Fiscal\u00eda General de la Naci\u00f3n","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website"},"datePublished":"2021-09-14T13:00:57+00:00","dateModified":"2021-09-14T13:00:57+00:00","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","breadcrumb":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/medida-de-internamiento-para-joven-que-habria-abusado-sexualmente-de-una-nina-de-8-anos-en-casanare\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/medida-de-internamiento-para-joven-que-habria-abusado-sexualmente-de-una-nina-de-8-anos-en-casanare\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/medida-de-internamiento-para-joven-que-habria-abusado-sexualmente-de-una-nina-de-8-anos-en-casanare\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fiscalia.gov.co\/colombia\/"},{"@type":"ListItem","position":2,"name":"Medida de internamiento para joven que habr\u00eda abusado sexualmente de una ni\u00f1a de 8 a\u00f1os en Casanare\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","name":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization","name":"Fiscal\u00eda General de la Naci\u00f3n","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","contentUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","width":300,"height":90,"caption":"Fiscal\u00eda General de la Naci\u00f3n"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FiscaliaCol","https:\/\/x.com\/FiscaliaCol","https:\/\/www.instagram.com\/fiscaliacol","https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/","https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh"]},{"@type":"Person","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/2e76b9aba5ecf875ed565ce4de0e0415","name":"Katherine Loaiza Mart\u00ednez","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ab775a2f394c1b83b6d6f78680e57b50?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ab775a2f394c1b83b6d6f78680e57b50?s=96&d=mm&r=g","caption":"Katherine Loaiza Mart\u00ednez"},"url":"https:\/\/www.fiscalia.gov.co\/colombia\/author\/kloaiza\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/229741","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/users\/175"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/comments?post=229741"}],"version-history":[{"count":1,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/229741\/revisions"}],"predecessor-version":[{"id":229742,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/229741\/revisions\/229742"}],"wp:attachment":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/media?parent=229741"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/categories?post=229741"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/tags?post=229741"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}