{"id":226682,"date":"2021-08-05T13:23:24","date_gmt":"2021-08-05T18:23:24","guid":{"rendered":"https:\/\/www.fiscalia.gov.co\/colombia\/?p=226682"},"modified":"2021-08-05T13:24:12","modified_gmt":"2021-08-05T18:24:12","slug":"a-prision-un-hombre-por-presuntamente-transportar-mas-de-1000-kilos-de-plantaciones-vegetales","status":"publish","type":"post","link":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-prision-un-hombre-por-presuntamente-transportar-mas-de-1000-kilos-de-plantaciones-vegetales\/","title":{"rendered":"A prisi\u00f3n un hombre por, presuntamente, transportar m\u00e1s de 1000 kilos de plantaciones vegetales"},"content":{"rendered":"<p>En el marco de la Estrategia de Investigaci\u00f3n Integral Regional, una fiscal de la Direcci\u00f3n Especializada contra el Narcotr\u00e1fico en Putumayo judicializ\u00f3 a \u00a0por su posible autor\u00eda en el delito de\u00a0<strong>conservaci\u00f3n o financiaci\u00f3n de plantaciones<\/strong>.<\/p>\n<p>En labores de patrullaje, registro y control agentes de la Polic\u00eda Nacional observaron un cami\u00f3n conducido por el imputado, en el cual eran trasportados varios\u00a0\u00a0<strong>bultos de fibra<\/strong>\u00a0con\u00a0<strong>semilla de hoja de coca;<\/strong>\u00a0plantaciones verificadas por el perito en Corpoamazonia quien certific\u00f3 que corresponden a la especie Erythoroxylum coca.<\/p>\n<figure id=\"attachment_226684\" aria-describedby=\"caption-attachment-226684\" style=\"width: 696px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-226684\" src=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Felipe-Oliver-1024x851.jpeg\" alt=\"\" width=\"696\" height=\"578\" srcset=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Felipe-Oliver-1024x851.jpeg 1024w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Felipe-Oliver-300x249.jpeg 300w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Felipe-Oliver-768x638.jpeg 768w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Felipe-Oliver-696x579.jpeg 696w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Felipe-Oliver-1068x888.jpeg 1068w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Felipe-Oliver-505x420.jpeg 505w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Felipe-Oliver.jpeg 1280w\" sizes=\"auto, (max-width: 696px) 100vw, 696px\" \/><figcaption id=\"caption-attachment-226684\" class=\"wp-caption-text\">Felipe Oliver al parecer transportar\u00eda 1.190 kilos de hojas y tallos de coca.<\/figcaption><\/figure>\n<p>En el procedimiento fueron incautados\u00a0<strong>1.190 kilogramos de hojas y tallos de coca<\/strong>, lo mismo que el<strong>\u00a0<\/strong>\u00a0cami\u00f3n que se movilizaba por\u00a0el barrio La Amistad en Valle del Guamuez (Putumayo).<\/p>\n<p>Luego de que el juez de control de garant\u00edas legalizara la captura en flagrancia y la\u00a0<a href=\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/incautados-15-kilos-de-marihuana-y-plantaciones-en-zona-rural-de-buga-valle-del-cauca\/\">incautaci\u00f3n<\/a>\u00a0del veh\u00edculo, el funcionario judicial dispuso\u00a0<strong>medida de aseguramiento privativa de la libertad domiciliaria<\/strong>\u00a0para el implicado, quien no\u00a0<strong>acept\u00f3 los cargos<\/strong>.<\/p>\n<p>La Fiscal\u00eda publica esta informaci\u00f3n por razones de inter\u00e9s general.<\/p>\n<p><strong>LMGM\/MAGA\/GRM<\/strong><\/p>\n<p><em>La informaci\u00f3n contenida en este bolet\u00edn de prensa corresponde a la narraci\u00f3n de los hechos noticiosos objetivos, suministrados por los funcionarios encargados de adelantar las investigaciones penales al interior de la Fiscal\u00eda General de la Naci\u00f3n. Para el momento de la divulgaci\u00f3n de este comunicado, la situaci\u00f3n jur\u00eddica de la(s) persona(s) relacionada(s) se encuentra pendiente de resolver por la autoridad judicial competente, siempre bajo los preceptos de la presunci\u00f3n de inocencia, consagrados en el art\u00edculo 29 de la Constituci\u00f3n Pol\u00edtica y el art\u00edculo 7\u00ba de la Ley 906 de 2004.<\/em><\/p>\n<p>&nbsp;<\/p>\n\n<div class=\"twitter-share\"><a href=\"https:\/\/twitter.com\/intent\/tweet?via=fiscaliacol\" class=\"twitter-share-button\">Tweet<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>En el marco de la Estrategia de Investigaci\u00f3n Integral Regional, una fiscal de la Direcci\u00f3n Especializada contra el Narcotr\u00e1fico en Putumayo judicializ\u00f3 a \u00a0por su posible autor\u00eda en el delito [&hellip;]<\/p>\n","protected":false},"author":171,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[1,2910,303,24103],"tags":[17565,2279,28090,28089,13626,27867],"class_list":["post-226682","post","type-post","status-publish","format-standard","category-noticias","category-seccional-mocoa","category-seccionales","category-trafico-de-estupefacientes","tag-conservacion-o-financiacion-de-plantaciones","tag-putumayo","tag-semillas-de-coca","tag-tallos-de-coca","tag-transporte","tag-valle-del-guamuez"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fiscal\u00eda General de la Naci\u00f3n<\/title>\n<meta name=\"description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-prision-un-hombre-por-presuntamente-transportar-mas-de-1000-kilos-de-plantaciones-vegetales\/\" \/>\n<meta property=\"og:site_name\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FiscaliaCol\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-05T18:23:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-05T18:24:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Felipe-Oliver-1024x851.jpeg\" \/>\n<meta name=\"author\" content=\"Ana Mar\u00eda Gomez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:site\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ana Mar\u00eda Gomez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-prision-un-hombre-por-presuntamente-transportar-mas-de-1000-kilos-de-plantaciones-vegetales\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-prision-un-hombre-por-presuntamente-transportar-mas-de-1000-kilos-de-plantaciones-vegetales\/\"},\"author\":{\"name\":\"Ana Mar\u00eda Gomez\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/06aa2210fe4d79203f428ff671dee360\"},\"headline\":\"A prisi\u00f3n un hombre por, presuntamente, transportar m\u00e1s de 1000 kilos de plantaciones vegetales\",\"datePublished\":\"2021-08-05T18:23:24+00:00\",\"dateModified\":\"2021-08-05T18:24:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-prision-un-hombre-por-presuntamente-transportar-mas-de-1000-kilos-de-plantaciones-vegetales\/\"},\"wordCount\":321,\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-prision-un-hombre-por-presuntamente-transportar-mas-de-1000-kilos-de-plantaciones-vegetales\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Felipe-Oliver-1024x851.jpeg\",\"keywords\":[\"conservaci\u00f3n o financiaci\u00f3n de plantaciones\",\"Putumayo\",\"semillas de coca\",\"tallos de coca\",\"Transporte\",\"Valle del Guamuez\"],\"articleSection\":[\"Noticias\",\"Seccional Mocoa\",\"Seccionales\",\"Tr\u00e1fico de estupefacientes\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-prision-un-hombre-por-presuntamente-transportar-mas-de-1000-kilos-de-plantaciones-vegetales\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-prision-un-hombre-por-presuntamente-transportar-mas-de-1000-kilos-de-plantaciones-vegetales\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-prision-un-hombre-por-presuntamente-transportar-mas-de-1000-kilos-de-plantaciones-vegetales\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-prision-un-hombre-por-presuntamente-transportar-mas-de-1000-kilos-de-plantaciones-vegetales\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Felipe-Oliver-1024x851.jpeg\",\"datePublished\":\"2021-08-05T18:23:24+00:00\",\"dateModified\":\"2021-08-05T18:24:12+00:00\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-prision-un-hombre-por-presuntamente-transportar-mas-de-1000-kilos-de-plantaciones-vegetales\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-prision-un-hombre-por-presuntamente-transportar-mas-de-1000-kilos-de-plantaciones-vegetales\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-prision-un-hombre-por-presuntamente-transportar-mas-de-1000-kilos-de-plantaciones-vegetales\/#primaryimage\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Felipe-Oliver-1024x851.jpeg\",\"contentUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Felipe-Oliver-1024x851.jpeg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-prision-un-hombre-por-presuntamente-transportar-mas-de-1000-kilos-de-plantaciones-vegetales\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A prisi\u00f3n un hombre por, presuntamente, transportar m\u00e1s de 1000 kilos de plantaciones vegetales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"contentUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"width\":300,\"height\":90,\"caption\":\"Fiscal\u00eda General de la Naci\u00f3n\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/FiscaliaCol\",\"https:\/\/x.com\/FiscaliaCol\",\"https:\/\/www.instagram.com\/fiscaliacol\",\"https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/\",\"https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/06aa2210fe4d79203f428ff671dee360\",\"name\":\"Ana Mar\u00eda Gomez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a38115d98a7f8a96cbb96af2b2c37a0b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a38115d98a7f8a96cbb96af2b2c37a0b?s=96&d=mm&r=g\",\"caption\":\"Ana Mar\u00eda Gomez\"},\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/author\/agomez\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Fiscal\u00eda General de la Naci\u00f3n","og_description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","og_url":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-prision-un-hombre-por-presuntamente-transportar-mas-de-1000-kilos-de-plantaciones-vegetales\/","og_site_name":"Fiscal\u00eda General de la Naci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/FiscaliaCol","article_published_time":"2021-08-05T18:23:24+00:00","article_modified_time":"2021-08-05T18:24:12+00:00","og_image":[{"url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Felipe-Oliver-1024x851.jpeg","type":"","width":"","height":""}],"author":"Ana Mar\u00eda Gomez","twitter_card":"summary_large_image","twitter_creator":"@FiscaliaCol","twitter_site":"@FiscaliaCol","twitter_misc":{"Escrito por":"Ana Mar\u00eda Gomez","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-prision-un-hombre-por-presuntamente-transportar-mas-de-1000-kilos-de-plantaciones-vegetales\/#article","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-prision-un-hombre-por-presuntamente-transportar-mas-de-1000-kilos-de-plantaciones-vegetales\/"},"author":{"name":"Ana Mar\u00eda Gomez","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/06aa2210fe4d79203f428ff671dee360"},"headline":"A prisi\u00f3n un hombre por, presuntamente, transportar m\u00e1s de 1000 kilos de plantaciones vegetales","datePublished":"2021-08-05T18:23:24+00:00","dateModified":"2021-08-05T18:24:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-prision-un-hombre-por-presuntamente-transportar-mas-de-1000-kilos-de-plantaciones-vegetales\/"},"wordCount":321,"publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-prision-un-hombre-por-presuntamente-transportar-mas-de-1000-kilos-de-plantaciones-vegetales\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Felipe-Oliver-1024x851.jpeg","keywords":["conservaci\u00f3n o financiaci\u00f3n de plantaciones","Putumayo","semillas de coca","tallos de coca","Transporte","Valle del Guamuez"],"articleSection":["Noticias","Seccional Mocoa","Seccionales","Tr\u00e1fico de estupefacientes"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-prision-un-hombre-por-presuntamente-transportar-mas-de-1000-kilos-de-plantaciones-vegetales\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-prision-un-hombre-por-presuntamente-transportar-mas-de-1000-kilos-de-plantaciones-vegetales\/","name":"Fiscal\u00eda General de la Naci\u00f3n","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-prision-un-hombre-por-presuntamente-transportar-mas-de-1000-kilos-de-plantaciones-vegetales\/#primaryimage"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-prision-un-hombre-por-presuntamente-transportar-mas-de-1000-kilos-de-plantaciones-vegetales\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Felipe-Oliver-1024x851.jpeg","datePublished":"2021-08-05T18:23:24+00:00","dateModified":"2021-08-05T18:24:12+00:00","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","breadcrumb":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-prision-un-hombre-por-presuntamente-transportar-mas-de-1000-kilos-de-plantaciones-vegetales\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-prision-un-hombre-por-presuntamente-transportar-mas-de-1000-kilos-de-plantaciones-vegetales\/"]}]},{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-prision-un-hombre-por-presuntamente-transportar-mas-de-1000-kilos-de-plantaciones-vegetales\/#primaryimage","url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Felipe-Oliver-1024x851.jpeg","contentUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Felipe-Oliver-1024x851.jpeg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/noticias\/a-prision-un-hombre-por-presuntamente-transportar-mas-de-1000-kilos-de-plantaciones-vegetales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fiscalia.gov.co\/colombia\/"},{"@type":"ListItem","position":2,"name":"A prisi\u00f3n un hombre por, presuntamente, transportar m\u00e1s de 1000 kilos de plantaciones vegetales"}]},{"@type":"WebSite","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","name":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization","name":"Fiscal\u00eda General de la Naci\u00f3n","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","contentUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","width":300,"height":90,"caption":"Fiscal\u00eda General de la Naci\u00f3n"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FiscaliaCol","https:\/\/x.com\/FiscaliaCol","https:\/\/www.instagram.com\/fiscaliacol","https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/","https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh"]},{"@type":"Person","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/06aa2210fe4d79203f428ff671dee360","name":"Ana Mar\u00eda Gomez","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a38115d98a7f8a96cbb96af2b2c37a0b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a38115d98a7f8a96cbb96af2b2c37a0b?s=96&d=mm&r=g","caption":"Ana Mar\u00eda Gomez"},"url":"https:\/\/www.fiscalia.gov.co\/colombia\/author\/agomez\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/226682","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/users\/171"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/comments?post=226682"}],"version-history":[{"count":2,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/226682\/revisions"}],"predecessor-version":[{"id":226685,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/226682\/revisions\/226685"}],"wp:attachment":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/media?parent=226682"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/categories?post=226682"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/tags?post=226682"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}