{"id":215758,"date":"2021-03-15T11:42:09","date_gmt":"2021-03-15T16:42:09","guid":{"rendered":"https:\/\/www.fiscalia.gov.co\/colombia\/?p=215758"},"modified":"2021-03-15T11:43:55","modified_gmt":"2021-03-15T16:43:55","slug":"aseguramiento-en-carcel-alias-la-bestia-presunto-integrante-del-brazo-armado-de-la-organizacion-la-huesuda","status":"publish","type":"post","link":"https:\/\/www.fiscalia.gov.co\/colombia\/crimen-organizado\/aseguramiento-en-carcel-alias-la-bestia-presunto-integrante-del-brazo-armado-de-la-organizacion-la-huesuda\/","title":{"rendered":"Aseguramiento en c\u00e1rcel alias \u2018La Bestia\u2019, presunto integrante del brazo armado de la organizaci\u00f3n \u2018La Huesuda\u2019"},"content":{"rendered":"<div><span style=\"font-size: medium;\"><span style=\"color: #212121;\"><span lang=\"es\">Por solicitud de un fiscal de la Seccional Risaralda, el juzgado con funci\u00f3n de control de garant\u00edas de La Celia, impuso medida de aseguramiento intramuros contra Jhon James D\u00edaz Cano, alias La Bestia quien, al parecer, har\u00eda parte del grupo delincuencial conocido como\u00a0<\/span><\/span><a href=\"https:\/\/www.fiscalia.gov.co\/colombia\/hay-justicia\/dos-miembros-de-la-organizacion-criminal-la-huesuda-condenados-por-multiples-delitos-en-risaralda\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span lang=\"es\">\u2018La Huesuda\u2019<\/span><\/a><span style=\"color: #212121;\"><span lang=\"es\">. Dicha banda delincuencial ser\u00eda la responsable de controlar la cadena de microtr\u00e1fico en el noroccidente del departamento de Risaralda y en l\u00edmites con el norte del Valle del Cauca.<\/span><\/span><\/span><\/div>\n<div><span style=\"font-size: medium;\"><span style=\"color: black;\">\u00a0<\/span><\/span><\/div>\n<div><span style=\"font-size: medium;\"><span style=\"color: #212121;\"><span lang=\"es\">El hoy imputado ser\u00eda el presunto responsable de homicidios realizados en zona rural de los municipios risaraldenses de Santuario y La Celia. Las acciones de violencia en esa zona del pa\u00eds obedecer\u00edan al control de los sitios de expendio, por lo cual habr\u00edan sido asesinadas varias personas que se seguir las \u00f3rdenes impartidas por\u00a0<\/span><\/span><a href=\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/sentenciados-miembros-de-organizacion-criminal-dedicada-trafico-de-estupefacientes-y-responsables-de-varios-homicidios-en-risaralda\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span lang=\"es\">la organizaci\u00f3n ilegal<\/span><\/a><span style=\"color: #212121;\"><span lang=\"es\">.<\/span><\/span><\/span><\/div>\n<div><span style=\"font-size: medium;\"><span style=\"color: #212121;\"><span lang=\"es\">\u00a0<\/span><\/span><\/span><\/div>\n<div><span style=\"font-size: medium;\"><span style=\"color: #212121;\"><span lang=\"es\">D\u00edaz Cano fue imputado por la Fiscal\u00eda como presunto responsable de los delitos de concierto para delinquir agravado con fines de tr\u00e1fico estupefacientes y homicidio agravado; cargos que no acept\u00f3 el implicado.<\/span><\/span><\/span><\/div>\n<div><span style=\"font-size: medium;\"><span style=\"color: #212121;\"><span lang=\"es\">\u00a0<\/span><\/span><\/span><\/div>\n<div><span style=\"font-size: medium;\"><span style=\"color: #212121;\"><span lang=\"es\">El procesado fue capturado por funcionarios del CTI, grupo GOTI, con el apoyo de la Sijin en la invasi\u00f3n Brisas del Cauca, ubicada en el corregimiento Caimalito de Pereira (Risaralda).<\/span><\/span><\/span><\/div>\n<div><span style=\"font-size: medium;\"><span style=\"color: #212121;\"><span lang=\"es\">\u00a0<\/span><\/span><\/span><\/div>\n<div><span style=\"font-size: medium;\"><span style=\"color: #212121;\"><span lang=\"es\">Estos resultados se enmarcan dentro de la directriz del Fiscal General de la Naci\u00f3n, Francisco Barbosa Delgado, de judicializar a personas cuya actividad delictiva atente contra la seguridad ciudadana en los territorios.<\/span><\/span><\/span><\/div>\n<div><span style=\"font-size: medium;\"><span style=\"color: #212121;\"><span lang=\"es\">\u00a0<\/span><\/span><\/span><\/div>\n<div><span style=\"font-size: medium;\"><span style=\"color: #212121;\"><span lang=\"es\">La Fiscal\u00eda publica esta informaci\u00f3n por considerarla de inter\u00e9s general.<\/span><\/span><\/span><\/div>\n<div><span style=\"font-size: medium;\"><span style=\"color: #212121;\"><span lang=\"es\">\u00a0<\/span><\/span><\/span><\/div>\n<div><span style=\"font-size: medium;\"><span style=\"color: #1f497d;\"><span lang=\"es\"><b>CLCG\/MAGA\/JHM<\/b><\/span><\/span><\/span><\/div>\n<div><\/div>\n<p><i><span lang=\"ES\">La informaci\u00f3n contenida en este bolet\u00edn de prensa corresponde a la narraci\u00f3n de los hechos noticiosos objetivos, suministrados por los funcionarios encargados de adelantar las investigaciones penales al interior de la Fiscal\u00eda General de la Naci\u00f3n. Para el momento de la divulgaci\u00f3n de este comunicado, la situaci\u00f3n jur\u00eddica de la(s) persona(s) relacionada(s) se encuentra pendiente de resolver por la autoridad judicial competente, siempre bajo los preceptos de la presunci\u00f3n de inocencia, consagrados en el art\u00edculo 29 de la Constituci\u00f3n Pol\u00edtica y el art\u00edculo 7\u00ba de la Ley 906 de 2004.<\/span><\/i><\/p>\n\n<div class=\"twitter-share\"><a href=\"https:\/\/twitter.com\/intent\/tweet?via=fiscaliacol\" class=\"twitter-share-button\">Tweet<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Por solicitud de un fiscal de la Seccional Risaralda, el juzgado con funci\u00f3n de control de garant\u00edas de La Celia, impuso medida de aseguramiento intramuros contra Jhon James D\u00edaz Cano, [&hellip;]<\/p>\n","protected":false},"author":171,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[24098,335,303],"tags":[26260],"class_list":["post-215758","post","type-post","status-publish","format-standard","category-crimen-organizado","category-seccional-pereira","category-seccionales","tag-la-bestia-la-huesuda-pereira-homicidio-armas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fiscal\u00eda General de la Naci\u00f3n<\/title>\n<meta name=\"description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fiscalia.gov.co\/colombia\/crimen-organizado\/aseguramiento-en-carcel-alias-la-bestia-presunto-integrante-del-brazo-armado-de-la-organizacion-la-huesuda\/\" \/>\n<meta property=\"og:site_name\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FiscaliaCol\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-15T16:42:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-15T16:43:55+00:00\" \/>\n<meta name=\"author\" content=\"Ana Mar\u00eda Gomez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:site\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ana Mar\u00eda Gomez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/crimen-organizado\/aseguramiento-en-carcel-alias-la-bestia-presunto-integrante-del-brazo-armado-de-la-organizacion-la-huesuda\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/crimen-organizado\/aseguramiento-en-carcel-alias-la-bestia-presunto-integrante-del-brazo-armado-de-la-organizacion-la-huesuda\/\"},\"author\":{\"name\":\"Ana Mar\u00eda Gomez\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/06aa2210fe4d79203f428ff671dee360\"},\"headline\":\"Aseguramiento en c\u00e1rcel alias \u2018La Bestia\u2019, presunto integrante del brazo armado de la organizaci\u00f3n \u2018La Huesuda\u2019\",\"datePublished\":\"2021-03-15T16:42:09+00:00\",\"dateModified\":\"2021-03-15T16:43:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/crimen-organizado\/aseguramiento-en-carcel-alias-la-bestia-presunto-integrante-del-brazo-armado-de-la-organizacion-la-huesuda\/\"},\"wordCount\":378,\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"keywords\":[\"LA BESTIA \u2013 LA HUESUDA \u2013 PEREIRA \u2013 HOMICIDIO \u2013 ARMAS \u2013\"],\"articleSection\":[\"Crimen organizado\",\"Seccional Pereira\",\"Seccionales\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/crimen-organizado\/aseguramiento-en-carcel-alias-la-bestia-presunto-integrante-del-brazo-armado-de-la-organizacion-la-huesuda\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/crimen-organizado\/aseguramiento-en-carcel-alias-la-bestia-presunto-integrante-del-brazo-armado-de-la-organizacion-la-huesuda\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\"},\"datePublished\":\"2021-03-15T16:42:09+00:00\",\"dateModified\":\"2021-03-15T16:43:55+00:00\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/crimen-organizado\/aseguramiento-en-carcel-alias-la-bestia-presunto-integrante-del-brazo-armado-de-la-organizacion-la-huesuda\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fiscalia.gov.co\/colombia\/crimen-organizado\/aseguramiento-en-carcel-alias-la-bestia-presunto-integrante-del-brazo-armado-de-la-organizacion-la-huesuda\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/crimen-organizado\/aseguramiento-en-carcel-alias-la-bestia-presunto-integrante-del-brazo-armado-de-la-organizacion-la-huesuda\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aseguramiento en c\u00e1rcel alias \u2018La Bestia\u2019, presunto integrante del brazo armado de la organizaci\u00f3n \u2018La Huesuda\u2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"contentUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"width\":300,\"height\":90,\"caption\":\"Fiscal\u00eda General de la Naci\u00f3n\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/FiscaliaCol\",\"https:\/\/x.com\/FiscaliaCol\",\"https:\/\/www.instagram.com\/fiscaliacol\",\"https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/\",\"https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/06aa2210fe4d79203f428ff671dee360\",\"name\":\"Ana Mar\u00eda Gomez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a38115d98a7f8a96cbb96af2b2c37a0b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a38115d98a7f8a96cbb96af2b2c37a0b?s=96&d=mm&r=g\",\"caption\":\"Ana Mar\u00eda Gomez\"},\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/author\/agomez\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Fiscal\u00eda General de la Naci\u00f3n","og_description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","og_url":"https:\/\/www.fiscalia.gov.co\/colombia\/crimen-organizado\/aseguramiento-en-carcel-alias-la-bestia-presunto-integrante-del-brazo-armado-de-la-organizacion-la-huesuda\/","og_site_name":"Fiscal\u00eda General de la Naci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/FiscaliaCol","article_published_time":"2021-03-15T16:42:09+00:00","article_modified_time":"2021-03-15T16:43:55+00:00","author":"Ana Mar\u00eda Gomez","twitter_card":"summary_large_image","twitter_creator":"@FiscaliaCol","twitter_site":"@FiscaliaCol","twitter_misc":{"Escrito por":"Ana Mar\u00eda Gomez","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/crimen-organizado\/aseguramiento-en-carcel-alias-la-bestia-presunto-integrante-del-brazo-armado-de-la-organizacion-la-huesuda\/#article","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/crimen-organizado\/aseguramiento-en-carcel-alias-la-bestia-presunto-integrante-del-brazo-armado-de-la-organizacion-la-huesuda\/"},"author":{"name":"Ana Mar\u00eda Gomez","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/06aa2210fe4d79203f428ff671dee360"},"headline":"Aseguramiento en c\u00e1rcel alias \u2018La Bestia\u2019, presunto integrante del brazo armado de la organizaci\u00f3n \u2018La Huesuda\u2019","datePublished":"2021-03-15T16:42:09+00:00","dateModified":"2021-03-15T16:43:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/crimen-organizado\/aseguramiento-en-carcel-alias-la-bestia-presunto-integrante-del-brazo-armado-de-la-organizacion-la-huesuda\/"},"wordCount":378,"publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"keywords":["LA BESTIA \u2013 LA HUESUDA \u2013 PEREIRA \u2013 HOMICIDIO \u2013 ARMAS \u2013"],"articleSection":["Crimen organizado","Seccional Pereira","Seccionales"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/crimen-organizado\/aseguramiento-en-carcel-alias-la-bestia-presunto-integrante-del-brazo-armado-de-la-organizacion-la-huesuda\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/crimen-organizado\/aseguramiento-en-carcel-alias-la-bestia-presunto-integrante-del-brazo-armado-de-la-organizacion-la-huesuda\/","name":"Fiscal\u00eda General de la Naci\u00f3n","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website"},"datePublished":"2021-03-15T16:42:09+00:00","dateModified":"2021-03-15T16:43:55+00:00","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","breadcrumb":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/crimen-organizado\/aseguramiento-en-carcel-alias-la-bestia-presunto-integrante-del-brazo-armado-de-la-organizacion-la-huesuda\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fiscalia.gov.co\/colombia\/crimen-organizado\/aseguramiento-en-carcel-alias-la-bestia-presunto-integrante-del-brazo-armado-de-la-organizacion-la-huesuda\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/crimen-organizado\/aseguramiento-en-carcel-alias-la-bestia-presunto-integrante-del-brazo-armado-de-la-organizacion-la-huesuda\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fiscalia.gov.co\/colombia\/"},{"@type":"ListItem","position":2,"name":"Aseguramiento en c\u00e1rcel alias \u2018La Bestia\u2019, presunto integrante del brazo armado de la organizaci\u00f3n \u2018La Huesuda\u2019"}]},{"@type":"WebSite","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","name":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization","name":"Fiscal\u00eda General de la Naci\u00f3n","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","contentUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","width":300,"height":90,"caption":"Fiscal\u00eda General de la Naci\u00f3n"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FiscaliaCol","https:\/\/x.com\/FiscaliaCol","https:\/\/www.instagram.com\/fiscaliacol","https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/","https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh"]},{"@type":"Person","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/06aa2210fe4d79203f428ff671dee360","name":"Ana Mar\u00eda Gomez","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a38115d98a7f8a96cbb96af2b2c37a0b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a38115d98a7f8a96cbb96af2b2c37a0b?s=96&d=mm&r=g","caption":"Ana Mar\u00eda Gomez"},"url":"https:\/\/www.fiscalia.gov.co\/colombia\/author\/agomez\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/215758","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/users\/171"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/comments?post=215758"}],"version-history":[{"count":2,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/215758\/revisions"}],"predecessor-version":[{"id":215760,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/215758\/revisions\/215760"}],"wp:attachment":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/media?parent=215758"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/categories?post=215758"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/tags?post=215758"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}