{"id":211586,"date":"2021-01-26T15:54:13","date_gmt":"2021-01-26T20:54:13","guid":{"rendered":"https:\/\/www.fiscalia.gov.co\/colombia\/?p=211586"},"modified":"2021-01-26T16:07:11","modified_gmt":"2021-01-26T21:07:11","slug":"fiscalia-lidera-la-investigacion-por-el-asesinato-de-los-5-jovenes-en-buga","status":"publish","type":"post","link":"https:\/\/www.fiscalia.gov.co\/colombia\/hechos-concretos\/fiscalia-lidera-la-investigacion-por-el-asesinato-de-los-5-jovenes-en-buga\/","title":{"rendered":"Fiscal\u00eda lidera la investigaci\u00f3n por el asesinato de los 5 j\u00f3venes en Buga"},"content":{"rendered":"<p>Fuente: Noticias RCN<\/p>\n<p>Son 100 en total los hallazgos reportados por los peritos de la Fiscal\u00eda General de la Naci\u00f3n, entre ellos varias vainillas de proyectil 9 mil\u00edmetros y un celular, que ser\u00edan clave para determinar los m\u00f3viles de este homicidio m\u00faltiple que enluta a Buga.<\/p>\n\n<div class=\"twitter-share\"><a href=\"https:\/\/twitter.com\/intent\/tweet?via=fiscaliacol\" class=\"twitter-share-button\">Tweet<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Fuente: Noticias RCN Son 100 en total los hallazgos reportados por los peritos de la Fiscal\u00eda General de la Naci\u00f3n, entre ellos varias vainillas de proyectil 9 mil\u00edmetros y un [&hellip;]<\/p>\n","protected":false},"author":175,"featured_media":211616,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[24184],"tags":[10172,24401,24188],"class_list":["post-211586","post","type-post","status-publish","format-video","has-post-thumbnail","category-hechos-concretos","tag-el-fiscal-general-de-la-nacion","tag-fiscal-barbosa-delgado","tag-fiscal-francisco-barbosa","post_format-post-format-video"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fiscal\u00eda General de la Naci\u00f3n<\/title>\n<meta name=\"description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fiscalia.gov.co\/colombia\/hechos-concretos\/fiscalia-lidera-la-investigacion-por-el-asesinato-de-los-5-jovenes-en-buga\/\" \/>\n<meta property=\"og:site_name\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FiscaliaCol\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-26T20:54:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-26T21:07:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Youtube-masacre-buga.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Katherine Loaiza Mart\u00ednez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:site\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Katherine Loaiza Mart\u00ednez\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/hechos-concretos\/fiscalia-lidera-la-investigacion-por-el-asesinato-de-los-5-jovenes-en-buga\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/hechos-concretos\/fiscalia-lidera-la-investigacion-por-el-asesinato-de-los-5-jovenes-en-buga\/\"},\"author\":{\"name\":\"Katherine Loaiza Mart\u00ednez\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/2e76b9aba5ecf875ed565ce4de0e0415\"},\"headline\":\"Fiscal\u00eda lidera la investigaci\u00f3n por el asesinato de los 5 j\u00f3venes en Buga\",\"datePublished\":\"2021-01-26T20:54:13+00:00\",\"dateModified\":\"2021-01-26T21:07:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/hechos-concretos\/fiscalia-lidera-la-investigacion-por-el-asesinato-de-los-5-jovenes-en-buga\/\"},\"wordCount\":65,\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/hechos-concretos\/fiscalia-lidera-la-investigacion-por-el-asesinato-de-los-5-jovenes-en-buga\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Youtube-masacre-buga.jpeg\",\"keywords\":[\"El Fiscal General de la Naci\u00f3n\",\"Fiscal Barbosa Delgado\",\"Fiscal Francisco Barbosa\"],\"articleSection\":[\"Hechos concretos\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/hechos-concretos\/fiscalia-lidera-la-investigacion-por-el-asesinato-de-los-5-jovenes-en-buga\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/hechos-concretos\/fiscalia-lidera-la-investigacion-por-el-asesinato-de-los-5-jovenes-en-buga\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/hechos-concretos\/fiscalia-lidera-la-investigacion-por-el-asesinato-de-los-5-jovenes-en-buga\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/hechos-concretos\/fiscalia-lidera-la-investigacion-por-el-asesinato-de-los-5-jovenes-en-buga\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Youtube-masacre-buga.jpeg\",\"datePublished\":\"2021-01-26T20:54:13+00:00\",\"dateModified\":\"2021-01-26T21:07:11+00:00\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/hechos-concretos\/fiscalia-lidera-la-investigacion-por-el-asesinato-de-los-5-jovenes-en-buga\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fiscalia.gov.co\/colombia\/hechos-concretos\/fiscalia-lidera-la-investigacion-por-el-asesinato-de-los-5-jovenes-en-buga\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/hechos-concretos\/fiscalia-lidera-la-investigacion-por-el-asesinato-de-los-5-jovenes-en-buga\/#primaryimage\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Youtube-masacre-buga.jpeg\",\"contentUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Youtube-masacre-buga.jpeg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/hechos-concretos\/fiscalia-lidera-la-investigacion-por-el-asesinato-de-los-5-jovenes-en-buga\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fiscal\u00eda lidera la investigaci\u00f3n por el asesinato de los 5 j\u00f3venes en Buga\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"contentUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"width\":300,\"height\":90,\"caption\":\"Fiscal\u00eda General de la Naci\u00f3n\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/FiscaliaCol\",\"https:\/\/x.com\/FiscaliaCol\",\"https:\/\/www.instagram.com\/fiscaliacol\",\"https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/\",\"https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/2e76b9aba5ecf875ed565ce4de0e0415\",\"name\":\"Katherine Loaiza Mart\u00ednez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ab775a2f394c1b83b6d6f78680e57b50?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ab775a2f394c1b83b6d6f78680e57b50?s=96&d=mm&r=g\",\"caption\":\"Katherine Loaiza Mart\u00ednez\"},\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/author\/kloaiza\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Fiscal\u00eda General de la Naci\u00f3n","og_description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","og_url":"https:\/\/www.fiscalia.gov.co\/colombia\/hechos-concretos\/fiscalia-lidera-la-investigacion-por-el-asesinato-de-los-5-jovenes-en-buga\/","og_site_name":"Fiscal\u00eda General de la Naci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/FiscaliaCol","article_published_time":"2021-01-26T20:54:13+00:00","article_modified_time":"2021-01-26T21:07:11+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Youtube-masacre-buga.jpeg","type":"image\/jpeg"}],"author":"Katherine Loaiza Mart\u00ednez","twitter_card":"summary_large_image","twitter_creator":"@FiscaliaCol","twitter_site":"@FiscaliaCol","twitter_misc":{"Escrito por":"Katherine Loaiza Mart\u00ednez"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/hechos-concretos\/fiscalia-lidera-la-investigacion-por-el-asesinato-de-los-5-jovenes-en-buga\/#article","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/hechos-concretos\/fiscalia-lidera-la-investigacion-por-el-asesinato-de-los-5-jovenes-en-buga\/"},"author":{"name":"Katherine Loaiza Mart\u00ednez","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/2e76b9aba5ecf875ed565ce4de0e0415"},"headline":"Fiscal\u00eda lidera la investigaci\u00f3n por el asesinato de los 5 j\u00f3venes en Buga","datePublished":"2021-01-26T20:54:13+00:00","dateModified":"2021-01-26T21:07:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/hechos-concretos\/fiscalia-lidera-la-investigacion-por-el-asesinato-de-los-5-jovenes-en-buga\/"},"wordCount":65,"publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/hechos-concretos\/fiscalia-lidera-la-investigacion-por-el-asesinato-de-los-5-jovenes-en-buga\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Youtube-masacre-buga.jpeg","keywords":["El Fiscal General de la Naci\u00f3n","Fiscal Barbosa Delgado","Fiscal Francisco Barbosa"],"articleSection":["Hechos concretos"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/hechos-concretos\/fiscalia-lidera-la-investigacion-por-el-asesinato-de-los-5-jovenes-en-buga\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/hechos-concretos\/fiscalia-lidera-la-investigacion-por-el-asesinato-de-los-5-jovenes-en-buga\/","name":"Fiscal\u00eda General de la Naci\u00f3n","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/hechos-concretos\/fiscalia-lidera-la-investigacion-por-el-asesinato-de-los-5-jovenes-en-buga\/#primaryimage"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/hechos-concretos\/fiscalia-lidera-la-investigacion-por-el-asesinato-de-los-5-jovenes-en-buga\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Youtube-masacre-buga.jpeg","datePublished":"2021-01-26T20:54:13+00:00","dateModified":"2021-01-26T21:07:11+00:00","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","breadcrumb":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/hechos-concretos\/fiscalia-lidera-la-investigacion-por-el-asesinato-de-los-5-jovenes-en-buga\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fiscalia.gov.co\/colombia\/hechos-concretos\/fiscalia-lidera-la-investigacion-por-el-asesinato-de-los-5-jovenes-en-buga\/"]}]},{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/hechos-concretos\/fiscalia-lidera-la-investigacion-por-el-asesinato-de-los-5-jovenes-en-buga\/#primaryimage","url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Youtube-masacre-buga.jpeg","contentUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/Youtube-masacre-buga.jpeg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/hechos-concretos\/fiscalia-lidera-la-investigacion-por-el-asesinato-de-los-5-jovenes-en-buga\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fiscalia.gov.co\/colombia\/"},{"@type":"ListItem","position":2,"name":"Fiscal\u00eda lidera la investigaci\u00f3n por el asesinato de los 5 j\u00f3venes en Buga"}]},{"@type":"WebSite","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","name":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization","name":"Fiscal\u00eda General de la Naci\u00f3n","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","contentUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","width":300,"height":90,"caption":"Fiscal\u00eda General de la Naci\u00f3n"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FiscaliaCol","https:\/\/x.com\/FiscaliaCol","https:\/\/www.instagram.com\/fiscaliacol","https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/","https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh"]},{"@type":"Person","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/2e76b9aba5ecf875ed565ce4de0e0415","name":"Katherine Loaiza Mart\u00ednez","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ab775a2f394c1b83b6d6f78680e57b50?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ab775a2f394c1b83b6d6f78680e57b50?s=96&d=mm&r=g","caption":"Katherine Loaiza Mart\u00ednez"},"url":"https:\/\/www.fiscalia.gov.co\/colombia\/author\/kloaiza\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/211586","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/users\/175"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/comments?post=211586"}],"version-history":[{"count":1,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/211586\/revisions"}],"predecessor-version":[{"id":211615,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/211586\/revisions\/211615"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/media\/211616"}],"wp:attachment":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/media?parent=211586"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/categories?post=211586"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/tags?post=211586"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}