{"id":208953,"date":"2020-12-08T11:05:06","date_gmt":"2020-12-08T16:05:06","guid":{"rendered":"https:\/\/www.fiscalia.gov.co\/colombia\/?p=208953"},"modified":"2020-12-08T11:05:06","modified_gmt":"2020-12-08T16:05:06","slug":"judicializado-exalcalde-de-piedras-tolima-por-presuntas-irregularidades-en-contrato-para-la-tarima-cubierta-del-parque-principal-del-municipio","status":"publish","type":"post","link":"https:\/\/www.fiscalia.gov.co\/colombia\/corrupcion\/judicializado-exalcalde-de-piedras-tolima-por-presuntas-irregularidades-en-contrato-para-la-tarima-cubierta-del-parque-principal-del-municipio\/","title":{"rendered":"Judicializado exalcalde de Piedras (Tolima) por presuntas irregularidades en contrato para la tarima cubierta del parque principal del municipio"},"content":{"rendered":"<p class=\"xmsonormal\"><span lang=\"ES\">Un despacho seccional de la <b>Fiscal\u00eda General de la Naci\u00f3n, Seccional Tolima, adscrito a la Unidad de Administraci\u00f3n P\u00fablica<\/b>, adelant\u00f3 la semana que acaba de terminar audiencia de formulaci\u00f3n de imputaci\u00f3n de cargos contra Arqu\u00edmedes \u00c1vila Rond\u00f3n, exalcalde del municipio de Piedras (Tolima), presuntamente, comprometido en el delito de\u00a0<\/span><a href=\"https:\/\/www.fiscalia.gov.co\/colombia\/corrupcion\/imputado-exalcalde-de-piedras-tolima-y-dos-personas-mas-por-supuestas-irregularidades-en-contrato-para-obras-de-alcantarillado-en-2010\/\" target=\"_blank\" rel=\"noopener noreferrer\"><b><span lang=\"ES\">contrato sin cumplimiento de los requisitos legales<\/span><\/b><\/a><span lang=\"ES\">.\u00a0<\/span><\/p>\n<p class=\"xmsonormal\"><span lang=\"ES\">Servidores del CTI de la Fiscal\u00eda detectaron posibles irregularidades en la etapa de tr\u00e1mite y ejecuci\u00f3n del convenio 013 de 2012, celebrado entre la Administraci\u00f3n Municipal y otra entidad que, al parecer, subcontrat\u00f3 los servicios pues no cumpl\u00eda con los requisitos para suplir las necesidades enmarcadas dentro del contrato celebrado; esto la convert\u00eda en un simple intermediario contractual.\u00a0<\/span><\/p>\n<p class=\"xmsonormal\"><span lang=\"ES\">El objeto del contrato era aunar esfuerzos en la ejecuci\u00f3n de operaciones t\u00e9cnicas, de infraestructura y cient\u00edficas en el proyecto para el dise\u00f1o y construcci\u00f3n de la tarima cubierta del parque principal del municipio, cuyo valor alcanz\u00f3 los <b>703 millones de pesos<\/b>.\u00a0<\/span><\/p>\n<p><span lang=\"ES\">Fue as\u00ed como, al parecer, se incumpli\u00f3 el principio de econom\u00eda consagrado en la ley 80 de 1993 que establece la necesidad de asegurar la selecci\u00f3n objetiva del contratista mediante los procedimientos y etapas que fueran necesarios.<\/span><\/p>\n<p class=\"xmsonormal\"><span lang=\"ES\">El implicado no acept\u00f3 cargos y seguir\u00e1 vinculado al proceso investigativo.\u00a0<\/span><\/p>\n<p class=\"xmsonormal\"><span lang=\"ES\">Estos resultados hacen parte de la pol\u00edtica institucional del <b>Fiscal General de la Naci\u00f3n, Francisco Barbosa Delgado<\/b>, en su lucha contra la corrupci\u00f3n.\u00a0<\/span><\/p>\n<p class=\"xmsonormal\"><span lang=\"ES\">La Fiscal\u00eda hace p\u00fablica esta informaci\u00f3n por razones de inter\u00e9s general.\u00a0<\/span><\/p>\n<p class=\"xmsonormal\"><span lang=\"ES\">PAAM\/MAGA\/JGSG<\/span><\/p>\n<p class=\"xmsonormal\"><i><span lang=\"ES\">La informaci\u00f3n contenida en este bolet\u00edn de prensa corresponde a la narraci\u00f3n de los hechos noticiosos objetivos, suministrados por los funcionarios encargados de adelantar las investigaciones penales al interior de la Fiscal\u00eda General de la Naci\u00f3n. Para el momento de la divulgaci\u00f3n de este comunicado, la situaci\u00f3n jur\u00eddica de la(s) persona(s) relacionada(s) se encuentra pendiente de resolver por la autoridad judicial competente, siempre bajo los preceptos de la presunci\u00f3n de inocencia, consagrados en el art\u00edculo 29 de la Constituci\u00f3n Pol\u00edtica y el art\u00edculo 7\u00ba de la Ley 906 de 2004.\u00a0\u00a0\u00a0\u00a0<\/span><\/i><\/p>\n\n<div class=\"twitter-share\"><a href=\"https:\/\/twitter.com\/intent\/tweet?via=fiscaliacol\" class=\"twitter-share-button\">Tweet<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Un despacho seccional de la Fiscal\u00eda General de la Naci\u00f3n, Seccional Tolima, adscrito a la Unidad de Administraci\u00f3n P\u00fablica, adelant\u00f3 la semana que acaba de terminar audiencia de formulaci\u00f3n de [&hellip;]<\/p>\n","protected":false},"author":171,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[24097,329],"tags":[12486,427,806,24185,1047,23838,24946,24211,12189],"class_list":["post-208953","post","type-post","status-publish","format-standard","category-corrupcion","category-seccional-ibague","tag-contrato-sin-cumplimiento-de-los-requisitos-legales","tag-corrupcion","tag-ex-alacalde","tag-fiscal-barbosa","tag-fiscalia-general-de-la-nacion","tag-ibague","tag-piedras","tag-seccional-tolima","tag-tolima"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fiscal\u00eda General de la Naci\u00f3n<\/title>\n<meta name=\"description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fiscalia.gov.co\/colombia\/corrupcion\/judicializado-exalcalde-de-piedras-tolima-por-presuntas-irregularidades-en-contrato-para-la-tarima-cubierta-del-parque-principal-del-municipio\/\" \/>\n<meta property=\"og:site_name\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FiscaliaCol\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-08T16:05:06+00:00\" \/>\n<meta name=\"author\" content=\"Ana Mar\u00eda Gomez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:site\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ana Mar\u00eda Gomez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/corrupcion\/judicializado-exalcalde-de-piedras-tolima-por-presuntas-irregularidades-en-contrato-para-la-tarima-cubierta-del-parque-principal-del-municipio\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/corrupcion\/judicializado-exalcalde-de-piedras-tolima-por-presuntas-irregularidades-en-contrato-para-la-tarima-cubierta-del-parque-principal-del-municipio\/\"},\"author\":{\"name\":\"Ana Mar\u00eda Gomez\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/06aa2210fe4d79203f428ff671dee360\"},\"headline\":\"Judicializado exalcalde de Piedras (Tolima) por presuntas irregularidades en contrato para la tarima cubierta del parque principal del municipio\",\"datePublished\":\"2020-12-08T16:05:06+00:00\",\"dateModified\":\"2020-12-08T16:05:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/corrupcion\/judicializado-exalcalde-de-piedras-tolima-por-presuntas-irregularidades-en-contrato-para-la-tarima-cubierta-del-parque-principal-del-municipio\/\"},\"wordCount\":385,\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"keywords\":[\"contrato sin cumplimiento de los requisitos legales\",\"Corrupci\u00f3n\",\"Exalcalde\",\"Fiscal Barbosa\",\"Fiscal\u00eda General de la Naci\u00f3n\",\"Ibagu\u00e9\",\"Piedras\",\"Seccional Tolima\",\"Tolima\"],\"articleSection\":[\"Corrupci\u00f3n\",\"Seccional Ibagu\u00e9\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/corrupcion\/judicializado-exalcalde-de-piedras-tolima-por-presuntas-irregularidades-en-contrato-para-la-tarima-cubierta-del-parque-principal-del-municipio\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/corrupcion\/judicializado-exalcalde-de-piedras-tolima-por-presuntas-irregularidades-en-contrato-para-la-tarima-cubierta-del-parque-principal-del-municipio\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\"},\"datePublished\":\"2020-12-08T16:05:06+00:00\",\"dateModified\":\"2020-12-08T16:05:06+00:00\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/corrupcion\/judicializado-exalcalde-de-piedras-tolima-por-presuntas-irregularidades-en-contrato-para-la-tarima-cubierta-del-parque-principal-del-municipio\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fiscalia.gov.co\/colombia\/corrupcion\/judicializado-exalcalde-de-piedras-tolima-por-presuntas-irregularidades-en-contrato-para-la-tarima-cubierta-del-parque-principal-del-municipio\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/corrupcion\/judicializado-exalcalde-de-piedras-tolima-por-presuntas-irregularidades-en-contrato-para-la-tarima-cubierta-del-parque-principal-del-municipio\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Judicializado exalcalde de Piedras (Tolima) por presuntas irregularidades en contrato para la tarima cubierta del parque principal del municipio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"contentUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"width\":300,\"height\":90,\"caption\":\"Fiscal\u00eda General de la Naci\u00f3n\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/FiscaliaCol\",\"https:\/\/x.com\/FiscaliaCol\",\"https:\/\/www.instagram.com\/fiscaliacol\",\"https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/\",\"https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/06aa2210fe4d79203f428ff671dee360\",\"name\":\"Ana Mar\u00eda Gomez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a38115d98a7f8a96cbb96af2b2c37a0b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a38115d98a7f8a96cbb96af2b2c37a0b?s=96&d=mm&r=g\",\"caption\":\"Ana Mar\u00eda Gomez\"},\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/author\/agomez\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Fiscal\u00eda General de la Naci\u00f3n","og_description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","og_url":"https:\/\/www.fiscalia.gov.co\/colombia\/corrupcion\/judicializado-exalcalde-de-piedras-tolima-por-presuntas-irregularidades-en-contrato-para-la-tarima-cubierta-del-parque-principal-del-municipio\/","og_site_name":"Fiscal\u00eda General de la Naci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/FiscaliaCol","article_published_time":"2020-12-08T16:05:06+00:00","author":"Ana Mar\u00eda Gomez","twitter_card":"summary_large_image","twitter_creator":"@FiscaliaCol","twitter_site":"@FiscaliaCol","twitter_misc":{"Escrito por":"Ana Mar\u00eda Gomez","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/corrupcion\/judicializado-exalcalde-de-piedras-tolima-por-presuntas-irregularidades-en-contrato-para-la-tarima-cubierta-del-parque-principal-del-municipio\/#article","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/corrupcion\/judicializado-exalcalde-de-piedras-tolima-por-presuntas-irregularidades-en-contrato-para-la-tarima-cubierta-del-parque-principal-del-municipio\/"},"author":{"name":"Ana Mar\u00eda Gomez","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/06aa2210fe4d79203f428ff671dee360"},"headline":"Judicializado exalcalde de Piedras (Tolima) por presuntas irregularidades en contrato para la tarima cubierta del parque principal del municipio","datePublished":"2020-12-08T16:05:06+00:00","dateModified":"2020-12-08T16:05:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/corrupcion\/judicializado-exalcalde-de-piedras-tolima-por-presuntas-irregularidades-en-contrato-para-la-tarima-cubierta-del-parque-principal-del-municipio\/"},"wordCount":385,"publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"keywords":["contrato sin cumplimiento de los requisitos legales","Corrupci\u00f3n","Exalcalde","Fiscal Barbosa","Fiscal\u00eda General de la Naci\u00f3n","Ibagu\u00e9","Piedras","Seccional Tolima","Tolima"],"articleSection":["Corrupci\u00f3n","Seccional Ibagu\u00e9"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/corrupcion\/judicializado-exalcalde-de-piedras-tolima-por-presuntas-irregularidades-en-contrato-para-la-tarima-cubierta-del-parque-principal-del-municipio\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/corrupcion\/judicializado-exalcalde-de-piedras-tolima-por-presuntas-irregularidades-en-contrato-para-la-tarima-cubierta-del-parque-principal-del-municipio\/","name":"Fiscal\u00eda General de la Naci\u00f3n","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website"},"datePublished":"2020-12-08T16:05:06+00:00","dateModified":"2020-12-08T16:05:06+00:00","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","breadcrumb":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/corrupcion\/judicializado-exalcalde-de-piedras-tolima-por-presuntas-irregularidades-en-contrato-para-la-tarima-cubierta-del-parque-principal-del-municipio\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fiscalia.gov.co\/colombia\/corrupcion\/judicializado-exalcalde-de-piedras-tolima-por-presuntas-irregularidades-en-contrato-para-la-tarima-cubierta-del-parque-principal-del-municipio\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/corrupcion\/judicializado-exalcalde-de-piedras-tolima-por-presuntas-irregularidades-en-contrato-para-la-tarima-cubierta-del-parque-principal-del-municipio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fiscalia.gov.co\/colombia\/"},{"@type":"ListItem","position":2,"name":"Judicializado exalcalde de Piedras (Tolima) por presuntas irregularidades en contrato para la tarima cubierta del parque principal del municipio"}]},{"@type":"WebSite","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","name":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization","name":"Fiscal\u00eda General de la Naci\u00f3n","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","contentUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","width":300,"height":90,"caption":"Fiscal\u00eda General de la Naci\u00f3n"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FiscaliaCol","https:\/\/x.com\/FiscaliaCol","https:\/\/www.instagram.com\/fiscaliacol","https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/","https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh"]},{"@type":"Person","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/06aa2210fe4d79203f428ff671dee360","name":"Ana Mar\u00eda Gomez","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a38115d98a7f8a96cbb96af2b2c37a0b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a38115d98a7f8a96cbb96af2b2c37a0b?s=96&d=mm&r=g","caption":"Ana Mar\u00eda Gomez"},"url":"https:\/\/www.fiscalia.gov.co\/colombia\/author\/agomez\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/208953","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/users\/171"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/comments?post=208953"}],"version-history":[{"count":1,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/208953\/revisions"}],"predecessor-version":[{"id":208954,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/208953\/revisions\/208954"}],"wp:attachment":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/media?parent=208953"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/categories?post=208953"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/tags?post=208953"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}