{"id":207805,"date":"2020-11-25T14:07:59","date_gmt":"2020-11-25T19:07:59","guid":{"rendered":"https:\/\/www.fiscalia.gov.co\/colombia\/?p=207805"},"modified":"2020-11-25T14:21:26","modified_gmt":"2020-11-25T19:21:26","slug":"en-tiempo-record-fue-capturado-el-presunto-homicida-del-docente-duglas-cortes","status":"publish","type":"post","link":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-pereira\/en-tiempo-record-fue-capturado-el-presunto-homicida-del-docente-duglas-cortes\/","title":{"rendered":"En tiempo r\u00e9cord fue capturado el presunto homicida del docente Duglas Cort\u00e9s"},"content":{"rendered":"<p><span lang=\"es\">En menos de 48 horas, y con el apoyo del Cuerpo T\u00e9cnico de Investigaci\u00f3n \u2013 CTI &#8211;\u00a0 y la SIJIN de la Polic\u00eda Nacional, un fiscal de la Seccional Risaralda obtuvo una orden de captura contra el presunto implicado en la\u00a0<\/span><a href=\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-pereira\/judicializados-dos-hombres-por-homicidio-y-tortura-de-dos-personas-en-pereira-risaralda\/\" target=\"_blank\" rel=\"noopener noreferrer\" data-auth=\"NotApplicable\"><span lang=\"es\">muerte<\/span><\/a><span lang=\"es\">\u00a0del docente Douglas Cort\u00e9s Mosquera.<\/span><\/p>\n<figure id=\"attachment_207809\" aria-describedby=\"caption-attachment-207809\" style=\"width: 696px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-207809 size-large\" src=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/dir-seccional-Risaralda-1024x638.jpeg\" alt=\"\" width=\"696\" height=\"434\" srcset=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/dir-seccional-Risaralda-1024x638.jpeg 1024w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/dir-seccional-Risaralda-300x187.jpeg 300w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/dir-seccional-Risaralda-768x478.jpeg 768w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/dir-seccional-Risaralda-696x433.jpeg 696w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/dir-seccional-Risaralda-1068x665.jpeg 1068w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/dir-seccional-Risaralda-675x420.jpeg 675w, https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/dir-seccional-Risaralda.jpeg 1280w\" sizes=\"auto, (max-width: 696px) 100vw, 696px\" \/><figcaption id=\"caption-attachment-207809\" class=\"wp-caption-text\">Declaraci\u00f3n Directora Seccional de Fiscal\u00edas Risaralda, Maritza Ch\u00e1varro Anturi, y Coronel Juan Carlos Morales Castro, Comandante Polic\u00eda Metropolitana de Pereira, sobre captura en tiempo r\u00e9cord del presunto responsable del homicidio del docente Duglas Cort\u00e9s, en La Virginia, Risaralda.<\/figcaption><\/figure>\n<p><span lang=\"es\">Esta r\u00e1pida acci\u00f3n permiti\u00f3 que pocas horas despu\u00e9s la polic\u00eda judicial detuviera al implicado para ser presentado ante un juez de la Rep\u00fablica.<\/span><\/p>\n<p><span lang=\"es\">\u00a0<\/span><span lang=\"es\">Los hechos que terminaron con la vida del profesor Cort\u00e9s Mosquera ocurrieron el 21 de noviembre pasado en el municipio de La Virginia (Risaralda).<\/span><\/p>\n<p><span lang=\"es\">\u00a0<\/span><span lang=\"es\">Cort\u00e9s Mosquera fue impactado con proyectiles de arma de fuego en un establecimiento comercial; al parecer, por problemas pasionales.<\/span><\/p>\n<p><span lang=\"es\">\u00a0<\/span><span lang=\"es\">Es importante anotar que Douglas Cort\u00e9s Mosquera, en la actualidad, no ostentaba calidad de l\u00edder social.\u00a0\u00a0\u00a0 En las siguientes horas se realizar\u00e1n las audiencias preliminares donde la Fiscal\u00eda imputar\u00e1 al detenido como presunto responsable de los delitos de homicidio agravado y porte ilegal de armas de fuego.<\/span><\/p>\n<p><span lang=\"es\">\u00a0<\/span><span lang=\"es\">Estos resultados obedecen a los lineamientos del Fiscal General de la Naci\u00f3n, Francisco Barbosa Delgado, en el sentido de esclarecer todos los hechos que atentan contra la integridad de los ciudadanos.<\/span><\/p>\n<p><span lang=\"es\">\u00a0<\/span><span lang=\"es\">La Fiscal\u00eda publica esta informaci\u00f3n por razones de inter\u00e9s general.<\/span><\/p>\n<p><span lang=\"es\">\u00a0<\/span><span lang=\"es\">CLCG\/MAGA\/MCHA<\/span><\/p>\n\n<div class=\"twitter-share\"><a href=\"https:\/\/twitter.com\/intent\/tweet?via=fiscaliacol\" class=\"twitter-share-button\">Tweet<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>En menos de 48 horas, y con el apoyo del Cuerpo T\u00e9cnico de Investigaci\u00f3n \u2013 CTI &#8211;\u00a0 y la SIJIN de la Polic\u00eda Nacional, un fiscal de la Seccional Risaralda [&hellip;]<\/p>\n","protected":false},"author":171,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[335,24099],"tags":[6188,409,23872,24751],"class_list":["post-207805","post","type-post","status-publish","format-standard","category-seccional-pereira","category-seguridad-territorial","tag-docente","tag-homicidio","tag-risaralda","tag-tiempo-record"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fiscal\u00eda General de la Naci\u00f3n<\/title>\n<meta name=\"description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-pereira\/en-tiempo-record-fue-capturado-el-presunto-homicida-del-docente-duglas-cortes\/\" \/>\n<meta property=\"og:site_name\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FiscaliaCol\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-25T19:07:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-25T19:21:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/dir-seccional-Risaralda-1024x638.jpeg\" \/>\n<meta name=\"author\" content=\"Ana Mar\u00eda Gomez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:site\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ana Mar\u00eda Gomez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-pereira\/en-tiempo-record-fue-capturado-el-presunto-homicida-del-docente-duglas-cortes\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-pereira\/en-tiempo-record-fue-capturado-el-presunto-homicida-del-docente-duglas-cortes\/\"},\"author\":{\"name\":\"Ana Mar\u00eda Gomez\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/06aa2210fe4d79203f428ff671dee360\"},\"headline\":\"En tiempo r\u00e9cord fue capturado el presunto homicida del docente Duglas Cort\u00e9s\",\"datePublished\":\"2020-11-25T19:07:59+00:00\",\"dateModified\":\"2020-11-25T19:21:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-pereira\/en-tiempo-record-fue-capturado-el-presunto-homicida-del-docente-duglas-cortes\/\"},\"wordCount\":285,\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-pereira\/en-tiempo-record-fue-capturado-el-presunto-homicida-del-docente-duglas-cortes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/dir-seccional-Risaralda-1024x638.jpeg\",\"keywords\":[\"Docente\",\"Homicidio\",\"Risaralda\",\"Tiempo record\"],\"articleSection\":[\"Seccional Pereira\",\"Seguridad territorial\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-pereira\/en-tiempo-record-fue-capturado-el-presunto-homicida-del-docente-duglas-cortes\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-pereira\/en-tiempo-record-fue-capturado-el-presunto-homicida-del-docente-duglas-cortes\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-pereira\/en-tiempo-record-fue-capturado-el-presunto-homicida-del-docente-duglas-cortes\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-pereira\/en-tiempo-record-fue-capturado-el-presunto-homicida-del-docente-duglas-cortes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/dir-seccional-Risaralda-1024x638.jpeg\",\"datePublished\":\"2020-11-25T19:07:59+00:00\",\"dateModified\":\"2020-11-25T19:21:26+00:00\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-pereira\/en-tiempo-record-fue-capturado-el-presunto-homicida-del-docente-duglas-cortes\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-pereira\/en-tiempo-record-fue-capturado-el-presunto-homicida-del-docente-duglas-cortes\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-pereira\/en-tiempo-record-fue-capturado-el-presunto-homicida-del-docente-duglas-cortes\/#primaryimage\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/dir-seccional-Risaralda-1024x638.jpeg\",\"contentUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/dir-seccional-Risaralda-1024x638.jpeg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-pereira\/en-tiempo-record-fue-capturado-el-presunto-homicida-del-docente-duglas-cortes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"En tiempo r\u00e9cord fue capturado el presunto homicida del docente Duglas Cort\u00e9s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"contentUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"width\":300,\"height\":90,\"caption\":\"Fiscal\u00eda General de la Naci\u00f3n\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/FiscaliaCol\",\"https:\/\/x.com\/FiscaliaCol\",\"https:\/\/www.instagram.com\/fiscaliacol\",\"https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/\",\"https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/06aa2210fe4d79203f428ff671dee360\",\"name\":\"Ana Mar\u00eda Gomez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a38115d98a7f8a96cbb96af2b2c37a0b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a38115d98a7f8a96cbb96af2b2c37a0b?s=96&d=mm&r=g\",\"caption\":\"Ana Mar\u00eda Gomez\"},\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/author\/agomez\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Fiscal\u00eda General de la Naci\u00f3n","og_description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","og_url":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-pereira\/en-tiempo-record-fue-capturado-el-presunto-homicida-del-docente-duglas-cortes\/","og_site_name":"Fiscal\u00eda General de la Naci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/FiscaliaCol","article_published_time":"2020-11-25T19:07:59+00:00","article_modified_time":"2020-11-25T19:21:26+00:00","og_image":[{"url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/dir-seccional-Risaralda-1024x638.jpeg","type":"","width":"","height":""}],"author":"Ana Mar\u00eda Gomez","twitter_card":"summary_large_image","twitter_creator":"@FiscaliaCol","twitter_site":"@FiscaliaCol","twitter_misc":{"Escrito por":"Ana Mar\u00eda Gomez","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-pereira\/en-tiempo-record-fue-capturado-el-presunto-homicida-del-docente-duglas-cortes\/#article","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-pereira\/en-tiempo-record-fue-capturado-el-presunto-homicida-del-docente-duglas-cortes\/"},"author":{"name":"Ana Mar\u00eda Gomez","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/06aa2210fe4d79203f428ff671dee360"},"headline":"En tiempo r\u00e9cord fue capturado el presunto homicida del docente Duglas Cort\u00e9s","datePublished":"2020-11-25T19:07:59+00:00","dateModified":"2020-11-25T19:21:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-pereira\/en-tiempo-record-fue-capturado-el-presunto-homicida-del-docente-duglas-cortes\/"},"wordCount":285,"publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-pereira\/en-tiempo-record-fue-capturado-el-presunto-homicida-del-docente-duglas-cortes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/dir-seccional-Risaralda-1024x638.jpeg","keywords":["Docente","Homicidio","Risaralda","Tiempo record"],"articleSection":["Seccional Pereira","Seguridad territorial"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-pereira\/en-tiempo-record-fue-capturado-el-presunto-homicida-del-docente-duglas-cortes\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-pereira\/en-tiempo-record-fue-capturado-el-presunto-homicida-del-docente-duglas-cortes\/","name":"Fiscal\u00eda General de la Naci\u00f3n","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-pereira\/en-tiempo-record-fue-capturado-el-presunto-homicida-del-docente-duglas-cortes\/#primaryimage"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-pereira\/en-tiempo-record-fue-capturado-el-presunto-homicida-del-docente-duglas-cortes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/dir-seccional-Risaralda-1024x638.jpeg","datePublished":"2020-11-25T19:07:59+00:00","dateModified":"2020-11-25T19:21:26+00:00","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","breadcrumb":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-pereira\/en-tiempo-record-fue-capturado-el-presunto-homicida-del-docente-duglas-cortes\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-pereira\/en-tiempo-record-fue-capturado-el-presunto-homicida-del-docente-duglas-cortes\/"]}]},{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-pereira\/en-tiempo-record-fue-capturado-el-presunto-homicida-del-docente-duglas-cortes\/#primaryimage","url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/dir-seccional-Risaralda-1024x638.jpeg","contentUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/dir-seccional-Risaralda-1024x638.jpeg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-pereira\/en-tiempo-record-fue-capturado-el-presunto-homicida-del-docente-duglas-cortes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fiscalia.gov.co\/colombia\/"},{"@type":"ListItem","position":2,"name":"En tiempo r\u00e9cord fue capturado el presunto homicida del docente Duglas Cort\u00e9s"}]},{"@type":"WebSite","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","name":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization","name":"Fiscal\u00eda General de la Naci\u00f3n","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","contentUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","width":300,"height":90,"caption":"Fiscal\u00eda General de la Naci\u00f3n"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FiscaliaCol","https:\/\/x.com\/FiscaliaCol","https:\/\/www.instagram.com\/fiscaliacol","https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/","https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh"]},{"@type":"Person","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/06aa2210fe4d79203f428ff671dee360","name":"Ana Mar\u00eda Gomez","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a38115d98a7f8a96cbb96af2b2c37a0b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a38115d98a7f8a96cbb96af2b2c37a0b?s=96&d=mm&r=g","caption":"Ana Mar\u00eda Gomez"},"url":"https:\/\/www.fiscalia.gov.co\/colombia\/author\/agomez\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/207805","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/users\/171"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/comments?post=207805"}],"version-history":[{"count":4,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/207805\/revisions"}],"predecessor-version":[{"id":207813,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/207805\/revisions\/207813"}],"wp:attachment":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/media?parent=207805"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/categories?post=207805"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/tags?post=207805"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}