{"id":200884,"date":"2020-08-28T11:02:45","date_gmt":"2020-08-28T16:02:45","guid":{"rendered":"https:\/\/www.fiscalia.gov.co\/colombia\/?p=200884"},"modified":"2020-08-28T11:02:45","modified_gmt":"2020-08-28T16:02:45","slug":"asegurada-una-mujer-por-homicidio-de-su-propio-esposo-para-reclamar-tres-seguros-de-vida","status":"publish","type":"post","link":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/asegurada-una-mujer-por-homicidio-de-su-propio-esposo-para-reclamar-tres-seguros-de-vida\/","title":{"rendered":"Asegurada una mujer por homicidio de su propio esposo para reclamar tres seguros de vida"},"content":{"rendered":"<blockquote class=\"td_quote_box td_box_center\">\n<h4 style=\"text-align: left;\"><strong><i><span lang=\"es\">Tres hombres tambi\u00e9n fueron privados de la libertad y ninguno acept\u00f3 cargos.\u00a0<\/span><\/i><\/strong><\/h4>\n<\/blockquote>\n<p><span lang=\"es\">Cuatro personas se\u00f1aladas como presuntas integrantes de una\u00a0<b>organizaci\u00f3n delincuencial denominada Los Pelaos,\u00a0<\/b>fueron privadas de la libertad este jueves 27 de agosto,\u00a0luego de que la Fiscal\u00eda General de la Naci\u00f3n, a trav\u00e9s de un despacho de la Seccional Huila, les imput\u00f3 los delitos de\u00a0<b>homicidio agravado\u00a0<\/b>en concurso heterog\u00e9neo con<b>\u00a0fabricaci\u00f3n, tr\u00e1fico porte o tenencia de armas de fuego, partes o municiones agravado<\/b>. <\/span><span lang=\"es\">\u00a0<\/span><\/p>\n<p><span lang=\"es\">La investigaci\u00f3n adelantada se relaciona con el asesinato del comerciante\u00a0<b>Hernando Velasco Cort\u00e9s el 5 de septiembre de 2019,\u00a0<\/b>el cual se presume que fue perpetrado con el fin de<b>\u00a0reclamar tres seguros de vida.<\/b>\u00a0\u00a0<\/span><\/p>\n<p><span lang=\"es\">El d\u00eda de los hechos\u00a0la v\u00edctima se desplazaba desde la localidad de Baraya (Huila) hacia su casa en una finca ubicada en la vereda La Espinaloza de esa misma municipalidad, y<b>\u00a0fue interceptada en el camino<\/b>\u00a0por un hombre que le dispar\u00f3 en repetidas ocasiones.\u00a0<\/span><\/p>\n<p><span lang=\"es\">Debido a la gravedad de sus heridas muri\u00f3 el 29 de octubre de la misma anualidad en el hospital local.\u00a0<\/span><\/p>\n<p><span lang=\"es\">En desarrollo de las actividades de polic\u00eda judicial se logr\u00f3 inferir la presunta responsabilidad de la pareja de la v\u00edctima,\u00a0<\/span><b><span lang=\"es\">Jennifer Alexandra Ot\u00e1lora Vargas, conocida como la Mona<\/span><\/b><span lang=\"es\">, en el crimen. As\u00ed, el ente acusador logr\u00f3 que fuera afectada con\u00a0<b>medida de aseguramiento<\/b>, la cual\u00a0el juez le concedi\u00f3 en detenci\u00f3n domiciliaria.\u00a0<\/span><\/p>\n<p><span lang=\"es\">Por otra parte, fueron\u00a0<b>enviados a la c\u00e1rcel<\/b>\u00a0como medida preventiva<\/span>\u00a0<span lang=\"es\">\u00d3scar Eduardo Rodr\u00edguez Cano<b>, alias Tata<\/b>; John Jairo Cu\u00e9llar Cardozo,\u00a0<b>alias el Zorro<\/b>; y Jhon Jairo Cu\u00e9llar Cu\u00e9llar,\u00a0<b>alias Pitirri<\/b>.\u00a0<\/span><\/p>\n<p><span lang=\"es\">Ninguno de los procesados acept\u00f3 los cargos enrostrados por el delegado fiscal.\u00a0<\/span><span lang=\"es\">\u00a0<\/span><\/p>\n<p><b><u><span lang=\"es\">Tres seguros de vida de por medio\u00a0<\/span>\u00a0<\/u><\/b><\/p>\n<p><span lang=\"es\">Las pesquisas indican que\u00a0los m\u00f3viles del crimen estar\u00edan relacionados con el inter\u00e9s de beneficiarse del dinero de Velasco Cort\u00e9s, quien pose\u00eda varias propiedades y los<b>\u00a0tres seguros de vida: dos a nombre de su compa\u00f1era sentimental<\/b>, la hoy procesada,<b>\u00a0<\/b>y uno a nombre del hijo de ambos.\u00a0\u00a0<\/span><span lang=\"es\">\u00a0<\/span><\/p>\n<p><span lang=\"es\">Presuntamente,\u00a0<b>la mujer acord\u00f3 con alias Pitirri,\u00a0<\/b>con quien al parecer ten\u00eda una relaci\u00f3n cercana;<b>\u00a0<\/b>y<b>\u00a0con alias el Zorro, atentar contra la vida del comerciante.\u00a0<\/b>Estos<b>\u00a0\u00faltimos habr\u00edan contratado a alias Tata para que ejecutara el homicidio.\u00a0\u00a0<\/b><\/span><\/p>\n<p><span lang=\"es\">Estos resultados hacen parte de la pol\u00edtica institucional del Fiscal General de la Naci\u00f3n, Francisco Barbosa,\u00a0<b>\u201cEn la calle y en los territorios\u201d,\u00a0<\/b>en la lucha contra los fen\u00f3menos criminales que afectan la seguridad ciudadana.\u00a0<\/span><\/p>\n<p><span lang=\"es\">La Fiscal\u00eda hace p\u00fablica esta informaci\u00f3n por razones de inter\u00e9s general.<\/span><\/p>\n<p><span lang=\"es\">\u00a0<\/span><\/p>\n<p><span lang=\"es\">PAAM\/DLBM<\/span><span lang=\"es\">\u00a0<\/span><\/p>\n\n<div class=\"twitter-share\"><a href=\"https:\/\/twitter.com\/intent\/tweet?via=fiscaliacol\" class=\"twitter-share-button\">Tweet<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Tres hombres tambi\u00e9n fueron privados de la libertad y ninguno acept\u00f3 cargos.\u00a0 Cuatro personas se\u00f1aladas como presuntas integrantes de una\u00a0organizaci\u00f3n delincuencial denominada Los Pelaos,\u00a0fueron privadas de la libertad este jueves [&hellip;]<\/p>\n","protected":false},"author":162,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[333,303,24099],"tags":[],"class_list":["post-200884","post","type-post","status-publish","format-standard","category-seccional-neiva","category-seccionales","category-seguridad-territorial"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fiscal\u00eda General de la Naci\u00f3n<\/title>\n<meta name=\"description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/asegurada-una-mujer-por-homicidio-de-su-propio-esposo-para-reclamar-tres-seguros-de-vida\/\" \/>\n<meta property=\"og:site_name\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FiscaliaCol\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-28T16:02:45+00:00\" \/>\n<meta name=\"author\" content=\"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:site\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/asegurada-una-mujer-por-homicidio-de-su-propio-esposo-para-reclamar-tres-seguros-de-vida\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/asegurada-una-mujer-por-homicidio-de-su-propio-esposo-para-reclamar-tres-seguros-de-vida\/\"},\"author\":{\"name\":\"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf28d8ae7f1b287bbe3af484b04f43ea\"},\"headline\":\"Asegurada una mujer por homicidio de su propio esposo para reclamar tres seguros de vida\",\"datePublished\":\"2020-08-28T16:02:45+00:00\",\"dateModified\":\"2020-08-28T16:02:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/asegurada-una-mujer-por-homicidio-de-su-propio-esposo-para-reclamar-tres-seguros-de-vida\/\"},\"wordCount\":463,\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"articleSection\":[\"Seccional Neiva\",\"Seccionales\",\"Seguridad territorial\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/asegurada-una-mujer-por-homicidio-de-su-propio-esposo-para-reclamar-tres-seguros-de-vida\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/asegurada-una-mujer-por-homicidio-de-su-propio-esposo-para-reclamar-tres-seguros-de-vida\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\"},\"datePublished\":\"2020-08-28T16:02:45+00:00\",\"dateModified\":\"2020-08-28T16:02:45+00:00\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/asegurada-una-mujer-por-homicidio-de-su-propio-esposo-para-reclamar-tres-seguros-de-vida\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/asegurada-una-mujer-por-homicidio-de-su-propio-esposo-para-reclamar-tres-seguros-de-vida\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/asegurada-una-mujer-por-homicidio-de-su-propio-esposo-para-reclamar-tres-seguros-de-vida\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Asegurada una mujer por homicidio de su propio esposo para reclamar tres seguros de vida\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"contentUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"width\":300,\"height\":90,\"caption\":\"Fiscal\u00eda General de la Naci\u00f3n\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/FiscaliaCol\",\"https:\/\/x.com\/FiscaliaCol\",\"https:\/\/www.instagram.com\/fiscaliacol\",\"https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/\",\"https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf28d8ae7f1b287bbe3af484b04f43ea\",\"name\":\"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9d55ae161d32da16dbdd0b380c080a5f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9d55ae161d32da16dbdd0b380c080a5f?s=96&d=mm&r=g\",\"caption\":\"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n\"},\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/author\/kbonilla\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Fiscal\u00eda General de la Naci\u00f3n","og_description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","og_url":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/asegurada-una-mujer-por-homicidio-de-su-propio-esposo-para-reclamar-tres-seguros-de-vida\/","og_site_name":"Fiscal\u00eda General de la Naci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/FiscaliaCol","article_published_time":"2020-08-28T16:02:45+00:00","author":"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@FiscaliaCol","twitter_site":"@FiscaliaCol","twitter_misc":{"Escrito por":"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/asegurada-una-mujer-por-homicidio-de-su-propio-esposo-para-reclamar-tres-seguros-de-vida\/#article","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/asegurada-una-mujer-por-homicidio-de-su-propio-esposo-para-reclamar-tres-seguros-de-vida\/"},"author":{"name":"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf28d8ae7f1b287bbe3af484b04f43ea"},"headline":"Asegurada una mujer por homicidio de su propio esposo para reclamar tres seguros de vida","datePublished":"2020-08-28T16:02:45+00:00","dateModified":"2020-08-28T16:02:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/asegurada-una-mujer-por-homicidio-de-su-propio-esposo-para-reclamar-tres-seguros-de-vida\/"},"wordCount":463,"publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"articleSection":["Seccional Neiva","Seccionales","Seguridad territorial"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/asegurada-una-mujer-por-homicidio-de-su-propio-esposo-para-reclamar-tres-seguros-de-vida\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/asegurada-una-mujer-por-homicidio-de-su-propio-esposo-para-reclamar-tres-seguros-de-vida\/","name":"Fiscal\u00eda General de la Naci\u00f3n","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website"},"datePublished":"2020-08-28T16:02:45+00:00","dateModified":"2020-08-28T16:02:45+00:00","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","breadcrumb":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/asegurada-una-mujer-por-homicidio-de-su-propio-esposo-para-reclamar-tres-seguros-de-vida\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/asegurada-una-mujer-por-homicidio-de-su-propio-esposo-para-reclamar-tres-seguros-de-vida\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/asegurada-una-mujer-por-homicidio-de-su-propio-esposo-para-reclamar-tres-seguros-de-vida\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fiscalia.gov.co\/colombia\/"},{"@type":"ListItem","position":2,"name":"Asegurada una mujer por homicidio de su propio esposo para reclamar tres seguros de vida"}]},{"@type":"WebSite","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","name":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization","name":"Fiscal\u00eda General de la Naci\u00f3n","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","contentUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","width":300,"height":90,"caption":"Fiscal\u00eda General de la Naci\u00f3n"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FiscaliaCol","https:\/\/x.com\/FiscaliaCol","https:\/\/www.instagram.com\/fiscaliacol","https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/","https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh"]},{"@type":"Person","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf28d8ae7f1b287bbe3af484b04f43ea","name":"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9d55ae161d32da16dbdd0b380c080a5f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9d55ae161d32da16dbdd0b380c080a5f?s=96&d=mm&r=g","caption":"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n"},"url":"https:\/\/www.fiscalia.gov.co\/colombia\/author\/kbonilla\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/200884","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/users\/162"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/comments?post=200884"}],"version-history":[{"count":1,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/200884\/revisions"}],"predecessor-version":[{"id":200885,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/200884\/revisions\/200885"}],"wp:attachment":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/media?parent=200884"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/categories?post=200884"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/tags?post=200884"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}