{"id":200058,"date":"2020-08-14T13:49:22","date_gmt":"2020-08-14T18:49:22","guid":{"rendered":"https:\/\/www.fiscalia.gov.co\/colombia\/?p=200058"},"modified":"2020-08-14T15:06:58","modified_gmt":"2020-08-14T20:06:58","slug":"judicializados-un-concejal-y-una-mujer-que-estarian-involucrados-en-hechos-de-extorsion-en-casanare-con-presuntos-reincidentes-de-farc","status":"publish","type":"post","link":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/judicializados-un-concejal-y-una-mujer-que-estarian-involucrados-en-hechos-de-extorsion-en-casanare-con-presuntos-reincidentes-de-farc\/","title":{"rendered":"Judicializados un concejal y una mujer que estar\u00edan involucrados en hechos de extorsi\u00f3n en Casanare con presuntos reincidentes de Farc"},"content":{"rendered":"<p>En desarrollo de la investigaci\u00f3n adelantada por la Fiscal\u00eda para desmantelar grupos disidentes de las Farc en el oriente colombiano,\u00a0<b>se logr\u00f3 la captura y judicializaci\u00f3n de Yeny Solbey Rubiano Chaparro, alias Jeringa,<\/b>\u00a0de ocupaci\u00f3n enfermera,\u00a0<b>y Rusbel Carre\u00f1o G\u00f3mez, alias Tasador, actual concejal del municipio de Paz de Ariporo (Casanare).<\/b><\/p>\n<p>En la investigaci\u00f3n adelantada por la Fiscal\u00eda Especializada adscrita al Gaula, las dos personas\u00a0<b>estar\u00edan vinculados con supuestos hechos de extorsi\u00f3n presentados entre 2019 -2020, que afectaron a ganaderos, agricultores y contratistas del norte del departamento de Casanare<\/b>.<\/p>\n<p>Investigadores del\u00a0<b>CTI<\/b>\u00a0de la Fiscal\u00eda, con apoyo Militar del\u00a0<b>Gaula Ej\u00e9rcito<\/b>\u00a0Nacional, hicieron\u00a0<b>efectivas las \u00f3rdenes de captura<\/b>\u00a0de los dos presuntos implicados. Se les detuvo a las afueras de Paz de Ariporo (Casanare), y en v\u00eda p\u00fablica del \u00e1rea urbana de la misma ciudad. Posteriormente, fueron presentados ante un juzgado con funci\u00f3n de control de garant\u00edas.<\/p>\n<p>La Fiscal\u00eda imput\u00f3\u00a0<b>cargos contra Rubiano Chaparro y Carre\u00f1o G\u00f3mez por los delitos de concierto para delinquir agravado y extorsi\u00f3n<\/b>, que no fueron aceptados.<\/p>\n<p>Frente a la solicitud de medida de aseguramiento hecha por la Fiscal\u00eda, el juzgado orden\u00f3\u00a0<b>detenci\u00f3n domiciliaria contra la mujer e intramuros contra el concejal,<\/b>\u00a0sin embargo, por falta de cupo en la c\u00e1rcel estar\u00e1 en prisi\u00f3n domiciliaria hasta que puedan llevarlo a centro penitenciario.<\/p>\n<p>La Fiscal\u00eda General publica esta informaci\u00f3n por razones de inter\u00e9s general.<\/p>\n<p><span lang=\"es-MX\">PYM\/MRL<\/span><\/p>\n\n<div class=\"twitter-share\"><a href=\"https:\/\/twitter.com\/intent\/tweet?via=fiscaliacol\" class=\"twitter-share-button\">Tweet<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>En desarrollo de la investigaci\u00f3n adelantada por la Fiscal\u00eda para desmantelar grupos disidentes de las Farc en el oriente colombiano,\u00a0se logr\u00f3 la captura y judicializaci\u00f3n de Yeny Solbey Rubiano Chaparro, [&hellip;]<\/p>\n","protected":false},"author":162,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[24134,303,24099],"tags":[],"class_list":["post-200058","post","type-post","status-publish","format-standard","category-seccional-yopal","category-seccionales","category-seguridad-territorial"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fiscal\u00eda General de la Naci\u00f3n<\/title>\n<meta name=\"description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/judicializados-un-concejal-y-una-mujer-que-estarian-involucrados-en-hechos-de-extorsion-en-casanare-con-presuntos-reincidentes-de-farc\/\" \/>\n<meta property=\"og:site_name\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FiscaliaCol\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-14T18:49:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-14T20:06:58+00:00\" \/>\n<meta name=\"author\" content=\"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:site\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/judicializados-un-concejal-y-una-mujer-que-estarian-involucrados-en-hechos-de-extorsion-en-casanare-con-presuntos-reincidentes-de-farc\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/judicializados-un-concejal-y-una-mujer-que-estarian-involucrados-en-hechos-de-extorsion-en-casanare-con-presuntos-reincidentes-de-farc\/\"},\"author\":{\"name\":\"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf28d8ae7f1b287bbe3af484b04f43ea\"},\"headline\":\"Judicializados un concejal y una mujer que estar\u00edan involucrados en hechos de extorsi\u00f3n en Casanare con presuntos reincidentes de Farc\",\"datePublished\":\"2020-08-14T18:49:22+00:00\",\"dateModified\":\"2020-08-14T20:06:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/judicializados-un-concejal-y-una-mujer-que-estarian-involucrados-en-hechos-de-extorsion-en-casanare-con-presuntos-reincidentes-de-farc\/\"},\"wordCount\":277,\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"articleSection\":[\"Seccional Yopal\",\"Seccionales\",\"Seguridad territorial\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/judicializados-un-concejal-y-una-mujer-que-estarian-involucrados-en-hechos-de-extorsion-en-casanare-con-presuntos-reincidentes-de-farc\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/judicializados-un-concejal-y-una-mujer-que-estarian-involucrados-en-hechos-de-extorsion-en-casanare-con-presuntos-reincidentes-de-farc\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\"},\"datePublished\":\"2020-08-14T18:49:22+00:00\",\"dateModified\":\"2020-08-14T20:06:58+00:00\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/judicializados-un-concejal-y-una-mujer-que-estarian-involucrados-en-hechos-de-extorsion-en-casanare-con-presuntos-reincidentes-de-farc\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/judicializados-un-concejal-y-una-mujer-que-estarian-involucrados-en-hechos-de-extorsion-en-casanare-con-presuntos-reincidentes-de-farc\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/judicializados-un-concejal-y-una-mujer-que-estarian-involucrados-en-hechos-de-extorsion-en-casanare-con-presuntos-reincidentes-de-farc\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Judicializados un concejal y una mujer que estar\u00edan involucrados en hechos de extorsi\u00f3n en Casanare con presuntos reincidentes de Farc\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"contentUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"width\":300,\"height\":90,\"caption\":\"Fiscal\u00eda General de la Naci\u00f3n\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/FiscaliaCol\",\"https:\/\/x.com\/FiscaliaCol\",\"https:\/\/www.instagram.com\/fiscaliacol\",\"https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/\",\"https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf28d8ae7f1b287bbe3af484b04f43ea\",\"name\":\"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9d55ae161d32da16dbdd0b380c080a5f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9d55ae161d32da16dbdd0b380c080a5f?s=96&d=mm&r=g\",\"caption\":\"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n\"},\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/author\/kbonilla\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Fiscal\u00eda General de la Naci\u00f3n","og_description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","og_url":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/judicializados-un-concejal-y-una-mujer-que-estarian-involucrados-en-hechos-de-extorsion-en-casanare-con-presuntos-reincidentes-de-farc\/","og_site_name":"Fiscal\u00eda General de la Naci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/FiscaliaCol","article_published_time":"2020-08-14T18:49:22+00:00","article_modified_time":"2020-08-14T20:06:58+00:00","author":"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@FiscaliaCol","twitter_site":"@FiscaliaCol","twitter_misc":{"Escrito por":"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/judicializados-un-concejal-y-una-mujer-que-estarian-involucrados-en-hechos-de-extorsion-en-casanare-con-presuntos-reincidentes-de-farc\/#article","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/judicializados-un-concejal-y-una-mujer-que-estarian-involucrados-en-hechos-de-extorsion-en-casanare-con-presuntos-reincidentes-de-farc\/"},"author":{"name":"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf28d8ae7f1b287bbe3af484b04f43ea"},"headline":"Judicializados un concejal y una mujer que estar\u00edan involucrados en hechos de extorsi\u00f3n en Casanare con presuntos reincidentes de Farc","datePublished":"2020-08-14T18:49:22+00:00","dateModified":"2020-08-14T20:06:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/judicializados-un-concejal-y-una-mujer-que-estarian-involucrados-en-hechos-de-extorsion-en-casanare-con-presuntos-reincidentes-de-farc\/"},"wordCount":277,"publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"articleSection":["Seccional Yopal","Seccionales","Seguridad territorial"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/judicializados-un-concejal-y-una-mujer-que-estarian-involucrados-en-hechos-de-extorsion-en-casanare-con-presuntos-reincidentes-de-farc\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/judicializados-un-concejal-y-una-mujer-que-estarian-involucrados-en-hechos-de-extorsion-en-casanare-con-presuntos-reincidentes-de-farc\/","name":"Fiscal\u00eda General de la Naci\u00f3n","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website"},"datePublished":"2020-08-14T18:49:22+00:00","dateModified":"2020-08-14T20:06:58+00:00","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","breadcrumb":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/judicializados-un-concejal-y-una-mujer-que-estarian-involucrados-en-hechos-de-extorsion-en-casanare-con-presuntos-reincidentes-de-farc\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/judicializados-un-concejal-y-una-mujer-que-estarian-involucrados-en-hechos-de-extorsion-en-casanare-con-presuntos-reincidentes-de-farc\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/judicializados-un-concejal-y-una-mujer-que-estarian-involucrados-en-hechos-de-extorsion-en-casanare-con-presuntos-reincidentes-de-farc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fiscalia.gov.co\/colombia\/"},{"@type":"ListItem","position":2,"name":"Judicializados un concejal y una mujer que estar\u00edan involucrados en hechos de extorsi\u00f3n en Casanare con presuntos reincidentes de Farc"}]},{"@type":"WebSite","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","name":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization","name":"Fiscal\u00eda General de la Naci\u00f3n","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","contentUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","width":300,"height":90,"caption":"Fiscal\u00eda General de la Naci\u00f3n"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FiscaliaCol","https:\/\/x.com\/FiscaliaCol","https:\/\/www.instagram.com\/fiscaliacol","https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/","https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh"]},{"@type":"Person","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf28d8ae7f1b287bbe3af484b04f43ea","name":"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9d55ae161d32da16dbdd0b380c080a5f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9d55ae161d32da16dbdd0b380c080a5f?s=96&d=mm&r=g","caption":"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n"},"url":"https:\/\/www.fiscalia.gov.co\/colombia\/author\/kbonilla\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/200058","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/users\/162"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/comments?post=200058"}],"version-history":[{"count":2,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/200058\/revisions"}],"predecessor-version":[{"id":200068,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/200058\/revisions\/200068"}],"wp:attachment":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/media?parent=200058"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/categories?post=200058"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/tags?post=200058"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}