{"id":178898,"date":"2019-05-06T16:03:21","date_gmt":"2019-05-06T21:03:21","guid":{"rendered":"https:\/\/www.fiscalia.gov.co\/colombia\/?p=178898"},"modified":"2019-05-06T16:03:21","modified_gmt":"2019-05-06T21:03:21","slug":"asegurados-7-de-los-luna-estructura-que-vende-estupefacientes-al-menudeo-en-pereira","status":"publish","type":"post","link":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/asegurados-7-de-los-luna-estructura-que-vende-estupefacientes-al-menudeo-en-pereira\/","title":{"rendered":"Asegurados 7 de Los Luna, estructura que vende estupefacientes al menudeo en Pereira"},"content":{"rendered":"<p>Un <strong>juzgado penal<\/strong> con funci\u00f3n de control de garant\u00edas de Pereira <strong>envi\u00f3 a prisi\u00f3n<\/strong> a <strong>siete<\/strong> personas, presuntamente, dedicadas a la <strong>venta de sustancias il\u00edcitas<\/strong> en la comuna <strong>R\u00edo Ot\u00fan<\/strong>, barrio <strong>Nuevo Pe\u00f1ol de Pereira<\/strong> (Risaralda).<\/p>\n<p>Se trata de personas presuntamente vinculadas con la estructura denominada <strong>La Luna<\/strong>. El material probatorio recaudado permiti\u00f3 conocer como la banda ser\u00eda la encargada de <strong>comercializar <\/strong><strong>marihuana hidrop\u00f3nica<\/strong> y clorhidrato de <strong>coca\u00edna<\/strong> frente a una instituci\u00f3n educativa del Instituto Colombiano de Bienestar Familiar (<strong>ICBF<\/strong>).<\/p>\n<p>Este caso fue conocido por una fiscal de la <strong>URA<\/strong>, Seccional Risaralda, quien con apoyo del <strong>Cuerpo T\u00e9cnico de Investigaci\u00f3n<\/strong>\u00a0 (CTI) de la <strong>Fiscal\u00eda General\u00a0 de la Naci\u00f3n<\/strong> y la <strong>Polic\u00eda Nacional<\/strong> concretaron las capturas el 30 de abril pasado.<\/p>\n<p>Se trata de:<\/p>\n<ul>\n<li>Andr\u00e9s Fernando Jaramillo Sierra<\/li>\n<li>Maicol Stiven Montoya Ot\u00e1lvaro<\/li>\n<li>John Edison Gaviria Hern\u00e1ndez<\/li>\n<li>Ariel Fernando Qui\u00f1\u00f3nez Jim\u00e9nez<\/li>\n<li>V\u00edctor Alfonso Giraldo Cortes<\/li>\n<li>Henry Z\u00fa\u00f1iga Gonz\u00e1les y<\/li>\n<li>\u00c9dgar Enrique Manjares.<\/li>\n<\/ul>\n<p>Estas personas fueron imputadas por la Fiscal\u00eda como como responsables de los <strong>delitos de tr\u00e1fico, fabricaci\u00f3n o porte de estupefacientes y concierto para delinquir<\/strong>.<\/p>\n<p>La Fiscal\u00eda General de la Naci\u00f3n hace p\u00fablica esta informaci\u00f3n por razones de inter\u00e9s general.<\/p>\n<p>&nbsp;<\/p>\n<p>CRV\/MAGA<\/p>\n\n<div class=\"twitter-share\"><a href=\"https:\/\/twitter.com\/intent\/tweet?via=fiscaliacol\" class=\"twitter-share-button\">Tweet<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Un juzgado penal con funci\u00f3n de control de garant\u00edas de Pereira envi\u00f3 a prisi\u00f3n a siete personas, presuntamente, dedicadas a la venta de sustancias il\u00edcitas en la comuna R\u00edo Ot\u00fan, [&hellip;]<\/p>\n","protected":false},"author":163,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[335,303,24103],"tags":[],"class_list":["post-178898","post","type-post","status-publish","format-standard","category-seccional-pereira","category-seccionales","category-trafico-de-estupefacientes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fiscal\u00eda General de la Naci\u00f3n<\/title>\n<meta name=\"description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/asegurados-7-de-los-luna-estructura-que-vende-estupefacientes-al-menudeo-en-pereira\/\" \/>\n<meta property=\"og:site_name\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FiscaliaCol\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-06T21:03:21+00:00\" \/>\n<meta name=\"author\" content=\"Federico Bar\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:site\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Federico Bar\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/asegurados-7-de-los-luna-estructura-que-vende-estupefacientes-al-menudeo-en-pereira\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/asegurados-7-de-los-luna-estructura-que-vende-estupefacientes-al-menudeo-en-pereira\/\"},\"author\":{\"name\":\"Federico Bar\u00f3n\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/6c583a82254e9615e852ba9db84e67ee\"},\"headline\":\"Asegurados 7 de Los Luna, estructura que vende estupefacientes al menudeo en Pereira\",\"datePublished\":\"2019-05-06T21:03:21+00:00\",\"dateModified\":\"2019-05-06T21:03:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/asegurados-7-de-los-luna-estructura-que-vende-estupefacientes-al-menudeo-en-pereira\/\"},\"wordCount\":235,\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"articleSection\":[\"Seccional Pereira\",\"Seccionales\",\"Tr\u00e1fico de estupefacientes\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/asegurados-7-de-los-luna-estructura-que-vende-estupefacientes-al-menudeo-en-pereira\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/asegurados-7-de-los-luna-estructura-que-vende-estupefacientes-al-menudeo-en-pereira\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\"},\"datePublished\":\"2019-05-06T21:03:21+00:00\",\"dateModified\":\"2019-05-06T21:03:21+00:00\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/asegurados-7-de-los-luna-estructura-que-vende-estupefacientes-al-menudeo-en-pereira\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/asegurados-7-de-los-luna-estructura-que-vende-estupefacientes-al-menudeo-en-pereira\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/asegurados-7-de-los-luna-estructura-que-vende-estupefacientes-al-menudeo-en-pereira\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Asegurados 7 de Los Luna, estructura que vende estupefacientes al menudeo en Pereira\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"contentUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"width\":300,\"height\":90,\"caption\":\"Fiscal\u00eda General de la Naci\u00f3n\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/FiscaliaCol\",\"https:\/\/x.com\/FiscaliaCol\",\"https:\/\/www.instagram.com\/fiscaliacol\",\"https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/\",\"https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/6c583a82254e9615e852ba9db84e67ee\",\"name\":\"Federico Bar\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/30ff8ce2c54287c7927de9067165726c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/30ff8ce2c54287c7927de9067165726c?s=96&d=mm&r=g\",\"caption\":\"Federico Bar\u00f3n\"},\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/author\/fbaron\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Fiscal\u00eda General de la Naci\u00f3n","og_description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","og_url":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/asegurados-7-de-los-luna-estructura-que-vende-estupefacientes-al-menudeo-en-pereira\/","og_site_name":"Fiscal\u00eda General de la Naci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/FiscaliaCol","article_published_time":"2019-05-06T21:03:21+00:00","author":"Federico Bar\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@FiscaliaCol","twitter_site":"@FiscaliaCol","twitter_misc":{"Escrito por":"Federico Bar\u00f3n","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/asegurados-7-de-los-luna-estructura-que-vende-estupefacientes-al-menudeo-en-pereira\/#article","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/asegurados-7-de-los-luna-estructura-que-vende-estupefacientes-al-menudeo-en-pereira\/"},"author":{"name":"Federico Bar\u00f3n","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/6c583a82254e9615e852ba9db84e67ee"},"headline":"Asegurados 7 de Los Luna, estructura que vende estupefacientes al menudeo en Pereira","datePublished":"2019-05-06T21:03:21+00:00","dateModified":"2019-05-06T21:03:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/asegurados-7-de-los-luna-estructura-que-vende-estupefacientes-al-menudeo-en-pereira\/"},"wordCount":235,"publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"articleSection":["Seccional Pereira","Seccionales","Tr\u00e1fico de estupefacientes"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/asegurados-7-de-los-luna-estructura-que-vende-estupefacientes-al-menudeo-en-pereira\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/asegurados-7-de-los-luna-estructura-que-vende-estupefacientes-al-menudeo-en-pereira\/","name":"Fiscal\u00eda General de la Naci\u00f3n","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website"},"datePublished":"2019-05-06T21:03:21+00:00","dateModified":"2019-05-06T21:03:21+00:00","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","breadcrumb":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/asegurados-7-de-los-luna-estructura-que-vende-estupefacientes-al-menudeo-en-pereira\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/asegurados-7-de-los-luna-estructura-que-vende-estupefacientes-al-menudeo-en-pereira\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/asegurados-7-de-los-luna-estructura-que-vende-estupefacientes-al-menudeo-en-pereira\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fiscalia.gov.co\/colombia\/"},{"@type":"ListItem","position":2,"name":"Asegurados 7 de Los Luna, estructura que vende estupefacientes al menudeo en Pereira"}]},{"@type":"WebSite","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","name":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization","name":"Fiscal\u00eda General de la Naci\u00f3n","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","contentUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","width":300,"height":90,"caption":"Fiscal\u00eda General de la Naci\u00f3n"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FiscaliaCol","https:\/\/x.com\/FiscaliaCol","https:\/\/www.instagram.com\/fiscaliacol","https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/","https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh"]},{"@type":"Person","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/6c583a82254e9615e852ba9db84e67ee","name":"Federico Bar\u00f3n","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/30ff8ce2c54287c7927de9067165726c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/30ff8ce2c54287c7927de9067165726c?s=96&d=mm&r=g","caption":"Federico Bar\u00f3n"},"url":"https:\/\/www.fiscalia.gov.co\/colombia\/author\/fbaron\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/178898","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/users\/163"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/comments?post=178898"}],"version-history":[{"count":1,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/178898\/revisions"}],"predecessor-version":[{"id":178899,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/178898\/revisions\/178899"}],"wp:attachment":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/media?parent=178898"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/categories?post=178898"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/tags?post=178898"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}