{"id":177798,"date":"2019-04-02T17:18:27","date_gmt":"2019-04-02T22:18:27","guid":{"rendered":"https:\/\/www.fiscalia.gov.co\/colombia\/?p=177798"},"modified":"2019-04-02T17:18:27","modified_gmt":"2019-04-02T22:18:27","slug":"mas-de-20-capturados-en-medellin-y-antioquia-por-distribucion-de-narcoticos-en-entornos-escolares","status":"publish","type":"post","link":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-antioquia\/mas-de-20-capturados-en-medellin-y-antioquia-por-distribucion-de-narcoticos-en-entornos-escolares\/","title":{"rendered":"M\u00e1s de 20 capturados en Medell\u00edn y Antioquia por distribuci\u00f3n de narc\u00f3ticos en entornos escolares"},"content":{"rendered":"<p><em>Durante los allanamientos se incautaron estupefacientes, armas de fuego y se inmovilizaron cuatro motos usadas para el microtr\u00e1fico.<\/em><\/p>\n<p>Medell\u00edn (Antioquia), martes 2 de abril de 2019.<\/p>\n<p>Dentro de\u00a0\u00a0la estrategia de protecci\u00f3n a entornos escolares, la Fiscal\u00eda General de la Naci\u00f3n \u2014a trav\u00e9s de su polic\u00eda judicial del Cuerpo T\u00e9cnico de Investigaci\u00f3n\u2014, con apoyo del Ej\u00e9rcito\u00a0y la Polic\u00eda Nacional captur\u00f3 a <strong>21 personas en Medell\u00edn<\/strong> y los municipios de <strong>Chigorod\u00f3 y Rionegro<\/strong>.<\/p>\n<p>En la capital antioque\u00f1a los operativos se adelantaron en los barrios Aranjuez, Villa Hermosa, Robledo y La Candelaria, lo mismo que en el corregimiento San Antonio de Prado, donde fueron incautados <strong>1100 gramos de marihuana, 80 gramos de coca\u00edna y 11 frascos de Popper<\/strong>.\u00a0 En las acciones tambi\u00e9n fueron capturadas 2 personas en flagrancia, una de ellas menor de edad; tambi\u00e9n se incaut\u00f3 una <strong>pistola calibre 9 mil\u00edmetros<\/strong> con tres cartuchos.<\/p>\n<p>Las acciones contra el microtr\u00e1fico de la Seccional de Fiscal\u00edas de\u00a0 Antioquia se adelantaron en el municipio de Chigorod\u00f3, donde se logr\u00f3 la captura por orden judicial\u00a0 de <strong>14 presuntos integrantes<\/strong> de una organizaci\u00f3n criminal conocida como <strong>La Empresa<\/strong>, que trabaja para el llamado <strong>Clan del Golfo<\/strong>.<\/p>\n<p>En esa poblaci\u00f3n del Urab\u00e1 Antioque\u00f1o se logr\u00f3 el decomiso de\u00a0 <strong>38 dosis de marihuana<\/strong> que iban a ser comercializadas en un colegio, as\u00ed como la incautaci\u00f3n de <strong>2 millones de pesos en efectivo<\/strong> y la inmovilizaci\u00f3n de <strong>cuatro motocicletas<\/strong>.<\/p>\n<p>A uno de los aprehendidos se le encontr\u00f3 un rev\u00f3lver de fogueo.<\/p>\n<p><strong><u>Golpe en Rionegro.<\/u><\/strong><\/p>\n<p>En este municipio del Oriente antioque\u00f1o fue capturado un soldado profesional que facilitaba la <strong>distribuci\u00f3n de marihuana<\/strong> en un batall\u00f3n de la zona.\u00a0Tambi\u00e9n fue aprehendido un mototaxista que usaba su veh\u00edculo para <strong>comercializaci\u00f3n\u00a0 de estupefacientes en inmediaciones de la guarnici\u00f3n militar<\/strong>; un labriego dedicado al cultivo, secado y venta de la hierba;\u00a0 as\u00ed como dos coordinadores de <strong>plazas de vicio<\/strong> ubicadas muy cerca a <strong>instituciones educativas veredales<\/strong>.<\/p>\n<p>En los procedimientos judiciales fueron incautados una <strong>libra de marihuana, 100 gramos de bazuco, 5 celulares y 11 matas de marihuana.<\/strong>\u00a0 Tambi\u00e9n se incautaron con fines de comiso, <strong>un carro y una motocicleta<\/strong> al parecer utilizados para actividades il\u00edcitas.<\/p>\n<p>La Fiscal\u00eda hace p\u00fablica esta informaci\u00f3n por razones de inter\u00e9s general<\/p>\n<p>&nbsp;<\/p>\n<p>LFML\/DLBM<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n\n<div class=\"twitter-share\"><a href=\"https:\/\/twitter.com\/intent\/tweet?via=fiscaliacol\" class=\"twitter-share-button\">Tweet<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Durante los allanamientos se incautaron estupefacientes, armas de fuego y se inmovilizaron cuatro motos usadas para el microtr\u00e1fico. Medell\u00edn (Antioquia), martes 2 de abril de 2019. Dentro de\u00a0\u00a0la estrategia de [&hellip;]<\/p>\n","protected":false},"author":143,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[318,24103],"tags":[],"class_list":["post-177798","post","type-post","status-publish","format-standard","category-seccional-antioquia","category-trafico-de-estupefacientes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fiscal\u00eda General de la Naci\u00f3n<\/title>\n<meta name=\"description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-antioquia\/mas-de-20-capturados-en-medellin-y-antioquia-por-distribucion-de-narcoticos-en-entornos-escolares\/\" \/>\n<meta property=\"og:site_name\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FiscaliaCol\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-02T22:18:27+00:00\" \/>\n<meta name=\"author\" content=\"dfgordillo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:site\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"dfgordillo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-antioquia\/mas-de-20-capturados-en-medellin-y-antioquia-por-distribucion-de-narcoticos-en-entornos-escolares\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-antioquia\/mas-de-20-capturados-en-medellin-y-antioquia-por-distribucion-de-narcoticos-en-entornos-escolares\/\"},\"author\":{\"name\":\"dfgordillo\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/3903856a3ce2d54b094c69eb29247895\"},\"headline\":\"M\u00e1s de 20 capturados en Medell\u00edn y Antioquia por distribuci\u00f3n de narc\u00f3ticos en entornos escolares\",\"datePublished\":\"2019-04-02T22:18:27+00:00\",\"dateModified\":\"2019-04-02T22:18:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-antioquia\/mas-de-20-capturados-en-medellin-y-antioquia-por-distribucion-de-narcoticos-en-entornos-escolares\/\"},\"wordCount\":411,\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"articleSection\":[\"Seccional Antioquia\",\"Tr\u00e1fico de estupefacientes\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-antioquia\/mas-de-20-capturados-en-medellin-y-antioquia-por-distribucion-de-narcoticos-en-entornos-escolares\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-antioquia\/mas-de-20-capturados-en-medellin-y-antioquia-por-distribucion-de-narcoticos-en-entornos-escolares\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\"},\"datePublished\":\"2019-04-02T22:18:27+00:00\",\"dateModified\":\"2019-04-02T22:18:27+00:00\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-antioquia\/mas-de-20-capturados-en-medellin-y-antioquia-por-distribucion-de-narcoticos-en-entornos-escolares\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-antioquia\/mas-de-20-capturados-en-medellin-y-antioquia-por-distribucion-de-narcoticos-en-entornos-escolares\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-antioquia\/mas-de-20-capturados-en-medellin-y-antioquia-por-distribucion-de-narcoticos-en-entornos-escolares\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00e1s de 20 capturados en Medell\u00edn y Antioquia por distribuci\u00f3n de narc\u00f3ticos en entornos escolares\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"contentUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"width\":300,\"height\":90,\"caption\":\"Fiscal\u00eda General de la Naci\u00f3n\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/FiscaliaCol\",\"https:\/\/x.com\/FiscaliaCol\",\"https:\/\/www.instagram.com\/fiscaliacol\",\"https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/\",\"https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/3903856a3ce2d54b094c69eb29247895\",\"name\":\"dfgordillo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b6356e21c5657c60757fe6fb9493e947?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b6356e21c5657c60757fe6fb9493e947?s=96&d=mm&r=g\",\"caption\":\"dfgordillo\"},\"sameAs\":[\"dfgordillo\"],\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/author\/dfgordillo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Fiscal\u00eda General de la Naci\u00f3n","og_description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","og_url":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-antioquia\/mas-de-20-capturados-en-medellin-y-antioquia-por-distribucion-de-narcoticos-en-entornos-escolares\/","og_site_name":"Fiscal\u00eda General de la Naci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/FiscaliaCol","article_published_time":"2019-04-02T22:18:27+00:00","author":"dfgordillo","twitter_card":"summary_large_image","twitter_creator":"@FiscaliaCol","twitter_site":"@FiscaliaCol","twitter_misc":{"Escrito por":"dfgordillo","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-antioquia\/mas-de-20-capturados-en-medellin-y-antioquia-por-distribucion-de-narcoticos-en-entornos-escolares\/#article","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-antioquia\/mas-de-20-capturados-en-medellin-y-antioquia-por-distribucion-de-narcoticos-en-entornos-escolares\/"},"author":{"name":"dfgordillo","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/3903856a3ce2d54b094c69eb29247895"},"headline":"M\u00e1s de 20 capturados en Medell\u00edn y Antioquia por distribuci\u00f3n de narc\u00f3ticos en entornos escolares","datePublished":"2019-04-02T22:18:27+00:00","dateModified":"2019-04-02T22:18:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-antioquia\/mas-de-20-capturados-en-medellin-y-antioquia-por-distribucion-de-narcoticos-en-entornos-escolares\/"},"wordCount":411,"publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"articleSection":["Seccional Antioquia","Tr\u00e1fico de estupefacientes"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-antioquia\/mas-de-20-capturados-en-medellin-y-antioquia-por-distribucion-de-narcoticos-en-entornos-escolares\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-antioquia\/mas-de-20-capturados-en-medellin-y-antioquia-por-distribucion-de-narcoticos-en-entornos-escolares\/","name":"Fiscal\u00eda General de la Naci\u00f3n","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website"},"datePublished":"2019-04-02T22:18:27+00:00","dateModified":"2019-04-02T22:18:27+00:00","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","breadcrumb":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-antioquia\/mas-de-20-capturados-en-medellin-y-antioquia-por-distribucion-de-narcoticos-en-entornos-escolares\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-antioquia\/mas-de-20-capturados-en-medellin-y-antioquia-por-distribucion-de-narcoticos-en-entornos-escolares\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/seccional-antioquia\/mas-de-20-capturados-en-medellin-y-antioquia-por-distribucion-de-narcoticos-en-entornos-escolares\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fiscalia.gov.co\/colombia\/"},{"@type":"ListItem","position":2,"name":"M\u00e1s de 20 capturados en Medell\u00edn y Antioquia por distribuci\u00f3n de narc\u00f3ticos en entornos escolares"}]},{"@type":"WebSite","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","name":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization","name":"Fiscal\u00eda General de la Naci\u00f3n","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","contentUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","width":300,"height":90,"caption":"Fiscal\u00eda General de la Naci\u00f3n"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FiscaliaCol","https:\/\/x.com\/FiscaliaCol","https:\/\/www.instagram.com\/fiscaliacol","https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/","https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh"]},{"@type":"Person","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/3903856a3ce2d54b094c69eb29247895","name":"dfgordillo","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b6356e21c5657c60757fe6fb9493e947?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b6356e21c5657c60757fe6fb9493e947?s=96&d=mm&r=g","caption":"dfgordillo"},"sameAs":["dfgordillo"],"url":"https:\/\/www.fiscalia.gov.co\/colombia\/author\/dfgordillo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/177798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/users\/143"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/comments?post=177798"}],"version-history":[{"count":1,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/177798\/revisions"}],"predecessor-version":[{"id":177799,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/177798\/revisions\/177799"}],"wp:attachment":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/media?parent=177798"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/categories?post=177798"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/tags?post=177798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}