{"id":159242,"date":"2018-02-08T09:50:12","date_gmt":"2018-02-08T14:50:12","guid":{"rendered":"https:\/\/www.fiscalia.gov.co\/colombia\/?p=159242"},"modified":"2018-02-08T09:51:20","modified_gmt":"2018-02-08T14:51:20","slug":"imputado-alcalde-de-barrancabermeja-santander-y-varios-de-sus-colaboradores-por-delitos-de-constrenimiento-al-elector","status":"publish","type":"post","link":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/imputado-alcalde-de-barrancabermeja-santander-y-varios-de-sus-colaboradores-por-delitos-de-constrenimiento-al-elector\/","title":{"rendered":"Imputado alcalde de Barrancabermeja (Santander) y varios de sus colaboradores por delitos de constre\u00f1imiento al elector"},"content":{"rendered":"<p>Ante el Juzgado 46 Penal de Bogot\u00e1, con funci\u00f3n de control de garant\u00edas, la Fiscal\u00eda General de la Naci\u00f3n imput\u00f3 los delitos de concierto para delinquir, perturbaci\u00f3n al certamen democr\u00e1tico, constre\u00f1imiento al sufragante y corrupci\u00f3n de sufragante, al alcalde del municipio de Barrancabermeja (Santander), Dar\u00edo Echeverry Serrano; as\u00ed como a sus colaboradores Cristian Juliao Camacho, Jhon Jairo Moros y Diego Armando Acosta.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n<p>Por otra parte, a la esposa del primer mandatario de municipio Mariluz N\u00fa\u00f1ez Herrera, le fueron endilgadas las conductas de concierto para delinquir y corrupci\u00f3n al sufragante.<\/p>\n<p>La investigaci\u00f3n, fundamentada en denuncias, entrevistas y la informaci\u00f3n entregada por la Misi\u00f3n de Observaci\u00f3n Electoral (MOE), da cuenta de una serie de irregularidades registradas seis meses antes de las elecciones de revocatoria del mandato al alcalde local, programadas para el 2 de julio de 2017.<\/p>\n<p>De acuerdo con la argumentaci\u00f3n del delegado fiscal, buscaron convencer a los ciudadanos de que no acudieran a las urnas, para no alcanzar el umbral que exige la ley.<\/p>\n<p>Ellos realizaron eventos de car\u00e1cter religioso mediante los cuales supuestamente obligaron a los sufragantes a permanecer ocupados el d\u00eda de las elecciones; adem\u00e1s, hubo campa\u00f1as de desinformaci\u00f3n, restricci\u00f3n del transporte p\u00fablico el d\u00eda de la votaci\u00f3n y eventos en los que les fue retenida la c\u00e9dula de ciudadan\u00eda a los habitantes para evitar que acudieran a depositar su voto.<\/p>\n<p>Del mismo modo, \u201cse realiz\u00f3 una persecuci\u00f3n laboral a quienes estaban a favor de la revocatoria hasta el punto de inducir al despido de 100 integrantes de un sindicato de trabajadores\u201d, asegur\u00f3 el fiscal al realizar la imputaci\u00f3n de cargos.&nbsp;<\/p>\n<p>Agreg\u00f3 el delegado acusador que fue suspendido el pago mensual a una fundaci\u00f3n de personas de la tercera edad, por lo que les dejaron de suministrar alimentos a los ancianos, por su inter\u00e9s en apoyar la revocatoria del mandato.<\/p>\n<p>\u201cSe organizaron sancochos en varios puntos de Barrancabermeja para los cuales los l\u00edderes sociales daban 500.000 pesos, se realizaron bingos, se organizaron partidos de f\u00fatbol, bazares y piques ilegales para retener a los electores\u201d, indic\u00f3 tambi\u00e9n el fiscal.<\/p>\n<p>Igualmente, se dedicaron a \u201camedrentar, amenazar, se utilizaron las redes sociales para hacer fotomontajes para que la gente desconociera el evento democr\u00e1tico\u201d, resalt\u00f3.<\/p>\n<p>Finalmente, se\u00f1al\u00f3 que \u201cse ejerc\u00eda presi\u00f3n psicol\u00f3gica a las personas que estaban sometidas bajo su poder en&nbsp; el municipio\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>CMRM\/DLBM<\/p>\n\n<div class=\"twitter-share\"><a href=\"https:\/\/twitter.com\/intent\/tweet?via=fiscaliacol\" class=\"twitter-share-button\">Tweet<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ante el Juzgado 46 Penal de Bogot\u00e1, con funci\u00f3n de control de garant\u00edas, la Fiscal\u00eda General de la Naci\u00f3n imput\u00f3 los delitos de concierto para delinquir, perturbaci\u00f3n al certamen democr\u00e1tico, [&hellip;]<\/p>\n","protected":false},"author":162,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[24107,322,303],"tags":[],"class_list":["post-159242","post","type-post","status-publish","format-standard","category-lucha-contra-corrupcion","category-seccional-bucaramanga","category-seccionales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fiscal\u00eda General de la Naci\u00f3n<\/title>\n<meta name=\"description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/imputado-alcalde-de-barrancabermeja-santander-y-varios-de-sus-colaboradores-por-delitos-de-constrenimiento-al-elector\/\" \/>\n<meta property=\"og:site_name\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FiscaliaCol\" \/>\n<meta property=\"article:published_time\" content=\"2018-02-08T14:50:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-02-08T14:51:20+00:00\" \/>\n<meta name=\"author\" content=\"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:site\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/imputado-alcalde-de-barrancabermeja-santander-y-varios-de-sus-colaboradores-por-delitos-de-constrenimiento-al-elector\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/imputado-alcalde-de-barrancabermeja-santander-y-varios-de-sus-colaboradores-por-delitos-de-constrenimiento-al-elector\/\"},\"author\":{\"name\":\"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf28d8ae7f1b287bbe3af484b04f43ea\"},\"headline\":\"Imputado alcalde de Barrancabermeja (Santander) y varios de sus colaboradores por delitos de constre\u00f1imiento al elector\",\"datePublished\":\"2018-02-08T14:50:12+00:00\",\"dateModified\":\"2018-02-08T14:51:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/imputado-alcalde-de-barrancabermeja-santander-y-varios-de-sus-colaboradores-por-delitos-de-constrenimiento-al-elector\/\"},\"wordCount\":445,\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"articleSection\":[\"Corrupci\u00f3n\",\"Seccional Bucaramanga\",\"Seccionales\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/imputado-alcalde-de-barrancabermeja-santander-y-varios-de-sus-colaboradores-por-delitos-de-constrenimiento-al-elector\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/imputado-alcalde-de-barrancabermeja-santander-y-varios-de-sus-colaboradores-por-delitos-de-constrenimiento-al-elector\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\"},\"datePublished\":\"2018-02-08T14:50:12+00:00\",\"dateModified\":\"2018-02-08T14:51:20+00:00\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/imputado-alcalde-de-barrancabermeja-santander-y-varios-de-sus-colaboradores-por-delitos-de-constrenimiento-al-elector\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/imputado-alcalde-de-barrancabermeja-santander-y-varios-de-sus-colaboradores-por-delitos-de-constrenimiento-al-elector\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/imputado-alcalde-de-barrancabermeja-santander-y-varios-de-sus-colaboradores-por-delitos-de-constrenimiento-al-elector\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Imputado alcalde de Barrancabermeja (Santander) y varios de sus colaboradores por delitos de constre\u00f1imiento al elector\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"contentUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"width\":300,\"height\":90,\"caption\":\"Fiscal\u00eda General de la Naci\u00f3n\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/FiscaliaCol\",\"https:\/\/x.com\/FiscaliaCol\",\"https:\/\/www.instagram.com\/fiscaliacol\",\"https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/\",\"https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf28d8ae7f1b287bbe3af484b04f43ea\",\"name\":\"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9d55ae161d32da16dbdd0b380c080a5f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9d55ae161d32da16dbdd0b380c080a5f?s=96&d=mm&r=g\",\"caption\":\"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n\"},\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/author\/kbonilla\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Fiscal\u00eda General de la Naci\u00f3n","og_description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","og_url":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/imputado-alcalde-de-barrancabermeja-santander-y-varios-de-sus-colaboradores-por-delitos-de-constrenimiento-al-elector\/","og_site_name":"Fiscal\u00eda General de la Naci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/FiscaliaCol","article_published_time":"2018-02-08T14:50:12+00:00","article_modified_time":"2018-02-08T14:51:20+00:00","author":"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@FiscaliaCol","twitter_site":"@FiscaliaCol","twitter_misc":{"Escrito por":"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/imputado-alcalde-de-barrancabermeja-santander-y-varios-de-sus-colaboradores-por-delitos-de-constrenimiento-al-elector\/#article","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/imputado-alcalde-de-barrancabermeja-santander-y-varios-de-sus-colaboradores-por-delitos-de-constrenimiento-al-elector\/"},"author":{"name":"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf28d8ae7f1b287bbe3af484b04f43ea"},"headline":"Imputado alcalde de Barrancabermeja (Santander) y varios de sus colaboradores por delitos de constre\u00f1imiento al elector","datePublished":"2018-02-08T14:50:12+00:00","dateModified":"2018-02-08T14:51:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/imputado-alcalde-de-barrancabermeja-santander-y-varios-de-sus-colaboradores-por-delitos-de-constrenimiento-al-elector\/"},"wordCount":445,"publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"articleSection":["Corrupci\u00f3n","Seccional Bucaramanga","Seccionales"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/imputado-alcalde-de-barrancabermeja-santander-y-varios-de-sus-colaboradores-por-delitos-de-constrenimiento-al-elector\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/imputado-alcalde-de-barrancabermeja-santander-y-varios-de-sus-colaboradores-por-delitos-de-constrenimiento-al-elector\/","name":"Fiscal\u00eda General de la Naci\u00f3n","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website"},"datePublished":"2018-02-08T14:50:12+00:00","dateModified":"2018-02-08T14:51:20+00:00","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","breadcrumb":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/imputado-alcalde-de-barrancabermeja-santander-y-varios-de-sus-colaboradores-por-delitos-de-constrenimiento-al-elector\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/imputado-alcalde-de-barrancabermeja-santander-y-varios-de-sus-colaboradores-por-delitos-de-constrenimiento-al-elector\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/imputado-alcalde-de-barrancabermeja-santander-y-varios-de-sus-colaboradores-por-delitos-de-constrenimiento-al-elector\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fiscalia.gov.co\/colombia\/"},{"@type":"ListItem","position":2,"name":"Imputado alcalde de Barrancabermeja (Santander) y varios de sus colaboradores por delitos de constre\u00f1imiento al elector"}]},{"@type":"WebSite","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","name":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization","name":"Fiscal\u00eda General de la Naci\u00f3n","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","contentUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","width":300,"height":90,"caption":"Fiscal\u00eda General de la Naci\u00f3n"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FiscaliaCol","https:\/\/x.com\/FiscaliaCol","https:\/\/www.instagram.com\/fiscaliacol","https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/","https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh"]},{"@type":"Person","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf28d8ae7f1b287bbe3af484b04f43ea","name":"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9d55ae161d32da16dbdd0b380c080a5f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9d55ae161d32da16dbdd0b380c080a5f?s=96&d=mm&r=g","caption":"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n"},"url":"https:\/\/www.fiscalia.gov.co\/colombia\/author\/kbonilla\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/159242","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/users\/162"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/comments?post=159242"}],"version-history":[{"count":1,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/159242\/revisions"}],"predecessor-version":[{"id":159243,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/159242\/revisions\/159243"}],"wp:attachment":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/media?parent=159242"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/categories?post=159242"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/tags?post=159242"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}