{"id":159054,"date":"2018-02-02T17:01:56","date_gmt":"2018-02-02T22:01:56","guid":{"rendered":"https:\/\/www.fiscalia.gov.co\/colombia\/?p=159054"},"modified":"2018-02-02T17:01:56","modified_gmt":"2018-02-02T22:01:56","slug":"condenan-a-dos-jovenes-por-homicidio-de-un-habitante-de-calle","status":"publish","type":"post","link":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/condenan-a-dos-jovenes-por-homicidio-de-un-habitante-de-calle\/","title":{"rendered":"Condenan a dos j\u00f3venes por homicidio de un habitante de calle"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-family: 'Arial',sans-serif; color: black;\">La madrugada del 25 de mayo de 2016, tres j\u00f3venes apu\u00f1alaron sin raz\u00f3n aparente y le causaron la muerte&nbsp;al habitante de calle Duqueiro Alberto \u00c1lvarez Torres, de 35 a\u00f1os de edad, quien se encontraba en los alrededores de la Plaza Minorista de la capital antioque\u00f1a.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: 'Arial',sans-serif; color: black;\">Los agresores identificados como Juan Manuel Betancur Cardona, alias Pitu; Mateo Posada Casta\u00f1o, alias Teo;&nbsp;y un menor de edad, fueron capturados el mismo d\u00eda de los hechos y presentados ante un juez de control de garant\u00edas. El menor qued\u00f3 con medida de internamiento y los dos mayores fueron dejados en&nbsp;libertad por el Juzgado 13 Penal Municipal de Medell\u00edn, por considerar que hubo irregularidad en la captura porque fueron llevados primero a un CAI de la Polic\u00eda y luego a la Unidad &nbsp;de Reacci\u00f3n Inmediata (URI).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: 'Arial',sans-serif; color: black;\">Los investigadores establecieron que antes de cometer el homicidio, los tres j\u00f3venes agredieron con arma blanca a otro habitante de calle que dorm\u00eda en el sector.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: 'Arial',sans-serif; color: black;\">Tras la apelaci\u00f3n presentada por &nbsp;la Fiscal\u00eda General de la Naci\u00f3n, un juez de segunda instancia revoc\u00f3 la decisi\u00f3n inicial y orden\u00f3 la recaptura de los procesados.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: 'Arial',sans-serif; color: black;\">Culminado el juicio oral, el Juzgado Cuarto Penal del Circuito de Medell\u00edn conden\u00f3 a&nbsp;Betancur Cardona&nbsp;a una pena de &nbsp;38 a\u00f1os de prisi\u00f3n por el delito de homicidio agravado pero el &nbsp;fallo fue apelado por la defensa ante la Sala Penal del Tribunal Superior de Medell\u00edn. Por su parte, Posada Casta\u00f1o lleg\u00f3 a un acuerdo judicial con&nbsp;la Fiscal\u00eda durante la etapa&nbsp;del juicio y fue sentenciado a 26 a\u00f1os de prisi\u00f3n por homicidio simple.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: 'Arial',sans-serif; color: black;\">LFML\/DLBM<\/span><\/p>\n\n<div class=\"twitter-share\"><a href=\"https:\/\/twitter.com\/intent\/tweet?via=fiscaliacol\" class=\"twitter-share-button\">Tweet<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La madrugada del 25 de mayo de 2016, tres j\u00f3venes apu\u00f1alaron sin raz\u00f3n aparente y le causaron la muerte&nbsp;al habitante de calle Duqueiro Alberto \u00c1lvarez Torres, de 35 a\u00f1os de [&hellip;]<\/p>\n","protected":false},"author":162,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[331,303,24099],"tags":[],"class_list":["post-159054","post","type-post","status-publish","format-standard","category-seccional-medellin","category-seccionales","category-seguridad-territorial"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fiscal\u00eda General de la Naci\u00f3n<\/title>\n<meta name=\"description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/condenan-a-dos-jovenes-por-homicidio-de-un-habitante-de-calle\/\" \/>\n<meta property=\"og:site_name\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FiscaliaCol\" \/>\n<meta property=\"article:published_time\" content=\"2018-02-02T22:01:56+00:00\" \/>\n<meta name=\"author\" content=\"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:site\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/condenan-a-dos-jovenes-por-homicidio-de-un-habitante-de-calle\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/condenan-a-dos-jovenes-por-homicidio-de-un-habitante-de-calle\/\"},\"author\":{\"name\":\"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf28d8ae7f1b287bbe3af484b04f43ea\"},\"headline\":\"Condenan a dos j\u00f3venes por homicidio de un habitante de calle\",\"datePublished\":\"2018-02-02T22:01:56+00:00\",\"dateModified\":\"2018-02-02T22:01:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/condenan-a-dos-jovenes-por-homicidio-de-un-habitante-de-calle\/\"},\"wordCount\":306,\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"articleSection\":[\"Seccional Medell\u00edn\",\"Seccionales\",\"Seguridad territorial\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/condenan-a-dos-jovenes-por-homicidio-de-un-habitante-de-calle\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/condenan-a-dos-jovenes-por-homicidio-de-un-habitante-de-calle\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\"},\"datePublished\":\"2018-02-02T22:01:56+00:00\",\"dateModified\":\"2018-02-02T22:01:56+00:00\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/condenan-a-dos-jovenes-por-homicidio-de-un-habitante-de-calle\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/condenan-a-dos-jovenes-por-homicidio-de-un-habitante-de-calle\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/condenan-a-dos-jovenes-por-homicidio-de-un-habitante-de-calle\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Condenan a dos j\u00f3venes por homicidio de un habitante de calle\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"contentUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"width\":300,\"height\":90,\"caption\":\"Fiscal\u00eda General de la Naci\u00f3n\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/FiscaliaCol\",\"https:\/\/x.com\/FiscaliaCol\",\"https:\/\/www.instagram.com\/fiscaliacol\",\"https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/\",\"https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf28d8ae7f1b287bbe3af484b04f43ea\",\"name\":\"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9d55ae161d32da16dbdd0b380c080a5f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9d55ae161d32da16dbdd0b380c080a5f?s=96&d=mm&r=g\",\"caption\":\"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n\"},\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/author\/kbonilla\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Fiscal\u00eda General de la Naci\u00f3n","og_description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","og_url":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/condenan-a-dos-jovenes-por-homicidio-de-un-habitante-de-calle\/","og_site_name":"Fiscal\u00eda General de la Naci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/FiscaliaCol","article_published_time":"2018-02-02T22:01:56+00:00","author":"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@FiscaliaCol","twitter_site":"@FiscaliaCol","twitter_misc":{"Escrito por":"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/condenan-a-dos-jovenes-por-homicidio-de-un-habitante-de-calle\/#article","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/condenan-a-dos-jovenes-por-homicidio-de-un-habitante-de-calle\/"},"author":{"name":"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf28d8ae7f1b287bbe3af484b04f43ea"},"headline":"Condenan a dos j\u00f3venes por homicidio de un habitante de calle","datePublished":"2018-02-02T22:01:56+00:00","dateModified":"2018-02-02T22:01:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/condenan-a-dos-jovenes-por-homicidio-de-un-habitante-de-calle\/"},"wordCount":306,"publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"articleSection":["Seccional Medell\u00edn","Seccionales","Seguridad territorial"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/condenan-a-dos-jovenes-por-homicidio-de-un-habitante-de-calle\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/condenan-a-dos-jovenes-por-homicidio-de-un-habitante-de-calle\/","name":"Fiscal\u00eda General de la Naci\u00f3n","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website"},"datePublished":"2018-02-02T22:01:56+00:00","dateModified":"2018-02-02T22:01:56+00:00","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","breadcrumb":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/condenan-a-dos-jovenes-por-homicidio-de-un-habitante-de-calle\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/condenan-a-dos-jovenes-por-homicidio-de-un-habitante-de-calle\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/condenan-a-dos-jovenes-por-homicidio-de-un-habitante-de-calle\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fiscalia.gov.co\/colombia\/"},{"@type":"ListItem","position":2,"name":"Condenan a dos j\u00f3venes por homicidio de un habitante de calle"}]},{"@type":"WebSite","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","name":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization","name":"Fiscal\u00eda General de la Naci\u00f3n","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","contentUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","width":300,"height":90,"caption":"Fiscal\u00eda General de la Naci\u00f3n"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FiscaliaCol","https:\/\/x.com\/FiscaliaCol","https:\/\/www.instagram.com\/fiscaliacol","https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/","https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh"]},{"@type":"Person","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf28d8ae7f1b287bbe3af484b04f43ea","name":"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9d55ae161d32da16dbdd0b380c080a5f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9d55ae161d32da16dbdd0b380c080a5f?s=96&d=mm&r=g","caption":"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n"},"url":"https:\/\/www.fiscalia.gov.co\/colombia\/author\/kbonilla\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/159054","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/users\/162"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/comments?post=159054"}],"version-history":[{"count":1,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/159054\/revisions"}],"predecessor-version":[{"id":159055,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/159054\/revisions\/159055"}],"wp:attachment":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/media?parent=159054"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/categories?post=159054"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/tags?post=159054"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}