{"id":158875,"date":"2018-01-31T15:11:17","date_gmt":"2018-01-31T20:11:17","guid":{"rendered":"https:\/\/www.fiscalia.gov.co\/colombia\/?p=158875"},"modified":"2018-01-31T15:11:17","modified_gmt":"2018-01-31T20:11:17","slug":"afectada-industria-ilegal-dedicada-a-la-fasificacion-de-kits-escolares-y-libros-academicos-en-cartagena","status":"publish","type":"post","link":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/afectada-industria-ilegal-dedicada-a-la-fasificacion-de-kits-escolares-y-libros-academicos-en-cartagena\/","title":{"rendered":"Afectada industria ilegal dedicada a la fasificaci\u00f3n de kits escolares y libros acad\u00e9micos en Cartagena"},"content":{"rendered":"<p><em><u>17 personas vinculadas al il\u00edcito fueron capturadas y presentadas ante juez de control de garant\u00edas. En las audiencias, que se cumplieron por procedimiento abreviado (ley 1826 de 2017), la Fiscal\u00eda acus\u00f3 a los detenidos por violaci\u00f3n a los derechos patrimoniales de autor y derechos conexos. Todos los procesados recibieron medida de aseguramiento privativa de la libertad.<\/u><\/em><\/p>\n<p>Cartagena (Bol\u00edvar), 31 de enero de 2017<\/p>\n<p>El inicio del a\u00f1o escolar para varios estudiantes de Cartagena y otras ciudades de la Costa Atl\u00e1ntica pretend\u00eda ser aprovechado por un grupo de personas que puso en funcionamiento un complejo industrial dedicado a la falsificaci\u00f3n a gran escala de textos acad\u00e9micos y kits escolares.<\/p>\n<p>La Fiscal\u00eda Seccional Bol\u00edvar recibi\u00f3 varias denuncias que, m\u00e1s all\u00e1 de poner en evidencia las p\u00e9rdidas econ\u00f3micas que esta actividad ilegal generaba al sector editorial, permitieron conocer que los elementos vendidos a los padres de familia no cumpl\u00edan con los requerimientos de calidad y durabilidad.<\/p>\n<p>Con detalles sobre la ubicaci\u00f3n de los puntos de fabricaci\u00f3n y comercializaci\u00f3n de los \u00fatiles escolares falsificados, el CTI de la Fiscal\u00eda Seccional Bol\u00edvar realiz\u00f3 la operaci\u00f3n denominada Los Acad\u00e9micos.<\/p>\n<p>En diligencias de allanamiento y registro a dos locales comerciales y a una vivienda ubicada en el barrio Chiquinquir\u00e1, en la que se elaboraban los libros, fueron capturadas 17 personas en flagrancia. Los investigadores las encontraron en el proceso de impresi\u00f3n y acondicionamiento de los textos, muchos de ellos estaban empacados e iban a ser entregados a domicilio.<\/p>\n<p>Entre los detenidos est\u00e1n: el representante legal de los dos establecimientos y cuatro ciudadanos venezolanos. Adicionalmente, fueron incautadas 32 impresoras a color multifuncionales, tres fotocopiadoras, cuatro guillotinas, una refiladora, ocho computadores y 2.680&nbsp; libros falsificados de varias editoriales.<\/p>\n<p>Las audiencias concentradas se cumplieron por procedimiento abreviado (ley 1826 de 2017), y las Fiscal\u00eda acus\u00f3 a los procesados por violaci\u00f3n a los derechos patrimoniales de autor y derechos conexos, cargos que solo fueron aceptados por el representante legal.<\/p>\n<p>Por su parte, el juez suspendi\u00f3 el poder dispositivo sobre los elementos incautados con fines de comiso y cobij\u00f3 a los capturados con medida de aseguramiento privativa de la libertad en los lugares de residencia.<\/p>\n<p>El delito de violaci\u00f3n a los derechos patrimoniales de autor est\u00e1 consagrado en el art\u00edculo 271 de C\u00f3digo Penal y la pena oscila entre cuatro y ocho a\u00f1os de prisi\u00f3n, y multa de veintis\u00e9is punto sesenta y seis (26.66) a mil (1.000) salarios m\u00ednimos legales mensuales vigentes.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n\n<div class=\"twitter-share\"><a href=\"https:\/\/twitter.com\/intent\/tweet?via=fiscaliacol\" class=\"twitter-share-button\">Tweet<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>17 personas vinculadas al il\u00edcito fueron capturadas y presentadas ante juez de control de garant\u00edas. En las audiencias, que se cumplieron por procedimiento abreviado (ley 1826 de 2017), la Fiscal\u00eda [&hellip;]<\/p>\n","protected":false},"author":162,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[325,303,24099],"tags":[],"class_list":["post-158875","post","type-post","status-publish","format-standard","category-seccional-cartagena","category-seccionales","category-seguridad-territorial"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fiscal\u00eda General de la Naci\u00f3n<\/title>\n<meta name=\"description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/afectada-industria-ilegal-dedicada-a-la-fasificacion-de-kits-escolares-y-libros-academicos-en-cartagena\/\" \/>\n<meta property=\"og:site_name\" content=\"Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FiscaliaCol\" \/>\n<meta property=\"article:published_time\" content=\"2018-01-31T20:11:17+00:00\" \/>\n<meta name=\"author\" content=\"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:site\" content=\"@FiscaliaCol\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/afectada-industria-ilegal-dedicada-a-la-fasificacion-de-kits-escolares-y-libros-academicos-en-cartagena\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/afectada-industria-ilegal-dedicada-a-la-fasificacion-de-kits-escolares-y-libros-academicos-en-cartagena\/\"},\"author\":{\"name\":\"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf28d8ae7f1b287bbe3af484b04f43ea\"},\"headline\":\"Afectada industria ilegal dedicada a la fasificaci\u00f3n de kits escolares y libros acad\u00e9micos en Cartagena\",\"datePublished\":\"2018-01-31T20:11:17+00:00\",\"dateModified\":\"2018-01-31T20:11:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/afectada-industria-ilegal-dedicada-a-la-fasificacion-de-kits-escolares-y-libros-academicos-en-cartagena\/\"},\"wordCount\":441,\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"articleSection\":[\"Seccional Cartagena\",\"Seccionales\",\"Seguridad territorial\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/afectada-industria-ilegal-dedicada-a-la-fasificacion-de-kits-escolares-y-libros-academicos-en-cartagena\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/afectada-industria-ilegal-dedicada-a-la-fasificacion-de-kits-escolares-y-libros-academicos-en-cartagena\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\"},\"datePublished\":\"2018-01-31T20:11:17+00:00\",\"dateModified\":\"2018-01-31T20:11:17+00:00\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/afectada-industria-ilegal-dedicada-a-la-fasificacion-de-kits-escolares-y-libros-academicos-en-cartagena\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/afectada-industria-ilegal-dedicada-a-la-fasificacion-de-kits-escolares-y-libros-academicos-en-cartagena\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/afectada-industria-ilegal-dedicada-a-la-fasificacion-de-kits-escolares-y-libros-academicos-en-cartagena\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Afectada industria ilegal dedicada a la fasificaci\u00f3n de kits escolares y libros acad\u00e9micos en Cartagena\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#website\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"description\":\"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.\",\"publisher\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#organization\",\"name\":\"Fiscal\u00eda General de la Naci\u00f3n\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"contentUrl\":\"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg\",\"width\":300,\"height\":90,\"caption\":\"Fiscal\u00eda General de la Naci\u00f3n\"},\"image\":{\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/FiscaliaCol\",\"https:\/\/x.com\/FiscaliaCol\",\"https:\/\/www.instagram.com\/fiscaliacol\",\"https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/\",\"https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf28d8ae7f1b287bbe3af484b04f43ea\",\"name\":\"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9d55ae161d32da16dbdd0b380c080a5f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9d55ae161d32da16dbdd0b380c080a5f?s=96&d=mm&r=g\",\"caption\":\"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n\"},\"url\":\"https:\/\/www.fiscalia.gov.co\/colombia\/author\/kbonilla\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Fiscal\u00eda General de la Naci\u00f3n","og_description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","og_url":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/afectada-industria-ilegal-dedicada-a-la-fasificacion-de-kits-escolares-y-libros-academicos-en-cartagena\/","og_site_name":"Fiscal\u00eda General de la Naci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/FiscaliaCol","article_published_time":"2018-01-31T20:11:17+00:00","author":"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@FiscaliaCol","twitter_site":"@FiscaliaCol","twitter_misc":{"Escrito por":"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/afectada-industria-ilegal-dedicada-a-la-fasificacion-de-kits-escolares-y-libros-academicos-en-cartagena\/#article","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/afectada-industria-ilegal-dedicada-a-la-fasificacion-de-kits-escolares-y-libros-academicos-en-cartagena\/"},"author":{"name":"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf28d8ae7f1b287bbe3af484b04f43ea"},"headline":"Afectada industria ilegal dedicada a la fasificaci\u00f3n de kits escolares y libros acad\u00e9micos en Cartagena","datePublished":"2018-01-31T20:11:17+00:00","dateModified":"2018-01-31T20:11:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/afectada-industria-ilegal-dedicada-a-la-fasificacion-de-kits-escolares-y-libros-academicos-en-cartagena\/"},"wordCount":441,"publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"articleSection":["Seccional Cartagena","Seccionales","Seguridad territorial"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/afectada-industria-ilegal-dedicada-a-la-fasificacion-de-kits-escolares-y-libros-academicos-en-cartagena\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/afectada-industria-ilegal-dedicada-a-la-fasificacion-de-kits-escolares-y-libros-academicos-en-cartagena\/","name":"Fiscal\u00eda General de la Naci\u00f3n","isPartOf":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website"},"datePublished":"2018-01-31T20:11:17+00:00","dateModified":"2018-01-31T20:11:17+00:00","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","breadcrumb":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/afectada-industria-ilegal-dedicada-a-la-fasificacion-de-kits-escolares-y-libros-academicos-en-cartagena\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/afectada-industria-ilegal-dedicada-a-la-fasificacion-de-kits-escolares-y-libros-academicos-en-cartagena\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/seccionales\/afectada-industria-ilegal-dedicada-a-la-fasificacion-de-kits-escolares-y-libros-academicos-en-cartagena\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fiscalia.gov.co\/colombia\/"},{"@type":"ListItem","position":2,"name":"Afectada industria ilegal dedicada a la fasificaci\u00f3n de kits escolares y libros acad\u00e9micos en Cartagena"}]},{"@type":"WebSite","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#website","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","name":"Fiscal\u00eda General de la Naci\u00f3n","description":"P\u00e1gina oficial de la Fiscal\u00eda General de la Naci\u00f3n \u2013 Colombia. Garantizamos el acceso efectivo a la justicia, la verdad y la reparaci\u00f3n de las v\u00edctimas de los delitos.","publisher":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fiscalia.gov.co\/colombia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#organization","name":"Fiscal\u00eda General de la Naci\u00f3n","url":"https:\/\/www.fiscalia.gov.co\/colombia\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/","url":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","contentUrl":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-content\/uploads\/LogoHorizontal_1.jpg","width":300,"height":90,"caption":"Fiscal\u00eda General de la Naci\u00f3n"},"image":{"@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FiscaliaCol","https:\/\/x.com\/FiscaliaCol","https:\/\/www.instagram.com\/fiscaliacol","https:\/\/www.linkedin.com\/company\/fiscalia-general-de-la-naci-n\/","https:\/\/youtube.com\/@fiscaliageneraldelanacion-4668?si=6nN79nyQICPU5iTh"]},{"@type":"Person","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/bf28d8ae7f1b287bbe3af484b04f43ea","name":"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/www.fiscalia.gov.co\/colombia\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9d55ae161d32da16dbdd0b380c080a5f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9d55ae161d32da16dbdd0b380c080a5f?s=96&d=mm&r=g","caption":"Direcci\u00f3n de Comunicaciones Fiscal\u00eda General de la Naci\u00f3n"},"url":"https:\/\/www.fiscalia.gov.co\/colombia\/author\/kbonilla\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/158875","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/users\/162"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/comments?post=158875"}],"version-history":[{"count":1,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/158875\/revisions"}],"predecessor-version":[{"id":158882,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/posts\/158875\/revisions\/158882"}],"wp:attachment":[{"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/media?parent=158875"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/categories?post=158875"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fiscalia.gov.co\/colombia\/wp-json\/wp\/v2\/tags?post=158875"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}